{"id":734634,"date":"2026-01-21T04:34:15","date_gmt":"2026-01-21T04:34:15","guid":{"rendered":"https:\/\/www.europesays.com\/de\/734634\/"},"modified":"2026-01-21T04:34:15","modified_gmt":"2026-01-21T04:34:15","slug":"pro-kurdische-demo-polizisten-durch-boeller-verletzt-2","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/734634\/","title":{"rendered":"Pro-kurdische Demo: Polizisten durch B\u00f6ller verletzt"},"content":{"rendered":"<p>Demonstration <\/p>\n<p>Pro-kurdische Demo: Polizisten durch B\u00f6ller verletzt<\/p>\n<p>Aktualisiert am 20.01.2026 &#8211; 22:26 UhrLesedauer: 1 Min.<\/p>\n<p><a href=\"#focus-0\" class=\"transition-colors duration-200 block text-current relative\" data-sctrack=\"FocusGalleryImage.Reference\"><img fetchpriority=\"high\" data-testid=\"Opener.Image\" style=\"--lqipURL:url('https:\/\/images.t-online.de\/2026\/01\/gWlnl9mGCyRz\/0x107:2048x1152\/fit-in\/150x0\/filters:blur(25)\/sieben-beamte-sind-bei-einem-demo-einsatz-in-dortmund-durch-boeller-verletzt-worden-vermutlich-erlitten-sie-knalltraumata-wie-ein-sprecher-sagte.jpg')\"   loading=\"eager\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/01\/sieben-beamte-sind-bei-einem-demo-einsatz-in-dortmund-durch-boeller-verletzt-worden-vermutlich-erlit.jpeg\" alt=\"Pro-kurdische Demo in Dortmund\" title=\"Pro-kurdische Demo in Dortmund\" width=\"2048\" height=\"1152\" class=\"bg-[url:var(--lqipURL)] bg-cover bg-center flex h-full w-full max-w-full\" decoding=\"async\"\/><img style=\"--width:32;--height:32\" loading=\"lazy\" src=\"https:\/\/www.t-online.de\/s\/paper\/_next\/static\/media\/zoom-in.f7dae02f.svg\" alt=\"Vergr\u00f6\u00dfern des Bildes\" title=\"Vergr\u00f6\u00dfern des Bildes\" class=\"block h-[calc(var(--height)_\/_16_*_1rem)] w-[calc(var(--width)_\/_16_*_1rem)] max-w-none absolute bottom-8 right-8 rounded-4 bg-snow p-8\" decoding=\"async\"\/><\/a><\/p>\n<p>Sieben Beamte sind bei einem Demo-Einsatz in Dortmund durch B\u00f6ller verletzt worden. Vermutlich erlitten sie Knalltraumata, wie ein Sprecher sagte. (Quelle: Alex Talash\/dpa\/dpa-bilder)<\/p>\n<p class=\"font-bold text-18 leading-17\">Bei einer pro-kurdischen Demo in Dortmund wurden sieben Polizisten durch B\u00f6ller verletzt. Die Ermittlungen laufen \u2013 auch zu einer Attacke auf einen Imbiss.<\/p>\n<p class=\"text-18 leading-17\">Bei einer pro-kurdischen Demonstration in der Dortmunder Innenstadt sind sieben Polizisten durch B\u00f6llerexplosionen verletzt worden. Sie seien am Bahnhof im Einsatz gewesen, sagte ein Polizeisprecher. Die Beamten h\u00e4tten vermutlich Knalltraumata erlitten. Es gebe keine Hinweise, dass die B\u00f6ller gezielt gegen die Beamten geworfen worden seien, sagte der Sprecher weiter.<\/p>\n<p class=\"text-18 leading-17\">Die Demo stand vermutlich im Zusammenhang mit den gewaltt\u00e4tigen Auseinandersetzungen in Syrien. In der Spitze sollen rund 4.000 Menschen an der Demo teilgenommen haben. Die Polizei war mit einem Gro\u00dfaufgebot vor Ort.<\/p>\n<p class=\"text-18 leading-17\">W\u00e4hrend der Demonstration schlugen nach Angaben der Polizei Versammlungsteilnehmer mehrere Scheiben an einem Imbiss ein. Ermittelt werde gegen unbekannt, sagte ein Polizeisprecher. Warum der Imbiss attackiert wurde, wird noch ermittelt.<\/p>\n","protected":false},"excerpt":{"rendered":"Demonstration Pro-kurdische Demo: Polizisten durch B\u00f6ller verletzt Aktualisiert am 20.01.2026 &#8211; 22:26 UhrLesedauer: 1 Min. Sieben Beamte sind&hellip;\n","protected":false},"author":2,"featured_media":733906,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1833],"tags":[3110,19184,3364,507,29,217,30,157022,1209,121],"class_list":{"0":"post-734634","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dortmund","8":"tag-attacke","9":"tag-boeller","10":"tag-de","11":"tag-demonstration","12":"tag-deutschland","13":"tag-dortmund","14":"tag-germany","15":"tag-knalltrauma","16":"tag-nordrhein-westfalen","17":"tag-polizei"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/115931228784205447","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/734634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=734634"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/734634\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/733906"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=734634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=734634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=734634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}