{"id":760051,"date":"2026-01-31T03:37:37","date_gmt":"2026-01-31T03:37:37","guid":{"rendered":"https:\/\/www.europesays.com\/de\/760051\/"},"modified":"2026-01-31T03:37:37","modified_gmt":"2026-01-31T03:37:37","slug":"verdi-ruft-zu-nahverkehr-streik-am-montag-in-bielefeld-und-guetersloh-auf","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/760051\/","title":{"rendered":"Verdi ruft zu Nahverkehr-Streik am Montag in Bielefeld und G\u00fctersloh auf"},"content":{"rendered":"<p id=\"absatz1\" class=\"em_text\" data-end=\"407\" data-start=\"58\">Bielefeld\/G\u00fctersloh. Fahrg\u00e4ste des \u00f6ffentlichen Nahverkehrs in Ostwestfalen-Lippe m\u00fcssen sich am Montag auf Ausf\u00e4lle und Versp\u00e4tungen einrichten. Die Gewerkschaft Verdi hat die Besch\u00e4ftigten der kommunalen Verkehrsbetriebe mit Beginn der Fr\u00fchschicht aufgerufen, die Arbeit niederzulegen. Dies gelte bis auf wenige Ausnahmen fl\u00e4chendeckend, sagte eine Verdi-Sprecherin.<\/p>\n<p id=\"absatz2\" class=\"em_text\" data-end=\"753\" data-start=\"414\">Gestreikt werde bei verschiedenen Nahverkehrsunternehmen in ganz Deutschland. Mit dabei sind auch Besch\u00e4ftigte der Bielefelder Mobiel GmbH und der Stadtbus G\u00fctersloh GmbH. Das teilte ein Verdi-Vertreter mit.<\/p>\n<p id=\"absatz3\" class=\"em_text\" data-end=\"753\" data-start=\"414\">Der Streik betrifft Besch\u00e4ftigte aus dem Fahrdienst, den Werkst\u00e4tten, den Leitstellen und der Verwaltung. Der Warnstreik beginnt am Montag, 2. Februar, um 4 Uhr und endet voraussichtlich am Dienstag, 3. Februar, um 4 Uhr. In dieser Zeit kommt es zu Ausf\u00e4llen im Bus- und Bahnverkehr. Regional- und S-Bahnen sind nicht von den Streikma\u00dfnahmen betroffen.<\/p>\n<p>\n        \u00d7\n    <\/p>\n<p>\n            Sie erhalten in wenigen Minuten eine E-Mail zur Best\u00e4tigung Ihrer Anmeldung.\n        <\/p>\n<p>Erst danach ist diese abgeschlossen.<\/p>\n<p>Bitte pr\u00fcfen Sie auch den Spam-Ordner.<\/p>\n<p>\n        \u00d7\n    <\/p>\n<p>\n            Sie haben bisher Ihre E-Mail-Adresse noch nicht best\u00e4tigt.\n        <\/p>\n<p>Erst danach ist diese abgeschlossen.<\/p>\n<p>Bitte pr\u00fcfen Sie auch den Spam-Ordner.<\/p>\n<p>\n        \u00d7\n    <\/p>\n<p>\n            Es ist einen Fehler aufgetreten\n        <\/p>\n<p>Bei Fragen hilft unser Newsletter-Support<\/p>\n<p> Newsletter<\/p>\n<p> Update zum Mittag<\/p>\n<p>Top-News, t\u00e4glich aus der Chefredaktion zusammengestellt.<\/p>\n<p>                Jetzt anmelden<\/p>\n<p>Keine Mobiel-Busse und Stadtbahnen in Bielefeld<\/p>\n<p class=\"em_text\" data-end=\"971\" data-start=\"760\">In Bielefeld f\u00e4llt der Nahverkehr an diesem Tag komplett aus. \u201eVon 4 Uhr morgens bis 4 Uhr am Dienstag wird keine Stadtbahn unterwegs sein und auch kein Mobiel-Bus fahren\u201c, teilt Mobiel mit.<\/p>\n<p id=\"absatz5\" class=\"em_text\" data-end=\"1287\" data-start=\"978\">\u201eWir m\u00fcssen mit einer hohen Beteiligung der Besch\u00e4ftigten rechnen und kommen deshalb aus betrieblichen Gr\u00fcnden an dieser Ma\u00dfnahme nicht vorbei\u201c, sagt Mobiel-Gesch\u00e4ftsf\u00fchrer Arne Petersen. Das Bielefelder Nahverkehrsunternehmen plane jedoch, auf Teilstrecken Ersatzbusse von Fremdunternehmen fahren zu lassen.<\/p>\n<p id=\"absatz6\" class=\"em_text\" data-end=\"1504\" data-start=\"1294\">Eine \u00dcbersicht der Ersatzfahrten finden Sie <a href=\"https:\/\/www.mobiel.de\/aktuelles\/aktuelle-news\/infos-zum-streik-am-2-februar-2026\/\" rel=\"noopener\" target=\"_blank\">hier.<\/a> Au\u00dferdem erscheinen die stattfindenden Fahrten regul\u00e4r in der Mobiel-App, hei\u00dft es in einer Pressemeldung des Unternehmens. Auch die Fahrten in die Nachbarst\u00e4dte von Mobiel entfallen. Unter anderem sind hiervon die Linien 52, 53, 152 und 153 nach Herford betroffen.<\/p>\n<p id=\"absatz7\" class=\"em_text\" data-end=\"1504\" data-start=\"1294\">In G\u00fctersloh wird ebenfalls gestreikt. Nach Angaben des Verkehrsunternehmens Stadtbus G\u00fctersloh fallen am Montag ganzt\u00e4gig Stadtbusse, Schulbusse sowie der Shuttlebus-Verkehr aus.<\/p>\n<p>        <a href=\"https:\/\/www.nw.de\/_em_daten\/_cache\/image\/1xRDhlVms3Mk03Y3o2VzVYUUVVNzVjU29oWG04SFg2aE1lWFUyODhocWEzZjRzYTNPRGw3MWx5NEZBbnBYbGdzeEFPOWQzcEpRM2Z2aGhqbHlUYkt3SmVzOHZLSURIZ3FQazFqUmpRMmFtbFE9\/260130-1042-807744268.jpg\" class=\"nw-article-image\" title=\"Die Mobiel-Busse werden bei dem Warnstreik am Montag stillstehen.\" data-glightbox=\"type: image; description: Die Mobiel-Busse werden bei dem Warnstreik am Montag stillstehen.  | \u00a9 Barbara Franke \" target=\"_blank\" rel=\"noopener\"><br \/>\n            <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/01\/260130-1042-807744268.jpg\" class=\"nw-img-fluid nw-w-full nw-lazy nw-rounded-t-md\" alt=\"Die Mobiel-Busse werden bei dem Warnstreik am Montag stillstehen. - \u00a9 Barbara Franke\" data-format=\"16:9\"\/><br \/>\n        <\/a><\/p>\n<p>                Die Mobiel-Busse werden bei dem Warnstreik am Montag stillstehen.<br \/>\n                                    | \u00a9 Barbara Franke<\/p>\n<p>Verdi will mehr Ruhezeiten und Zuschl\u00e4ge<\/p>\n<p class=\"em_text\">Mit den Warnstreiks soll der Druck auf die Arbeitgeber erh\u00f6ht werden, die zweite Verhandlungsrunde der Tarifgespr\u00e4che ist f\u00fcr den 2. M\u00e4rz geplant. Auch in anderen Bundesl\u00e4ndern soll der Nahverkehr weitgehend zum Stillstand kommen. Insgesamt betroffen seien fast 100.000 Besch\u00e4ftigte in 150 st\u00e4dtischen Verkehrsunternehmen und Busbetrieben.<\/p>\n<p id=\"absatz9\" class=\"em_text\">Verdi NRW fordert, die w\u00f6chentliche Arbeitszeit von 39 Stunden bei vollem Lohnausgleich zu verk\u00fcrzen. Auf welche Stundenzahl genau soll noch konkretisiert werden. Die Ruhezeit zwischen zwei Schichten soll von zehn auf elf Stunden erh\u00f6ht werden, und der Zuschlag f\u00fcr Sonntagsarbeit soll von 25 Prozent des Stundenentgelts auf mindestens 40 Prozent steigen.<\/p>\n<p id=\"absatz10\" class=\"nw-text-base nw-text-gray-500 nw-font-medium\"><b class=\"bold\">AfD im Betrieb:<\/b> <a href=\"https:\/\/www.nw.de\/nachrichten\/nachrichten\/24240989_Verdi-Chef-gegen-Rechtstendenzen-in-Betrieben.html\" target=\"_blank\" rel=\"noopener\">Verdi-Chef gegen Rechtstendenzen in Betrieben<\/a><\/p>\n<p id=\"absatz11\" class=\"em_text\">Au\u00dferdem pocht die Gewerkschaft auf deutlich mehr Investitionen in Infrastruktur und Personal. Beim vorangegangenen Tarifkonflikt um die Entgelte der Besch\u00e4ftigten in den kommunalen Verkehrsbetrieben in NRW legten Warnstreiks den Nahverkehr in vielen Gro\u00dfst\u00e4dten lahm, teilweise \u00fcber mehrere Tage.<\/p>\n<p>Arbeitgeber lehnen Forderungen ab<\/p>\n<p id=\"absatz12\" class=\"em_text\">\u201eDie Belastung im \u00d6PNV ist in NRW seit Jahren extrem hoch\u201c, sagte Verdi-NRW-Verhandlungsf\u00fchrer Heinz Rech. \u201eSchichtdienste, Zeitdruck und Personalmangel treiben viele an ihre Grenzen.\u201c Er warf den Arbeitgebern vor, keine Verbesserungen zuzulassen. Die Besch\u00e4ftigten seien aber bereit, f\u00fcr bessere Bedingungen zu k\u00e4mpfen. \u201eDer Streik ist ein klares Signal an die Arbeitgeber, endlich Bewegung zu zeigen.\u201c<\/p>\n<p id=\"absatz13\" class=\"em_text\">Die Arbeitgeber werfen Verdi unrealistische Forderungen vor. Die Gewerkschaft ignoriere dabei die schlechte Finanzlage der kommunalen Nahverkehrsunternehmen. W\u00fcrde man den Forderungen nachkommen, m\u00fcsste voraussichtlich an vielen Stellen verst\u00e4rkt etwa \u00fcber die Einstellung von Linien, \u00fcber l\u00e4ngere Takte und \u00fcber die Vergabe von Bef\u00f6rderungsleistungen an das private Busgewerbe nachgedacht werden, argumentiert der Kommunale Arbeitgeberverband Nordrhein-Westfalen.<\/p>\n<p>Warnstreik im Nahverkehr: Das m\u00fcssen Arbeitnehmer wissen<\/p>\n<p id=\"absatz14\" class=\"em_text\">Was bedeutet der Warnstreik f\u00fcr Arbeitnehmerinnen und Arbeitnehmer, die auf dem Weg zum Job auf den \u00d6PNV angewiesen sind? Die wichtigsten Punkte im \u00dcberblick.<\/p>\n<p>Arbeitnehmer sind f\u00fcr ihren Arbeitsweg verantwortlich<\/p>\n<p id=\"absatz15\" class=\"em_text\">Grunds\u00e4tzlich gilt, dass Arbeitnehmerinnen und Arbeitnehmer selbst daf\u00fcr verantwortlich sind, p\u00fcnktlich im Betrieb anzukommen, sie tragen das sogenannte \u201eWegerisiko\u201c. Das gilt bei Streik genauso wie etwa bei Schnee und Gl\u00e4tte. Hei\u00dft: Auch wenn Busse und Bahnen nicht fahren, d\u00fcrfen Angestellte nicht einfach zu sp\u00e4t kommen. Darauf macht Volker G\u00f6rzel vom Verband deutscher Arbeitsrechtsanw\u00e4lte (VDAA) aufmerksam.<\/p>\n<p id=\"absatz16\" class=\"em_text\">Wenn das Homeoffice keine L\u00f6sung ist, m\u00fcssen Angestellte also nach zumutbaren Alternativen suchen. Gibt die M\u00f6glichkeit, Angebote von Unternehmen zu nutzen, die nicht bestreikt werden \u2013 etwa die Deutsche Bahn oder andere private Unternehmen? Ist das eigene Auto eine Option oder sind Fahrgemeinschaften mit Kolleginnen denkbar? Auch das Taxi kann eine Alternative sein.<\/p>\n<p>Viel zu sp\u00e4t dran: Diese Konsequenzen sind m\u00f6glich<\/p>\n<p id=\"absatz17\" class=\"em_text\">Wichtig: Wer keine der zumutbaren Alternativen nutzt und dann zu sp\u00e4t oder gar nicht zur Arbeit kommt, muss im Zweifelsfall mit Konsequenzen rechnen, hei\u00dft es vom VDAA. Wenn es hart auf hart kommt, gilt laut VDAA der Grundsatz \u201eohne Arbeit kein Lohn\u201c. Wer also wegen eines Streiks zu sp\u00e4t oder im schlimmsten Fall gar nicht arbeitet, hat auch keinen Anspruch auf Bezahlung \u2013 das Gehalt kann entsprechend gek\u00fcrzt werden. Auch eine Abmahnung ist denkbar.<\/p>\n<p>        <a href=\"https:\/\/www.nw.de\/_em_daten\/_cache\/image\/1xblY5ZWlKTjJTYjUwc1NOV3NJVFAyWEc5Y2MybTNod2tvWExzQTVqNXhqVTk5bXF6cUtCWjgvc3pxL3BlaXAza0k4N3pzSFVXbFNsenZsUHkzMXB1M3Z3VXBvSVVVQzRrOVZCbGRzd00vY009\/260130-1257-808790628.jpg\" class=\"nw-article-image\" title=\"Stillstand im Nahverkehr: Flexible L\u00f6sungen wie Homeoffice, Gleitzeit oder Urlaub k\u00f6nnen eine Alternative sein \u2013 ein Gespr\u00e4ch mit den Vorgesetzten kann helfen.\" data-glightbox=\"type: image; description: Stillstand im Nahverkehr: Flexible L\u00f6sungen wie Homeoffice, Gleitzeit oder Urlaub k\u00f6nnen eine Alternative sein \u2013 ein Gespr\u00e4ch mit den Vorgesetzten kann helfen.  | \u00a9 Fabian Strauch\/dpa\/dpa-tmn \" target=\"_blank\" rel=\"noopener\"><br \/>\n            <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/01\/260130-1257-808790628.jpg\" class=\"nw-img-fluid nw-w-full nw-lazy nw-rounded-t-md\" alt=\"Stillstand im Nahverkehr: Flexible L\u00f6sungen wie Homeoffice, Gleitzeit oder Urlaub k\u00f6nnen eine Alternative sein \u2013 ein Gespr\u00e4ch mit den Vorgesetzten kann helfen. - \u00a9 Fabian Strauch\/dpa\/dpa-tmn\" data-format=\"16:9\"\/><br \/>\n        <\/a><\/p>\n<p>                Stillstand im Nahverkehr: Flexible L\u00f6sungen wie Homeoffice, Gleitzeit oder Urlaub k\u00f6nnen eine Alternative sein \u2013 ein Gespr\u00e4ch mit den Vorgesetzten kann helfen.<br \/>\n                                    | \u00a9 Fabian Strauch\/dpa\/dpa-tmn<\/p>\n<p>Schon vor dem Streik mit den Vorgesetzten sprechen<\/p>\n<p class=\"em_text\">Je nach Arbeitsvertrag, Betriebsvereinbarung oder Tarifvertrag k\u00f6nnte auch eine Nacharbeit f\u00fcr die verpasste Zeit eine Option sein. Hier komme es in der Praxis darauf an, eine annehmbare L\u00f6sung f\u00fcr beide Seiten zu finden.<\/p>\n<p id=\"absatz19\" class=\"em_text\">Doch soweit muss es nicht kommen. Angestellte sollten schon bei der Ank\u00fcndigung eines Streiks mit ihren Vorgesetzten ins Gespr\u00e4ch gehen und die eigene Situation schildern. Oft gebe es f\u00fcr solche F\u00e4lle betriebliche Regelungen, so der VDAA. Neben dem Homeoffice in einigen Berufen k\u00f6nnten auch Gleitzeit oder kurzfristiger Urlaub L\u00f6sungen sein.<\/p>\n<p id=\"absatz20\" class=\"em_text\">\u00dcbrigens: Wer erst auf dem Arbeitsweg merkt, dass er oder sie sich versp\u00e4tet, sollte Vorgesetzte umgehend informieren \u2013 auch das kann \u00c4rger ersparen, ganz unabh\u00e4ngig von Streik und Schnee.<\/p>\n<p id=\"absatz21\">mit dpa-Material<\/p>\n","protected":false},"excerpt":{"rendered":"Bielefeld\/G\u00fctersloh. Fahrg\u00e4ste des \u00f6ffentlichen Nahverkehrs in Ostwestfalen-Lippe m\u00fcssen sich am Montag auf Ausf\u00e4lle und Versp\u00e4tungen einrichten. Die Gewerkschaft&hellip;\n","protected":false},"author":2,"featured_media":760052,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1841],"tags":[21005,173146,2227,1605,3364,29,10120,30,16398,9307,1611,1609,2379,167802,2377,2378,734,2381,164252,26093,1613,26010,4186,1209,176,22058,16406,15156,2523],"class_list":{"0":"post-760051","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-bielefeld","8":"tag-pnv","9":"tag-arne-petersen","10":"tag-bahnverkehr","11":"tag-bielefeld","12":"tag-de","13":"tag-deutschland","14":"tag-gtersloh","15":"tag-germany","16":"tag-herford","17":"tag-label_foto","18":"tag-label_informiere-mich","19":"tag-label_plus-ok","20":"tag-label_push","21":"tag-label_rg-top-1","22":"tag-label_startseite","23":"tag-label_umfrage","24":"tag-meta_artikelklasse_nachricht","25":"tag-meta_copyrights_rgowl_freier_mitarbeiter","26":"tag-meta_eo_zusammenfassung","27":"tag-meta_themen_verkehr_mobilitaet","28":"tag-meta_userneeds_informieremich","29":"tag-mobiel","30":"tag-nahverkehr","31":"tag-nordrhein-westfalen","32":"tag-nrw","33":"tag-ostwestfalen-lippe","34":"tag-schnee","35":"tag-vereinte-dienstleistungsgewerkschaft","36":"tag-warnstreik"},"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/760051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=760051"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/760051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/760052"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=760051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=760051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=760051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}