{"id":767795,"date":"2026-02-03T04:19:22","date_gmt":"2026-02-03T04:19:22","guid":{"rendered":"https:\/\/www.europesays.com\/de\/767795\/"},"modified":"2026-02-03T04:19:22","modified_gmt":"2026-02-03T04:19:22","slug":"jugendamt-zieht-positive-zwischenbilanz-zum-kita-portal","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/767795\/","title":{"rendered":"Jugendamt zieht positive Zwischenbilanz zum Kita-Portal"},"content":{"rendered":"<p>Durch bereits erfolgte Umstellungen von Ganztagsgruppen hin zu Ganztags- und Halbtagsmischgruppen konnten zudem rund 500 zuvor nicht belegbare Betreuungspl\u00e4tze in st\u00e4dtischen Einrichtungen angeboten werden. Grund hierf\u00fcr ist der passgenaue Einsatz von Teilzeitkr\u00e4ften.<\/p>\n<p>Trotz der genannten Verbesserungen gelingt es noch nicht in jedem Fall, einer Familie sofort ihren Wunsch-Platz anzubieten. Mitte Januar 2026 waren im Portal 768 Kinder mit Wunschaufnahmedatum bis Ende Januar registriert, die bereits ein Platzangebot erhalten haben, dieses aber verpasst oder abgelehnt haben. 855 Kindern mit diesem Wunschaufnahmedatum konnte bislang kein Platz angeboten werden. Damit ist die Zahl der unversorgten Kinder in Stuttgart deutlich zur\u00fcckgegangen. Vor allem bei den f\u00fcnf- und sechsj\u00e4hrigen Kindern, die bislang keinen Platz erhalten, abgelehnt oder verpasst haben, sank die Zahl auf nunmehr 68. In diesen F\u00e4llen arbeitet der Kitaservice gemeinsam mit den Eltern intensiv an L\u00f6sungen.<\/p>\n<p>Insgesamt unterst\u00fctzt das Kita-Portal die bedarfsgerechte Versorgung mit Kitapl\u00e4tzen seit seiner Einf\u00fchrung ma\u00dfgeblich. Gemeinsam mit der Einf\u00fchrung der \u00fcberarbeiteten Platzvergabekriterien wurden zwei Meilensteine im Kita-Weiterentwicklungsprozess erreicht. Da die im Prozess definierten Schritte abgeschlossen werden konnten, wurde der Prozess Ende vergangenen Jahres formal beendet und die Themen zur Weiterentwicklung der Kindertagesbetreuung in die Regelstruktur beim Jugendamt \u00fcberf\u00fchrt.<\/p>\n","protected":false},"excerpt":{"rendered":"Durch bereits erfolgte Umstellungen von Ganztagsgruppen hin zu Ganztags- und Halbtagsmischgruppen konnten zudem rund 500 zuvor nicht belegbare&hellip;\n","protected":false},"author":2,"featured_media":4018,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1830],"tags":[1634,174473,174474,3364,29,174475,174476,174477,30,70045,28432,174478,174479,2818,174480,174481,174482,174483,68537,142923,25228,11628,3491,174484,79113,29945,174485,1441,145957,162822,174486],"class_list":{"0":"post-767795","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-stuttgart","8":"tag-baden-wuerttemberg","9":"tag-betriebskindertageseinrichtung","10":"tag-betriebskindertageseinrichtungen","11":"tag-de","12":"tag-deutschland","13":"tag-eltern-kind-gruppe","14":"tag-evangelischer-kindergarten","15":"tag-ganztageseinrichtung","16":"tag-germany","17":"tag-hort","18":"tag-jugendamt","19":"tag-katholischer-kindergarten","20":"tag-kiga","21":"tag-kindergarten","22":"tag-kindergartenplatz","23":"tag-kinderkrippe","24":"tag-kinderkrippenplatz","25":"tag-kindertagesbetreuung","26":"tag-kindertageseinrichtung","27":"tag-kindertageseinrichtungen","28":"tag-kindertagesstaette","29":"tag-kindertagesstaetten","30":"tag-kita","31":"tag-kits","32":"tag-montessori","33":"tag-portal","34":"tag-staedtischer-kindergarten","35":"tag-stuttgart","36":"tag-tageseinrichtungen","37":"tag-waldkindergarten","38":"tag-waldorfkindergarten"},"share_on_mastodon":{"url":"","error":"Validation failed: Text character limit of 500 exceeded"},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/767795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=767795"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/767795\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/4018"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=767795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=767795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=767795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}