{"id":768650,"date":"2026-02-03T12:29:09","date_gmt":"2026-02-03T12:29:09","guid":{"rendered":"https:\/\/www.europesays.com\/de\/768650\/"},"modified":"2026-02-03T12:29:09","modified_gmt":"2026-02-03T12:29:09","slug":"bpol-f-gefaehrliche-koerperverletzung-zum-nachteil-eines-reisenden-zeugenaufruf","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/768650\/","title":{"rendered":"BPOL-F: Gef\u00e4hrliche K\u00f6rperverletzung zum Nachteil eines Reisenden &#8211; Zeugenaufruf"},"content":{"rendered":"<p class=\"date\">03.02.2026 \u2013 12:34<\/p>\n<p class=\"customer\">\n                        <a class=\"story-customer\" title=\"weiter zum newsroom von Bundespolizeiinspektion Frankfurt\/Main\" href=\"https:\/\/www.presseportal.de\/blaulicht\/nr\/63987\" rel=\"nofollow noopener\" target=\"_blank\">Bundespolizeiinspektion Frankfurt\/Main<\/a>\n                    <\/p>\n<p><a data-category=\"citylink-story-view\" data-action=\"click\" data-label=\"Citylink in Meldungsansicht\" class=\"story-city event-trigger\" href=\"https:\/\/www.presseportal.de\/regional\/Frankfurt%20am%20Main\" title=\"News aus Frankfurt am Main \" rel=\"nofollow noopener\" target=\"_blank\">Frankfurt am Main<\/a> (ots)<\/p>\n<p>Frankfurt am Main &#8211; Die Bundespolizei ermittelt wegen des Verdachts der gef\u00e4hrlichen K\u00f6rperverletzung zum Nachteil eines Reisenden und bittet die \u00d6ffentlichkeit um Mithilfe.<\/p>\n<p>Am Sonntag, den 1. Februar 2026, kam es im Zeitraum zwischen 13:42 Uhr und 16:30 Uhr in einer S-Bahn der Linie S4 auf der Strecke Kronberg &#8211; Frankfurt-S\u00fcd zu einer k\u00f6rperlichen Auseinandersetzung. Der Vorfall ereignete sich nach bisherigen Erkenntnissen im Bereich des S-Bahnsteigs 101 am Frankfurter Hauptbahnhof.<\/p>\n<p>Ein Zeuge informierte die Bundespolizei rund 20 Minuten nach dem Geschehen dar\u00fcber, dass drei Jugendliche in der S-Bahn gemeinschaftlich auf einen m\u00e4nnlichen Reisenden eingeschlagen haben sollen. W\u00e4hrend der Auseinandersetzung sei zudem ein pistolen\u00e4hnlicher Gegenstand zu Boden gefallen. Ob es im Zusammenhang mit dem Vorfall zu einem Bedrohungs- oder Raubdelikt gekommen ist, ist weiter Gegenstand der Ermittlungen.<\/p>\n<p>Im Rahmen der sofort eingeleiteten Ma\u00dfnahmen der Bundespolizeiinspektion Frankfurt am Main, inklusive der Auswertung der Videoaufzeichnungen aus dem Bahnhofsbereich konnten drei mutma\u00dflich tatbeteiligte Personen identifiziert werden.<\/p>\n<p>Auf den Aufnahmen ist unter anderem zu erkennen, wie eine der Personen beim Betreten der S-Bahn Trittbewegungen gegen den Gesch\u00e4digten ausf\u00fchrt. Beim Verlassen der S-Bahn f\u00fchrt diese Person einen pistolen\u00e4hnlichen Gegenstand mit sich, den sie anschlie\u00dfend im Hosenbund verstaut. Die Person wird dabei von zwei weiteren Beteiligten begleitet.<\/p>\n<p>Im Anschluss fl\u00fcchteten alle drei Tatverd\u00e4chtigen vom Ereignisort und bestiegen eine Regionalbahn an Gleis 10 des Frankfurter Hauptbahnhofs.<\/p>\n<p>Die Bundespolizei bittet nun Zeuginnen und Zeugen, die den Vorfall beobachtet haben oder Angaben zu den beteiligten Personen, deren Fluchtrichtung oder dem mitgef\u00fchrten Gegenstand machen k\u00f6nnen, sich zu melden.<\/p>\n<p>Hinweise nimmt die Bundespolizeiinspektion Frankfurt am Main unter der Telefonnummer 069 \/ 130-145 0 oder \u00fcber jede andere Polizeidienststelle entgegen.<\/p>\n<p>Hinweise k\u00f6nnen auch anonym erfolgen.<\/p>\n<p class=\"contact-headline\">R\u00fcckfragen bitte an:<\/p>\n<p class=\"contact-text\">R\u00fcckfragen bitte an:<br \/>Bundespolizeiinspektion Frankfurt am Main<br \/>Pressestelle<br \/>Telefon: 069 \/ 130145 0<\/p>\n<p>E-Mail: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/63987\/mailto: bpoli.frankfurt.am.main.presse@polizei.bund.de\" class=\"uri-mailto\" rel=\"nofollow noopener\" target=\"_blank\"> bpoli.frankfurt.am.main.presse@polizei.bund.de<\/a><\/p>\n<p class=\"originator\">Original-Content von: Bundespolizeiinspektion Frankfurt\/Main, \u00fcbermittelt durch news aktuell<\/p>\n","protected":false},"excerpt":{"rendered":"03.02.2026 \u2013 12:34 Bundespolizeiinspektion Frankfurt\/Main Frankfurt am Main (ots) Frankfurt am Main &#8211; Die Bundespolizei ermittelt wegen des&hellip;\n","protected":false},"author":2,"featured_media":386213,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1829],"tags":[29,2050,2051,30,1087,2052,177,121,178,180,179,181,17273],"class_list":["post-768650","post","type-post","status-publish","format-standard","has-post-thumbnail","category-frankfurt-am-main","tag-deutschland","tag-frankfurt","tag-frankfurt-am-main","tag-germany","tag-he","tag-hessen","tag-kriminalitt","tag-polizei","tag-presse","tag-pressemeldung","tag-pressemitteilung","tag-pressemitteilungen","tag-rp"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116006706436922364","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/768650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=768650"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/768650\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/386213"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=768650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=768650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=768650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}