{"id":773794,"date":"2026-02-05T12:16:15","date_gmt":"2026-02-05T12:16:15","guid":{"rendered":"https:\/\/www.europesays.com\/de\/773794\/"},"modified":"2026-02-05T12:16:15","modified_gmt":"2026-02-05T12:16:15","slug":"fahrgastverband-kritisiert-chaos-zwischen-potsdam-und-berlin","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/773794\/","title":{"rendered":"Fahrgastverband kritisiert Chaos zwischen Potsdam und Berlin"},"content":{"rendered":"<p class=\"tspCCnp tspCCnq\">Pendlern zwischen Potsdam und Berlin wird noch bis Ende Februar eine \u00dcberraschung geboten: Zwar fahren die Z\u00fcge des Regionalexpress 1, betrieben von der Ostdeutschen Eisenbahn (Odeg), aus der Landeshauptstadt Richtung Berliner Zentrum, doch wie weit, kann sich erheblich unterscheiden. Mal ist in Berlin-Charlottenburg Schluss, mal am Zoologischen Garten oder am Ostbahnhof. In seltenen F\u00e4llen sollen die Z\u00fcge sogar bis Ostkreuz fahren. <\/p>\n<p>Potsdam Heute Newsletter<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/04\/pnn-widget.png\" alt=\"\" class=\"tspCFgx\"\/><\/p>\n<p class=\"tspCFn5\"> Der Newsletter aus der PNN-Chefredaktion. Wissen, was in Potsdam wichtig ist \u2014 kostenlos freitags in Ihrer Mailbox. <\/p>\n<p class=\"tspCCnp\">Das Zug-Lotto emp\u00f6rt nun den Deutschen Bahnkundenverband. \u201eDie Informationen dazu auf den Webseiten der Odeg sind eine Zumutung f\u00fcr die Fahrg\u00e4ste. Welcher Zug an welchen Tagen wohin f\u00e4hrt, erschlie\u00dft sich erst nach zeitaufwendigen Recherchen\u201c, teilt der Regionalverband Potsdam-Mittelmark mit. Als Ersatz werde auf die \u201enicht besonders zuverl\u00e4ssige\u201c S 7 verwiesen.<\/p>\n<p class=\"tspCCnp\">\u201eDer Deutsche Bahnkundenverband forderte im Interesse der Pendler und der Reisenden, die in Berlin Hauptbahnhof zwischen RE 1 und dem Fernverkehr umsteigen, eine Durchbindung aller RE 1 an allen Tagen bis Ostbahnhof oder Ostkreuz\u201c, hei\u00dft es weiter. Die Odeg werde aufgefordert, einen lesbaren Ersatzfahrplan auf ihren Webseiten einzustellen. <\/p>\n<p class=\"tspCCnp\">Hintergrund der Sperrung sind Bauarbeiten der DB InfraGo \u2013 dabei handelt es sich um den Netzbetreiber der Deutschen Bahn. Die DB teilt auf Anfrage mit, dass Fernbahngleise gesperrt werden, <a href=\"https:\/\/www.tagesspiegel.de\/berlin\/bezirke\/einschrankungen-im-bahnverkehr-drohen-s-bahnhof-in-berlin-treptow-wird-umgebaut-11982335.html?icid=in-text-link_15219625\" class=\"link link--internal\" data-gtm-class=\"article-text-link\" data-gtm-val=\"internal\" target=\"_blank\" rel=\"noopener\">weil am Berliner S-Bahnhof K\u00f6penick gebaut wird<\/a>. Dort sollen Br\u00fcckenteile \u00fcber die H\u00e4mmerlingstra\u00dfe eingeschoben werden. <\/p>\n<p>Lesen Sie auch:<a href=\"https:\/\/www.tagesspiegel.de\/potsdam\/landeshauptstadt\/bauarbeiten-auf-wichtiger-pendlerstrecke-regionalexpress-wird-umgeleitet-oder-fallt-ganz-aus-15183391.html?icid=topic-list_15219625___\" data-gtm-class=\"article-mzt-link\" data-hydrate-fingerprint=\"09740a54944caac75fd2c0c63fd5c5df\" data-hydrate-props=\"{&amp;escapedquot;element&amp;escapedquot;:{&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;relatedContent&amp;escapedquot;,&amp;escapedquot;fieldMap&amp;escapedquot;:{},&amp;escapedquot;relation&amp;escapedquot;:{&amp;escapedquot;fields&amp;escapedquot;:{&amp;escapedquot;isPaid&amp;escapedquot;:null},&amp;escapedquot;href&amp;escapedquot;:&amp;escapedquot;\/potsdam\/landeshauptstadt\/bauarbeiten-auf-wichtiger-pendlerstrecke-regionalexpress-wird-umgeleitet-oder-fallt-ganz-aus-15183391.html&amp;escapedquot;,&amp;escapedquot;teaserTitle&amp;escapedquot;:{&amp;escapedquot;kicker&amp;escapedquot;:&amp;escapedquot;Einschr\u00e4nkungen f\u00fcr Potsdamer und Berliner Pendler&amp;escapedquot;,&amp;escapedquot;headline&amp;escapedquot;:&amp;escapedquot;Regionalexpress RE1 wird wegen Bauarbeiten umgeleitet oder f\u00e4llt ganz aus&amp;escapedquot;},&amp;escapedquot;id&amp;escapedquot;:&amp;escapedquot;15183391&amp;escapedquot;,&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;story&amp;escapedquot;},&amp;escapedquot;isPartOfList&amp;escapedquot;:true,&amp;escapedquot;topicListType&amp;escapedquot;:&amp;escapedquot;topic-list&amp;escapedquot;},&amp;escapedquot;showArrow&amp;escapedquot;:true}\" data-hydrate-slots=\"{&#039;default&#039;:[]}\" class=\"tspC3qb tspC2p9\" target=\"_blank\" rel=\"noopener\">Einschr\u00e4nkungen f\u00fcr Potsdamer und Berliner Pendler Regionalexpress RE1 wird wegen Bauarbeiten umgeleitet oder f\u00e4llt ganz aus <\/a><a href=\"https:\/\/www.tagesspiegel.de\/potsdam\/landeshauptstadt\/fahrplanwechsel-am-14-dezember-das-andert-sich-im-regionalverkehr-in-potsdam-und-umgebung-14899781.html?icid=topic-list_15219625___\" data-gtm-class=\"article-mzt-link\" data-hydrate-fingerprint=\"09740a54944caac75fd2c0c63fd5c5df\" data-hydrate-props=\"{&amp;escapedquot;element&amp;escapedquot;:{&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;relatedContent&amp;escapedquot;,&amp;escapedquot;fieldMap&amp;escapedquot;:{},&amp;escapedquot;relation&amp;escapedquot;:{&amp;escapedquot;fields&amp;escapedquot;:{&amp;escapedquot;isPaid&amp;escapedquot;:null},&amp;escapedquot;href&amp;escapedquot;:&amp;escapedquot;\/potsdam\/landeshauptstadt\/fahrplanwechsel-am-14-dezember-das-andert-sich-im-regionalverkehr-in-potsdam-und-umgebung-14899781.html&amp;escapedquot;,&amp;escapedquot;teaserTitle&amp;escapedquot;:{&amp;escapedquot;kicker&amp;escapedquot;:&amp;escapedquot;Fahrplanwechsel am 14. Dezember&amp;escapedquot;,&amp;escapedquot;headline&amp;escapedquot;:&amp;escapedquot;Das \u00e4ndert sich im Regionalverkehr in Potsdam und Umgebung&amp;escapedquot;},&amp;escapedquot;id&amp;escapedquot;:&amp;escapedquot;14899781&amp;escapedquot;,&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;story&amp;escapedquot;},&amp;escapedquot;isPartOfList&amp;escapedquot;:true,&amp;escapedquot;topicListType&amp;escapedquot;:&amp;escapedquot;topic-list&amp;escapedquot;},&amp;escapedquot;showArrow&amp;escapedquot;:true}\" data-hydrate-slots=\"{&#039;default&#039;:[]}\" class=\"tspC3qb tspC2p9\" target=\"_blank\" rel=\"noopener\">Fahrplanwechsel am 14. Dezember Das \u00e4ndert sich im Regionalverkehr in Potsdam und Umgebung <\/a><a href=\"https:\/\/www.tagesspiegel.de\/berlin\/kernsanierung-am-alexanderplatz-neue-strecke-zum-hauptbahnhof-diese-baustellen-erwarten-berlins-fahrgaste-in-2026-15076162.html?icid=topic-list_15219625___\" data-gtm-class=\"article-mzt-link\" data-hydrate-fingerprint=\"09740a54944caac75fd2c0c63fd5c5df\" data-hydrate-props=\"{&amp;escapedquot;element&amp;escapedquot;:{&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;relatedContent&amp;escapedquot;,&amp;escapedquot;fieldMap&amp;escapedquot;:{},&amp;escapedquot;relation&amp;escapedquot;:{&amp;escapedquot;fields&amp;escapedquot;:{&amp;escapedquot;isPaid&amp;escapedquot;:null},&amp;escapedquot;href&amp;escapedquot;:&amp;escapedquot;\/berlin\/kernsanierung-am-alexanderplatz-neue-strecke-zum-hauptbahnhof-diese-baustellen-erwarten-berlins-fahrgaste-in-2026-15076162.html&amp;escapedquot;,&amp;escapedquot;teaserTitle&amp;escapedquot;:{&amp;escapedquot;kicker&amp;escapedquot;:&amp;escapedquot;Kernsanierung am Alex, neue Strecke zum Hauptbahnhof&amp;escapedquot;,&amp;escapedquot;headline&amp;escapedquot;:&amp;escapedquot;Diese Baustellen erwarten Berlins Fahrg\u00e4ste in 2026&amp;escapedquot;},&amp;escapedquot;id&amp;escapedquot;:&amp;escapedquot;15076162&amp;escapedquot;,&amp;escapedquot;type&amp;escapedquot;:&amp;escapedquot;story&amp;escapedquot;},&amp;escapedquot;isPartOfList&amp;escapedquot;:true,&amp;escapedquot;topicListType&amp;escapedquot;:&amp;escapedquot;topic-list&amp;escapedquot;},&amp;escapedquot;showArrow&amp;escapedquot;:true}\" data-hydrate-slots=\"{&#039;default&#039;:[]}\" class=\"tspC3qb tspC2p9\" target=\"_blank\" rel=\"noopener\">Kernsanierung am Alex, neue Strecke zum Hauptbahnhof Diese Baustellen erwarten Berlins Fahrg\u00e4ste in 2026 <\/a><\/p>\n<p class=\"tspCCnp\">Eins ist allerdings sicher: Bis nach Frankfurt (Oder) fahren die Z\u00fcge nie durch. Denn zwischen Ostkreuz und Erkner befindet sich die Baustelle. Und es wird auch nicht die letzte Sperrung der Strecke bleiben: \u201eEine weitere Sperrung im Bereich K\u00f6penick (Fernbahngleise) ist vom 10. Juli bis 24. August vorgesehen\u201c, so ein Bahnsprecher.<\/p>\n<p class=\"tspCCnp\">Die S-Bahnlinie S7 ist von den Bauarbeiten nicht betroffen. Sie hat eigene Gleise, ist aber langsamer unterwegs. Vom Potsdamer zum Berliner Hauptbahnhof dauert es dann 37 Minuten statt 22 bis 26 Minuten.<\/p>\n","protected":false},"excerpt":{"rendered":"Pendlern zwischen Potsdam und Berlin wird noch bis Ende Februar eine \u00dcberraschung geboten: Zwar fahren die Z\u00fcge des&hellip;\n","protected":false},"author":2,"featured_media":773795,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1825],"tags":[17655,296,2030,29,30,6486],"class_list":{"0":"post-773794","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-berlin","8":"tag-baustellen","9":"tag-berlin","10":"tag-deutsche-bahn","11":"tag-deutschland","12":"tag-germany","13":"tag-lotto"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116017980015437134","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/773794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=773794"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/773794\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/773795"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=773794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=773794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=773794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}