{"id":791382,"date":"2026-02-12T08:44:14","date_gmt":"2026-02-12T08:44:14","guid":{"rendered":"https:\/\/www.europesays.com\/de\/791382\/"},"modified":"2026-02-12T08:44:14","modified_gmt":"2026-02-12T08:44:14","slug":"deutschland-totes-kind-und-schwerverletzte-bei-hochhausbrand-in-berlin","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/791382\/","title":{"rendered":"Deutschland: Totes Kind und Schwerverletzte bei Hochhausbrand in Berlin"},"content":{"rendered":"<p>  <img decoding=\"async\" class=\"m-image-and-caption__image lazyload\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/dc86ac00-74e7-45fa-838d-2fe99a2feb69.jpeg\"  data- alt=\"dpatopbilder - Bei einem Hochhausbrand im Berliner Osten sind nach Feuerwehrangaben mehrere Menschen verletzt worden. Foto: Annette Riedl\/dpa\"\/><\/p>\n<p>      dpatopbilder &#8211; Bei einem Hochhausbrand im Berliner Osten sind nach Feuerwehrangaben mehrere Menschen verletzt worden. Foto: Annette Riedl\/dpa<\/p>\n<p>        Keystone\n      <\/p>\n<p class=\"a-paragraph a-paragraph--lead\" data-t-name=\"Paragraph\">Nach einem verheerenden Brand in einem Hochhaus in Berlin ist ein Kind gestorben, der Zustand eines weiteren schwer verletzten Kindes und einer Frau ist unklar.<\/p>\n<p class=\"a-paragraph\" data-t-name=\"Paragraph\">Alle drei wurden laut Feuerwehr bewusstlos im Hausflur der dritten Etage gefunden, wo auch die Brandwohnung war. Bei der Fahrt in eine Klinik wurden sie reanimiert. 20 Wohnungen in dem Komplex im Stadtteil Friedrichsfelde mit sch\u00e4tzungsweise mehr als 150 Wohnungen seien vorerst nicht bewohnbar, sagte ein Sprecher.<\/p>\n<p class=\"a-paragraph\" data-t-name=\"Paragraph\">170 Feuerwehrleute waren im Einsatz, sie holten unter Atemschutz 70 Menschen aus dem verrauchten Geb\u00e4ude mit 20 Geschossen beziehungsweise brachten sie in Sicherheit. Insgesamt acht Menschen wurden in Kliniken gebracht. Schwerverletzt wurde neben der Frau und dem Kind ein weiterer Mensch.<\/p>\n<p class=\"a-paragraph\" data-t-name=\"Paragraph\">Das Feuer war am Mittwochabend in einer Wohnung des Komplexes im Bezirk Lichtenberg ausgebrochen. Es breitete sich rasant aus, da die R\u00e4ume mit zahlreichen Gegenst\u00e4nden zugestellt waren. Nach Informationen der Deutschen Presse-Agentur (dpa) handelte es sich um eine sogenannte Messie-Wohnung, die grosse Unordnung erschwerte die Brandbek\u00e4mpfung.<\/p>\n<p class=\"a-paragraph\" data-t-name=\"Paragraph\">Als die Einsatzkr\u00e4fte eintrafen, brannte die Wohnung bereits komplett. Im ganzen Geb\u00e4ude breitete sich Rauch aus, aus den Fenstern schlugen Flammen. Im Hausflur nahe der Brandwohnung entdeckten die Einsatzkr\u00e4fte die zwei Kinder und die Frau bewusstlos und brachten sie ins Freie.<\/p>\n<p>Bewohner machten an Fenstern auf sich aufmerksam<\/p>\n<p class=\"a-paragraph\" data-t-name=\"Paragraph\">Der Bewohner der Wohnung hatte sich laut Feuerwehr selbst nach draussen retten k\u00f6nnen. Auch andere Bewohner des Hauses gelangten dem Sprecher zufolge selbst ins Freie, viele andere w\u00e4hlten den Notruf oder machten an den Fenstern auf sich aufmerksam. Sie wurden von Feuerwehrtrupps durch das Treppenhaus nach draussen gebracht.<\/p>\n<p class=\"a-paragraph\" data-t-name=\"Paragraph\">Insgesamt sammelten sich vor dem Haus so 70 Bewohner, wie der Sprecher mitteilte. Die Einsatzkr\u00e4fte pr\u00fcften etwa 60 Wohnungen, einsturzgef\u00e4hrdet war das Haus nicht.<\/p>\n<p>Bezirk bem\u00fcht sich um alternative Unterk\u00fcnfte<\/p>\n<p class=\"a-paragraph\" data-t-name=\"Paragraph\">Viele Bewohner mussten erst einmal anderweitig unterkommen. In manchen der unbewohnbaren Einheiten gebe es keinen Strom und kein Wasser. Andere seien so verraucht, dass man dort nicht schlafen k\u00f6nne. Wer nicht bei Verwandten oder Bekannten unterkomme, k\u00f6nne heute in einer nahegelegenen Turnhalle schlafen. Der Bezirk versuche, f\u00fcr die Zeit danach Wohnungen und Hotels zu organisieren, hiess es.<\/p>\n<p class=\"a-paragraph\" data-t-name=\"Paragraph\">Die Polizei ermittelt zur Ursache.<\/p>\n","protected":false},"excerpt":{"rendered":"dpatopbilder &#8211; Bei einem Hochhausbrand im Berliner Osten sind nach Feuerwehrangaben mehrere Menschen verletzt worden. Foto: Annette Riedl\/dpa&hellip;\n","protected":false},"author":2,"featured_media":791383,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1825],"tags":[1941,1939,296,1937,29,30,1940,1938],"class_list":["post-791382","post","type-post","status-publish","format-standard","has-post-thumbnail","category-berlin","tag-aktuelle-nachrichten-aus-berlin","tag-aktuelle-news-aus-berlin","tag-berlin","tag-berlin-news","tag-deutschland","tag-germany","tag-nachrichten-aus-berlin","tag-news-aus-berlin"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116056782740418504","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/791382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=791382"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/791382\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/791383"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=791382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=791382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=791382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}