{"id":797945,"date":"2026-02-14T21:34:14","date_gmt":"2026-02-14T21:34:14","guid":{"rendered":"https:\/\/www.europesays.com\/de\/797945\/"},"modified":"2026-02-14T21:34:14","modified_gmt":"2026-02-14T21:34:14","slug":"2-liga-elversberg-siegt-nach-rueckstand-in-dresden-und-schiebt-sich-an-schalke-vorbei-sport","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/797945\/","title":{"rendered":"2. Liga: Elversberg siegt nach R\u00fcckstand in Dresden und schiebt sich an Schalke vorbei | Sport"},"content":{"rendered":"<p><a class=\"skip-content skip-content--link\" href=\"#in-content-skip-link-target-v-0-0\">TTS-Player \u00fcberspringen\u21b5<\/a><a id=\"in-content-skip-link-target-v-0-0\" class=\"skip-content--target-link-hidden skip-content skip-content--target-link\" href=\"#in-content-skip-link-target-v-0-0\">Artikel weiterlesen<\/a><\/p>\n<p><b>Der Aufstiegskandidat setzt sich durch! Elversberg siegt in Dresden nach R\u00fcckstand mit 2:1. Dynamo bleibt in der Tabelle auf Platz 17, w\u00e4hrend Elversberg im Aufstiegsrennen auf Platz 2 vorr\u00fcckt und somit vorerst auch Schalke (aktuell nur Vierter) hinter sich l\u00e4sst. Die K\u00f6nigsblauen treten am Sonntag bei Holstein Kiel (13.30 Uhr, Sky und <\/b><a href=\"https:\/\/sport.bild.de\/fussball\/2-bundesliga\/ma11200025\/holstein-kiel_fc-schalke-04\/liveticker\/\" target=\"_blank\" rel=\"nofollow noopener\" class=\"text-link--external text-link\"><b>auf bild.de im Live-Ticker<\/b><\/a><b>) an.<\/b><\/p>\n<p>Dynamo nimmt im Vergleich zum 2:2 auf Schalke vier Startelf-\u00c4nderungen vor. U.a. fehlt Innenverteidiger Julian Pauly nach seiner Brummsch\u00e4del-Aktion (Zusammenprall mit Schalkes Nikola Katic). Er wird durch Youngster Friedrich M\u00fcller ersetzt, der am Tag des Spiels seinen 20. Geburtstag feiert.<\/p>\n<p>Dresden-Knaller, doch Elversberg kontert<\/p>\n<p>Ein echter Knaller bringt <a href=\"https:\/\/www.bild.de\/sport\/fussball\/dynamo-dresden\/startseite-dynamo-46789412.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Dresden<\/a> in F\u00fchrung: Jonas Sterner spielt zu Niklas Hauptmann, der auf Ben Bobzien legt. Der bedient von Au\u00dfenverteidiger zu Au\u00dfenverteidiger Alexander Rossipal. Und der knallt den Ball mit 114 km\/h ins Netz! F\u00fcr Rossipal ist es schon das vierte Saisontor. Er ist der torgef\u00e4hrlichste Abwehrspieler der 2. Liga in dieser Saison.<\/p>\n<p>Jason Ceka erzielt vermeintlich das zweite Tor von Dresden, doch er steht im Abseits (24.). Der Schiri nimmt nach Hinweis des Video-Unparteiischen den Treffer zur\u00fcck. Generell spielt Dynamo in den ersten 30 Minuten sehr \u00fcberzeugend.<\/p>\n<p><img decoding=\"async\" width=\"992\" height=\"558\" alt=\"Intensives Spiel zwischen Dresden und Elversberg\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/fb3cacedfdcdc69a298ffa94ee80765b,3b6c3a74.jpeg\"   class=\"landscape\" loading=\"lazy\"\/><\/p>\n<p class=\"fig__caption__text\">Intensives Spiel zwischen Dresden und Elversberg<\/p>\n<p>Foto: Frank Hammerschmidt\/dpa<\/p>\n<p>In der zweiten H\u00e4lfte wird <a href=\"https:\/\/www.bild.de\/sport\/fussball\/sv-elversberg\/startseite-elversberg-84236332.bild.html\" class=\"text-link\" rel=\"nofollow noopener\" target=\"_blank\">Elversberg<\/a> besser. Nicholas Mickelson verwandelt nach hohem Steilpass von Maximilian Rohr aus rund zehn Metern zum 1:1 (58.). Und Lukas Petkov trifft nach einem von Dresden-Torwart Tim Schreiber nach vorn abgewehrtem Schuss von Lasse G\u00fcnther per Abstauber zum 2:1 f\u00fcr Elversberg (78.).<\/p>\n<p>F\u00fcr Dynamo ist es die erste Niederlage in der R\u00fcckrunde \u2013 nach zuvor zwei Siegen und zwei Unentschieden aus den letzten vier Spielen. Elversberg zeigt eine Reaktion auf das 0:3 gegen Hertha in der Vorwoche \u2013 das war die erste Heimniederlage seit knapp einem Jahr.<\/p>\n","protected":false},"excerpt":{"rendered":"TTS-Player \u00fcberspringen\u21b5Artikel weiterlesen Der Aufstiegskandidat setzt sich durch! Elversberg siegt in Dresden nach R\u00fcckstand mit 2:1. Dynamo bleibt&hellip;\n","protected":false},"author":2,"featured_media":797946,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1835],"tags":[3364,29,2386,3766,347,30,859,5079,45,1261,14465,784],"class_list":{"0":"post-797945","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dresden","8":"tag-de","9":"tag-deutschland","10":"tag-dresden","11":"tag-dynamo-dresden","12":"tag-fussball","13":"tag-germany","14":"tag-sachsen","15":"tag-sv-elversberg","16":"tag-texttospeech","17":"tag-toralarm-top-news","18":"tag-verteidiger","19":"tag-zweite-bundesliga"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116071135190455169","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/797945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=797945"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/797945\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/797946"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=797945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=797945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=797945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}