{"id":809797,"date":"2026-02-19T14:59:18","date_gmt":"2026-02-19T14:59:18","guid":{"rendered":"https:\/\/www.europesays.com\/de\/809797\/"},"modified":"2026-02-19T14:59:18","modified_gmt":"2026-02-19T14:59:18","slug":"pol-ka-ka-bruchsal-rheinstetten-angebliche-handwerker-erbeuten-bargeld-polizei","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/809797\/","title":{"rendered":"POL-KA: (KA) Bruchsal\/Rheinstetten &#8211; Angebliche Handwerker erbeuten Bargeld &#8211; Polizei &#8230;"},"content":{"rendered":"<p class=\"date\">19.02.2026 \u2013 15:26<\/p>\n<p class=\"customer\">\n                        <a class=\"story-customer\" title=\"weiter zum newsroom von Polizeipr\u00e4sidium Karlsruhe\" href=\"https:\/\/www.presseportal.de\/blaulicht\/nr\/110972\" rel=\"nofollow noopener\" target=\"_blank\">Polizeipr\u00e4sidium Karlsruhe<\/a>\n                    <\/p>\n<p><a data-category=\"citylink-story-view\" data-action=\"click\" data-label=\"Citylink in Meldungsansicht\" class=\"story-city event-trigger\" href=\"https:\/\/www.presseportal.de\/regional\/Karlsruhe\" title=\"News aus Karlsruhe \" rel=\"nofollow noopener\" target=\"_blank\">Karlsruhe<\/a> (ots)<\/p>\n<p>Nach derzeitigem Ermittlungsstand gaben sich in Bruchsal und Rheinstetten bislang unbekannte M\u00e4nner als Handwerker aus und erbeuteten Bargeld und Wertgegenst\u00e4nde.<\/p>\n<p>Ein bislang unbekannter T\u00e4ter verschaffte sich mutma\u00dflich in betr\u00fcgerischer Absicht gegen 13:10 Uhr Zutritt zu einer Wohnung in der Schlo\u00dfstra\u00dfe in Bruchsal. Hierbei gelang es dem T\u00e4ter eine 90-j\u00e4hrige Frau unter dem Vorwand, Reparaturen t\u00e4tigen zu m\u00fcssen, zu t\u00e4uschen und anschlie\u00dfend einen dreistelligen Bargeldbetrag und zwei Mobiltelefone zu erbeuten.<\/p>\n<p>Ein \u00e4hnlich gelagerter Trickdiebstahl ereignete sich am selben Tag in Forchheim in der Vogesenstra\u00dfe. Gegen 14:30 Uhr gaben sich zwei M\u00e4nner als angebliche Wasserwerker aus und t\u00e4uschten ebenfalls vor, Handwerksarbeiten durchf\u00fchren zu m\u00fcssen.<br \/>\nNachdem die Betr\u00fcger die Wohnung verlie\u00dfen, stellte die 81-J\u00e4hrige das Fehlen mehrerer tausend Euro Bargeld fest und alarmierte die Polizei.<\/p>\n<p>Ob die beiden Taten in Zusammenhang miteinander stehen bedarf weiterer Ermittlungen.<\/p>\n<p>Die Kriminalpolizei hat die Ermittlungen aufgenommen und bittet Zeugen, die im Tatzeitraum verd\u00e4chtige Personen oder Fahrzeuge wahrgenommen haben, sich unter 0721 666-5555 beim Kriminaldauerdienst Karlsruhe zu melden.<\/p>\n<p>Aus aktuellem Anlass r\u00e4t die Polizei:<\/p>\n<p>   &#8211;\tWerden Sie misstrauisch bei Forderungen nach schnellen<br \/>\nEntscheidungen, Kontaktaufnahme mit Fremden sowie Herausgabe von<br \/>\npers\u00f6nlichen Daten, Bargeld, Schmuck oder Wertgegenst\u00e4nden.   &#8211;\tLassen Sie sich am Telefon nicht unter Druck setzen. Legen Sie<br \/>\nden H\u00f6rer auf. So werden Sie Betr\u00fcger los.   &#8211;\tW\u00e4hlen Sie die 110 und teilen Sie den Sachverhalt mit. Benutzen<br \/>\nSie nicht die R\u00fcckruftaste, da Sie sonst unter Umst\u00e4nden wieder bei<br \/>\nden T\u00e4tern landen. &#8211;\tSprechen Sie am Telefon nicht \u00fcber Ihre<br \/>\npers\u00f6nlichen und finanziellen Verh\u00e4ltnisse.   &#8211;\tBeraten Sie sich mit Ihrer Familie oder Personen, denen Sie<br \/>\nvertrauen.<\/p>\n<p>Weitere Informationen und Pr\u00e4ventionstipps finden Sie unter:<br \/>\n<a target=\"_blank\" class=\"uri-ext outbound\" rel=\"noopener nofollow\" href=\"https:\/\/www.polizei-beratung.de\">www.polizei-beratung.de<\/a><\/p>\n<p>Ogulcan Bozkurt &#8211; Pressestelle<\/p>\n<p class=\"contact-headline\">R\u00fcckfragen bitte an:<\/p>\n<p class=\"contact-text\">Polizeipr\u00e4sidium Karlsruhe<br \/>Telefon: 0721 666-1111<br \/>E-Mail: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/110972\/mailto: pressestelle.ka@polizei.bwl.de\" class=\"uri-mailto\" rel=\"nofollow noopener\" target=\"_blank\"> pressestelle.ka@polizei.bwl.de<\/a><br \/><a target=\"_blank\" class=\"uri-ext outbound\" rel=\"noopener nofollow\" href=\"http:\/\/www.polizei-bw.de\/\">http:\/\/www.polizei-bw.de\/<\/a><\/p>\n<p class=\"originator\">Original-Content von: Polizeipr\u00e4sidium Karlsruhe, \u00fcbermittelt durch news aktuell<\/p>\n","protected":false},"excerpt":{"rendered":"19.02.2026 \u2013 15:26 Polizeipr\u00e4sidium Karlsruhe Karlsruhe (ots) Nach derzeitigem Ermittlungsstand gaben sich in Bruchsal und Rheinstetten bislang unbekannte&hellip;\n","protected":false},"author":2,"featured_media":386213,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1844],"tags":[1634,6187,3364,29,30,8903,177,121,178,180,179,181],"class_list":{"0":"post-809797","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-karlsruhe","8":"tag-baden-wuerttemberg","9":"tag-bw","10":"tag-de","11":"tag-deutschland","12":"tag-germany","13":"tag-karlsruhe","14":"tag-kriminalitt","15":"tag-polizei","16":"tag-presse","17":"tag-pressemeldung","18":"tag-pressemitteilung","19":"tag-pressemitteilungen"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116097893631828735","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/809797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=809797"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/809797\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/386213"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=809797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=809797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=809797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}