{"id":815793,"date":"2026-02-21T23:48:24","date_gmt":"2026-02-21T23:48:24","guid":{"rendered":"https:\/\/www.europesays.com\/de\/815793\/"},"modified":"2026-02-21T23:48:24","modified_gmt":"2026-02-21T23:48:24","slug":"liveticker-statistik-rb-leipzig-bvb-dortmund-22","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/815793\/","title":{"rendered":"Liveticker &#038; Statistik: RB Leipzig &#8211; BVB Dortmund 2:2"},"content":{"rendered":"<p><a name=\"stats\" id=\"stats\"><\/a><\/p>\n<p>Statistik<\/p>\n<p>Tore<\/p>\n<p>1:0 Baumgartner (20.)<br \/>2:0 Baumgartner (40.)<br \/>2:1 Romulo (50.\/ET)<br \/>2:2 Fabio Silva (90.+5)<\/p>\n<p>RB Leipzig<\/p>\n<p>Vandevoordt &#8211; Baku (81. Henrichs), Orban, Lukeba,   Raum &#8211; Schlager (65. Nusa), Seiwald &#8211; Gruda   (81. Banzuzi), Baumgartner, Diomande   (90.+4 Finkgr\u00e4fe) &#8211; Romulo (81. Harder)<\/p>\n<p>BVB Dortmund<\/p>\n<p>Kobel &#8211; Ryerson, Reggiani (64. Couto), Anton,   Bensebaini, Svensson &#8211; Nmecha (64. Chukwuemeka), Bellingham,   Sabitzer (76. Adeyemi) &#8211; Beier (64. Brandt), Guirassy (71. Fabio   Silva)<\/p>\n<p>Zuschauer<\/p>\n<p>47.800<\/p>\n<p>Ticker<\/p>\n<p>Zusammenfassung<\/p>\n<p>RB Leipzig hat gegen Borussia   Dortmund eine F\u00fchrung ganz sp\u00e4t aus   der Hand gegeben und nur 2:2 (2:0)   gespielt. Die Mannschaft von Trainer   Ole Werner zeigte zun\u00e4chst eine   dominante und spielfreudige   Vorstellung. Christoph Baumgartner   erzielte die F\u00fchrung (20.) und legte   sp\u00e4ter selbst nach (40.) &#8211; jeweils   nach baugleichen Kombinationen. Nach   dem Seitenwechsel machte Romulos   Eigentor das Spiel wieder spannend   (50.). RB kontrollierte die Partie   zwar weiter, doch brachte die F\u00fchrung   nicht ins Ziel. In der Nachspielzeit   rettete Fabio Silva f\u00fcr den \u00fcber   weite Strecken harmlosen BVB immerhin   ein Remis.<\/p>\n<p>Abpfiff<\/p>\n<p>Schluss in Leipzig! RB gibt den Sieg   im Topspiel gegen Dortmund ganz sp\u00e4t   aus der Hand. Ein zun\u00e4chst   spielfreudiges und lange Zeit   dominantes Leipzig bringt es nicht zu   Ende. Dortmund trotz einer \u00fcber weite   Strecken zu harmlosen Vorstellung   noch mit dem sp\u00e4ten Punktgewinn!<\/p>\n<p>90+8 Riesenchance Dortmund!!!<\/p>\n<p>Der BVB fast noch mit dem Siegtreffer!   Vandevoordt rettet gegen Brandt!<\/p>\n<p>90+6 Wie \u00e4rgerlich f\u00fcr RB!<\/p>\n<p>RB hat hier auch nach dem   Anschlusstreffer das Spiel weitgehend   kontrolliert, aber eben nicht zu Ende   gebracht &#8211; trotz der spielfreudigen,   tollen ersten Halbzeit.<\/p>\n<p>90+5 Tor B. Dortmund!<\/p>\n<p>Toooooor f\u00fcr Dortmund! In der 95.   Minute gibt RB den Sieg doch noch aus   der Hand. Adeyemi wird von Brandt auf   die Reise geschickt, die Hereingabe   verwandelt Silva am zweiten Pfosten   gegen die Laufrichtung von   Vandevoordt zum 2:2.<\/p>\n<p>90+4 Wechsel RB Leipzig<\/p>\n<p>Finkgr\u00e4fe f\u00fcr Diomande<\/p>\n<p>90&#8242; Nachspielzeit<\/p>\n<p>Es gibt sieben Minuten zus\u00e4tzlich.<\/p>\n<p>90&#8242; Kein Elfmeter!<\/p>\n<p>Adeyemi wird geschickt und geht nach   Kontakt mit Lukeba zu Boden. Aber die   Schiedsrichter um Benjamin Brand   entscheiden: Kein Elfmeter!<\/p>\n<p>87&#8242; Die letzten Minuten laufen<\/p>\n<p>Jetzt hat Dortmund den Ball. RB muss   sich hinter die Ziellinie k\u00e4mpfen. Nach   wie vor gilt aber, dass dem BVB nicht   allzu viel einf\u00e4llt.<\/p>\n<p>83&#8242; Konterchance RB<\/p>\n<p>Dortmund dr\u00fcckt jetzt &#8211; und Leipzig   kontert. Diomande legt einen weiteren   Sprint ein, doch verzieht.<\/p>\n<p>81&#8242; Wechsel RB Leipzig<\/p>\n<p>Henrichs f\u00fcr Baku<\/p>\n<p>81&#8242; Wechsel RB Leipzig<\/p>\n<p>Harder f\u00fcr Romulo<\/p>\n<p>81&#8242; Wechsel RB Leipzig<\/p>\n<p>Banzuzi f\u00fcr Gruda<\/p>\n<p>80&#8242; Schlussphase<\/p>\n<p>So langsam ist Dortmund aufgewacht und   dr\u00fcckt auf den Ausgleich.<\/p>\n<p>78&#8242; Gelbe Karte B. Dortmund<\/p>\n<p>Fabio Silva unterbindet den   anschlie\u00dfenden Konterversuch &#8211; Gelb.<\/p>\n<p>78&#8242; Chance BVB<\/p>\n<p>Da ist der BVB! Es sind die   Eingewechselten, die nun f\u00fcr Gefahr   sorgen. Fabio Silva bedient Adeyemi,   dessen Schuss wird geblockt. Das Ding   ist hier noch nicht durch!<\/p>\n<p>77&#8242; Wechsel B. Dortmund<\/p>\n<p>Adeyemi f\u00fcr Sabitzer<\/p>\n<p>73&#8242; Chance RB<\/p>\n<p>Baku bekommt den Ball in den Lauf   gespielt, umkurvt Kobel und gibt die   Kugel aus spitzem Winkel ins Zentrum,   doch die Dortmunder k\u00f6nnen kl\u00e4ren.<\/p>\n<p>71&#8242; Wechsel B. Dortmund<\/p>\n<p>Fabio Silva f\u00fcr Guirassy<\/p>\n<p>69&#8242; Gelbe Karte B. Dortmund<\/p>\n<p>Anton<\/p>\n<p>70&#8242; Chance RB<\/p>\n<p>Da ist wieder eine Chance f\u00fcr RB!   Diomande mit einem T\u00e4nzchen gegen die   halbe BVB-Abwehr, legt nochmal ab auf   Nusa, dessen Schuss wird abgef\u00e4lscht   und rauscht \u00fcber den Kasten.<\/p>\n<p>66&#8242; RB kontrolliert Spiel weiter<\/p>\n<p>RB hat trotz des Anschlusstreffers   weiter Spielkontrolle, auch wenn die   Gastgeber nicht mehr wirklich zu   Chancen kommen. Der BVB hat die   rechte Abwehrseite zubekommen, aber   zeigt nach vorn immer noch zu wenig.<\/p>\n<p>65&#8242; Wechsel RB Leipzig<\/p>\n<p>Nusa f\u00fcr Schlager<\/p>\n<p>64&#8242; Wechsel B. Dortmund<\/p>\n<p>Brandt f\u00fcr Beier<\/p>\n<p>64&#8242; Wechsel B. Dortmund<\/p>\n<p>Chukwuemeka f\u00fcr Nmecha<\/p>\n<p>64&#8242; Wechsel B. Dortmund<\/p>\n<p>Couto f\u00fcr Reggiani<\/p>\n<p>60&#8242; Kein Elfmeter!<\/p>\n<p>Nach Ryerson-Flanke geht Guirassy im   Zweikampf zu Boden, das war aber zu   wenig f\u00fcr einen Elfmeter.<\/p>\n<p>58&#8242; Knapp Stunde vorbei<\/p>\n<p>RB hat sich zumindest entschieden, sich   nicht nur auf eine Abwehrschlacht   einzulassen, und schaltet wieder in den   Vorw\u00e4rtsgang.<\/p>\n<p>54&#8242; Gelbe Karte B. Dortmund<\/p>\n<p>Reggiani sieht Gelb nach taktischem   Foul.<\/p>\n<p>54&#8242; Spannung drin<\/p>\n<p>Nun darf man gespannt sein, ob das   bisher so spielfreudige RB Leipzig auch   unter Druck sein starkes Niveau halten   kann.<\/p>\n<p>52&#8242; Dortmund wieder dran<\/p>\n<p>Nun ist wieder Spannung drin! Danach   hatte es in der ersten Halbzeit   wirklich nicht ausgesehen. Es   brauchte daf\u00fcr eine ungl\u00fcckliche   Aktion aus RB-Sicht!<\/p>\n<p>50&#8242; Tor B. Dortmund!<\/p>\n<p>Tooooor f\u00fcr Dortmund! Aus dem Nichts   ist Dortmund wieder dran. Einen Eckball   von links bugsiert Romulo ungl\u00fccklich   mit dem Kopf ins eigene Tor.<\/p>\n<p>46&#8242; Anpfiff<\/p>\n<p>Weiter geht&#8217;s in Leipzig. Die Gastgeber   haben Ansto\u00df.<\/p>\n<p>Halbzeit<\/p>\n<p>RB f\u00fchrt vollkommen verdient mit 2:0   gegen Borussia Dortmund. Die   Gastgeber immer wieder mit dem   gleichen Muster, zweimal waren sie   auf diese Weise erfolgreich &#8211; und sie   h\u00e4tten sogar mehr Tore erzielen   k\u00f6nnen. Die Dortmunder nach vorn zu   einfallslos, hinten lassen sie sich   d\u00fcpieren.<\/p>\n<p>45&#8242; Gelbe Karte B. Dortmund<\/p>\n<p>Bensebaini sieht Gelb nach taktischem   Foul.<\/p>\n<p>45&#8242; Gleich Halbzeit<\/p>\n<p>RB spielt hier Strg + V. Dortmunds   Abwehr ist hingegen noch auf Netzsuche.<\/p>\n<p>43&#8242; Freisto\u00df BVB<\/p>\n<p>Gute Freisto\u00dfposition f\u00fcr den BVB.   Sabitzer tritt an, aber zu zentral &#8211;   Vandevoort lenkt den Ball \u00fcber die   Latte.<\/p>\n<p>41&#8242; Gelbe Karte RB Leipzig<\/p>\n<p>Baumgartner<\/p>\n<p>40&#8242; Tor RB Leipzig!<\/p>\n<p>Toooooor f\u00fcr RB Leipzig! Es ist   wirklich nicht zu fassen! Wieder wird   Raum auf der linken Seite in Szene   gebracht, dessen Eingabe verwandelt   Baumgartner zum 2:0. Schema F!<\/p>\n<p>38&#8242; Ein Abschluss vom BVB!<\/p>\n<p>Der BVB ist noch da! Nmecha mit einem   Wachmacher-Abschluss, den Vandevoordt   sicher entsch\u00e4rft.<\/p>\n<p>37&#8242; Chance RB<\/p>\n<p>Dortmund l\u00e4sst sich immer wieder auf   die gleiche Art und Weise d\u00fcpieren.   Es ist wirklich bemerkenswert. Aber   Baumgartner nach Raum-Flanke erneut   knapp neben das Tor.<\/p>\n<p>35&#8242; Zu weit vorgelegt<\/p>\n<p>RB setzt nach, dann wird Diomande auf   die Reise geschickt, legt sich aber den   Ball etwas zu weit vor &#8211; Kobel kann ihn   aufnehmen.<\/p>\n<p>33&#8242; Halbe Stunde vorbei<\/p>\n<p>RB gibt hier den Ton an, kann sogar   nachlegen. Von Dortmund kommt gerade   nicht viel.<\/p>\n<p>31&#8242; Gelbe Karte RB Leipzig<\/p>\n<p>Romulo<\/p>\n<p>29&#8242; Wieder RB<\/p>\n<p>Schlager bekommt den Ball in den Lauf   gespielt, der Querpass &#8211; diesmal von   rechts! &#8211; findet aber keinen Abnehmer.   Da war keiner mitgelaufen.<\/p>\n<p>28&#8242; Chance RB<\/p>\n<p>Wieder das gleiche Schema: Romulo mit   dem Zuspiel von links, Baumgartners   Abschluss geht diesmal knapp vorbei.<\/p>\n<p>26&#8242; RB spielfreudiger<\/p>\n<p>Die Gastgeber zeigen sich bislang   spielfreudiger und mit mehr Tempo.   Der BVB hat es aus dem eigenen   Positionsangriff bislang nicht   geschafft, RB gef\u00e4hrlich zu werden.<\/p>\n<p>22&#8242; F\u00fchrung RB<\/p>\n<p>RB mit einer starken Phase. Die   Gastgeber besch\u00e4ftigen den BVB. Immer   wieder geht es \u00fcber links. Und nun   belohnt sich Leipzig mit dem   F\u00fchrungstor.<\/p>\n<p>21&#8242; \u00dcberpr\u00fcfung des Tores<\/p>\n<p>Das Tor musste wegen einer m\u00f6glichen   Abseitsstellung \u00fcberpr\u00fcft werden. Es   war wirklich ganz knapp. Aber es z\u00e4hlt!<\/p>\n<p>20&#8242; Tor RB Leipzig!<\/p>\n<p>Tooooooor f\u00fcr Leipzig!   Seitenverlagerung auf Diomande, der   bittet zum Tanz und gibt den Ball   dann scharf ins Zentrum, wo   Baumgartner wundersch\u00f6n zum 1:0   abschlie\u00dft!<\/p>\n<p>19&#8242; Freisto\u00df RB<\/p>\n<p>Raum schl\u00e4gt den Ball von links,   Seiwalds Kopfball ist aber deutlich zu   schwach und unplatziert.<\/p>\n<p>16&#8242; Romulo verpasst knapp<\/p>\n<p>Raums scharfe Hereingabe verpasst   Romulo im Zentrum nur knapp. Wieder   ging es \u00fcber links bei den Gastgebern.<\/p>\n<p>13&#8242; Verteiltes Spiel<\/p>\n<p>Es ist ein verteiltes Spiel in der   Anfangsphase, noch kann sich keine   der beiden Seiten einen wirklichen   Vorteil erarbeiten. Auff\u00e4llig:   Zweik\u00e4mpfe werden intensiv gef\u00fchrt.<\/p>\n<p>10&#8242; Erste Offensivaktionen<\/p>\n<p>Das Topspiel hat nun also auch seine   ersten gef\u00e4hrlichen Offensivaktionen.   So kann es doch weitergehen!<\/p>\n<p>8&#8242; Riesenchance BVB<\/p>\n<p>Im Gegenzug hat der BVB die   Monsterchance: Beier kann allein auf   das Tor zusteuern, aber scheitert mit   dem flachen Abschluss an Vandevoort!<\/p>\n<p>8&#8242; Chance RB<\/p>\n<p>RB kombiniert auf der linken Seite, die   Hereingabe nimmt Romulo direkt, aber   auch direkt auf Kobel.<\/p>\n<p>6&#8242; Anfangsphase<\/p>\n<p>Schon einige Fouls in der Anfangsphase,   beide Teams schenken sich nichts. Noch   keine wirkliche Gefahr vor den Toren.<\/p>\n<p>4&#8242; Freisto\u00df RB<\/p>\n<p>Erste vorsichtige Ann\u00e4herung der   Gastgeber. Raum schl\u00e4gt einen Freisto\u00df   von der rechten Seite in den Strafraum,   aber Kobel ohne Probleme.<\/p>\n<p>1&#8242; Anpfiff<\/p>\n<p>Los geht&#8217;s in Leipzig!<\/p>\n<p>Werner fordert Topleistung<\/p>\n<p>RB-Trainer Werner forderte vor dem   Spiel eine &#8222;Topleistung&#8220; von seiner   Mannschaft. Zwar zeige Dortmund   &#8222;nicht jede Woche Hurrafu\u00dfball&#8220;,   dennoch pr\u00e4sentiere sich der   Champions-League-Teilnehmer enorm   effektiv. Er spiele &#8222;extrem   erfolgreich, stabil und abgezockt&#8220;.<\/p>\n<p>Aufstellung BVB<\/p>\n<p>Beim BVB gibt es im Vergleich zum 2:0   gegen Atalanta Bergamo in der Champions   League nur einen Wechsel: Sabitzer   startet f\u00fcr Brandt.<\/p>\n<p>Aufstellung RB<\/p>\n<p>RB-Trainer Ole Werner nimmt nach dem   2:2 gegen Wolfsburg f\u00fcnf Wechsel vor.   Im Tor steht Vandevoordt f\u00fcr den   verletzten Gulacsi. Dar\u00fcber hinaus   stehen Raum, Lukeba, Baku und Romulo   f\u00fcr Henrichs, Finkgr\u00e4fe, Nusa und   Harder in der Startelf.<\/p>\n<p>Ausgangslage<\/p>\n<p>Die Leipziger k\u00e4mpfen um den Einzug   in die Champions League und k\u00f6nnen   davon profitieren, dass Leverkusen   bei Union Berlin patzte und 0:1   verlor. Stuttgart spielt erst morgen   in Heidenheim. Ein Sieg gegen den BVB   &#8211; und Leipzig w\u00fcrde \u00fcber Nacht auf   Platz vier springen.<\/p>\n<p>Ausgangslage<\/p>\n<p>F\u00fcr Dortmund geht es darum, an   Spitzenreiter Bayern M\u00fcnchen   dranzubleiben. Der Rekordmeister hat   vorgelegt, gegen Frankfurt aber nur   knapp 3:2 gewonnen. Mit einem Sieg   w\u00fcrde der BVB den Sechs-Punkte-  R\u00fcckstand halten.<\/p>\n<p>Herzlich Willkommen<\/p>\n<p>Das Topspiel am 23. Spieltag der   Bundesliga steht an. RB Leipzig trifft   auf Borussia Dortmund &#8211; der F\u00fcnfte   spielt gegen den Zweiten.<\/p>\n","protected":false},"excerpt":{"rendered":"Statistik Tore 1:0 Baumgartner (20.)2:0 Baumgartner (40.)2:1 Romulo (50.\/ET)2:2 Fabio Silva (90.+5) RB Leipzig Vandevoordt &#8211; Baku (81.&hellip;\n","protected":false},"author":2,"featured_media":3888,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1833],"tags":[3364,29,217,30,81,1209,3499,3498],"class_list":{"0":"post-815793","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dortmund","8":"tag-de","9":"tag-deutschland","10":"tag-dortmund","11":"tag-germany","12":"tag-mdr","13":"tag-nordrhein-westfalen","14":"tag-spio","15":"tag-sport-im-osten"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116111298061850513","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/815793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=815793"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/815793\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/3888"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=815793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=815793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=815793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}