{"id":816941,"date":"2026-02-22T11:25:15","date_gmt":"2026-02-22T11:25:15","guid":{"rendered":"https:\/\/www.europesays.com\/de\/816941\/"},"modified":"2026-02-22T11:25:15","modified_gmt":"2026-02-22T11:25:15","slug":"kommunalwahl-in-muenchen-ob-triell-der-sz-hier-sehen-sie-den-livestream-muenchen","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/816941\/","title":{"rendered":"Kommunalwahl in M\u00fcnchen: OB-Triell der SZ &#8211; hier sehen Sie den Livestream &#8211; M\u00fcnchen"},"content":{"rendered":"<p>YouTubeDie SZ-Redaktion hat diesen Artikel mit einem Inhalt von YouTube angereichert<\/p>\n<p class=\"css-kxe210\">Um Ihre Daten zu sch\u00fctzen, wurde er nicht ohne Ihre Zustimmung geladen.<\/p>\n<p>Inhalt jetzt laden<\/p>\n<p class=\"css-orh8zx\">Ich bin damit einverstanden, dass mir Inhalte von YouTube angezeigt werden. Damit werden personenbezogene Daten an den Betreiber des Portals zur Nutzungsanalyse \u00fcbermittelt. Mehr Informationen und eine Widerrufsm\u00f6glichkeit finden Sie unter\u00a0<a href=\"https:\/\/datenschutz.sueddeutsche.de\/sz\" class=\"css-lqefuc\" rel=\"nofollow noopener\" target=\"_blank\">sz.de\/datenschutz<\/a>.<\/p>\n<ul class=\"css-195ec0u\">\n<li data-manual=\"bulletList\" data-schema-org-speakable=\"true\" class=\"css-j1uxhs\"><strong>12.16 Uhr:<\/strong> Der letzte Themenkomplex dreht sich um Finanzen: M\u00fcnchen hat noch immer viel Geld zur Verf\u00fcgung, der st\u00e4dtische Haushalt umfasst etwa zw\u00f6lf Milliarden Euro. Doch die Schulden steigen und es sind Ausgabenk\u00fcrzungen n\u00f6tig, schmerzhafte. Wie die Haushaltskrise abwenden? Clemens Baumg\u00e4rtner fragt: \u201eMuss es immer der Luxusstandard sein?\u201c Er fordert, zehn Prozent einzusparen. Dominik Krause sieht Einsparungsm\u00f6glichkeiten beispielsweise durch KI, aber er betont, dass es auch Bereiche gibt, in denen Investitionen n\u00f6tig sind: bei Kitas, Schulen, beim sozialen Wohnungsbau oder Klimaschutz. Hier d\u00fcrfe nicht einfach der Rotstift angesetzt werden. Dieter Reiter erl\u00e4utert, wie stark die Kosten f\u00fcr Investitionen durch die Krisen der Welt gestiegen sind, zum Beispiel beim Schulbau. Nat\u00fcrlich m\u00fcssten begonnene Projekte jetzt fertiggestellt werden. Erstmals wird von Reiter das Thema Migration angesprochen, das im Wahlkampf in der Gro\u00dfstadt M\u00fcnchen eine verh\u00e4ltnism\u00e4\u00dfig kleine Rolle spielt: \u201eWir wollen anst\u00e4ndig mit Gefl\u00fcchteten umgehen. Das ist eine politische Entscheidung.\u201c Reiter erh\u00e4lt daf\u00fcr Applaus im Saal.<\/li>\n<\/ul>\n<ul class=\"css-195ec0u\">\n<li data-manual=\"bulletList\" data-schema-org-speakable=\"true\" class=\"css-j1uxhs\"><strong>12.06 Uhr:<\/strong> Eine Abschlussfrage zum Thema Verkehr: Die Kandidaten sollen ein Verkehrsprojekt in der Stadt nennen, das richtig gut gelaufen ist. Baumg\u00e4rtner: \u201eDie K\u00f6niginstra\u00dfe.\u201c Zuvor hatte der CSU-Politiker ausgef\u00fchrt, dass er es war, der den Umbau zur Radstra\u00dfe vor Jahren angeregt hatte. Reiter: Der U-Bahnbau nach Pasing. \u201eDas leistet sich nicht jede Stadt.\u201c Krause: \u201eIch w\u00fcrde die Lindwurmstra\u00dfe nennen.\u201c Da entz\u00fcndet sich bereits der n\u00e4chste Streit zwischen Reiter und Krause. Der Umbau des Radwegs auf der Lindwurmstra\u00dfe hatte sich verz\u00f6gert, schlie\u00dflich wurde er in einer abgespeckten Version verh\u00e4ltnism\u00e4\u00dfig z\u00fcgig gebaut.<\/li>\n<\/ul>\n<ul class=\"css-195ec0u\">\n<li data-manual=\"bulletList\" data-schema-org-speakable=\"true\" class=\"css-j1uxhs\"><strong>12.03 Uhr:<\/strong> Ein wenig ironisch meldet sich Dominik Krause zu Wort: \u201eWir sind uns ja sehr einig auf der B\u00fchne, dass wir unideologisch die Verkehrswende voranbringen wollen.\u201c Anschlie\u00dfend f\u00fchrt er jedoch auf, wie unterschiedlich die Signale aus den Parteien beim Thema Verkehr sind \u2013 und wie schwer deswegen die Arbeit f\u00fcr das Mobilit\u00e4tsreferat gewesen sei. Ein Lieblingsthema von Dieter Reiter: Sofort best\u00e4rkt der Oberb\u00fcrgermeister seine Kritik an Mobilit\u00e4tsreferent Georg Dunkel, mit dessen Arbeit er sich in den vergangenen Jahren oft nicht zufrieden zeigte. Wieder duellieren sich zwei Politiker, die eigentlich Koalitionspartner sind.<\/li>\n<\/ul>\n<ul class=\"css-195ec0u\">\n<li data-manual=\"bulletList\" data-schema-org-speakable=\"true\" class=\"css-j1uxhs\"><strong>11:51 Uhr:<\/strong> Weiter geht es mit dem Thema Verkehr. M\u00fcnchen werde oft als Radlhauptstadt bezeichnet, sagt eine M\u00fcnchnerin in einem Videoeinspieler. Doch aus ihrer Sicht zu Unrecht. Dominik Krause richtet sich in seinem Sitz auf, es ist eines der wichtigsten Themen f\u00fcr den Gr\u00fcnen-Politiker. Krause berichtet, dass er sich oft den Vorwurf \u201eAutohasser\u201c gefallen lassen muss. Baumg\u00e4rtner fordert, in der Verkehrspolitik \u201ePriorit\u00e4ten zu setzen\u201c. Aus Sicht des CSU-Politikers geh\u00f6rt dazu vor allem der U-Bahnausbau. Warum die CSU dann die Trambahn-Westtangente nicht bef\u00fcrworte, erkundigt sich Krause. Baumg\u00e4rtners Antwort: \u201eEine Trambahn, da, wo sie gebraucht wird. Der Bus h\u00e4tte an der Stelle auch ausgereicht.\u201c Diesmal ist es Dieter Reiter, der sich zun\u00e4chst zur\u00fcckh\u00e4lt. Dann sagt er: \u201eDer Radwegbau sei nicht ein finanzielles Problem\u201c, das sei eher eine Scheindiskussion. Wie Baumg\u00e4rtner spricht der Oberb\u00fcrgermeister von \u201ePriorit\u00e4ten setzen\u201c. Oberste Priorit\u00e4t habe der \u00f6ffentliche Nahverkehr\u00a0\u2013 \u201enur dar\u00fcber geht die Verkehrswende\u201c. Reiter kritisiert, dass die S-Bahn vernachl\u00e4ssigt wurde\u00a0\u2013 verantwortlich ist hier der Freistaat.<\/li>\n<\/ul>\n<ul class=\"css-195ec0u\">\n<li data-manual=\"bulletList\" data-schema-org-speakable=\"true\" class=\"css-j1uxhs\"><strong>11.33 Uhr:<\/strong> Vor wenigen Tagen hatte Dieter Reiter gefordert, die <a href=\"https:\/\/www.sueddeutsche.de\/muenchen\/muenchen-sem-nord-nordost-reiter-enteignung-li.3391561\" rel=\"nofollow noopener\" target=\"_blank\">St\u00e4dtebauliche Entwicklungsma\u00dfnahmen (SEM) im M\u00fcnchner Norden zu stoppen<\/a>, wo Wohnraum geschaffen werden soll. Er pl\u00e4diert f\u00fcr einen Neuanfang ohne Drohungen von Enteignungen der Grundbesitzer. Dominik Krause dagegen wundert sich, dass der Oberb\u00fcrgermeister pl\u00f6tzlich von der SEM abr\u00fcckt, obwohl es im gemeinsamen Wahlprogramm von 2020 stehe \u2013 und sogar im aktuellen Wahlprogramm der SPD. Clemens Baumg\u00e4rtner schaut zu, wie sich die Koalitionspartner beharken, und meldet sich dann zu Wort. Auch der CSU-Politiker ist der Meinung, dass es richtig ist, die SEM abzusagen. SZ-Ressortleiter Ren\u00e9 Hofmann ringt den Kandidaten noch eine konkrete Antwort ab. Welches Versprechen geben sie den W\u00e4hlerinnen und W\u00e4hlern, wann findet der erste Spatenstich statt im M\u00fcnchner Norden? Reiter: \u201eIn sp\u00e4testens f\u00fcnf Jahren.\u201c Krause: \u201eInnerhalb der n\u00e4chsten Periode.\u201c Baumg\u00e4rtner: \u201e2027.\u201c Ein Raunen geht durch den Saal. Eher ein ungl\u00e4ubiges bei dem Dauerthema SEM.<\/li>\n<\/ul>\n<ul class=\"css-195ec0u\">\n<li data-manual=\"bulletList\" data-schema-org-speakable=\"true\" class=\"css-j1uxhs\"><strong>11.22 Uhr:<\/strong> Die Diskussion beginnt mit dem Thema, das viele umtreibt: die hohen Mieten. Seit 2014 ist der durchschnittliche Mietpreis pro Quadratmeter in M\u00fcnchen um 50 Prozent gestiegen. In einem Videoeinspieler berichtet eine Studentin von ihrer Situation: Sie wohnt am Stadtrand bei ihrer Oma, eine eigene Wohnung kann sie sich nicht leisten. Wie kann die Politik da gegensteuern? Dieter Reiter sagt: \u201eWir m\u00fcssen als Stadt bezahlbare Wohnungen bauen. Wir m\u00fcssen schauen, dass die Mieten nicht weiter explodieren.\u201c Dominik Krause erkl\u00e4rt, ihm sei vor allem wichtig, k\u00fcnftig die Umnutzung von leerstehenden B\u00fcrofl\u00e4chen in Wohnraum voranzutreiben. Er kann sich daf\u00fcr eine \u201eUmwandlungsagentur\u201c vorstellen. Clemens Baumg\u00e4rtner dagegen schl\u00e4gt vor, die Immobilienfirmen zu entlasten: sie nicht mehr zu so vielen Vorgaben zu verpflichten, sondern Anreize f\u00fcr sie zu schaffen.<\/li>\n<\/ul>\n<ul class=\"css-195ec0u\">\n<li data-manual=\"bulletList\" data-schema-org-speakable=\"true\" class=\"css-j1uxhs\"><strong>11.10 Uhr:<\/strong> Der Saal im Residenztheater ist gut gef\u00fcllt. Auf die erste Frage antwortet Oberb\u00fcrgermeister Dieter Reiter gewohnt l\u00e4ssig. Wie sehr er dem Ministerpr\u00e4sidenten Markus S\u00f6der zu Dank verpflichtet ist, dass der die Altersgrenze f\u00fcr Oberb\u00fcrgermeister aufgehoben hat und er nun noch einmal antreten kann? \u201eDer Ministerpr\u00e4sident macht grunds\u00e4tzlich nur gute Dinge\u201c, sagt Reiter mit einem Augenzwinkern. Der 67-J\u00e4hrige nimmt in der Mitte Platz, links von ihm Dominik Krause, rechts von ihm Clemens Baumg\u00e4rtner.<\/li>\n<\/ul>\n<ul class=\"css-195ec0u\">\n<li data-manual=\"bulletList\" data-schema-org-speakable=\"true\" class=\"css-j1uxhs\"><strong>11 Uhr:<\/strong> Zwei Wochen vor der Wahl treffen drei OB-Kandidaten beim Triell der S\u00fcddeutschen Zeitung aufeinander. Im Residenztheater nehmen Oberb\u00fcrgermeister Dieter Reiter (SPD), der Zweite B\u00fcrgermeister Dominik Krause (Gr\u00fcne) und der ehemalige Wirtschaftsreferent Clemens Baumg\u00e4rtner (CSU) Stellung zu den dr\u00e4ngendsten Themen der Stadt. Moderiert wird die Veranstaltung von Ulrike Heidenreich und Ren\u00e9 Hofmann, den beiden Ressortleitern f\u00fcr M\u00fcnchen, die Region und Bayern.<\/li>\n<\/ul>\n<ul class=\"css-195ec0u\">\n<li data-manual=\"bulletList\" data-schema-org-speakable=\"true\" class=\"css-j1uxhs\">Das sind die drei Kandidaten im \u00dcberblick:<\/li>\n<\/ul>\n<p>Der Pragmatiker<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Dass sich Amtsinhaber\u00a0<a href=\"https:\/\/www.sueddeutsche.de\/thema\/Dieter_Reiter\" rel=\"nofollow noopener\" target=\"_blank\">Dieter Reiter<\/a>\u00a0(SPD)\u00a0am 8. M\u00e4rz erneut zur Wahl des M\u00fcnchner Oberb\u00fcrgermeisters stellen kann, hat er ironischerweise dem CSU-Ministerpr\u00e4sidenten Markus S\u00f6der zu verdanken: Der initiierte vor drei Jahren, dass die Altersgrenze f\u00fcr Landr\u00e4te und B\u00fcrgermeister in Bayern aufgehoben wurde; bis dahin durften sie beim Amtsantritt nicht \u00e4lter als 66 Jahre sein. Die Gesetzes\u00e4nderung er\u00f6ffnete dem inzwischen 67 Jahre alten Reiter die M\u00f6glichkeit, in diesem Jahr ein weiteres Mal anzutreten.<\/p>\n<p><a href=\"https:\/\/www.sueddeutsche.de\/projekte\/artikel\/muenchen\/kommunalwahl-2026-muenchen-wahlomat-parteien-waehlen-e088241\/\" aria-label=\"Artikelverlinkung:\" data-track-szde=\"{&quot;event&quot;:&quot;teaser_clicked&quot;,&quot;teaser_clicked&quot;:{&quot;article_title&quot;:&quot;machen_sie_den_test_welche_partei_passt_zu_ihnen&quot;,&quot;doctype&quot;:&quot;&quot;,&quot;label&quot;:&quot;&quot;,&quot;main_topic&quot;:&quot;politik_muenchen&quot;,&quot;object_id&quot;:&quot;er.e088241&quot;,&quot;pcat&quot;:&quot;free&quot;,&quot;section&quot;:&quot;muenchen&quot;,&quot;teaser_type&quot;:&quot;article_teaser_top&quot;}}\" data-manual=\"teaser-url\" data-tb-link=\"\" aria-labelledby=\"teaser-httpswwwsueddeutschedeprojekteartikelmuenchenkommunalwahl-2026-muenchen-wahlomat-parteien-waehlen-e088241\" class=\"css-14tg8sh\" rel=\"nofollow noopener\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/e6e3fcbc-cd45-4dfd-967c-c094491de04c.jpg\"   alt=\"\" loading=\"lazy\" class=\"css-8atqhb\"\/><\/p>\n<p>SZ-Wahlcheck f\u00fcr M\u00fcnchen<\/p>\n<p>:Machen Sie den Test: Welche Partei passt zu Ihnen?<\/p>\n<p class=\"css-a6ecqs\" data-manual=\"teaser-text\" data-tb-description=\"\" data-schema-org-speakable=\"true\">34 Fragen zum Durchklicken \u2013 und am Ende ein Ergebnis: Mit dem SZ-Wahlcheck finden Sie heraus, welche Partei bei der Kommunalwahl in M\u00fcnchen Ihrer Meinung am n\u00e4chsten kommt.<\/p>\n<p>Von SZ-Autorinnen und SZ-Autoren<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Seine erste Amtszeit begann 2014, die zweite 2020\u00a0\u2013 beide Male setzte er sich jeweils in der Stichwahl gegen Konkurrenz aus der CSU durch, erst gegen Josef Schmid, dann gegen Kristina Frank. Als Reiter 2014 die Nachfolge seines Parteikollegen Christian Ude \u00fcbernahm, der damals noch aus Altersgr\u00fcnden nicht mehr kandidieren konnte, beendete er eine fast 25 Jahre bestehende rot-gr\u00fcne Koalition im Stadtrat und regierte mit einer schwarz-roten Mehrheit. Weil die Gr\u00fcnen 2020 st\u00e4rkste Fraktion wurden und mit den Christsozialen keine Mehrheit mehr m\u00f6glich war, stand Reiter in den vergangenen sechs Jahren wieder einem B\u00fcndnis mit den Gr\u00fcnen vor, diesmal mit seiner SPD als Juniorpartner. Er hat den Koalitionspartner freilich oft sp\u00fcren lassen, dass er mit der CSU gl\u00fccklicher w\u00e4re.<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Der diplomierte Verwaltungswirt arbeitet seit dem Abschluss seines Studiums bei und f\u00fcr die Landeshauptstadt <a href=\"https:\/\/www.sueddeutsche.de\/thema\/M%C3%BCnchen\" rel=\"nofollow noopener\" target=\"_blank\">M\u00fcnchen<\/a>, zun\u00e4chst in verschiedenen Funktionen in der Stadtk\u00e4mmerei. 2009 wurde er vom Stadtrat zum Referenten f\u00fcr Arbeit und Wirtschaft gew\u00e4hlt, aus diesem Amt heraus bewarb er sich dann erfolgreich als Oberb\u00fcrgermeister. Seine bisherige Amtszeit war gepr\u00e4gt von globalen Krisen, erst die Fl\u00fcchtlingswelle 2015, zu Beginn der Zwanzigerjahre dann die Corona-Pandemie.<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Reiter versteht sich als l\u00f6sungsorientierter Pragmatiker, nicht als Ideologe. In der Parteiarbeit engagiert er sich nicht sonderlich, ein Amt in der M\u00fcnchner SPD hatte er nie. Trotzdem k\u00fcrten ihn die hiesigen Sozialdemokraten mit einer \u00fcberw\u00e4ltigenden Mehrheit im November zu ihrem offiziellen OB-Kandidaten. In seiner Dankesrede sagte Reiter, er wolle \u201emit Hirn, Herz und Handlungen\u201c die Stadt gestalten. Wichtigster Punkt in seiner Politik ist bezahlbarer Wohnraum; das Thema Wohnen und Mieten stand bereits 2020 ganz oben auf seiner Agenda.<\/p>\n<p><a href=\"https:\/\/www.sueddeutsche.de\/projekte\/artikel\/muenchen\/muenchen-kommunalwahl-oberbuergermeister-dieter-reiter-clemens-baumgaertner-dominik-krause-ob-kandidaten-interview-e055781\/\" aria-label=\"Artikelverlinkung:\" data-track-szde=\"{&quot;event&quot;:&quot;teaser_clicked&quot;,&quot;teaser_clicked&quot;:{&quot;article_title&quot;:&quot;sagen_sie_jetzt_nichts_die_herren&quot;,&quot;doctype&quot;:&quot;&quot;,&quot;label&quot;:&quot;szplus&quot;,&quot;main_topic&quot;:&quot;politik_muenchen&quot;,&quot;object_id&quot;:&quot;er.e055781&quot;,&quot;pcat&quot;:&quot;paid&quot;,&quot;section&quot;:&quot;muenchen&quot;,&quot;teaser_type&quot;:&quot;article_teaser_top&quot;}}\" data-manual=\"teaser-url\" data-tb-link=\"\" aria-labelledby=\"teaser-httpswwwsueddeutschedeprojekteartikelmuenchenmuenchen-kommunalwahl-oberbuergermeister-dieter-reiter-clemens-baumgaertner-dominik-krause-ob-kandidaten-interview-e055781\" class=\"css-14tg8sh\" rel=\"nofollow noopener\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/c015bd6d-fafa-45b6-a31d-854814c87cc8.jpg\"   alt=\"\" loading=\"lazy\" class=\"css-8atqhb\"\/><\/p>\n<p>OB-Kandidaten im Foto-Interview<\/p>\n<p>:Sagen Sie jetzt nichts, die Herren!<\/p>\n<p class=\"css-a6ecqs\" data-manual=\"teaser-text\" data-tb-description=\"\" data-schema-org-speakable=\"true\">Die SZ hat die M\u00fcnchner OB-Kandidaten der drei gr\u00f6\u00dften Parteien zum Interview ohne Worte gebeten: Welche zarte Seite Clemens Baumg\u00e4rtner offenbart, warum Dominik Krause zum Bohrer greift und welche Sportart Dieter Reiter liebt (au\u00dfer Fu\u00dfball).<\/p>\n<p>SZ PlusFotos: Johannes SimonDer Sachliche<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Zumindest indirekt hat es auch\u00a0Dominik Krause (Gr\u00fcne) der Aufhebung der Altersgrenze zu verdanken, dass er nun f\u00fcr seine Partei als OB-Kandidat antritt. Dabei ist Krause erst 35 Jahre alt und damit nur unwesentlich \u00e4lter als es Hans-Jochen Vogel (SPD) war, als dieser 1960 mit 34 Jahren zum j\u00fcngsten Oberb\u00fcrgermeister der M\u00fcnchner Geschichte gew\u00e4hlt worden ist.<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Urspr\u00fcnglich hatte sich Krauses Parteifreundin Katrin Habenschaden gute Chancen bei der OB-Wahl 2026 ausgerechnet, doch als klar war, dass sie dann erneut gegen Dieter Reiter antreten m\u00fcsse, zog sie sich im Herbst 2023 aus der Politik zur\u00fcck und wechselte zur Deutschen Bahn. Das Amt des Zweiten B\u00fcrgermeisters \u00fcbernahm damals Dominik Krause, bis dahin Co-Vorsitzender der Fraktion von Gr\u00fcnen und Rosa Liste.<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Bei den M\u00fcnchner Gr\u00fcnen hatte Krause zu dieser Zeit schon alle F\u00fchrungspositionen durchlaufen: Er war Chef der Gr\u00fcnen Jugend (von 2012 bis 2014), dann auch des Kreisverbands (2019\/2020), schlie\u00dflich Vorsitzender der Stadtratsfraktion (2022\/23). In den Stadtrat gew\u00e4hlt wurde er erstmals 2014, also mit 23 Jahren.<\/p>\n<p><a href=\"https:\/\/www.sueddeutsche.de\/muenchen\/muenchen-kommunalwahl-2026-oberbuergermeister-stadtrat-briefwahl-stimmzettel-li.3368820\" aria-label=\"Artikelverlinkung:\" data-track-szde=\"{&quot;event&quot;:&quot;teaser_clicked&quot;,&quot;teaser_clicked&quot;:{&quot;article_title&quot;:&quot;panaschieren_kumulieren_oder_nur_ein_kreuz_setzen_was_bei_der_wahl_zu_beachten_ist&quot;,&quot;doctype&quot;:&quot;&quot;,&quot;label&quot;:&quot;&quot;,&quot;main_topic&quot;:&quot;politik_muenchen&quot;,&quot;object_id&quot;:&quot;li.3368820&quot;,&quot;pcat&quot;:&quot;metered&quot;,&quot;section&quot;:&quot;muenchen&quot;,&quot;teaser_type&quot;:&quot;article_teaser_top&quot;}}\" data-manual=\"teaser-url\" data-tb-link=\"\" aria-labelledby=\"teaser-httpswwwsueddeutschedemuenchenmuenchen-kommunalwahl-2026-oberbuergermeister-stadtrat-briefwahl-stimmzettel-li3368820\" class=\"css-14tg8sh\" rel=\"nofollow noopener\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/1771759514_578_d305d44b-08bd-4b26-b3b9-a998cb4611aa.jpg\"   alt=\"\" loading=\"lazy\" class=\"css-8atqhb\"\/><\/p>\n<p>Kommunalwahl in M\u00fcnchen<\/p>\n<p>:Panaschieren, kumulieren oder nur ein Kreuz setzen \u2013 was bei der Wahl zu beachten ist<\/p>\n<p class=\"css-a6ecqs\" data-manual=\"teaser-text\" data-tb-description=\"\" data-schema-org-speakable=\"true\">Mehr als ein Dutzend Oberb\u00fcrgermeister-Kandidaten und ein riesiger Stimmzettel, auf dem f\u00fcr den Stadtrat 80 einzelne Stimmen vergeben werden k\u00f6nnen\u00a0\u2013 was bei der Kommunalwahl zu beachten ist.<\/p>\n<p>Von Heiner Effern und Anna Hoben<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Nach seinem Zivildienst hatte Krause Physik an der TU M\u00fcnchen studiert; in seiner Masterarbeit besch\u00e4ftigte er sich mit dem Energiesystem der bayerischen Landeshauptstadt. Er wei\u00df also, wovon er spricht, wenn er eine Energiewende propagiert. Und als passionierter Radfahrer und Nutzer des \u00f6ffentlichen Nahverkehrs kann er auch auf eigene praktische Erfahrungen verweisen, wenn er sich f\u00fcr eine Verkehrswende engagiert. Auf einen Dienstwagen, der ihm als B\u00fcrgermeister zustehen w\u00fcrde, hat Krause verzichtet.<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Als Dieter Reiter im vorigen Jahr wegen einer Schulter-Operation mehrere Wochen krankgeschrieben war, f\u00fchrte Krause als sein erster Stellvertreter die Amtsgesch\u00e4fte ohne gr\u00f6\u00dfere Aufregung weiter. Diese Phase habe ihn ermuntert und ermutigt, die Stadt auch \u00fcber einen l\u00e4ngeren Zeitraum zu regieren und zu gestalten, sagte er unl\u00e4ngst in einer Gespr\u00e4chsrunde. In Rathaus-Kreisen gilt Dominik Krause als korrekt und durchaus abw\u00e4gend. \u201eEr trifft niemals eine Entscheidung aus dem Bauch heraus\u201c, sagt die Fraktionsvorsitzende Mona Fuchs: \u201eEr trifft sie immer aufgrund von wissenschaftlichen Erkenntnissen.\u201c<\/p>\n<p>Der Markante<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Obwohl die CSU ihren OB-Kandidaten <a href=\"https:\/\/www.sueddeutsche.de\/thema\/Clemens_Baumg%C3%A4rtner\" rel=\"nofollow noopener\" target=\"_blank\">Clemens Baumg\u00e4rtner<\/a>\u00a0bereits sehr fr\u00fch benannt hatte, n\u00e4mlich im Juli 2024, pr\u00e4sentierte sie der breiten \u00d6ffentlichkeit auf den Wahlkampfplakaten und -bildern lange Zeit nur eine dicke, runde, blaue Brille. Erst in j\u00fcngerer Vergangenheit wurde das Gesicht dahinter zunehmend sichtbar.<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Baumg\u00e4rtner hat seine Kampagne ganz auf diese Brille abgestellt. Mit einer gewisser Selbstironie verriet er einmal, dass er mit dem markanten Gestell die Blicke von seiner Leibesf\u00fclle ablenken wolle. Inzwischen hat er zwar deutlich abgenommen, die Brille ist als Markenzeichen geblieben.<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Im Rennen um den OB-Sessel hat der 49-J\u00e4hrige eine schwierigere Ausgangsposition als seine Konkurrenten Reiter und Krause: Im Gegensatz zu denen kann er nicht aus einem Amt heraus kandidieren, ist also nicht schon dank einer Funktion in der \u00d6ffentlichkeit pr\u00e4sent.<\/p>\n<p><a href=\"https:\/\/www.sueddeutsche.de\/projekte\/artikel\/muenchen\/muenchen-politik-rathaus-koalition-versprechen-bilanz-wohnen-verkehr-kommunalwahl-2026-e551310\/\" aria-label=\"Artikelverlinkung:\" data-track-szde=\"{&quot;event&quot;:&quot;teaser_clicked&quot;,&quot;teaser_clicked&quot;:{&quot;article_title&quot;:&quot;81_versprechen_fuer_muenchen_was_hat_gruen_rot_wirklich_geschafft&quot;,&quot;doctype&quot;:&quot;&quot;,&quot;label&quot;:&quot;&quot;,&quot;main_topic&quot;:&quot;politik_muenchen&quot;,&quot;object_id&quot;:&quot;er.e551310&quot;,&quot;pcat&quot;:&quot;free&quot;,&quot;section&quot;:&quot;muenchen&quot;,&quot;teaser_type&quot;:&quot;article_teaser_top&quot;}}\" data-manual=\"teaser-url\" data-tb-link=\"\" aria-labelledby=\"teaser-httpswwwsueddeutschedeprojekteartikelmuenchenmuenchen-politik-rathaus-koalition-versprechen-bilanz-wohnen-verkehr-kommunalwahl-2026-e551310\" class=\"css-14tg8sh\" rel=\"nofollow noopener\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/766fb4ca-c5e9-4cbc-ad4f-3d8e2c16caa6.jpg\"   alt=\"\" loading=\"lazy\" class=\"css-8atqhb\"\/><\/p>\n<p>Bilanz vor der Wahl<\/p>\n<p>:81 Versprechen f\u00fcr M\u00fcnchen \u2013 was hat Gr\u00fcn-Rot wirklich geschafft?<\/p>\n<p class=\"css-a6ecqs\" data-manual=\"teaser-text\" data-tb-description=\"\" data-schema-org-speakable=\"true\">Sechs Jahre lang hat die SZ \u00fcberpr\u00fcft, was aus dem Koalitionsvertrag eingel\u00f6st wurde \u2013 von Wohnen, \u00fcber Radfahren bis Kitas. Die gro\u00dfe Bilanz im interaktiven M\u00fcnchen-Tracker.<\/p>\n<p>Von SZ-Autorinnen und -Autoren<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Der Wirtschaftsanwalt Baumg\u00e4rtner war 2018 als Nachfolger seines Parteifreunds Josef Schmid zum Referenten f\u00fcr Arbeit und Wirtschaft der Landeshauptstadt gew\u00e4hlt worden; als solcher war er auch f\u00fcr das Oktoberfest verantwortlich. Aus dieser prestigetr\u00e4chtigen Position wurde Baumg\u00e4rtner dann am Ende seiner Amtszeit abgew\u00e4hlt, weil die SPD ihren Kandidaten Christian Scharpf an seiner Stelle installieren wollte. Seit M\u00e4rz 2025 ist Baumg\u00e4rtner deshalb ohne ein st\u00e4dtisches Amt. F\u00fcr den OB-Wahlkampf hat er sich ein Jahr Zeit genommen, in dieser Zeit lebe er von Erspartem, teilte er mit.<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">In der sichersten und wirtschaftlich st\u00e4rksten Gro\u00dfstadt Deutschlands setzt Baumg\u00e4rtner in seinem Wahlkampf schwerpunktm\u00e4\u00dfig auf die Themen Sicherheit und Wirtschaft \u2013 klassische Gebiete der CSU. \u201eIdeologie und Bevormundung lehne ich ab\u201c, sagt Baumg\u00e4rtner, er stehe \u201ef\u00fcr eine pragmatische und sachorientierte Politik\u201c. Wer das bezweifelt, den verweist er darauf, dass er im Bezirksausschuss Untergiesing-Harlaching zwischen 2012 und 2018 einem schwarz-gr\u00fcnen B\u00fcndnis vorgestanden habe.<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">In seine Amtszeit als Wirtschaftsreferent fallen der Umzug der Internationalen Automobil-Ausstellung IAA von Frankfurt nach M\u00fcnchen und die Ansiedlungen von global t\u00e4tigen Unternehmen wie Apple und Google. Au\u00dferdem gilt er als der Mann hinter den zehn Gro\u00dfkonzerten der britischen Pop-S\u00e4ngerin Adele auf dem Riemer Messegel\u00e4nde im August 2024.<\/p>\n","protected":false},"excerpt":{"rendered":"YouTubeDie SZ-Redaktion hat diesen Artikel mit einem Inhalt von YouTube angereichert Um Ihre Daten zu sch\u00fctzen, wurde er&hellip;\n","protected":false},"author":2,"featured_media":816942,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1827],"tags":[772,76378,29,8253,2177,30,48652,2839,55775,148,1268,3661,72871,149,3372],"class_list":{"0":"post-816941","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-muenchen","8":"tag-bayern","9":"tag-clemens-baumgaertner","10":"tag-deutschland","11":"tag-dieter-reiter","12":"tag-dominik-krause","13":"tag-germany","14":"tag-gruene-muenchen","15":"tag-kommunalpolitik","16":"tag-kommunalwahl-in-muenchen","17":"tag-leserdiskussion","18":"tag-muenchen","19":"tag-politik-muenchen","20":"tag-residenztheater","21":"tag-sueddeutsche-zeitung","22":"tag-theater-muenchen"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116114039130868609","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/816941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=816941"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/816941\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/816942"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=816941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=816941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=816941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}