{"id":823343,"date":"2026-02-25T01:22:13","date_gmt":"2026-02-25T01:22:13","guid":{"rendered":"https:\/\/www.europesays.com\/de\/823343\/"},"modified":"2026-02-25T01:22:13","modified_gmt":"2026-02-25T01:22:13","slug":"rund-8-000-auslaender-2025-von-ausweisungen-betroffen","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/823343\/","title":{"rendered":"Rund 8.000 Ausl\u00e4nder 2025 von Ausweisungen betroffen"},"content":{"rendered":"<p><img post-id=\"101338\" fifu-featured=\"1\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/dts_image_5643_hncrmkakpd_348_800_600.jpg\" alt=\"Rund 8.000 Ausl\u00e4nder 2025 von Ausweisungen betroffen\" title=\"Rund 8.000 Ausl\u00e4nder 2025 von Ausweisungen betroffen\" width=\"100%\" align=\"LEFT\"\/><br \/>Foto: Frauen mit Kopftuch (Archiv), via dts Nachrichtenagentur<\/p>\n<p>Berlin (dts Nachrichtenagentur) \u2013 Mehr als 8.000 Ausl\u00e4ndern ist 2025 das Aufenthaltsrecht in Deutschland entzogen worden. Betroffen von solchen Ausweisungsverf\u00fcgungen waren vor allem Menschen aus Georgien, Albanien und der T\u00fcrkei, wie aus der Antwort der Bundesregierung auf eine Kleine Anfrage der Linksfraktion hervorgeht, \u00fcber die die \u201eRheinische Post\u201c in ihrer Mittwochausgabe berichtet.<\/p>\n<p>Unter den im vergangenen Jahr laut Ausl\u00e4nderzentralregister insgesamt 8.232 betroffenen Personen \u2013 meist M\u00e4nner \u2013 stammten den Angaben zufolge 671 aus Georgien, 661 aus Albanien und 618 aus der T\u00fcrkei. Im Jahr 2024, als noch die Ampel-Koalition regierte, lag die Gesamtzahl der Ausweisungsverf\u00fcgungen mit 9.277 etwas h\u00f6her \u2013 am h\u00e4ufigsten ergingen die ebenfalls gegen Menschen aus Albanien (923), Georgien (740) und der T\u00fcrkei (701).<\/p>\n<p>Eine Ausweisung beendet die Rechtm\u00e4\u00dfigkeit des Aufenthalts und l\u00f6st eine Ausreisepflicht aus. Wie viele der Ausweisungen zu Abschiebungen f\u00fchrten, lie\u00df sich laut Regierung indes nicht seri\u00f6s beziffern.<\/p>\n<p>\u201eWeil das Ausweisungsrecht in den letzten Jahren mehrfach versch\u00e4rft wurde, k\u00f6nnen schon geringf\u00fcgige Taten zur Ausweisung f\u00fchren\u201c, sagte die Linken-Abgeordnete Clara B\u00fcnger. Das seien schwere Eingriffe in die Grundrechte von Menschen.<\/p>\n<p>\u201eBesonders alarmierend ist die Tatsache, dass regelm\u00e4\u00dfig auch Minderj\u00e4hrige ausgewiesen werden, selbst strafunm\u00fcndige Kinder unter 14 Jahren sind betroffen\u201c, so B\u00fcnger. Minderj\u00e4hrig waren 2025 insgesamt 43 von Ausweisung betroffene Personen: Davon waren 24 j\u00fcnger als 14 Jahre, 19 weitere waren Jugendliche im Alter von 14 bis 17 Jahren.<\/p>\n","protected":false},"excerpt":{"rendered":"Foto: Frauen mit Kopftuch (Archiv), via dts Nachrichtenagentur Berlin (dts Nachrichtenagentur) \u2013 Mehr als 8.000 Ausl\u00e4ndern ist 2025&hellip;\n","protected":false},"author":2,"featured_media":823344,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1825],"tags":[1941,1939,147,296,1937,29,30,1940,1938,16,55],"class_list":{"0":"post-823343","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-berlin","8":"tag-aktuelle-nachrichten-aus-berlin","9":"tag-aktuelle-news-aus-berlin","10":"tag-ausland","11":"tag-berlin","12":"tag-berlin-news","13":"tag-deutschland","14":"tag-germany","15":"tag-nachrichten-aus-berlin","16":"tag-news-aus-berlin","17":"tag-politik","18":"tag-wirtschaft"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116128654753353916","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/823343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=823343"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/823343\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/823344"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=823343"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=823343"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=823343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}