{"id":823479,"date":"2026-02-25T02:37:10","date_gmt":"2026-02-25T02:37:10","guid":{"rendered":"https:\/\/www.europesays.com\/de\/823479\/"},"modified":"2026-02-25T02:37:10","modified_gmt":"2026-02-25T02:37:10","slug":"oekonom-huether-merz-muss-gegenueber-xi-unfaire-handelspraktiken-adressieren","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/823479\/","title":{"rendered":"\u00d6konom H\u00fcther: Merz muss gegen\u00fcber Xi unfaire Handelspraktiken adressieren \/ &#8230;"},"content":{"rendered":"<p class=\"date\">25.02.2026 \u2013 01:00<\/p>\n<p class=\"customer\">\n                        <a class=\"story-customer\" title=\"weiter zum newsroom von Neue Osnabr\u00fccker Zeitung\" href=\"https:\/\/www.presseportal.de\/nr\/58964\" rel=\"nofollow noopener\" target=\"_blank\">Neue Osnabr\u00fccker Zeitung<\/a>\n                    <\/p>\n<p><a data-category=\"citylink-story-view\" data-action=\"click\" data-label=\"Citylink in Meldungsansicht\" class=\"story-city event-trigger\" href=\"https:\/\/www.presseportal.de\/regional\/Osnabr%FCck\" title=\"News aus Osnabr\u00fcck \" rel=\"nofollow noopener\" target=\"_blank\">Osnabr\u00fcck<\/a> (ots)<\/p>\n<p>Osnabr\u00fcck. Top-\u00d6konom Michael H\u00fcther hat Bundeskanzler Friedrich Merz vor dessen Gespr\u00e4chen mit der chinesischen F\u00fchrung (an diesem Mittwoch) zu klaren Ansagen aufgerufen. &#8222;Er sollte adressieren, dass unfaire Handelspraktiken keinen langen Atem haben, sondern Gegenma\u00dfnahmen provozieren. Das muss man den Chinesen sehr deutlich machen&#8220;, sagte der Direktor des Instituts der deutschen Wirtschaft (IW) im Gespr\u00e4ch mit der &#8222;Neuen Osnabr\u00fccker Zeitung&#8220; (noz, Mittwochsausgabe). &#8222;Friedrich Merz sollte sich in Peking nicht ins Bockshorn jagen lassen, was er vermutlich auch nicht tut.&#8220; Merz trifft am Mittwoch zun\u00e4chst den chinesischen Ministerpr\u00e4sidenten Li Qiang, bevor er von Staatspr\u00e4sident Xi Jinping zu einem Vieraugengespr\u00e4ch empfangen wird.<\/p>\n<p>H\u00fcther sagte noz: &#8222;Herr Merz kann in Peking ein selbstbewusstes Gespr\u00e4ch auf Augenh\u00f6he f\u00fchren. Deutschland und China sind die beiden gro\u00dfen Gewinner der Globalisierungsphase seit den 80er\/90er Jahren. Und beide L\u00e4nder stehen jetzt vor erheblichen strukturellen Herausforderungen. Gemeinsam geht das besser.&#8220; Auf chinesischer Seite nannte der IW-Direktor &#8222;die dramatische Alterung der Gesellschaft, die Fehlallokation von Kapital, die Probleme im Immobiliensektor&#8220; sowie &#8222;eine \u00dcberproduktionskrise&#8220; vor allem bei E-Autos.<\/p>\n<p>Zugleich trat der Wirtschaftswissenschaftler wachsenden Bef\u00fcrchtungen entgegen, China werde Europa technologisch abh\u00e4ngen. &#8222;Kann ein Land bei allen Produkten komparative Vorteile &#8211; wie wir \u00d6konomen sagen &#8211; haben? Das ist quasi ausgeschlossen&#8220;, so H\u00fcther zu noz. Begr\u00fcndet w\u00e4re die Sorge allenfalls, wenn hierzulande die Forschungsintensit\u00e4t nicht vorangetrieben w\u00fcrde. &#8222;Worauf es ankommt: Dass wir lernen, aus den Erkenntnissen der Universit\u00e4ten mehr Wertsch\u00f6pfung zu kreieren. Zum Beispiel durch Ausgr\u00fcndungen. Wenn wir da besser werden, und das k\u00f6nnen wir, m\u00fcssen wir nicht bef\u00fcrchten, von China \u00fcberrollt zu werden.&#8220; Zumal Deutschland und Europa wom\u00f6glich davon profitieren k\u00f6nnten, dass die Wissenschaftsfreiheit in den USA bedroht sei.<\/p>\n<p class=\"contact-headline\">Pressekontakt:<\/p>\n<p class=\"contact-text\">Neue Osnabr\u00fccker Zeitung<br \/>Redaktion<\/p>\n<p>Telefon: +49(0)541\/310 207<\/p>\n<p class=\"originator\">Original-Content von: Neue Osnabr\u00fccker Zeitung, \u00fcbermittelt durch news aktuell<\/p>\n","protected":false},"excerpt":{"rendered":"25.02.2026 \u2013 01:00 Neue Osnabr\u00fccker Zeitung Osnabr\u00fcck (ots) Osnabr\u00fcck. Top-\u00d6konom Michael H\u00fcther hat Bundeskanzler Friedrich Merz vor dessen&hellip;\n","protected":false},"author":2,"featured_media":386213,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1828],"tags":[29,30,1420,1209,178,180,179,181,21905,21904,55],"class_list":{"0":"post-823479","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-koeln","8":"tag-deutschland","9":"tag-germany","10":"tag-koeln","11":"tag-nordrhein-westfalen","12":"tag-presse","13":"tag-pressemeldung","14":"tag-pressemitteilung","15":"tag-pressemitteilungen","16":"tag-presseschau","17":"tag-reformen","18":"tag-wirtschaft"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116128949504805513","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/823479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=823479"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/823479\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/386213"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=823479"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=823479"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=823479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}