{"id":838189,"date":"2026-03-02T20:45:14","date_gmt":"2026-03-02T20:45:14","guid":{"rendered":"https:\/\/www.europesays.com\/de\/838189\/"},"modified":"2026-03-02T20:45:14","modified_gmt":"2026-03-02T20:45:14","slug":"cadeaux-leipzig-und-floriga-mit-besucherplus-%c2%b7-leipziger-zeitung","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/838189\/","title":{"rendered":"CADEAUX Leipzig und Floriga mit Besucherplus \u00b7 Leipziger Zeitung"},"content":{"rendered":"<p>Kompakt, orderstark und auf den regionalen Fachhandel zugeschnitten pr\u00e4sentierten sich die 67. CADEAUX Leipzig und die 33. Floriga am ersten M\u00e4rzwochenende. Bei fr\u00fchlingshaften Temperaturen kamen vom 28. Februar bis 2. M\u00e4rz 8.300 Besucher in die Leipziger Messehallen. \u00dcber 350 Aussteller und Marken aus elf L\u00e4ndern pr\u00e4sentierten dort ihre Neuheiten f\u00fcr die kommenden Saisons. G\u00e4ste aus Politik und Showbusiness sorgten f\u00fcr Aufmerksamkeit und gute Stimmung.<\/p>\n<p>Auf dem Gel\u00e4nde der Leipziger Messe wurde drei Tage lang geordert, entdeckt und gestaunt. Mehr als 350 Aussteller und Marken zeigten die ganze Sortimentsvielfalt von Gedeckter Tisch, Cook-Shop und Genuss \u00fcber Erzgebirgisches Kunsthandwerk, Floristik bis hin zu Wohnaccessoires, Papeterie, Beauty &amp; Wellness. \u00a0Damit best\u00e4tigt das Messe-Duo seine Bedeutung als zentrale Order- und Netzwerkplattform f\u00fcr den Fachhandel in Mitteldeutschland. <\/p>\n<p>\u201eHier informiert sich der regionale Handel \u00fcber Trends, stellt seine Sortimente f\u00fcr das laufende Gesch\u00e4ftsjahr, saisonale H\u00f6hepunkte und Weihnachten zusammen\u201c, sagt Martin Buhl-Wagner, Gesch\u00e4ftsf\u00fchrer der Leipziger Messe.<\/p>\n<p>Projektdirektor Andreas Zachlod betont die Bedeutung des pers\u00f6nlichen Austauschs: \u201eDas gewachsene Interesse zeigt, wie wichtig pers\u00f6nliche Begegnung, Inspiration und direkte Orderm\u00f6glichkeiten gerade in einem dynamischen Marktumfeld sind.\u201c<\/p>\n<p>Glanzvoll und mit viel Charme er\u00f6ffnete TV-Moderatorin Enie van de Meiklokjes die CADEAUX Leipzig am Messesamstag. Beim Mittagstalk mit Messe-Chef Martin Buhl-Wagner gestaltete Floristmeister David Gehrisch das Trendgesteck der Fr\u00fchjahrs-CADEAUX 2026 \u2013 ein Arrangement aus gr\u00fcnen Zweigen sowie gelben und hellblauen Bl\u00fcten.<\/p>\n<p>Erzgebirgisches Kunsthandwerk \u00fcberrascht mit Premieren und Jubil\u00e4en<\/p>\n<p>Bereits am ersten Messetag sorgte ein besonderes Highlight f\u00fcr Aufmerksamkeit: die feierliche Enth\u00fcllung eines 1,80 Meter gro\u00dfen erzgebirgischen Nussknackers im Forum Erzgebirge. Das Kunstobjekt entstand im Rahmen des Design-Wettbewerbs \u201eNewsknacker \u2013 So geht s\u00e4chsisch!\u201c und wurde erstmals \u00f6ffentlich pr\u00e4sentiert. Der Entwurf der Holzspielzeugmacherin Marie Friedrich setzte sich gegen \u00fcber 200 Einreichungen aus ganz Deutschland durch. Ihre Idee, Sachsen auf dem Nussknacker zu verewigen, \u00fcberzeugte die Jury. <\/p>\n<p>Die s\u00e4chsische Kultur- und Tourismusministerin Barbara Klepsch w\u00fcrdigte in ihrem Gru\u00dfwort die Verbindung der traditionellen erzgebirgischen Handwerkskunst mit der CADEAUX Leipzig: \u201eKunsthandwerk aus dem Erzgebirge ist nicht nur lebendige Tradition und Weltkulturerbe, sondern passt auch wunderbar zu den Lifestylethemen der CADEAUX Leipzig.\u201c<\/p>\n<p>Ebenfalls im Forum Erzgebirge gezeigt wurden die 30 besten Gestaltungsvorschl\u00e4ge aus denen die Messebesucher ihren Favoriten w\u00e4hlen konnten. Laut Frederic G\u00fcnther, dem Gesch\u00e4ftsf\u00fchrer des Verbands Erzgebirgischer Kunsthandwerker und Spielzeughersteller, gibt es bereits interessierte Firmen, die den Publikumsliebling in den Handel bringen m\u00f6chten.<\/p>\n<p> Die Aktion ist aus seiner Sicht ein voller Erfolg: \u201eDie CADEAUX Leipzig ist f\u00fcr uns ein wichtiges Branchenbarometer f\u00fcr die kommende Saison. Das Besucheraufkommen und die Stimmung waren durchweg positiv und haben unsere Erwartungen \u00fcbertroffen. Besonders die Nussknacker-Aktion hat im Forum Erzgebirge f\u00fcr zus\u00e4tzliche Frequenz gesorgt und gro\u00dfe Aufmerksamkeit erzielt\u201c, res\u00fcmiert Frederic G\u00fcnther.<\/p>\n<p>Auf der CADEAUX Leipzig pr\u00e4sentierten rund 30 Firmen aus dem Erzgebirge ihre Produkte. Die Firma Kleinkunst M\u00fcller feierte ein ganz besonderes Jubil\u00e4um \u2013 100 Jahre Messebeteiligung. Zugleich pr\u00e4sentierten sie eine Weltneuheit \u2013 einen elektrischen Schwibbogen ohne Verkabelung im Inneren. M\u00f6glich ist dies durch eine mit Leitern bedruckte d\u00fcnne Holzleiste, die den Schwibbogen innen und au\u00dfen beleuchtet. <\/p>\n<p>Der Prototyp des neuartigen Schwibbogens wurde mit dem Fraunhofer-Institut f\u00fcr Elektronische Nanosysteme und weiteren Projektpartnern in drei Jahren entwickelt. Laut Kleinkunst M\u00fcller ist der neuartige Schwibbogen langlebig, verschlei\u00dfarm und somit besonders nachhaltig.<\/p>\n<p>Aktionstag Bl\u00fchender Start<\/p>\n<p>Rund 80 Azubis der Floristik reisten aus Berufsschulen in Berlin, Dessau, Dresden, Halle und Wurzen am Messemontag nach Leipzig. In praxisorientierten Workshops sammelten sie frische Impulse f\u00fcr ihren zuk\u00fcnftigen Beruf. Die Deutsche Blumenfee, Hannes Schrader, ermutigte den Branchennachwuchs in ihrem Beruf laut, mutig und kreativ zu sein, Kooperationen einzugehen und vor allem, auf Social Media sichtbar zu sein \u2013 denn dort werden die Kunden von morgen erreicht.<\/p>\n<p>Es bl\u00fcht und gr\u00fcnt auf der Floriga<\/p>\n<p>P\u00fcnktlich zum meteorologischen Fr\u00fchlingsanfang l\u00e4utete die Floriga am 1. M\u00e4rz die Gartensaison ein. Auf der Fachb\u00f6rse f\u00fcr die gr\u00fcne Branche pr\u00e4sentierten 125 Aussteller und Marken aus Deutschland, Polen und den Niederlanden Trends und Neuheiten f\u00fcr Gartenbau, Floristik und Gartencenter.<\/p>\n<p>Der s\u00e4chsische Staatsminister Georg-Ludwig von Breitenbuch er\u00f6ffnete die Floriga mit einem Gru\u00dfwort und einem anschlie\u00dfenden Rundgang. Dabei kam er mit vielen Ausstellern ins Gespr\u00e4ch: \u201eIch bin beeindruckt von der positiven Stimmung und dem Engagement der Betriebe aus Sachsen und Mitteldeutschland. Gleichzeitig stehen diese Betriebe vor gro\u00dfen Herausforderungen. <\/p>\n<p>Mindestlohnerh\u00f6hungen, hohe Energiekosten und Anforderungen im Pflanzenschutz belasten viele Unternehmen sp\u00fcrbar. Auf Bundes- und auch auf europ\u00e4ischer Ebene m\u00fcssen wir daran arbeiten, die Rahmenbedingungen zu verbessern. Denn wir brauchen starke, regional verwurzelte Betriebe, die mit ihrem Land verbunden sind und ihr \u00fcber Generationen gewachsenes Wissen bewahren und weitergeben.\u201c<\/p>\n<p>Tobias Muschalek, Gesch\u00e4ftsf\u00fchrer der F\u00f6rdergesellschaft Gartenbau Sachsen mbH und ideeller Tr\u00e4ger der Floriga res\u00fcmiert: \u201eDie Besucherzahlen bewegen sich auf einem stabilen Niveau. Die Floristen und G\u00e4rtner, die die Floriga besucht haben, zeigen sich verhalten optimistisch. Von guten Verk\u00e4ufen berichten die Aussteller und ziehen insgesamt ein positives Fazit ihrer Gesch\u00e4ftsergebnisse auf der Floriga.\u201c<\/p>\n<p>Die Wahl der Pflanzen des Jahres stand unter dem Motto \u201eHarmonie in Pink\u201c f\u00fcr Beet und Balkon. Zur Balkonpflanze des Jahres 2026 wurde die Verbene namens \u201eEstrella Taffy Pink\u201c gew\u00e4hlt. Sie gilt als robust, wetterbest\u00e4ndig und ist f\u00fcr jeden Standort gut geeignet. Seit vier Jahren k\u00fcrt der Gartenbauverband Mitteldeutschland e.V. auch die Sommerpflanze des Jahres. In diesem Jahr darf die aufrecht wachsende Staude (Agastache) namens \u201ePink Pearl\u201c den Titel Sommerpflanze 2026 tragen. Sie bl\u00fcht bis weit in den Herbst hinein und bietet Bienen und Schmetterlingen Nahrung.\u00a0\u00a0<\/p>\n<p>Die n\u00e4chste CADEAUX Leipzig findet vom 5. bis 7. September 2026 statt. Der Termin f\u00fcr die n\u00e4chste Fr\u00fchjahrs-CADEAUX ist der 27. Februar bis 1. M\u00e4rz 2027 mit der Floriga am 28. Februar 2027.<\/p>\n","protected":false},"excerpt":{"rendered":"Kompakt, orderstark und auf den regionalen Fachhandel zugeschnitten pr\u00e4sentierten sich die 67. CADEAUX Leipzig und die 33. Floriga&hellip;\n","protected":false},"author":2,"featured_media":33036,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1832],"tags":[3364,29,30,71,47,859],"class_list":{"0":"post-838189","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-leipzig","8":"tag-de","9":"tag-deutschland","10":"tag-germany","11":"tag-leipzig","12":"tag-messe","13":"tag-sachsen"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116161539406549480","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/838189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=838189"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/838189\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/33036"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=838189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=838189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=838189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}