{"id":841401,"date":"2026-03-04T02:26:18","date_gmt":"2026-03-04T02:26:18","guid":{"rendered":"https:\/\/www.europesays.com\/de\/841401\/"},"modified":"2026-03-04T02:26:18","modified_gmt":"2026-03-04T02:26:18","slug":"european-league-hannover-jubelt-gruppensieg-und-viertelfinale-perfekt-sport","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/841401\/","title":{"rendered":"European League &#8211; Hannover jubelt &#8211; Gruppensieg und Viertelfinale perfekt &#8211; Sport"},"content":{"rendered":"<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Hannover (dpa\/lni) &#8211; Die TSV Hannover-Burgdorf hat schon am vorletzten Hauptrundenspieltag der <a href=\"https:\/\/www.sueddeutsche.de\/thema\/Handball\" rel=\"nofollow noopener\" target=\"_blank\">Handball<\/a>-European-League den Einzug in das Viertelfinale geschafft. Die \u201eRecken\u201c gewannen ihr Heimspiel gegen die Kadetten Schaffhausen aus der <a href=\"https:\/\/www.sueddeutsche.de\/thema\/Schweiz\" rel=\"nofollow noopener\" target=\"_blank\">Schweiz<\/a> 31:27 (15:15) und profitierten vom 33:26 (21:16) der Kroaten von RK Nexe Nasice gegen Fredericia HK aus D\u00e4nemark. Als bester Werfer steuerte August Pedersen neun Treffer zum vorzeitigen Gruppensieg der TSV bei. F\u00fcr die Kadetten erzielte Odinn Rikhardsson ebenfalls neun Tore.<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Eine Woche nach dem 36:24-Hinspielsieg der <a href=\"https:\/\/www.sueddeutsche.de\/thema\/Niedersachsen\" rel=\"nofollow noopener\" target=\"_blank\">Niedersachsen<\/a> in der Schweiz verlief die erste H\u00e4lfte ausgeglichen. Keine Mannschaft schaffte es, sich einen gr\u00f6\u00dferen Vorsprung herauszuwerfen. Mit einem Treffer in das leere Tor der G\u00e4ste glich Justus Fischer die Partie zur Halbzeit aus.<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">Auch ohne ihren verletzten Spielmacher Leif Tissier behielten die Gastgeber nach dem Seitenwechsel die Ruhe. Der Vorsprung wuchs immer weiter an. So steuerte das Team von Trainer Juan Carlos Pastor einem ungef\u00e4hrdeten Sieg entgegen.<\/p>\n<p data-manual=\"paragraph\" data-schema-org-speakable=\"true\" class=\"css-1eosz7k\">\u00a9 dpa-infocom, dpa:260303-930-764751\/1<\/p>\n","protected":false},"excerpt":{"rendered":"Hannover (dpa\/lni) &#8211; Die TSV Hannover-Burgdorf hat schon am vorletzten Hauptrundenspieltag der Handball-European-League den Einzug in das Viertelfinale&hellip;\n","protected":false},"author":2,"featured_media":841402,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1836],"tags":[147,3364,29,30872,30,1391,7491,46,5402,1411,293,265,149,10763,9658],"class_list":{"0":"post-841401","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-hannover","8":"tag-ausland","9":"tag-de","10":"tag-deutschland","11":"tag-european-league","12":"tag-germany","13":"tag-handball","14":"tag-handball-team","15":"tag-hannover","16":"tag-maenner","17":"tag-niedersachsen","18":"tag-schweiz","19":"tag-sport","20":"tag-sueddeutsche-zeitung","21":"tag-swiss-life-hall","22":"tag-tsv-hannover-burgdorf"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116168542837889331","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/841401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=841401"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/841401\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/841402"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=841401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=841401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=841401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}