{"id":841447,"date":"2026-03-04T02:50:14","date_gmt":"2026-03-04T02:50:14","guid":{"rendered":"https:\/\/www.europesays.com\/de\/841447\/"},"modified":"2026-03-04T02:50:14","modified_gmt":"2026-03-04T02:50:14","slug":"spd-politiker-ahmetovic-kritisiert-kommunikation-von-wadephul","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/841447\/","title":{"rendered":"SPD-Politiker Ahmetovic kritisiert Kommunikation von Wadephul"},"content":{"rendered":"<p><img post-id=\"101502\" fifu-featured=\"1\" decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/dts_image_92580_ehnfgncjkf_348_800_600.jpg\" alt=\"SPD-Politiker Ahmetovic kritisiert Kommunikation von Wadephul\" title=\"SPD-Politiker Ahmetovic kritisiert Kommunikation von Wadephul\" width=\"100%\" align=\"LEFT\"\/><br \/>Foto: Adis Ahmetovic (Archiv), via dts Nachrichtenagentur<\/p>\n<p>Berlin (dts Nachrichtenagentur) \u2013 SPD-Au\u00dfenpolitiker Adis Ahmetovic hat Kritik an der Krisenkommunikation von Au\u00dfenminister Johann Wadephul ge\u00fcbt.<\/p>\n<p>\u201eDie urspr\u00fcngliche Ank\u00fcndigung, keine Evakuierungsfl\u00fcge vorzusehen, hat am Wochenende Irritationen ausgel\u00f6st und viele Betroffene und ihre Angeh\u00f6rigen verunsichert\u201c, sagte der au\u00dfenpolitische Sprecher der SPD-Bundestagsfraktion dem Nachrichtenmagazin \u201eFocus\u201c. \u201eDeshalb ist es richtig, dass die Bundesregierung nun beginnt, im ersten Schritt vulnerable Deutsche bei der Ausreise zu unterst\u00fctzen. Das ist eine notwendige Kurskorrektur.\u201c<\/p>\n<p>Gleichzeitig werde das nicht ausreichen. \u201eWir sprechen \u00fcber zehntausende deutsche Staatsangeh\u00f6rige in der Region. Es m\u00fcssen weitere Unterst\u00fctzungspl\u00e4ne folgen\u201c, sagte Ahmetovic weiter. \u201eBesonders dringlich ist auch die Situation einiger FSJler, die zum Beispiel im Auftrag der Bundesregierung vor Ort sind \u2013 sie und ihre besorgten Eltern erwarten zu Recht eine schnelle und sichere L\u00f6sung.\u201c<\/p>\n","protected":false},"excerpt":{"rendered":"Foto: Adis Ahmetovic (Archiv), via dts Nachrichtenagentur Berlin (dts Nachrichtenagentur) \u2013 SPD-Au\u00dfenpolitiker Adis Ahmetovic hat Kritik an der&hellip;\n","protected":false},"author":2,"featured_media":841448,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1825],"tags":[1941,1939,147,296,1937,29,30,1940,1938,16,55],"class_list":{"0":"post-841447","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-berlin","8":"tag-aktuelle-nachrichten-aus-berlin","9":"tag-aktuelle-news-aus-berlin","10":"tag-ausland","11":"tag-berlin","12":"tag-berlin-news","13":"tag-deutschland","14":"tag-germany","15":"tag-nachrichten-aus-berlin","16":"tag-news-aus-berlin","17":"tag-politik","18":"tag-wirtschaft"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116168636883231140","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/841447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=841447"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/841447\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/841448"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=841447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=841447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=841447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}