{"id":843657,"date":"2026-03-04T23:46:12","date_gmt":"2026-03-04T23:46:12","guid":{"rendered":"https:\/\/www.europesays.com\/de\/843657\/"},"modified":"2026-03-04T23:46:12","modified_gmt":"2026-03-04T23:46:12","slug":"sitzung-des-kreiswahlausschusses-fuer-die-landtagswahl-2026","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/843657\/","title":{"rendered":"Sitzung des Kreiswahlausschusses f\u00fcr die Landtagswahl 2026"},"content":{"rendered":"<tr class=\"tribe-events-calendar-month__week\" data-js=\"tribe-events-month-grid-row\">\n<td class=\"tribe-events-calendar-month__day tribe-events-calendar-month__day--past tribe-events-calendar-month__day--other-month tribe-events-calendar-month__day--past-month\" aria-labelledby=\"tribe-events-calendar-day-2026-02-23\" data-js=\"tribe-events-month-grid-cell\">\n<p>0 Veranstaltungen\t\t<\/p>\n<p>23\n<\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day tribe-events-calendar-month__day--past tribe-events-calendar-month__day--other-month tribe-events-calendar-month__day--past-month\" aria-labelledby=\"tribe-events-calendar-day-2026-02-24\" data-js=\"tribe-events-month-grid-cell\">\n<p>0 Veranstaltungen\t\t<\/p>\n<p>24\n<\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day tribe-events-calendar-month__day--past tribe-events-calendar-month__day--other-month tribe-events-calendar-month__day--past-month\" aria-labelledby=\"tribe-events-calendar-day-2026-02-25\" data-js=\"tribe-events-month-grid-cell\">\n<p>8 Veranstaltungen\t\t<\/p>\n<p>25\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p>\nFrankenthal \u2013 Vortrag an der vhs Frankenthal \u2013 Musik! H\u00f6ren&amp;Verstehen: Chopins Klaviermusik<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/3232-2552-maxZZZ-633x500-1.jpg\" alt=\"3232 2552 maxZZZ 633x500\" title=\"3232-2552-maxZZZ-633\u00d7500\" width=\"633\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/mrn_news_platzhalter_logo-5-1-73.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"\" alt=\"\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day tribe-events-calendar-month__day--past tribe-events-calendar-month__day--other-month tribe-events-calendar-month__day--past-month\" aria-labelledby=\"tribe-events-calendar-day-2026-02-26\" data-js=\"tribe-events-month-grid-cell\">\n<p>8 Veranstaltungen\t\t<\/p>\n<p>26\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/brave_screenshot_www.nicolehuberhd.deZZZ_-2.jpg\"  alt=\"Brave screenshot www.nicolehuberhd.deZZZ\" title=\"brave_screenshot_www.nicolehuberhd.deZZZ\" width=\"550\" height=\"590\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/mrn_news_platzhalter_logo-5-1-115.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/Jobs-for-Futere.jpg\" alt=\"Jobs for Futere\" title=\"Jobs for Futere\" width=\"500\" height=\"333\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day tribe-events-calendar-month__day--past tribe-events-calendar-month__day--other-month tribe-events-calendar-month__day--past-month\" aria-labelledby=\"tribe-events-calendar-day-2026-02-27\" data-js=\"tribe-events-month-grid-cell\">\n<p>10 Veranstaltungen\t\t<\/p>\n<p>27\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/06-02-26.jpg\"  alt=\"06 02\" title=\"06-02-26\" width=\"1022\" height=\"313\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/Jobs-for-Futere.jpg\" alt=\"Jobs for Futere\" title=\"Jobs for Futere\" width=\"500\" height=\"333\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/Diamanten.jpg\"  alt=\"Diamanten\" title=\"Diamanten\" width=\"878\" height=\"522\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day tribe-events-calendar-month__day--past tribe-events-calendar-month__day--other-month tribe-events-calendar-month__day--past-month\" aria-labelledby=\"tribe-events-calendar-day-2026-02-28\" data-js=\"tribe-events-month-grid-cell\">\n<p>9 Veranstaltungen\t\t<\/p>\n<p>28\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/Shahram-Lang-Bild-privat-316x500-1.png\" alt=\"Shahram Lang Bild privat 316x500\" title=\"Shahram-Lang-Bild-privat-316\u00d7500\" width=\"316\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/Jobs-for-Futere.jpg\" alt=\"Jobs for Futere\" title=\"Jobs for Futere\" width=\"500\" height=\"333\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/1771900334_65_Antiquitaeten-Sammlerstuecke-KI-.jpg\"  alt=\"Antiquit\u00e4ten + Sammlerst\u00fccke KI\" title=\"Antiquit\u00e4ten + Sammlerst\u00fccke KI\" width=\"1071\" height=\"713\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day tribe-events-calendar-month__day--past\" aria-labelledby=\"tribe-events-calendar-day-2026-03-01\" data-js=\"tribe-events-month-grid-cell\">\n<p>3 Veranstaltungen\t\t<\/p>\n<p>1\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/Schlumpi-und-Pumpi.jpg\"  alt=\"Schlumpi und Pumpi\" title=\"Schlumpi und Pumpi\" width=\"644\" height=\"647\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/Meine-Braut-sein-Vater-und-ich-4.jpg\"  alt=\"Meine Braut, sein Vater und ich\" title=\"Meine Braut, sein Vater und ich\" width=\"1019\" height=\"761\"\/><\/p>\n<\/td>\n<\/tr>\n<tr class=\"tribe-events-calendar-month__week\" data-js=\"tribe-events-month-grid-row\">\n<td class=\"tribe-events-calendar-month__day tribe-events-calendar-month__day--past\" aria-labelledby=\"tribe-events-calendar-day-2026-03-02\" data-js=\"tribe-events-month-grid-cell\">\n<p>3 Veranstaltungen\t\t<\/p>\n<p>2\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-127.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/mrn_news_platzhalter_logo-5-1-79.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day tribe-events-calendar-month__day--past\" aria-labelledby=\"tribe-events-calendar-day-2026-03-03\" data-js=\"tribe-events-month-grid-cell\">\n<p>4 Veranstaltungen\t\t<\/p>\n<p>3\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-130.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-114.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/068-Nadja_Hieb.jpg\"  alt=\"068, Nadja Hieb\" title=\"068, Nadja_Hieb\" width=\"1000\" height=\"752\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day tribe-events-calendar-month__day--past\" aria-labelledby=\"tribe-events-calendar-day-2026-03-04\" data-js=\"tribe-events-month-grid-cell\">\n<p>6 Veranstaltungen\t\t<\/p>\n<p>4\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-166.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-162.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-148.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day tribe-events-calendar-month__day--current\" aria-labelledby=\"tribe-events-calendar-day-2026-03-05\" data-js=\"tribe-events-month-grid-cell\">\n<p>8 Veranstaltungen\t\t<\/p>\n<p>5\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-161.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-123.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/1024-1525ZZZ-1.jpg\"  alt=\"1024 1525ZZZ\" title=\"1024-1525ZZZ\" width=\"400\" height=\"596\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-06\" data-js=\"tribe-events-month-grid-cell\">\n<p>10 Veranstaltungen\t\t<\/p>\n<p>6\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p>\nLandau \u2013 Aktionstag \u201eSauberes Landau\u201c<\/p>\n<p>\nLudwigshafen \u2013 Ditzners Kino Roulette: 100 Jahre \u201eDie Abenteuer des Prinzen Achmed\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/075-Bewegungsangebot-HainfeldZZZ.jpg\"  alt=\"075, Bewegungsangebot HainfeldZZZ\" title=\"075, Bewegungsangebot HainfeldZZZ\" width=\"1000\" height=\"461\"\/><\/p>\n<p><img decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"\" alt=\"\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Gruppenbild-3.jpg\" alt=\"Gruppenbild\" title=\"Gruppenbild\" width=\"500\" height=\"411\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-07\" data-js=\"tribe-events-month-grid-cell\">\n<p>10 Veranstaltungen\t\t<\/p>\n<p>7\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p>\nHeidelberg \u2013 Seminar:  Gewaltfreie Kommunikation\u00ae (GFK)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/flohmarkt_2ZZZ.jpg\" alt=\"Flohmarkt 2ZZZ\" title=\"flohmarkt_2ZZZ\" width=\"700\" height=\"465\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-17.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-31.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-08\" data-js=\"tribe-events-month-grid-cell\">\n<p>15 Veranstaltungen\t\t<\/p>\n<p>8\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p>\nLudwigshafen \u2013 Wilhelm-Hack-Museum: \u00d6ffentliche F\u00fchrungen im M\u00e4rz<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-32.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/publicdomainpictures-singing-18438_640-1.jpg\" alt=\"Publicdomainpictures singing 18438\" title=\"publicdomainpictures-singing-18438_640\" width=\"640\" height=\"428\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/csm_abv_cemile_sahin_c_miriam_marlene_waldner_85458c2f79ZZZ.jpg\" alt=\"Csm abv cemile sahin c miriam marlene waldner 85458c2f79ZZZ\" title=\"csm_abv_cemile_sahin_c_miriam_marlene_waldner_85458c2f79ZZZ\" width=\"750\" height=\"423\"\/><\/p>\n<\/td>\n<\/tr>\n<tr class=\"tribe-events-calendar-month__week\" data-js=\"tribe-events-month-grid-row\">\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-09\" data-js=\"tribe-events-month-grid-cell\">\n<p>9 Veranstaltungen\t\t<\/p>\n<p>9\n<\/p>\n<p>\nLudwigshafen \u2013 Ditzners Kino Roulette: 100 Jahre \u201eDie Abenteuer des Prinzen Achmed\u201c<\/p>\n<p>\nLudwigshafen \u2013 Wilhelm-Hack-Museum: \u00d6ffentliche F\u00fchrungen im M\u00e4rz<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p>\nSchifferstadt -\u201eStarke Frauen\u201c Buch-Blind-Date in der Stadtb\u00fccherei!<\/p>\n<p>\nSchifferstadt -\u201eStarke Frauen\u201c Buch-Blind-Date in der Stadtb\u00fccherei!<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-8.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-9.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Sonst-Schoko-\u2013-Eiskauf-mit-Schwierigkeiten.jpg\"  alt=\"Sonst Schoko \u2013 Eiskauf mit Schwierigkeiten\" title=\"Sonst Schoko \u2013 Eiskauf mit Schwierigkeiten\" width=\"1019\" height=\"692\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-10\" data-js=\"tribe-events-month-grid-cell\">\n<p>8 Veranstaltungen\t\t<\/p>\n<p>10\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-2.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-23.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/02\/mrn_news_platzhalter_logo-5-1-63.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-11\" data-js=\"tribe-events-month-grid-cell\">\n<p>12 Veranstaltungen\t\t<\/p>\n<p>11\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-125.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/brave_screenshot_nextcloud.heidelberg.de-3ZZZ-1.jpg\"  alt=\"Brave screenshot nextcloud.heidelberg.de (3)ZZZ\" title=\"brave_screenshot_nextcloud.heidelberg.de (3)ZZZ\" width=\"500\" height=\"603\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Cover-Im-Dschung-wird-gewaehlt_@Prestel-VerlagZZZ-1.jpg\"  alt=\"Im Dschungel wird gewaehlt von Pedro Markun\" title=\"Im Dschungel wird gewaehlt von Pedro Markun\" width=\"600\" height=\"607\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-12\" data-js=\"tribe-events-month-grid-cell\">\n<p>11 Veranstaltungen\t\t<\/p>\n<p>12\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-123.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-129.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-152.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-13\" data-js=\"tribe-events-month-grid-cell\">\n<p>9 Veranstaltungen\t\t<\/p>\n<p>13\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Kleidertausch26ZZZ.jpg\"  alt=\"Kleidertausch26ZZZ\" title=\"Kleidertausch26ZZZ\" width=\"400\" height=\"566\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/04-03-2026-2.-Zukunftswerkstatt.jpg\"  alt=\"04 03 2026 2. Zukunftswerkstatt\" title=\"04-03-2026 2. Zukunftswerkstatt\" width=\"1500\" height=\"1000\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/c_Raphael-Fischer-Dieskau-Virtual-Sun-No.-0029-Mixed-Media.jpg\"  alt=\"C Raphael Fischer Dieskau, Virtual Sun No. 0029, Mixed Media\" title=\"c_Raphael Fischer-Dieskau, Virtual Sun No. 0029, Mixed Media\" width=\"1500\" height=\"1499\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-14\" data-js=\"tribe-events-month-grid-cell\">\n<p>18 Veranstaltungen\t\t<\/p>\n<p>14\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p>\nSpeyer \u2013 \u201eTag der Druckkunst\u201c: Druckerwochenende mit Peter Zaumseil<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/pdpics-cancer-389921_640.jpg\" alt=\"Pdpics cancer 389921\" title=\"pdpics-cancer-389921_640\" width=\"640\" height=\"424\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/olgavolkovitskaia-bride-and-groom-7202465_640-1.jpg\" alt=\"Olgavolkovitskaia bride and groom 7202465\" title=\"olgavolkovitskaia-bride-and-groom-7202465_640\" width=\"640\" height=\"427\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/brave_screenshot_www.aikq_.de-40ZZZ-1.jpg\" alt=\"Brave screenshot www.aikq.de (40)ZZZ\" title=\"brave_screenshot_www.aikq.de (40)ZZZ\" width=\"579\" height=\"342\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-15\" data-js=\"tribe-events-month-grid-cell\">\n<p>12 Veranstaltungen\t\t<\/p>\n<p>15\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/vielfalt-pflanzen-tag-der-offenen-tuerZZZ.jpg\"  alt=\"Vielfalt pflanzen tag der offenen t\u00fcrZZZ\" title=\"vielfalt-pflanzen-tag-der-offenen-t\u00fcrZZZ\" width=\"1000\" height=\"667\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/melody_art-ai-generated-9413948_640-1.png\" alt=\"Melody art ai generated 9413948\" title=\"melody_art-ai-generated-9413948_640\" width=\"640\" height=\"349\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Tobias-Martin-mit-Chor_Foto_ProtDekanatLU_WagnerZZZ.jpg\"  alt=\"Tobias Martin mit Chor Foto ProtDekanatLU WagnerZZZ\" title=\"Tobias Martin mit Chor_Foto_ProtDekanatLU_WagnerZZZ\" width=\"1000\" height=\"667\"\/><\/p>\n<\/td>\n<\/tr>\n<tr class=\"tribe-events-calendar-month__week\" data-js=\"tribe-events-month-grid-row\">\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-16\" data-js=\"tribe-events-month-grid-cell\">\n<p>6 Veranstaltungen\t\t<\/p>\n<p>16\n<\/p>\n<p>\nLudwigshafen \u2013 Wilhelm-Hack-Museum: \u00d6ffentliche F\u00fchrungen im M\u00e4rz<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p>\nWeinheim \u2013 Internationale Wochen gegen Rassismus 16. bis 29. M\u00e4rz<\/p>\n<p>\nHeidelberg \u2013 Digitale Themenwoche f\u00fcr Menschen ab 50<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Es-ist-nur-eine-Phase-Hase.jpg\"  alt=\"Es ist nur eine Phase, Hase\" title=\"Es ist nur eine Phase, Hase\" width=\"976\" height=\"739\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Pfalzbau2022.jpg\"  alt=\"Pfalzbau2022\" title=\"Pfalzbau2022\" width=\"800\" height=\"472\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-17\" data-js=\"tribe-events-month-grid-cell\">\n<p>9 Veranstaltungen\t\t<\/p>\n<p>17\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-20.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"\" alt=\"\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Es-ist-nur-eine-Phase-Hase.jpg\"  alt=\"Es ist nur eine Phase, Hase\" title=\"Es ist nur eine Phase, Hase\" width=\"976\" height=\"739\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-18\" data-js=\"tribe-events-month-grid-cell\">\n<p>8 Veranstaltungen\t\t<\/p>\n<p>18\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-29.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/wir_pixs-ai-generated-8253319_640.png\" alt=\"Wir pixs ai generated 8253319\" title=\"wir_pixs-ai-generated-8253319_640\" width=\"640\" height=\"366\"\/><\/p>\n<p><img decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"\" alt=\"\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-19\" data-js=\"tribe-events-month-grid-cell\">\n<p>8 Veranstaltungen\t\t<\/p>\n<p>19\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-123.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-129.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"\" alt=\"\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-20\" data-js=\"tribe-events-month-grid-cell\">\n<p>6 Veranstaltungen\t\t<\/p>\n<p>20\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-27.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/La-Boheme.jpg\"  alt=\"La Boheme\" title=\"La Boheme\" width=\"1017\" height=\"657\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-21\" data-js=\"tribe-events-month-grid-cell\">\n<p>11 Veranstaltungen\t\t<\/p>\n<p>21\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-144.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"\" alt=\"\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Autokino.jpg\" alt=\"Autokino\" title=\"Autokino\" width=\"500\" height=\"333\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-22\" data-js=\"tribe-events-month-grid-cell\">\n<p>7 Veranstaltungen\t\t<\/p>\n<p>22\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/brave_screenshot_nextcloud.heidelberg.de-2ZZZ-1.jpg\"  alt=\"Brave screenshot nextcloud.heidelberg.de (2)ZZZ\" title=\"brave_screenshot_nextcloud.heidelberg.de (2)ZZZ\" width=\"500\" height=\"599\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/La-Boheme.jpg\"  alt=\"La Boheme\" title=\"La Boheme\" width=\"1017\" height=\"657\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/IniDill-IdEdB_Ch.Jai-Gonzales-UT2024-Foto-Guenter-Kraemmer-DSC00336.jpg\"  alt=\"IniDill IdEdB Ch.Jai Gonzales UT2024 Foto Guenter Kraemmer DSC00336\" title=\"IniDill-IdEdB_Ch.Jai Gonzales UT2024- Foto Guenter Kraemmer-DSC00336\" width=\"1500\" height=\"1000\"\/><\/p>\n<\/td>\n<\/tr>\n<tr class=\"tribe-events-calendar-month__week\" data-js=\"tribe-events-month-grid-row\">\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-23\" data-js=\"tribe-events-month-grid-cell\">\n<p>3 Veranstaltungen\t\t<\/p>\n<p>23\n<\/p>\n<p>\nLudwigshafen \u2013 Wilhelm-Hack-Museum: \u00d6ffentliche F\u00fchrungen im M\u00e4rz<\/p>\n<p>\nWeinheim \u2013 Internationale Wochen gegen Rassismus 16. bis 29. M\u00e4rz<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-24\" data-js=\"tribe-events-month-grid-cell\">\n<p>7 Veranstaltungen\t\t<\/p>\n<p>24\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/On-the-Move-\u2013-Migration-and-Cross-Cultural-Encounters.jpg\"  alt=\"On the Move \u2013 Migration and Cross Cultural Encounters\" title=\"On the Move \u2013 Migration and Cross-Cultural Encounters\" width=\"1082\" height=\"706\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Bloch-Zentrum-1.jpg\" alt=\"Bloch Zentrum\" title=\"Bloch Zentrum\" width=\"700\" height=\"467\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Vortrag-Hoffnung-1.jpg\" alt=\"Vortrag Hoffnung\" title=\"Vortrag Hoffnung\" width=\"426\" height=\"282\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-25\" data-js=\"tribe-events-month-grid-cell\">\n<p>5 Veranstaltungen\t\t<\/p>\n<p>25\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-140.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Typen.jpg\"  alt=\"Typen\" title=\"Typen\" width=\"1052\" height=\"727\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-26\" data-js=\"tribe-events-month-grid-cell\">\n<p>8 Veranstaltungen\t\t<\/p>\n<p>26\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-123.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-129.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Barbara-Friebe_Titelbild-1ZZZ-1.jpg\"  alt=\"Barbara Friebe Titelbild (1)ZZZ\" title=\"Barbara Friebe_Titelbild (1)ZZZ\" width=\"500\" height=\"751\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-27\" data-js=\"tribe-events-month-grid-cell\">\n<p>4 Veranstaltungen\t\t<\/p>\n<p>27\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Barbara-Friebe_Titelbild-1ZZZ-1.jpg\"  alt=\"Barbara Friebe Titelbild (1)ZZZ\" title=\"Barbara Friebe_Titelbild (1)ZZZ\" width=\"500\" height=\"751\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-28\" data-js=\"tribe-events-month-grid-cell\">\n<p>6 Veranstaltungen\t\t<\/p>\n<p>28\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Barbara-Friebe_Titelbild-1ZZZ-1.jpg\"  alt=\"Barbara Friebe Titelbild (1)ZZZ\" title=\"Barbara Friebe_Titelbild (1)ZZZ\" width=\"500\" height=\"751\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Momo.jpg\"  alt=\"Momo\" title=\"Momo\" width=\"1197\" height=\"730\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Robert-John-Hope.jpg\"  alt=\"Robert John Hope\" title=\"Robert John Hope\" width=\"951\" height=\"594\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-29\" data-js=\"tribe-events-month-grid-cell\">\n<p>4 Veranstaltungen\t\t<\/p>\n<p>29\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Barbara-Friebe_Titelbild-1ZZZ-1.jpg\"  alt=\"Barbara Friebe Titelbild (1)ZZZ\" title=\"Barbara Friebe_Titelbild (1)ZZZ\" width=\"500\" height=\"751\"\/><\/p>\n<\/td>\n<\/tr>\n<tr class=\"tribe-events-calendar-month__week\" data-js=\"tribe-events-month-grid-row\">\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-30\" data-js=\"tribe-events-month-grid-cell\">\n<p>3 Veranstaltungen\t\t<\/p>\n<p>30\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Barbara-Friebe_Titelbild-1ZZZ-1.jpg\"  alt=\"Barbara Friebe Titelbild (1)ZZZ\" title=\"Barbara Friebe_Titelbild (1)ZZZ\" width=\"500\" height=\"751\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day\" aria-labelledby=\"tribe-events-calendar-day-2026-03-31\" data-js=\"tribe-events-month-grid-cell\">\n<p>2 Veranstaltungen\t\t<\/p>\n<p>31\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Barbara-Friebe_Titelbild-1ZZZ-1.jpg\"  alt=\"Barbara Friebe Titelbild (1)ZZZ\" title=\"Barbara Friebe_Titelbild (1)ZZZ\" width=\"500\" height=\"751\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day tribe-events-calendar-month__day--other-month tribe-events-calendar-month__day--next-month\" aria-labelledby=\"tribe-events-calendar-day-2026-04-01\" data-js=\"tribe-events-month-grid-cell\">\n<p>2 Veranstaltungen\t\t<\/p>\n<p>1\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Barbara-Friebe_Titelbild-1ZZZ-1.jpg\"  alt=\"Barbara Friebe Titelbild (1)ZZZ\" title=\"Barbara Friebe_Titelbild (1)ZZZ\" width=\"500\" height=\"751\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day tribe-events-calendar-month__day--other-month tribe-events-calendar-month__day--next-month\" aria-labelledby=\"tribe-events-calendar-day-2026-04-02\" data-js=\"tribe-events-month-grid-cell\">\n<p>4 Veranstaltungen\t\t<\/p>\n<p>2\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-123.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/mrn_news_platzhalter_logo-5-1-129.jpg\"  alt=\"Mrn news platzhalter logo 5\" title=\"mrn_news_platzhalter_logo-5-1\" width=\"900\" height=\"500\"\/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Barbara-Friebe_Titelbild-1ZZZ-1.jpg\"  alt=\"Barbara Friebe Titelbild (1)ZZZ\" title=\"Barbara Friebe_Titelbild (1)ZZZ\" width=\"500\" height=\"751\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day tribe-events-calendar-month__day--other-month tribe-events-calendar-month__day--next-month\" aria-labelledby=\"tribe-events-calendar-day-2026-04-03\" data-js=\"tribe-events-month-grid-cell\">\n<p>2 Veranstaltungen\t\t<\/p>\n<p>3\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Barbara-Friebe_Titelbild-1ZZZ-1.jpg\"  alt=\"Barbara Friebe Titelbild (1)ZZZ\" title=\"Barbara Friebe_Titelbild (1)ZZZ\" width=\"500\" height=\"751\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day tribe-events-calendar-month__day--other-month tribe-events-calendar-month__day--next-month\" aria-labelledby=\"tribe-events-calendar-day-2026-04-04\" data-js=\"tribe-events-month-grid-cell\">\n<p>2 Veranstaltungen\t\t<\/p>\n<p>4\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Barbara-Friebe_Titelbild-1ZZZ-1.jpg\"  alt=\"Barbara Friebe Titelbild (1)ZZZ\" title=\"Barbara Friebe_Titelbild (1)ZZZ\" width=\"500\" height=\"751\"\/><\/p>\n<\/td>\n<td class=\"tribe-events-calendar-month__day tribe-events-calendar-month__day--other-month tribe-events-calendar-month__day--next-month\" aria-labelledby=\"tribe-events-calendar-day-2026-04-05\" data-js=\"tribe-events-month-grid-cell\">\n<p>2 Veranstaltungen\t\t<\/p>\n<p>5\n<\/p>\n<p>\nLandau \u2013 Aktion \u201eMut zum Buch\u201c<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"tribe-events-calendar-list__event-featured-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/Barbara-Friebe_Titelbild-1ZZZ-1.jpg\"  alt=\"Barbara Friebe Titelbild (1)ZZZ\" title=\"Barbara Friebe_Titelbild (1)ZZZ\" width=\"500\" height=\"751\"\/><\/p>\n<\/td>\n<\/tr>\n","protected":false},"excerpt":{"rendered":"0 Veranstaltungen 23 0 Veranstaltungen 24 8 Veranstaltungen 25 Landau \u2013 Aktion \u201eMut zum Buch\u201c Frankenthal \u2013 Vortrag&hellip;\n","protected":false},"author":2,"featured_media":843658,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1845],"tags":[1634,3364,29,26417,587,548,663,3934,30,13,2096,25488,25489,2264,14,14480,15,5206,28951,12,24234,3041,64611],"class_list":{"0":"post-843657","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mannheim","8":"tag-baden-wuerttemberg","9":"tag-de","10":"tag-deutschland","11":"tag-donnerstag","12":"tag-ermittlung","13":"tag-eu","14":"tag-europa","15":"tag-europe","16":"tag-germany","17":"tag-headlines","18":"tag-mannheim","19":"tag-metropolregion","20":"tag-metropolregion-rhein-neckar","21":"tag-museum","22":"tag-nachrichten","23":"tag-neckar","24":"tag-news","25":"tag-rhein","26":"tag-rhein-neckar","27":"tag-schlagzeilen","28":"tag-sitzung","29":"tag-stadt","30":"tag-stadt-mannheim"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116173580723821959","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/843657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=843657"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/843657\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/843658"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=843657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=843657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=843657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}