{"id":84647,"date":"2025-05-04T21:04:14","date_gmt":"2025-05-04T21:04:14","guid":{"rendered":"https:\/\/www.europesays.com\/de\/84647\/"},"modified":"2025-05-04T21:04:14","modified_gmt":"2025-05-04T21:04:14","slug":"kinopolis-in-hamburg-neues-megakino-trotz-kinokrise-optimistisch-ndr-de-kultur","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/84647\/","title":{"rendered":"Kinopolis in Hamburg: Neues Megakino trotz Kinokrise optimistisch | NDR.de &#8211; Kultur"},"content":{"rendered":"<p>\nStand: 04.05.2025 21:44 Uhr\n<\/p>\n<p class=\"preface\">Das Kinopolis im neuen Einkaufszentrum Westfield ist das gr\u00f6\u00dfte Kino in Hamburg mit zehn S\u00e4len und 2.200 Sitzpl\u00e4tzen. Es hofft auf zahlreiche Besucherinnen und Besucher &#8211; trotz der Kinokrise.<\/p>\n<p class=\"textauthor\">von Danny Marques Marcalo<\/p>\n<p>Das Kinopolis zeigt einen Testfilm. Man sieht einen wei\u00dfen Punkt auf der Leinwand. Um den Punkt herum ist der Rest des Bildes schwarz. &#8222;Bisher dachten Sie immer, das ist schwarz. Aber nein, das ist schwarz!&#8220;, sagt ein Sprecher. Dann wird die schwarze Fl\u00e4che noch schw\u00e4rzer und der wei\u00dfe Punkt wird noch wei\u00dfer. Danach erscheinen Farben auf der Leinwand: extrem satte Farben. Zu sehen ist das im Dolby Cinema Saal im Kinopolis. Er ist der dritte Kinosaal dieser Art in Deutschland. Moderner wird Kino derzeit nicht. Der Zugang ist ein 30 Meter langer Tunnel. Der ist kurvig, damit von au\u00dfen kein Licht eindringt. Im Saal: alles pechschwarz, f\u00fcr eine bessere Projektion.<\/p>\n<p>Hoffnung auf Besucher trotz Kinokrise<\/p>\n<p><a href=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/05\/kinopolis104_v-contentgross.jpg\" class=\"zoomimage\" title=\"Kinopolis-Gesch\u00e4ftsf\u00fchrer Gregory Theile will das Kinopublikum mit besonderer Ausstattung locken. \u00a9 NDR Screenshot\"><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/05\/kinopolis104_v-contentgross.jpg\" alt=\"Kinopolis-Gesch\u00e4ftsf\u00fchrer Gregory Theile sitzt in einem indirekt in Rott\u00f6nen beleuchteten Kinosaal. \u00a9 NDR Screenshot \" title=\"Kinopolis-Gesch\u00e4ftsf\u00fchrer Gregory Theile sitzt in einem indirekt in Rott\u00f6nen beleuchteten Kinosaal.\" class=\"responsive\"\/><\/p>\n<p><\/a><br \/>\nKinopolis-Gesch\u00e4ftsf\u00fchrer Gregory Theile will das Kinopublikum mit besonderer Ausstattung locken.<\/p>\n<p>Der Saal ist das Highlight im Kinopolis. &#8222;Ich kann nicht mehr einen Theaterklappstuhl da hinstellen&#8220;, erkl\u00e4rt Kinopolis-Gesch\u00e4ftsf\u00fchrer Gregory Theile. &#8222;Man braucht hochwertige Sitze mit einem Zusatznutzen.&#8220; Zum Beispiel den D-Box Motion Seat, der sich beim Film synchron zur Filmhandlung bewege. Er setze auch auf Lounge-Atmosph\u00e4re im Foyer, viele Sofas, viel ged\u00e4mpftes Licht, gem\u00fctliche Stimmung. Der Konzern hat viel investiert in Hamburg. Wie viel genau, das will Theile nicht sagen. Er glaube, dass 600.000 oder mehr Besucherinnen und Besucher jedes Jahr kommen werden &#8211; trotz Kinokrise.<\/p>\n<p>Ins Kino zu investieren sei seine Antwort auf die Kinokrise, erl\u00e4utert Theile: &#8222;Gerade dann zu sagen: Wir gehen nach vorne. Wir bieten den G\u00e4sten die perfekten Argumente, ins Kino zu gehen.&#8220; Abwarten n\u00fctze nichts, denn von allein werde nichts besser, so Theile.<\/p>\n<p>Gro\u00dfe Lichtspielh\u00e4user wichtig f\u00fcr die Branche<\/p>\n<p>Nun hat Hamburg ja schon eine Reihe Multiplex-Kinos. Aber die seien in schlechtem Zustand, sagt Kinobetreiber Nick Jansen. Mit seinen vier Stadtteilkinos bespielt er ein anderes Publikum. Gute Megakinos seien aber f\u00fcr die gesamte Branche wichtig und die gebe es in Hamburg derzeit nicht. &#8222;Die Atmosph\u00e4re ist halt sehr trist&#8220;, sagt Jansen &#8211; f\u00fcr ihn eine Art Parkhausgef\u00fchl. &#8222;Es gibt nun mal ein gro\u00dfes Publikum, das sich nur in solchen H\u00e4usern bewegt. Und wenn man denen das Gef\u00fchl gibt, dass Kino nur eine Ramschware ist, dann wirkt sich das nat\u00fcrlich auch auf die n\u00e4chste Generation aus.&#8220; Der Kinobetreiber meint damit H\u00e4user von UCI und Cinemaxx. Die UCI-Kette reagierte auf eine NDR Anfrage nicht. Cinemaxx schreibt: Man arbeite an der Modernisierung aller Kinos.<\/p>\n<p>Gleich um die Ecke des neuen Kinopolis ist die Astor Filmlounge der Flebbe-Familie, die bundesweit H\u00e4user betreibt, in Hamburg das Savoy auf dem Steindamm und eben das Astor. Konkurrenz? Man gibt sich diplomatisch. &#8222;Erstmal ist das doch ein gutes Zeichen, dass jemand so viel in das Kinogesch\u00e4ft investiert&#8220;, sagt Kinobetreiber Tom Flebbe. &#8222;Wir haben keine Angst vor dem Wettbewerb. Sondern freuen uns, dass das Angebot steigt und mehr Besucher in die Kinos kommen.&#8220;<\/p>\n<p>Hamburger gehen im Vergleich selten ins Kino<\/p>\n<p>Andere H\u00e4user geben in den Gespr\u00e4chen allerdings zu: Wir haben Angst, dass das Kinopolis uns diejenigen Besucherinnen und Besucher abzieht, die nur selten und als Event ins Kino gehen. \u00dcberhaupt gehen die Menschen in Hamburg im Vergleich mit anderen Gro\u00dfst\u00e4dten in Deutschland selten ins Kino, erkl\u00e4rt Theile. &#8222;Wir glauben, dass da ein gro\u00dfes ungenutztes Potenzial liegt&#8220;, hofft er.<\/p>\n<p>Die Preise bei ihm sind allerdings deftig. Gute Pl\u00e4tze in den besten S\u00e4len kosten locker 20 Euro pro Person. Es gibt aber auch g\u00fcnstigere Tickets. Ob die Investition der Macher in Zeiten der Branchenflaute aufgeht, ist unklar. Dass Hamburg aber ein beeindruckendes, ja, begeisterndes neues Kino hat, ist ein Fakt.<\/p>\n<p>Weitere Informationen<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/05\/westfield146_v-contentgross.jpg\" alt=\"Besucher str\u00f6men am ersten Wochenende nach der Er\u00f6ffnung ins Westfield Einkauszentrum. \u00a9 picture alliance\/dpa Foto: Georg Wendt\" title=\"Besucher str\u00f6men am ersten Wochenende nach der Er\u00f6ffnung ins Westfield Einkauszentrum.\" class=\"responsive\"\/><\/p>\n<p>\nBei sonnigem Fr\u00fchlingswetter kamen nach der Er\u00f6ffnung mehr als 100.000 Besucher und f\u00fcllten das riesige Zentrum.<br \/>\n<a title=\"Zum Artikel: Gro\u00dfer Andrang im neuen Westfield-Einkaufszentrum\" href=\"https:\/\/www.ndr.de\/nachrichten\/hamburg\/Grosser-Andrang-in-neuem-Westfield-Einkaufszentrum,westfield144.html\" class=\"cta \" rel=\"nofollow noopener\" target=\"_blank\">mehr<\/a>\n<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/04\/schneewittchenmusical102_v-contentgross.jpg\" alt=\"Rachel Zegler als Schneewittchen in einer neuen Realverfilmung als Musical - mit Vogel auf der Hand \u00a9  2024 Disney Enterprises, Inc. All Rights Reserved. \" title=\"Rachel Zegler als Schneewittchen in einer neuen Realverfilmung als Musical - mit Vogel auf der Hand\" class=\"responsive\"\/><\/p>\n<p>\nDas Kinojahr bietet Remakes von &#8222;Momo&#8220; und &#8222;Willow&#8220;, eine Tierfabel, ein Live-Action-Remake von &#8222;Scheewittchen&#8220; und einen Zeichentrickfilm \u00fcber den Holocaust.<br \/>\n<a title=\"Zum Artikel: Kinofilme f\u00fcr Kinder und Familien: Tipps f\u00fcrs Fr\u00fchjahr 2025\" href=\"https:\/\/www.ndr.de\/kultur\/film\/tipps\/Kinofilme-fuer-Kinder-und-Familien-Tipps-fuers-Fruehjahr-2025,kinderkinofilme100.html\" class=\"cta \" rel=\"nofollow noopener\" target=\"_blank\">mehr<\/a>\n<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/04\/kanudesmanitu100_v-contentgross.jpg\" alt=\"Zwei M\u00e4nner, verkleidet als Indigene, schauen verwundert (links Abahachi, also Bully Herbig, rechts Ranger, gespielt von Christian Tramitz) \u00a9 Herb X-Film \/ Constantin Film \/ Luis Zeno Kuhn Foto:  Luis Zeno Kuhn\" title=\"Zwei M\u00e4nner, verkleidet als Indigene, schauen verwundert (links Abahachi, also Bully Herbig, rechts Ranger, gespielt von Christian Tramitz)\" class=\"responsive\"\/><\/p>\n<p>\nDer Kinojahrgang 2025 bietet gute Filme! Mit dabei sind &#8222;Avatar 3&#8220; und &#8222;Wicked 2&#8220;, au\u00dferdem gibt&#8217;s &#8222;Das Kanu des Manitu&#8220; und &#8222;Amrum&#8220; von Fatih Akin.<br \/>\n<a title=\"Zum Artikel: Filme 2025: Das kommt dieses Jahr ins Kino\" href=\"https:\/\/www.ndr.de\/kultur\/film\/Filme-2025-Das-kommt-dieses-Jahr-ins-Kino,kinohighlights138.html\" class=\"cta \" rel=\"nofollow noopener\" target=\"_blank\">mehr<\/a>\n<\/p>\n<p>Dieses Thema im Programm:<\/p>\n<p>NDR Kultur |<br \/>\nHamburg Journal |<br \/>\n01.05.2025 | 19:30 Uhr<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/03\/ndr_printlogo.gif\" alt=\"NDR Logo\" title=\"NDR Logo\"\/><\/p>\n","protected":false},"excerpt":{"rendered":"Stand: 04.05.2025 21:44 Uhr Das Kinopolis im neuen Einkaufszentrum Westfield ist das gr\u00f6\u00dfte Kino in Hamburg mit zehn&hellip;\n","protected":false},"author":2,"featured_media":84648,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1826],"tags":[29,1903,30,692,95,35491,9005,35492,438,439,440,5284],"class_list":["post-84647","post","type-post","status-publish","format-standard","has-post-thumbnail","category-hamburg","tag-deutschland","tag-dokumentarfilm","tag-germany","tag-hamburg","tag-kino","tag-kinokrise","tag-kinopolis","tag-megakino","tag-ndr","tag-norddeutscher-rundfunk","tag-norddeutschland","tag-spielfilm"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/114451596355206476","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/84647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=84647"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/84647\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/84648"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=84647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=84647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=84647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}