{"id":850322,"date":"2026-03-07T15:27:15","date_gmt":"2026-03-07T15:27:15","guid":{"rendered":"https:\/\/www.europesays.com\/de\/850322\/"},"modified":"2026-03-07T15:27:15","modified_gmt":"2026-03-07T15:27:15","slug":"3-liga-aue-kann-talfahrt-auch-gegen-aachen-nicht-stoppen","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/850322\/","title":{"rendered":"3. Liga: Aue kann Talfahrt auch gegen Aachen nicht stoppen"},"content":{"rendered":"<p>B\u00e4rs Halten mit Gelb bestraft<\/p>\n<p class=\"text\">\nDie ersten Minuten geh\u00f6rten den G\u00e4sten, die es immer wieder mit Ecken direkt auf Keeper M\u00e4nnel probierten. Dann kamen die Veilchen, die in einem schwarzen Jubil\u00e4umstrikot antraten, im Spiel an. Mittelst\u00fcrmer B\u00e4r wurde gehalten, da h\u00e4tte er selbst zum Abschluss kommen oder in die Mitte auf den freistehenden Ocansey passen k\u00f6nnen. Aachens Abwehrmann Da Silva Kiala war mit Gelb gut bedient (11.). Den folgenden Freisto\u00df von Stefaniak hielt Schlussmann Manuel Reimann. Mit ihm und M\u00e4nnel standen gleich zwei 37-J\u00e4hrige in den Toren. Nach Simnica-Balleroberung passte B\u00e4r auf Ocandey, Reimann kam heraus und rettete (22.). Der Routinier lie\u00df sich nicht \u00fcberwinden.\n<\/p>\n<p>Doppelschlag von Torj\u00e4ger Gindorf<\/p>\n<p class=\"text\">\nDann stand es pl\u00f6tzlich 0:1. Drittliga-Top-Torj\u00e4ger Gindorf hatte den Ball durchgelassen und wurde von Loune in Szene gesetzt, Gindorf \u00fcberwand aus spitzem Winkel M\u00e4nnel (22.). F\u00fcnf Minuten sp\u00e4ter machte es der von Hannover ausgeliehene Offensivmann \u00e4hnlich: Erneut spielte ihn Loune nach einem Durchlassen an, Gindorf wuchtete die Kugel per Fernschuss ins Netz (27.). Danach musste Aue diesen Doppelschock bis zur Pause verdauen, die Anh\u00e4nger im Fanblock drehten der Mannschaft den R\u00fccken zu.\n<\/p>\n<p>Malone sorgt f\u00fcr Hoffnung<\/p>\n<p class=\"text\">\nDie Sachsen kamen mit drei Neuen aus der Kabine: Weinhauer, Clausen und G\u00fcnther-Schmidt f\u00fcr Stefaniak, Guttau und Ocansey. Der Ex-Jenaer Weinhauer kam gleich an der Grundlinie an den Ball, fand in der Mitte aber keinen Mitspieler. Eine Minute sp\u00e4ter fand er Verteidiger Malone, der aus Nahdistanz eink\u00f6pfte (47.). Nun hatten die Veilchen das Momentum f\u00fcr sich. Der Druck nahm zu. Erneut Weinhauer hatte aus elf Metern das 2:2 vor Augen, kam aber nicht an Reimann vorbei (62.). Das Dabrowski-Team blieb dran, konnte sich im Strafraum aber nicht mehr so oft durchsetzen.\n<\/p>\n<p>Co-Produktion von Dresdner und Magdeburger<\/p>\n<p class=\"text\">\nAachen \u00fcberstand eine 25-min\u00fctige Druckphase der Gastgeber und trat dann selbst wieder offensiv in Erscheinung. Gindorf scheiterte von rechts noch an M\u00e4nnel (72.). F\u00fcnf Minuten sp\u00e4ter setzten sich die Domst\u00e4dter links durch, der vom 1. FC Magdeburg ausgeliehene Nadjombe vollendete in der Mitte. Der von Dynamo Dresden ausgeliehene Jonas Oehmichen hatte zum 1:3 beigetragen. Danach war die Partie entschieden. Aue konnte sich nicht mehr zur n\u00e4chsten Aufholjagd aufraffen.<\/p>\n","protected":false},"excerpt":{"rendered":"B\u00e4rs Halten mit Gelb bestraft Die ersten Minuten geh\u00f6rten den G\u00e4sten, die es immer wieder mit Ecken direkt&hellip;\n","protected":false},"author":2,"featured_media":850323,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1853],"tags":[45933,995,1424,999,3364,29,548,663,3934,15427,347,30,13,81,14,15,1209,12,3499,265,3498],"class_list":{"0":"post-850322","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-aachen","8":"tag-28-spieltag","9":"tag-3-liga","10":"tag-aachen","11":"tag-alemannia-aachen","12":"tag-de","13":"tag-deutschland","14":"tag-eu","15":"tag-europa","16":"tag-europe","17":"tag-fc-erzgebirge-aue","18":"tag-fussball","19":"tag-germany","20":"tag-headlines","21":"tag-mdr","22":"tag-nachrichten","23":"tag-news","24":"tag-nordrhein-westfalen","25":"tag-schlagzeilen","26":"tag-spio","27":"tag-sport","28":"tag-sport-im-osten"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116188600567119362","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/850322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=850322"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/850322\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/850323"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=850322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=850322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=850322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}