{"id":862033,"date":"2026-03-12T05:58:18","date_gmt":"2026-03-12T05:58:18","guid":{"rendered":"https:\/\/www.europesays.com\/de\/862033\/"},"modified":"2026-03-12T05:58:18","modified_gmt":"2026-03-12T05:58:18","slug":"friedrichsbau-variete-queen-leiht-den-titel-fuers-zauberertreffen-krz-plus","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/862033\/","title":{"rendered":"Friedrichsbau-Variet\u00e9: Queen leiht den Titel f\u00fcrs Zauberertreffen &#8211; KRZ Plus"},"content":{"rendered":"<p>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t \t\t\t\t   \t      \t\t\t\t   <img decoding=\"async\" id=\"article-image\" fetchpriority=\"high\" alt=\"Friedrichsbau-Variet\u00e9: Queen leiht den Titel f\u00fcrs Zauberertreffen\" title=\"Friedrichsbau-Variet\u00e9: Queen leiht den Titel f\u00fcrs Zauberertreffen\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/media.media.42565921-f7e7-4dbc-8bc2-d1716a804c14.original700.jpg\" data-linkto=\"https:\/\/www.krzbb.de\/javascript:void(0);\"\/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tEr ist verflucht: Winston Fuenmayor kriegt die Karten nicht los\u00a0Foto: Friedrichsbau\/Alex Klein\t\t\t<\/p>\n<p>Im Friedrichsbau wird wieder gezaubert. Ein Ensemble voller Magiere l\u00e4sst das Publikum staunen und r\u00e4tseln: Sind das wirklich Tricks?<\/p>\n<p>Es muss ein Trick sein. Nat\u00fcrlich. Aber wie macht er das? Winston Fuenmayor holt Spielkarten \u00fcberall hervor. Wirklich \u00fcberall. Sie kleben an seinen Fingern, purzeln aus seinem Mund; wenn er sich die Haut reibt, dr\u00e4ngen sie heraus, zu Dutzenden. Verzweifelt will er sie loswerden, aber es werden immer mehr. Das muss Magie sein. <\/p>\n<p>Oder doch nur ein Trick? Zu gerne h\u00e4tte man ja, dass es tats\u00e4chlich keine Illusion ist, nicht nur Fingerfertigkeit und Ablenkung, keine ausgekl\u00fcgelte Mechanik, sondern tats\u00e4chlich Zauberei. Sind wir nicht mit Harry Potter durch B\u00fccher und Filme gereist, haben getr\u00e4umt auch wir k\u00f6nnten mit einem Schwenk des Zauberstabs und einem Spruch Unm\u00f6gliches vollbringen. Uralt ist diese Sehnsucht, und uralt ist die Kunst. die Fuenmayor und seine Kollegen auf die B\u00fchne des Friedrichsbaus bringen. <\/p>\n<p>\u201eA Kind of Magic\u201c, hei\u00dft das neue Programm. Nach dem Lied von Queen. Teil des Soundtracks des Films \u201eHighlander\u201c. Und der Titel ist ein Zitat aus dem Film. Als der t\u00f6dlich verletzte Connor McLeod wieder aufsteht, sagt er einem staunenden Jungen: \u201eIt\u2019s a Kind of Magic\u201c. Magisch halt. Zeugen einer Auferstehung werden wir erst wieder an Ostern, so weit gehen sie im <a href=\"https:\/\/www.krzbb.de\/thema\/Friedrichsbau_Variet%C3%A9\" title=\"Friedrichsbau\" class=\"art_thema\" rel=\"nofollow noopener\" target=\"_blank\">Friedrichsbau<\/a> nicht. Aber es gibt doch so allerhand Staunenswertes und Unerkl\u00e4rliches.<\/p>\n<p>  <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/media.media.22a44a0f-bdf6-409b-b76f-7bda2c3c6877.original1024.media.jpeg\"\/>     Immer elegant: Hannu Juntunen    Foto: Friedrichsbau\/Klein    <\/p>\n<p>So hebt etwa die Lokalmoderatorin Janaa Felicitas die Schwerkraft auf. Man will hier ihren Tanzpartner nicht verraten, der \u00dcberraschung wegen. Es ist eine Nummer, an der sie lange gearbeitet hat. Sie t\u00fcftelten zwei Jahre an der Nummer und trat 2018 schlie\u00dflich in der Rosenau auf, um zu sehen: \u201eKann das \u00fcberhaupt funktionieren?\u201c Es funktionierte. In Frankreich begeisterte sie die Juroren bei \u201eFrance got Talent\u201c, der dortigen Version der RTL-Show \u201eDas Supertalent\u201c, und sie wurde 2022 Deutsche Meisterin. <\/p>\n<p>Der Ritterschlag aus Amerika <\/p>\n<p>Und es gab den Ritterschlag. Sie wurde nach Las Vegas in die TV-Show \u201ePenn and Teller: Fool Us\u201c eingeladen. Penn Jillette und sein Partner Teller sind dort gro\u00dfe Nummern, sie lassen sich Tricks vorf\u00fchren und wollen sich \u00fcberraschen lassen. Wie das mit dem Stuhl funktioniert, haben die Herren begriffen, schlie\u00dflich ist Teller ein Meister des Bewegens von Objekten. Doch Penn Jillette war voll des Lobes: \u201eDas ist so gut, so frisch.\u201c Jaana Felicitas zeige, dass es nicht mehr immer der gleiche alte verstaubte Kram sein m\u00fcsse. Deshalb durfte sie wiederkommen mit einer anderen Nummer. Da l\u00e4sst sie aus ihren H\u00e4nden Eiszapfen wachsen, sie schmelzen oder verdampfen. Wieder gab es viel Lob. <\/p>\n<p>  <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/media.media.8aa257f7-38a4-48f5-a663-15219ed25c7c.original1024.media.jpeg\"\/>     Jaana Felicitas zaubert mit Eis    Foto: Friedrichsbau\/Alex Klein    <\/p>\n<p>Nun darf man das mal wieder in der Heimat sehen. Einen weiteren Weg hatte Hannu Juntunen. Er kommt aus Finnland nach <a href=\"https:\/\/www.krzbb.de\/thema\/Stuttgart\" title=\"Stuttgart\" class=\"art_thema\" rel=\"nofollow noopener\" target=\"_blank\">Stuttgart<\/a>. Elegant kommt er daher, ein Magier der alten Schule, der genau so gut Tango tanzen k\u00f6nnte wie er mit Zeitungen zaubert. Andrea O\u2019Ryon und Lady V lieben dagegen die gro\u00dfe Geste, die gro\u00dfen Illusionen.<\/p>\n<p>Das alles zusammenzubinden ist die Aufgabe von Luke Dimon. Er zaubert, macht Comedy und die Ansagen. Und war gl\u00fccklicherweise noch rechtzeitig in Stuttgart, um proben zu k\u00f6nnen mit dem Ensemble. <a href=\"https:\/\/www.stuttgarter-zeitung.de\/inhalt.friedrichsbau-variet-was-fuer-eine-odyssee-vom-schiff-in-dubai-auf-die-buehne-nach-stuttgart.ae35a5af-9b5f-41c7-b421-1b38cf04ae5a.html\" target=\"_blank\" rel=\"nofollow noopener\">Denn er sa\u00df auf einem Kreuzfahrtschiff in Dubai fest.<\/a> Dort hatte er ein Engagement. Durch den Krieg gegen den Iran kam er nicht rechtzeitig zum Probenbeginn weg. Mit einer Woche Versp\u00e4tung schaffte er es noch dank einiger Umwege und einer 36 Stunden langen Reise. Nun wird halt l\u00e4nger geprobt, damit am Freitag alles so scheint, als k\u00f6nnten alle wirklich zaubern. <\/p>\n<p>   <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/media.media.5a5cc48f-298e-4df8-bd43-70ebfecb64f2.original1024.media.jpeg\"\/>     Das Ensemble    Foto: Friedrichsbau\/Klein    <\/p>\n<p>Wobei: Ganz andere Zauberkunst zeigt das Duo Rose, Samuel und Sylvia. Wie sie ihre K\u00f6rper biegen und verwinden, sich in der Luft bewegen, als habe diese tats\u00e4chlich Balken, das ist wirklich magisch. Ganz ohne Tricks. <\/p>\n","protected":false},"excerpt":{"rendered":"Er ist verflucht: Winston Fuenmayor kriegt die Karten nicht los\u00a0Foto: Friedrichsbau\/Alex Klein Im Friedrichsbau wird wieder gezaubert. Ein&hellip;\n","protected":false},"author":2,"featured_media":862034,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[1830],"tags":[18808,1634,3364,29,26630,30,12221,1441,21747],"class_list":["post-862033","post","type-post","status-publish","format-standard","has-post-thumbnail","category-stuttgart","tag-zauberer","tag-baden-wuerttemberg","tag-de","tag-deutschland","tag-friedrichsbau-variete","tag-germany","tag-magie","tag-stuttgart","tag-variete"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116214675019646955","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/862033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=862033"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/862033\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/862034"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=862033"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=862033"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=862033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}