{"id":863150,"date":"2026-03-12T16:29:15","date_gmt":"2026-03-12T16:29:15","guid":{"rendered":"https:\/\/www.europesays.com\/de\/863150\/"},"modified":"2026-03-12T16:29:15","modified_gmt":"2026-03-12T16:29:15","slug":"druschba-pipeline-victor-orban-und-der-beschlagnahmte-geldtransporter","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/863150\/","title":{"rendered":"Druschba-Pipeline: Victor Orb\u00e1n und der beschlagnahmte Geldtransporter"},"content":{"rendered":"<p class=\"paragraph article__item\">Ungarn und die <a class=\"rtr-entity\" href=\"https:\/\/www.zeit.de\/politik\/ausland\/ukraine-krieg-news-liveblog\" rel=\"nofollow noopener\" target=\"_blank\">Ukraine<\/a> <a href=\"https:\/\/www.zeit.de\/politik\/ausland\/2026-03\/eu-kommission-streit-ungarn-ukraine-drohung\" target=\"_blank\" rel=\"nofollow noopener\">sind immer mehr im Konflikt<\/a>. Hintergrund ist das enge Verh\u00e4ltnis des <a href=\"https:\/\/www.zeit.de\/2025\/54\/missbrauchsskandal-ungarn-viktor-orban-kinderheime-proteste-fidesz\" target=\"_blank\" rel=\"nofollow noopener\">ungarischen Ministerpr\u00e4sidenten Viktor Orb\u00e1n<\/a> zum russischen Machthaber Wladimir Putin. Seit Beginn des russischen Kriegs in der Ukraine hat Viktor Orb\u00e1n wiederholt EU-Sanktionen gegen Russland und <a href=\"https:\/\/www.zeit.de\/politik\/ausland\/2026-01\/ungarn-viktor-orban-ukraine-hilfen-petition-wahl-gxe\" target=\"_blank\" rel=\"nofollow noopener\">Hilfen f\u00fcr die Ukraine<\/a>\u00a0blockiert. Zuletzt spitzte sich der Konflikt um einen ukrainischen Geldtransporter aus \u00d6sterreich zu, beladen mit mehreren Millionen Euro und Gold, den die ungarischen Beh\u00f6rden beschlagnahmten und bislang zur\u00fcckhalten. Hinzu kommt die <a href=\"https:\/\/www.zeit.de\/politik\/ausland\/2025-08\/ukraine-russland-angriff-druschba-oel-pipeline\" target=\"_blank\" rel=\"nofollow noopener\">Druschba-\u00d6lpipeline<\/a>, \u00fcber die russisches \u00d6l \u00fcber die Ukraine nach Ungarn gelangt. Die Ukraine meldet Sch\u00e4den durch russische Angriffe, Ungarn vermutet hingegen politische Verz\u00f6gerungen. Die Pipeline ist entscheidend f\u00fcr die ungarische Energieversorgung. Ob die <a href=\"https:\/\/www.zeit.de\/politik\/ausland\/2026-03\/wahl-ungarn-russland-wahlkampf-einmischung-desinformation-5vor8\" target=\"_blank\" rel=\"nofollow noopener\">Parlamentswahl in Ungarn<\/a> in einem Monat eine Rolle in diesem Konflikt spielt, ordnet <a href=\"https:\/\/www.zeit.de\/autoren\/L\/Ulrich_Ladurner\/index.xml\" target=\"_blank\" rel=\"nofollow noopener\">Ulrich Ladurner<\/a>, Auslandskorrespondent der ZEIT, ein.\n<\/p>\n<p class=\"paragraph article__item\">Der neue oberste F\u00fchrer des Iran, <a href=\"https:\/\/www.zeit.de\/politik\/2026-03\/modschtaba-chamenei-iran-oberster-fuehrer-verletzung-gxe\" target=\"_blank\" rel=\"nofollow noopener\">Modschtaba Chamenei<\/a>, hat sich erstmals seit seiner Ernennung \u00f6ffentlich ge\u00e4u\u00dfert. In einer im Staatsfernsehen verlesenen Stellungnahme forderte er Rache f\u00fcr die Opfer des Kriegs, insbesondere f\u00fcr die Sch\u00fclerinnen, die mutma\u00dflich durch einen US-Luftangriff get\u00f6tet worden sind. Zudem sprach er sich daf\u00fcr aus, die strategisch wichtige <a href=\"https:\/\/www.zeit.de\/politik\/2026-03\/iran-krieg-modschtaba-chamenei-botschaft\" target=\"_blank\" rel=\"nofollow noopener\">Stra\u00dfe von Hormus geschlossen zu halten<\/a>, um sie als Druckmittel gegen die USA und Israel einzusetzen.\n<\/p>\n<p class=\"paragraph article__item\"><strong>Au\u00dferdem im Podcast:<\/strong>\n<\/p>\n<ul class=\"list article__item\">\n<li>Die Benzin- und Dieselpreise bleiben mit zwei Euro pro Liter hoch. Die<br \/>\nBundesregierung k\u00fcndigte Ma\u00dfnahmen gegen einen weiteren Anstieg an. Unter anderem d\u00fcrfen Tankstellen k\u00fcnftig Preise nur noch einmal t\u00e4glich erh\u00f6hen.<\/li>\n<li>Seit <a href=\"https:\/\/www.zeit.de\/politik\/ausland\/2026-03\/iran-ueberblick-drohnen-teheran-hisbollah-angriffe\" target=\"_blank\" rel=\"nofollow noopener\">Beginn des Irankriegs<\/a> sind nach Angaben des UN-Fl\u00fcchtlingshilfswerks UNHCR mehr als <a href=\"https:\/\/www.zeit.de\/politik\/ausland\/2026-03\/iran-krieg-usa-israel-liveblog\" target=\"_blank\" rel=\"nofollow noopener\">drei Millionen Menschen<\/a> auf der Flucht. <\/li>\n<\/ul>\n<p class=\"paragraph article__item\">Und sonst so? <a href=\"https:\/\/www.spiegel.de\/ausland\/donald-trump-und-jeffrey-epstein-in-titanic-pose-kollektiv-enthuellt-skulptur-in-washington-a-bf8cdbb3-ef79-440a-a1fe-25c57c3f5097\" target=\"_blank\" rel=\"nofollow noopener\">Skulptur zeigt Trump und Epstein in Titanic-Pose<\/a>\n<\/p>\n<p class=\"paragraph article__item\">Moderation und Produktion: <a href=\"https:\/\/www.zeit.de\/autoren\/F\/Moses_Fendel\/index\" target=\"_blank\" rel=\"nofollow noopener\">Moses Fendel<\/a>\n<\/p>\n<p class=\"paragraph article__item\">Redaktion: <a href=\"https:\/\/www.zeit.de\/autoren\/P\/Ole_Pflueger\/index\" target=\"_blank\" rel=\"nofollow noopener\">Ole Pfl\u00fcger<\/a>\n<\/p>\n<p class=\"paragraph article__item\">Mitarbeit: <a href=\"https:\/\/www.zeit.de\/autoren\/R\/Celine-Yasemin_Rolle\/index\" target=\"_blank\" rel=\"nofollow noopener\">Celine Yasemin Rolle<\/a>\n<\/p>\n<p class=\"paragraph article__item\">Alle Folgen unseres Podcasts finden Sie <a href=\"https:\/\/www.zeit.de\/was-jetzt\" target=\"_blank\" rel=\"nofollow noopener\">hier<\/a>. Fragen, Kritik, Anregungen? Sie erreichen uns unter <a href=\"https:\/\/www.zeit.de\/politik\/2026-03\/mailto:wasjetzt@zeit.de\" target=\"_blank\" rel=\"nofollow noopener\">wasjetzt@zeit.de<\/a>.\n<\/p>\n<p class=\"paragraph article__item\">Wenn Sie immer auf dem Laufenden bleiben wollen, abonnieren Sie <a href=\"https:\/\/www.whatsapp.com\/channel\/0029VaBT8La9mrGZuNla6q0Z\" target=\"_blank\" rel=\"nofollow noopener\">hier<\/a> die ZEIT auf WhatsApp.<\/p>\n","protected":false},"excerpt":{"rendered":"Ungarn und die Ukraine sind immer mehr im Konflikt. Hintergrund ist das enge Verh\u00e4ltnis des ungarischen Ministerpr\u00e4sidenten Viktor&hellip;\n","protected":false},"author":2,"featured_media":863151,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4012],"tags":[331,332,107801,13,1435,14,15,26734,16,307,12,317,501,500,306],"class_list":{"0":"post-863150","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ukraine","8":"tag-aktuelle-nachrichten","9":"tag-aktuelle-news","10":"tag-druschba-pipeline","11":"tag-headlines","12":"tag-krieg-in-der-ukraine","13":"tag-nachrichten","14":"tag-news","15":"tag-pipeline","16":"tag-politik","17":"tag-russland","18":"tag-schlagzeilen","19":"tag-ukraine","20":"tag-ungarn","21":"tag-viktor-orban","22":"tag-wladimir-putin"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116217155786888369","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/863150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=863150"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/863150\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/863151"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=863150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=863150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=863150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}