{"id":868890,"date":"2026-03-14T21:38:19","date_gmt":"2026-03-14T21:38:19","guid":{"rendered":"https:\/\/www.europesays.com\/de\/868890\/"},"modified":"2026-03-14T21:38:19","modified_gmt":"2026-03-14T21:38:19","slug":"liveticker-statistik-rot-weiss-essen-fc-erzgebirge-aue-42-2","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/868890\/","title":{"rendered":"Liveticker &#038; Statistik: Rot-Weiss Essen &#8211; FC Erzgebirge Aue 4:2"},"content":{"rendered":"<p><a name=\"stats\" id=\"stats\"><\/a><\/p>\n<p>Statistik<\/p>\n<p>Tore<\/p>\n<p>1:0 M\u00fcsel (28.), 2:0 Hofmann (32.), 3:0 <br \/>Janssen (37.), 3:1 Ehlers (45.+2), 3:2 <br \/>B\u00e4r (61.), 4:2 Mizuta (82.)<\/p>\n<p>Rot-Weiss Essen<\/p>\n<p>Golz &#8211; Hofmann, Rios Alonso, Schultz, Bouebari &#8211; Safi (68. Obuz), Reisig, Mizuta   (90.+1 Swajkowski), M\u00fcsel,   Brumme (68. Abiama) &#8211; Janssen (84. Cuber Potocnik)<\/p>\n<p>FC Erzgebirge Aue<\/p>\n<p>M\u00e4nnel &#8211; Fallmann, Malone, Zobel, Collins,   Ehlers &#8211; Clausen (46. Uhlmann), Simnica,   G\u00fcnther-Schmidt (75. Guttau) &#8211; B\u00e4r, Weinhauer (46. Stefaniak)<\/p>\n<p>Zuschauer<\/p>\n<p>16.537<\/p>\n<p>Gelb<\/p>\n<p>Collins, Bouebari, M\u00fcsel, Fallmann<\/p>\n<p>Zusammenfassung<\/p>\n<p>Erzgebirge Aue taumelt weiter dem   erstmaligen Abstieg aus der dritten   Fu\u00dfball-Liga entgegen. Beim   Aufstiegskandidaten RW Essen   kassierten die Sch\u00fctzlinge von   Trainer Christoph Dabrowski eine 2:4   (1:3)-Niederlage. Neun Spieltage vor   dem Saisonende weist Aue neun Punkte   R\u00fcckstand auf den ersten   Nichtabstiegsplatz auf. Bei der   R\u00fcckkehr von Dabrowski an seine   vorherige Station gerieten die   Sachsen nach einem guten Beginn   durch drei Treffer von der 28. bis   zur 37. Minute auf die   Verliererstra\u00dfe. M\u00fcsel per Hacke   (28.) und Hofmann mit Fernschuss in   den Winkel (33.) erzielten Traumtore.   Torj\u00e4ger Janssen erh\u00f6hte (37.). F\u00fcr   Hoffnung sorgte Ehlers mit   abgef\u00e4lschtem Abschluss (45.+2). Nach   dem Wechsel dr\u00e4ngte Aue. B\u00e4r k\u00f6pfte   den Anschluss (61.). G\u00fcnther-Schmidt   scheiterte an Golz und dem Pfosten   (74.). Mizuta entschied die Partie   dann nach einem Konter (82.).<\/p>\n<p>Tabelle<\/p>\n<p>Da hat Aue nun neun Punkte R\u00fcckstand   zum rettenden Ufer. N\u00e4chste Woche geht   es nach Mannheim.<\/p>\n<p>Abpfiff<\/p>\n<p>Ende in Essen: Aue verliert beim   Aufstiegsanw\u00e4rter 2:4. Nach dem 0:3   startete der FCE eine Aufholjagd.   Auch im siebten Spiel kein Sieg unter   Trainer Dabrowski, bei dessen   R\u00fcckkehr.<\/p>\n<p>90.+5<\/p>\n<p>Noch ein Freisto\u00df f\u00fcr die Gastgeber von   rechts. Der bringt nichts ein.<\/p>\n<p>90.+3<\/p>\n<p>Zobel erwischt M\u00e4nnel fast auf dem   falschen Fu\u00df. Es geht gut aus.<\/p>\n<p>90.+1 Wechsel RW Essen<\/p>\n<p>Swajkowski f\u00fcr Mizuta.<\/p>\n<p>90&#8242; Nachspielzeit<\/p>\n<p>Vier Minuten.<\/p>\n<p>90&#8242; Chance Aue<\/p>\n<p>Nach Kopfballverl\u00e4ngerung knallt B\u00e4r am   zweiten Pfosten dr\u00fcber.   Riesengelegenheit. Da war er auch unter   Bedr\u00e4ngnis.<\/p>\n<p>89&#8242; Torsch\u00fcsse<\/p>\n<p>9:13 aus Sicht von Aue.<\/p>\n<p>88&#8242;<\/p>\n<p>Potocnik kommt nach einer Flanke zu   sp\u00e4t. Wegen dessen Transfer nach K\u00f6ln   bekam der 1. FC einmal eine   Transfersperre aufgebrummt.<\/p>\n<p>88&#8242;<\/p>\n<p>Essen wehrt Aues Ecke ab.<\/p>\n<p>86&#8242;<\/p>\n<p>Aue l\u00e4uft wieder an.<\/p>\n<p>84&#8242; Wechsel RW Essen<\/p>\n<p>Cuber Potocnik f\u00fcr Janssen.<\/p>\n<p>83&#8242;<\/p>\n<p>In die Auer Drangphase. Das ist bitter   f\u00fcr die Veilchen.<\/p>\n<p>83&#8242; 4:2<\/p>\n<p>Joker Abiama hat rechts Platz, er   findet in der Mitte Mizuta, der von der   Strafraumgrenze M\u00e4nnel \u00fcberwindet.<\/p>\n<p>82&#8242; Tor RW Essen!<\/p>\n<p>Mizuta mit dem 4:2.<\/p>\n<p>81&#8242;<\/p>\n<p>Auch bei Favorit 1860 M\u00fcnchen dr\u00e4ngten   die Auer vor kurzem auf den Ausgleich.   Im Nebelspiel.<\/p>\n<p>76&#8242;<\/p>\n<p>Saarbr\u00fccken hat gegen Regensburg   ausgeglichen. 1:1. Aktuell damit neun   Punkte R\u00fcckstand f\u00fcr Aue.<\/p>\n<p>75&#8242; Wechsel Erzgeb. Aue<\/p>\n<p>Guttau f\u00fcr G\u00fcnther-Schmidt.<\/p>\n<p>75&#8242; Gelbe Karte Erzgeb. Aue<\/p>\n<p>Gelb f\u00fcr Fallmann.<\/p>\n<p>75&#8242; Gelbe Karte RW Essen<\/p>\n<p>Gelb f\u00fcr M\u00fcsel.<\/p>\n<p>74&#8242;<\/p>\n<p>Zwei Kopfballverl\u00e4ngerungen brachten   G\u00fcnther-Schmidt in Position: Im   Nachschuss traf er den linken Pfosten.   Zun\u00e4chst hatte Golz gerettet.<\/p>\n<p>73&#8242; Fast das 3:3<\/p>\n<p>G\u00fcnther-Schmidt k\u00f6pft aus Nahdistanz,   der Keeper ist dran, der Ball landet am   linken Pfosten!<\/p>\n<p>73&#8242; Gelbe Karte RW Essen<\/p>\n<p>F\u00fcr Bouebari nach einer Harakiri-  Gr\u00e4tsche gegen Simnica. Da ist er gut   mit Gelb bedient.<\/p>\n<p>71&#8242;<\/p>\n<p>Golz packt bei einer Uhlmann-Flanke von   links zu.<\/p>\n<p>70&#8242; Chance RWE<\/p>\n<p>Mizuta probiert es &#8211; zu zentral, M\u00e4nnel   h\u00e4lt.<\/p>\n<p>68&#8242; Wechsel RW Essen<\/p>\n<p>Abiama f\u00fcr Brumme.<\/p>\n<p>68&#8242; Wechsel RW Essen<\/p>\n<p>Obuz f\u00fcr Safi.<\/p>\n<p>67&#8242;<\/p>\n<p>Nach Collins-Flanke rettet ein Essener   vor Ehlers.<\/p>\n<p>64&#8242;<\/p>\n<p>Fallmann kl\u00e4rt am kurzen Pfosten nach   Schultz-Kopfball nach der Ecke.<\/p>\n<p>63&#8242;<\/p>\n<p>Fallmann gr\u00e4tscht Safi ab. Nach einem   Essener Konter.<\/p>\n<p>61&#8242; 3:2<\/p>\n<p>Nach einem weiten Einwurf von Malone   von links und zwei Verl\u00e4ngerungen nickt   B\u00e4r am zweiten Pfosten ein. Das geht   auch absolut in Ordnung.<\/p>\n<p>61&#8242; Tor Erzgeb. Aue!<\/p>\n<p>B\u00e4r k\u00f6pft das 2:3.<\/p>\n<p>60&#8242;<\/p>\n<p>Kleines Powerplay der Veilchen. Vor   allem \u00fcber links gerade.<\/p>\n<p>59&#8242; Gelbe Karte Erzgeb. Aue<\/p>\n<p>Gelb f\u00fcr Collins wegen Meckerns.<\/p>\n<p>58&#8242;<\/p>\n<p>Die Gastgeber bislang eher passiv nach   der Pause.<\/p>\n<p>58&#8242; Dr\u00fcber<\/p>\n<p>Collins knallt aus 18 Metern dr\u00fcber.   Aue versucht es.<\/p>\n<p>55&#8242;<\/p>\n<p>Ein Essener ist knapp vor Stefaniak am   Ball, der da am 2. Pfosten parat stand<\/p>\n<p>55&#8242;<\/p>\n<p>Aue spielt sich nach vorne, B\u00e4r wird   dann abgepfiffen, der Ball war wohl im   Aus.<\/p>\n<p>54&#8242;<\/p>\n<p>Fallmann gr\u00e4tscht gegen Mizuta, der   danach den Auer trifft. Freisto\u00df in der   FCE-H\u00e4lfte.<\/p>\n<p>51&#8242;<\/p>\n<p>Zobel foult Mizuta am Mittelkreis.<\/p>\n<p>49&#8242;<\/p>\n<p>Collins mit einer Flanke fast von der   Eckfahne, die ger\u00e4t zu weit. Viel FCE-  Ballbesitz nach der Pause.<\/p>\n<p>47&#8242;<\/p>\n<p>Zwei der vier Neuen sind also wieder   drau\u00dfen.<\/p>\n<p>46&#8242; Wechsel Erzgeb. Aue<\/p>\n<p>Stefaniak f\u00fcr Weinhauer, Uhlmann f\u00fcr   Clausen.<\/p>\n<p>46&#8242; 2. H\u00e4lfte<\/p>\n<p>Es geht weiter.<\/p>\n<p>\u00dcber das 1:3 ist Essen sauer. Koschinat    und der Sportchef Steegmann.<\/p>\n<p>Halbzeit<\/p>\n<p>Pause. Aue liegt bei der Dabrowski-  R\u00fcckkehr mit 1:3 hinten. Lange   passierte nicht so viel. Dann traf   Essen mit 2 Traumtoren. Aue bleibt   mit dem 1:3 zumindest halbwegs im   Spiel.<\/p>\n<p>45.+2 3:1<\/p>\n<p>Ehlers trifft abgef\u00e4lscht von halblinks   nach G\u00fcnther-Schmidt-Vorlage. Da   spielte sich Aue gut nach vorne,   zun\u00e4chst \u00fcber rechts.<\/p>\n<p>45.+2 Tor Erzgeb. Aue!<\/p>\n<p>Ehlers erfolgreich. 1:3.<\/p>\n<p>45&#8242; Nachspielzeit<\/p>\n<p>Zwei Minuten.<\/p>\n<p>45&#8242; Torsch\u00fcsse<\/p>\n<p>Da hei\u00dft es 3:9 aus Auer Sicht. Bei den   Zweik\u00e4mpfen liegt man vorne.<\/p>\n<p>44&#8242;<\/p>\n<p>Jetzt haben sich die Veilchen   zur\u00fcckgezogen.<\/p>\n<p>43&#8242;<\/p>\n<p>Kommen die Auer hier noch einmal   zur\u00fcck?<\/p>\n<p>40&#8242;<\/p>\n<p>Der Mittelst\u00fcrmer ist der beste Sch\u00fctze   2026 der 3. Liga. In diesem Spiel war   er sehr unauff\u00e4llig unterwegs.<\/p>\n<p>38&#8242; 3:0<\/p>\n<p>Janssen setzt sich gegen einen Auer   durch und trifft aus 19 Metern.<\/p>\n<p>37&#8242; Tor RW Essen!<\/p>\n<p>Janssen erh\u00f6ht.<\/p>\n<p>37&#8242;<\/p>\n<p>Malone kl\u00e4rt vor Mizuta in der Mitte.<\/p>\n<p>35&#8242; Chance Aue<\/p>\n<p>Golz holt einen B\u00e4r-Kopfball aus dem   Eck. Da fehlte ein wenig Power.<\/p>\n<p>35&#8242;<\/p>\n<p>Saarbr\u00fccken liegt auch hinten. Die   Chance auf die Aufholjagd w\u00e4re also da.   Es sind weiter acht Punkte R\u00fcckstand   aktuell.<\/p>\n<p>34&#8242;<\/p>\n<p>Zwei heftige Nackenschl\u00e4ge f\u00fcr Aue. Die   sich kaum andeuteten.<\/p>\n<p>33&#8242; 2:0<\/p>\n<p>Traumtor von Essen. Hofmann zimmert die   Kugel aus 28 Metern in den linken   Winkel &#8211; keine Chance f\u00fcr M\u00e4nnel.<\/p>\n<p>32&#8242; Tor RW Essen!<\/p>\n<p>Hofmann legt nach.<\/p>\n<p>31&#8242;<\/p>\n<p>M\u00fcsel kam zuletzt auch mal von der   Bank in Essen. Er sollte mal in   Gladbach Lars Stindl beerben, das war   aber ein paar Nummern zu gro\u00df. Damals   kam er aus Kaiserslautern. Nun ist er   Sechser, hier sah man seine   Abschlussqualit\u00e4ten als ehemaliger   Offensivmann.<\/p>\n<p>29&#8242; 1:0<\/p>\n<p>Den Freisto\u00df kann Aue zun\u00e4chst   verteidigen, im zweiten Versuch   landet der Ball bei M\u00fcsel, der mit   der Hacke am F\u00fcnfer trifft. Das war   auch seine einzige Variante.<\/p>\n<p>28&#8242; Tor RW Essen!<\/p>\n<p>M\u00fcsel trifft.<\/p>\n<p>27&#8242;<\/p>\n<p>Nach zwei Fouls rechts hinten gibt es   Freisto\u00df f\u00fcr Essen.<\/p>\n<p>26&#8242;<\/p>\n<p>Essen gewann zuletzt 2x, nach zuvor 2   Niederlagen. Aue mit vier Niederlagen   in Serie. Das erste Saisonduell endete   2:2. Im Vorjahr hie\u00df es in Essen 2:4.<\/p>\n<p>24&#8242;<\/p>\n<p>Wieder Essen: Hofmann von der   Grundlinie, M\u00e4nnel hat keine M\u00fche.<\/p>\n<p>23&#8242;<\/p>\n<p>Die Ecke bef\u00f6rdert Reisig rechts neben   den Kasten.<\/p>\n<p>22&#8242; Chance RWE<\/p>\n<p>Die Gastgeber mit einem Volley-  Abschluss von M\u00fcsel, nach Safi-Vorlage   &#8211; abgef\u00e4lscht zur Ecke<\/p>\n<p>20&#8242;<\/p>\n<p>Aue mit einer Flanke, die Bouebari   kl\u00e4rt.<\/p>\n<p>19&#8242;<\/p>\n<p>G\u00fcnther-Schmidt kommt links am ersten,   aber nicht am zweiten vorbei.<\/p>\n<p>18&#8242;<\/p>\n<p>Nach einer Flanke von links war Zobel   am Ball, mit der Hand. Das sah man   jetzt erst. Kaum zu sehen live.<\/p>\n<p>17&#8242;<\/p>\n<p>Ein Flanken-Abschluss von Essen fliegt   dr\u00fcber.<\/p>\n<p>19&#8242; Chance RWE<\/p>\n<p>Zobel rettet in hoher Not gegen   Reisig. Den hatte Brumme nach einem   Auer Fehlpass im Aufbau einsetzen   wollen. Clausen hatte sich den   Fehlpass geleistet, allerdings war   das Anspiel auch sehr hart auf   Clausen.<\/p>\n<p>13&#8242;<\/p>\n<p>Weinhauers Pass auf G\u00fcnther-Schmidt   ger\u00e4t zu ungenau. Das Zusammenspiel der   beiden Ex-Jenaer.<\/p>\n<p>12&#8242;<\/p>\n<p>RWE-Kapit\u00e4n Schultz k\u00f6pft nach einer   Ecke von links dr\u00fcber.<\/p>\n<p>11&#8242;<\/p>\n<p>N\u00e4chste Hereingabe von Safi,   abgef\u00e4lscht von Collins &#8211; M\u00e4nnel ist   da.<\/p>\n<p>10&#8242;<\/p>\n<p>Es gab vor der Partie intensive   Gespr\u00e4che von Koschinat mit seinem   Trainerteam. Die waren n\u00e4mlich schon   bei Dabrowski da. Das verriet Essens   Trainer in der Pressekonferenz.<\/p>\n<p>8&#8242; Chance Aue<\/p>\n<p>Aue erobert den Ball von Safi, dann   geht es \u00fcber Simnica, dessen scharfe   Hereingabe kl\u00e4rt Reisig vor B\u00e4r.<\/p>\n<p>6&#8242;<\/p>\n<p>Jamilu Collins probiert es \u00fcber links,   die abgef\u00e4lschte Flanke h\u00e4lt Golz fest.   Keine Ecke.<\/p>\n<p>5&#8242;<\/p>\n<p>Da wollte er M\u00e4nnel fast von der   Grundlinie \u00fcberwinden. Die Vorlage kam   von Mizuta.<\/p>\n<p>4&#8242; 1. Chance RWE<\/p>\n<p>Die Gastgeber pr\u00fcfen erstmals M\u00e4nnel,   durch einen Abschluss von Safi.<\/p>\n<p>3&#8242;<\/p>\n<p>In der Zeit in Essen feierte Christoph   Dabrowski seinen ersten Sieg im 7.   Spiel. Das ist es auch heute. Damals &#8211;   nat\u00fcrlich gegen Aue.<\/p>\n<p>2&#8242;<\/p>\n<p>Noch ein gutes Omen? Unter der Leitung   von Referee Assad Nouhoum hat Aue in   dieser Saison noch nicht verloren. Es   gab Remis gegen Rostock und Verl.<\/p>\n<p>Rund 200 Aue-Fans sind heute mit dabei.<\/p>\n<p>Man versuche das &#8222;Unm\u00f6gliche noch   m\u00f6glich zu machen&#8220;, sagte Aues Trainer   Dabrowski.<\/p>\n<p>Gutes Omen?<\/p>\n<p>Farblich f\u00fchlt sich Aue in er   G\u00e4stekabine sehr wohl. Denn die ist in   lila gestaltet, es ist die Heimkabine   der Frauen der SGS Essen.<\/p>\n<p>Besonders aufpassen m\u00fcssen die Veilchen   auf die formstarken Janssen und Mizuta   in der Essener Offensive.<\/p>\n<p>Drei Wechsel bei RWE<\/p>\n<p>Die Essener beginnen mit Golz im   Kasten f\u00fcr Casali, Brunne f\u00fcr Obuz   und M\u00fcsel f\u00fcr Routinier Gjasula. Auch   der bei einem B\u00f6ller beim Heimspiel   gegen Mannheim verletzte Ersatzkeeper   Wienand ist wieder fit und sitzt auf   der Bank.<\/p>\n<p>Bei Essen kehrt Stammkeeper Jakob Golz   in die Startelf zur\u00fcck.<\/p>\n<p>Mit Stefaniak, Guttau und Uhlmann   erwischt es also drei gro\u00dfe Saison-  Hoffnungen der Auer. Besonders   Weinhauer wurden von vielen Fans   gefordert.<\/p>\n<p>Vier Neue bei Aue<\/p>\n<p>Der FCE beginnt nach dem 1:3 gegen   Aachen mit Weinhauer, Clausen, G\u00fcnther-  Schmidt und Zobel f\u00fcr Guttau,   Stefaniak, Ocansey und Uhlmann.<\/p>\n<p>R\u00fcckkehr<\/p>\n<p>Aues Trainer Christoph Dabrowski   kehrt nach Essen zur\u00fcck. Dort   arbeitete er von 2022 bis 2024 und   holte in 111 Partien 1,49 Punkte im   Schnitt. Er hielt den damaligen   Aufsteiger in der Klasse.<\/p>\n<p>Essen gewann zuletzt zweimal, davor   gab es zwei Niederlagen. In der   heimischen Arena gab es seit Ende   August in zw\u00f6lf Partien nur eine   Niederlage, gegen Cottbus. Ein Punkt   w\u00e4re f\u00fcr Aue also wohl schon ein   Erfolg.<\/p>\n<p>Zehn Spieltage sind es noch. Die eine   oder andere Wunderrettung gab es in   der Historie der 3. Liga seit 2008   noch. Jena und Braunschweig schafften   es unter anderem. Ein Sieg in Essen   w\u00e4re ein Anfang, der viel Schub geben   k\u00f6nnte.<\/p>\n<p>Abstiegskampf vs. Aufstiegskampf<\/p>\n<p>Aue steht als 17. auf dem ersten   Abstiegsplatz, punktgleich mit Ulm.   Das rettende Ufer ist aktuell acht   Punkte entfernt. Plus die schlechtere   Tordifferenz. Essen liegt auf   Position vier. Es hei\u00dft also wieder   einmal Abstiegskampf gegen   Aufstiegskampf.<\/p>\n<p>Hallo<\/p>\n<p>und herzlich willkommen zum Gastspiel   von Erzgebirge Aue in der 3. Liga bei   Rot-Weiss Essen. K\u00f6nnen die Veilchen   im Kampf um den Klassenerhalt f\u00fcr   eine \u00dcberraschung sorgen?<\/p>\n","protected":false},"excerpt":{"rendered":"Statistik Tore 1:0 M\u00fcsel (28.), 2:0 Hofmann (32.), 3:0 Janssen (37.), 3:1 Ehlers (45.+2), 3:2 B\u00e4r (61.), 4:2&hellip;\n","protected":false},"author":2,"featured_media":3888,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1834],"tags":[3364,29,3688,30,81,1209,3499,3498],"class_list":{"0":"post-868890","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-essen","8":"tag-de","9":"tag-deutschland","10":"tag-essen","11":"tag-germany","12":"tag-mdr","13":"tag-nordrhein-westfalen","14":"tag-spio","15":"tag-sport-im-osten"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116229695494602012","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/868890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=868890"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/868890\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/3888"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=868890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=868890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=868890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}