{"id":883900,"date":"2026-03-20T20:24:17","date_gmt":"2026-03-20T20:24:17","guid":{"rendered":"https:\/\/www.europesays.com\/de\/883900\/"},"modified":"2026-03-20T20:24:17","modified_gmt":"2026-03-20T20:24:17","slug":"blockade-von-krediten-fuer-ukraine","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/883900\/","title":{"rendered":"Blockade von Krediten f\u00fcr Ukraine"},"content":{"rendered":"<p>                    <img decoding=\"async\" loading=\"lazy\" class=\"internal-image\" title=\"Ungarns Ministerpr\u00e4sident Orban und der slowakische Regierungschef Fico stehen nebeneinander im Konferenzsaalm und reden miteinander. \" alt=\"Ungarns Ministerpr\u00e4sident Orban und der slowakische Regierungschef Fico stehen nebeneinander im Konferenzsaalm und reden miteinander. \" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/vicotr-orban-100-1920x1080.jpg\" \/><\/p>\n<p>                  Blockierer: Ungarns Ministerpr\u00e4sident Victor Orb\u00e1n (l.) und der slowakische Regierungschef Fico (m.). (picture alliance \/ ASSOCIATED PRESS \/ Geert Vanden Wijngaert)<\/p>\n<p>Die EU m\u00fcsse nun einen &#8222;Plan C&#8220; ausarbeiten, um der Ukraine m\u00f6glichst schnell Gelder zukommen zu lassen und einen Staatsbankrott zu vermeiden, sagte Ha\u00dfelmann der Nachrichtenagentur AFP.<\/p>\n<p>Ungarns Ministerpr\u00e4sident Orban und der slowakische Regierungschef Fico hatten auf dem Gipfeltreffen die Auszahlung eines EU-Darlehens \u00fcber 90 Milliarden Euro an die Ukraine weiterhin blockiert. Beide argumentieren mit dem Ausbleiben von Erd\u00f6llieferungen durch die besch\u00e4digte Druschba-Pipeline, die normalerweise russisches \u00d6l durch die Ukraine transportiert.\u00a0Die erneute Blockade des Kredits stie\u00df bei den anderen Mitgliedsstaaten auf gro\u00dfe Ver\u00e4rgerung. Bundeskanzler Merz warf Orban einen &#8222;Akt grober Illoyalit\u00e4t&#8220; vor, der tiefe Spuren hinterlassen werde.<\/p>\n<p>Diese Nachricht wurde am 20.03.2026 im Programm Deutschlandfunk gesendet.<\/p>\n","protected":false},"excerpt":{"rendered":"Blockierer: Ungarns Ministerpr\u00e4sident Victor Orb\u00e1n (l.) und der slowakische Regierungschef Fico (m.). (picture alliance \/ ASSOCIATED PRESS \/&hellip;\n","protected":false},"author":2,"featured_media":883901,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4012],"tags":[331,332,13,14,15,12,317],"class_list":{"0":"post-883900","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ukraine","8":"tag-aktuelle-nachrichten","9":"tag-aktuelle-news","10":"tag-headlines","11":"tag-nachrichten","12":"tag-news","13":"tag-schlagzeilen","14":"tag-ukraine"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116263378297335058","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/883900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=883900"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/883900\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/883901"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=883900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=883900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=883900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}