{"id":887620,"date":"2026-03-22T09:08:14","date_gmt":"2026-03-22T09:08:14","guid":{"rendered":"https:\/\/www.europesays.com\/de\/887620\/"},"modified":"2026-03-22T09:08:14","modified_gmt":"2026-03-22T09:08:14","slug":"pol-ma-mannheim-neckarstadt-zusammenstoss-zwischen-zwei-strassenbahnen-pm-nr-2","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/887620\/","title":{"rendered":"POL-MA: Mannheim-Neckarstadt: Zusammensto\u00df zwischen zwei Stra\u00dfenbahnen &#8211; PM Nr. 2"},"content":{"rendered":"<p class=\"date\">22.03.2026 \u2013 08:56<\/p>\n<p class=\"customer\">\n                        <a class=\"story-customer\" title=\"weiter zum newsroom von Polizeipr\u00e4sidium Mannheim\" href=\"https:\/\/www.presseportal.de\/blaulicht\/nr\/14915\" rel=\"nofollow noopener\" target=\"_blank\">Polizeipr\u00e4sidium Mannheim<\/a>\n                    <\/p>\n<p><a data-category=\"citylink-story-view\" data-action=\"click\" data-label=\"Citylink in Meldungsansicht\" class=\"story-city event-trigger\" href=\"https:\/\/www.presseportal.de\/regional\/Mannheim\" title=\"News aus Mannheim \" rel=\"nofollow noopener\" target=\"_blank\">Mannheim<\/a> (ots)<\/p>\n<p>Mannheim-Neckarstadt: Zusammensto\u00df zwischen zwei Stra\u00dfenbahnen &#8211; PM Nr. 2<\/p>\n<p>Wie bereits berichtet, kam es am Samstagabend zu einem Verkehrsunfall zwischen zwei Stra\u00dfenbahnen. Nach bisherigen Erkenntnissen wollte ein 46-j\u00e4hriger Stra\u00dfenbahnfahrer der Linie 4 von der Friedrich-Ebert-Stra\u00dfe kommend nach rechts in Richtung Schafsweide abbiegen. Aus noch unbekannten Gr\u00fcnden, war die dortige Weiche jedoch nicht korrekt gestellt, sodass die Bahn geradeaus in Richtung Friedrich-Ebert-Br\u00fccke geleitet wurde. Da zeitgleich eine Stra\u00dfenbahn der Linie 4A aus Richtung Schafsweide kommend in die Friedrich-Ebert-Stra\u00dfe abbog, kam es zur Kollision. Infolge des Zusammensto\u00dfes entgleisten beide Stra\u00dfenbahnen.<\/p>\n<p>Gl\u00fccklicherweise wurde bei dem Unfall niemand verletzt. Der entstandene Sachschaden wird auf ca. 150.000 Euro gesch\u00e4tzt.<\/p>\n<p>F\u00fcr die Dauer der Verkehrsunfallaufnahme musste die Friedrich-Ebert-Stra\u00dfe in Fahrtrichtung Innenstadt bis ca. 23 Uhr gesperrt werden. Die beiden entgleisten Stra\u00dfenbahnen wurden durch die RNV geborgen. Gr\u00f6\u00dfere Verkehrsbeeintr\u00e4chtigungen blieben aus.<\/p>\n<p>Die Ermittlungen zum Unfallhergang hat das Polizeirevier Mannheim-Innenstadt aufgenommen.<\/p>\n<p class=\"contact-headline\">R\u00fcckfragen bitte an:<\/p>\n<p class=\"contact-text\">Polizeipr\u00e4sidium Mannheim<br \/>F\u00fchrungs- und Lagezentrum<br \/>Thomas Dierich<br \/>Telefon: 0621 174-1111<br \/>E-Mail: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/14915\/mailto: mannheim.pp@polizei.bwl.de\" class=\"uri-mailto\" rel=\"nofollow noopener\" target=\"_blank\"> mannheim.pp@polizei.bwl.de<\/a><br \/><a target=\"_blank\" class=\"uri-ext outbound\" rel=\"noopener nofollow\" href=\"http:\/\/www.polizei-bw.de\/\">http:\/\/www.polizei-bw.de\/<\/a><\/p>\n<p class=\"originator\">Original-Content von: Polizeipr\u00e4sidium Mannheim, \u00fcbermittelt durch news aktuell<\/p>\n","protected":false},"excerpt":{"rendered":"22.03.2026 \u2013 08:56 Polizeipr\u00e4sidium Mannheim Mannheim (ots) Mannheim-Neckarstadt: Zusammensto\u00df zwischen zwei Stra\u00dfenbahnen &#8211; PM Nr. 2 Wie bereits&hellip;\n","protected":false},"author":2,"featured_media":386213,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1845],"tags":[1634,6187,3364,29,548,663,3934,30,13,177,2096,14,15,121,178,180,179,181,12],"class_list":{"0":"post-887620","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mannheim","8":"tag-baden-wuerttemberg","9":"tag-bw","10":"tag-de","11":"tag-deutschland","12":"tag-eu","13":"tag-europa","14":"tag-europe","15":"tag-germany","16":"tag-headlines","17":"tag-kriminalitt","18":"tag-mannheim","19":"tag-nachrichten","20":"tag-news","21":"tag-polizei","22":"tag-presse","23":"tag-pressemeldung","24":"tag-pressemitteilung","25":"tag-pressemitteilungen","26":"tag-schlagzeilen"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116272044809785647","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/887620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=887620"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/887620\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/386213"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=887620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=887620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=887620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}