{"id":890798,"date":"2026-03-23T15:26:13","date_gmt":"2026-03-23T15:26:13","guid":{"rendered":"https:\/\/www.europesays.com\/de\/890798\/"},"modified":"2026-03-23T15:26:13","modified_gmt":"2026-03-23T15:26:13","slug":"pol-ma-mannheim-diebstahl-auf-rheinauer-friedhof-zeugen-und-geschaedigtenaufruf","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/890798\/","title":{"rendered":"POL-MA: Mannheim: Diebstahl auf Rheinauer Friedhof &#8211; Zeugen- und Gesch\u00e4digtenaufruf"},"content":{"rendered":"<p class=\"date\">23.03.2026 \u2013 16:10<\/p>\n<p class=\"customer\">\n                        <a class=\"story-customer\" title=\"weiter zum newsroom von Polizeipr\u00e4sidium Mannheim\" href=\"https:\/\/www.presseportal.de\/blaulicht\/nr\/14915\" rel=\"nofollow noopener\" target=\"_blank\">Polizeipr\u00e4sidium Mannheim<\/a>\n                    <\/p>\n<p><a data-category=\"citylink-story-view\" data-action=\"click\" data-label=\"Citylink in Meldungsansicht\" class=\"story-city event-trigger\" href=\"https:\/\/www.presseportal.de\/regional\/Mannheim\" title=\"News aus Mannheim \" rel=\"nofollow noopener\" target=\"_blank\">Mannheim<\/a> (ots)<\/p>\n<p>In der Nacht von Mittwoch, 18.03.2026, 18:00 Uhr, auf Donnerstag, 19.03.2026, 07:30 Uhr, entwendete bislang unbekannte T\u00e4terschaft auf dem Friedhof Mannheim-Rheinau Bronzeskulpturen, Grabschmuck sowie Ornamente von mehreren Gr\u00e4bern. Die T\u00e4terschaft entfernte die Gegenst\u00e4nde mittels grober Gewalt und nutzte offenbar nicht mehr im Gebrauch befindliche M\u00fclltonnen des Friedhofs zum Abtransport des Diebesgutes.<br \/>\nNach derzeitigem Ermittlungsstand ist von rund 20 besch\u00e4digten Gr\u00e4bern auszugehen. Die Schadensh\u00f6he ist bislang nicht bekannt.<br \/>\nDer Polizeiposten Mannheim-Rheinau des Polizeireviers Mannheim-Neckarau hat die Ermittlungen wegen St\u00f6rung der Totenruhe sowie Diebstahls \u00fcbernommen.<\/p>\n<p>Personen, deren Grab auf dem Friedhof Mannheim-Rheinau besch\u00e4digt wurde oder von dem Grabschmuck entwendet wurde, sowie Personen, welche in der genannten Tatnacht im Bereich des Friedhofs Mannheim-Rheinau verd\u00e4chtige Personen oder Fahrzeuge wahrgenommen haben oder sonstige sachdienliche Hinweise mitteilen k\u00f6nnen, werden gebeten, sich beim Polizeiposten Mannheim-Rheinau (08:00 Uhr bis 16:00 Uhr) unter der Telefonnummer 0621 87682-0 oder beim Polizeirevier Mannheim-Neckarau unter der Telefonnummer 0621 83397-0 zu melden.<\/p>\n<p class=\"contact-headline\">R\u00fcckfragen bitte an:<\/p>\n<p class=\"contact-text\">Polizeipr\u00e4sidium Mannheim<br \/>Stabsstelle \u00d6ffentlichkeitsarbeit<br \/>Anna Mifka<br \/>Telefon: 0621 174-1111<br \/>E-Mail: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/14915\/mailto: mannheim.pp.sts.oe@polizei.bwl.de\" class=\"uri-mailto\" rel=\"nofollow noopener\" target=\"_blank\"> mannheim.pp.sts.oe@polizei.bwl.de<\/a><br \/><a target=\"_blank\" class=\"uri-ext outbound\" rel=\"noopener nofollow\" href=\"http:\/\/www.polizei-bw.de\/\">http:\/\/www.polizei-bw.de\/<\/a><\/p>\n<p class=\"originator\">Original-Content von: Polizeipr\u00e4sidium Mannheim, \u00fcbermittelt durch news aktuell<\/p>\n","protected":false},"excerpt":{"rendered":"23.03.2026 \u2013 16:10 Polizeipr\u00e4sidium Mannheim Mannheim (ots) In der Nacht von Mittwoch, 18.03.2026, 18:00 Uhr, auf Donnerstag, 19.03.2026,&hellip;\n","protected":false},"author":2,"featured_media":386213,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1845],"tags":[1634,6187,3364,29,548,663,3934,30,13,177,2096,14,15,121,178,180,179,181,12],"class_list":{"0":"post-890798","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mannheim","8":"tag-baden-wuerttemberg","9":"tag-bw","10":"tag-de","11":"tag-deutschland","12":"tag-eu","13":"tag-europa","14":"tag-europe","15":"tag-germany","16":"tag-headlines","17":"tag-kriminalitt","18":"tag-mannheim","19":"tag-nachrichten","20":"tag-news","21":"tag-polizei","22":"tag-presse","23":"tag-pressemeldung","24":"tag-pressemitteilung","25":"tag-pressemitteilungen","26":"tag-schlagzeilen"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116279193620872734","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/890798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=890798"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/890798\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/386213"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=890798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=890798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=890798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}