{"id":891279,"date":"2026-03-23T19:58:13","date_gmt":"2026-03-23T19:58:13","guid":{"rendered":"https:\/\/www.europesays.com\/de\/891279\/"},"modified":"2026-03-23T19:58:13","modified_gmt":"2026-03-23T19:58:13","slug":"kochsternstunden-2026-mit-rekordbeteiligung-und-starker-saechsischer-gastronomie-50-restaurants-9-802-bewertungen-14-889-menues-petit-frank-siegt-gioia-ueberrascht","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/891279\/","title":{"rendered":"Kochsternstunden 2026 mit Rekordbeteiligung und starker s\u00e4chsischer Gastronomie \u2013 50 Restaurants, 9.802 Bewertungen, 14.889 Men\u00fcs; petit frank siegt, GIOIA \u00fcberrascht"},"content":{"rendered":"<p>petit frank gewinnt die Kochsternstunden 2026 in Sachsen \u2013 Rekordzahlen, 50 Restaurants, 14.889 Men\u00fcs und 9.802 Bewertungen.<\/p>\n<p>Die 16. Kochsternstunden sind entschieden: Frank Ollhoff vom &#8222;petit frank&#8220; stand gleich zweimal ganz oben auf dem Siegertreppchen \u2013\u00a0als beste Servicekraft und (zusammen mit seinem Chefkoch Andr\u00e9 Fr\u00f6bel) als bestes Restaurant.\u00a0 Wer da ein D\u00e9j\u00e0-vu hatte: so war&#8217;s auch 2024 schon. Vom 6. Februar bis zum 15. M\u00e4rz 2026 hatten 50 Restaurants in Dresden, Chemnitz, Leipzig und der umliegenden Region ihre G\u00e4ste eingeladen, eigens konzipierte Men\u00fcs zu verkosten und zu bewerten. Insgesamt 9.802 Stimmen wurden abgegeben, so viele wie nie zuvor.\u00a0<\/p>\n<p>Nach dem kleinen franz\u00f6sischen Restaurant, das schon seit 15 Jahren mitmacht, folgte\u00a0auf dem zweiten Platz das \u201efinesse by Elvis Herbek\u201c, ebenfalls in Dresden beheimatet. Das Restaurant war Sieger der Kochsternstunden 2025 und geh\u00f6rt mit seiner siebten Teilnahme ebenfalls zu den etablierten Gr\u00f6\u00dfen des Wettbewerbs. Den dritten Rang belegt mit \u201eGIOIA\u201c aus Radebeul ein Neuling: K\u00fcchenchef Dennis Pentzold gelingt damit auf Anhieb der Sprung aufs Podium.<\/p>\n<p>Knapp dahinter reihen sich zwei weitere Dresdner Betriebe ein. Das Restaurant Heiderand, im vergangenen Jahr mit einem Michelin-Stern ausgezeichnet, erreicht bei seiner zweiten Teilnahme erstmals eine Platzierung und landet auf Rang vier. Platz f\u00fcnf geht an Mario Pattis mit seinem Restaurant \u201eFeine Kost\u201c, das ebenfalls zum zweiten Mal dabei ist und sich nun erstmals unter den Besten behaupten kann.<\/p>\n","protected":false},"excerpt":{"rendered":"petit frank gewinnt die Kochsternstunden 2026 in Sachsen \u2013 Rekordzahlen, 50 Restaurants, 14.889 Men\u00fcs und 9.802 Bewertungen. Die&hellip;\n","protected":false},"author":2,"featured_media":891280,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1835],"tags":[3364,29,2386,6763,30,177486,195996,859],"class_list":{"0":"post-891279","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dresden","8":"tag-de","9":"tag-deutschland","10":"tag-dresden","11":"tag-gastronomie","12":"tag-germany","13":"tag-kochsternstunden","14":"tag-petit-frank","15":"tag-sachsen"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116280263039396021","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/891279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=891279"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/891279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/891280"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=891279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=891279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=891279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}