{"id":896006,"date":"2026-03-25T16:18:14","date_gmt":"2026-03-25T16:18:14","guid":{"rendered":"https:\/\/www.europesays.com\/de\/896006\/"},"modified":"2026-03-25T16:18:14","modified_gmt":"2026-03-25T16:18:14","slug":"22-jaehrige-greift-bundespolizisten-an-mannheim","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/896006\/","title":{"rendered":"22-J\u00e4hrige greift Bundespolizisten an &#8211; Mannheim"},"content":{"rendered":"<p><b\/>Eine 22-J\u00e4hrige hat  in der Nacht von Dienstag auf Mittwoch am Mannheimer Hauptbahnhof Einsatzkr\u00e4fte der <a class=\"rtr-entity\" data-rtr-entity=\"Bundespolizei\" data-rtr-id=\"80d963170b5df647eadbbe3b45e1a1f661ec57c8\" data-rtr-score=\"27.08838821490468\" data-rtr-etype=\"organisation\" data-rtr-index=\"3\" href=\"https:\/\/www.rheinpfalz.de\/themen\/bundespolizei?utm_source=rheinpfalz.de&amp;utm_medium=tms&amp;utm_campaign=intext\" rel=\"nofollow noopener\" target=\"_blank\">Bundespolizei<\/a> angegriffen. Verletzt wurde dabei niemand. Mitarbeiter des Sicherheitsdienstes der <a class=\"rtr-entity\" data-rtr-entity=\"Deutsche Bahn\" data-rtr-id=\"2c8485399ba5853abb187a70d476d39491b77207\" data-rtr-score=\"12.283362218370883\" data-rtr-etype=\"organisation\" data-rtr-index=\"2\" href=\"https:\/\/www.rheinpfalz.de\/themen\/deutsche-bahn?utm_source=rheinpfalz.de&amp;utm_medium=tms&amp;utm_campaign=intext\" rel=\"nofollow noopener\" target=\"_blank\">Deutschen Bahn<\/a> meldeten gegen 23.15 Uhr eine alkoholisierte Frau, die sich mit einem Fahrrad im Bahnhofsbereich bewegte. Einsatzkr\u00e4fte der Bundespolizei trafen die 22-J\u00e4hrige  kurze Zeit sp\u00e4ter auf einem Parkplatz an und kontrollierten sie, teilt die Polizei mit.<\/p>\n<p>Die Frau verweigerte bereits zu Beginn die Vorlage eines Ausweisdokuments. Im weiteren Verlauf versuchte sie, einen Beamten k\u00f6rperlich anzugehen, was verhindert wurde. W\u00e4hrend der anschlie\u00dfenden Fixierung hat die Tatverd\u00e4chtige Widerstand geleistet und wiederholt Beleidigungen ge\u00e4u\u00dfert.<\/p>\n<p>Die Staatsanwaltschaft Mannheim ordnete eine Blutentnahme an, um einen m\u00f6glichen Drogenkonsum festzustellen. Die 22-J\u00e4hrige wurde zur medizinischen Versorgung in ein Krankenhaus gebracht und anschlie\u00dfend an eine Angeh\u00f6rige \u00fcbergeben. Sie erwartet Strafanzeigen, unter anderem wegen t\u00e4tlichen Angriffs auf Polizeibeamte, Widerstands gegen Vollstreckungsbeamte und  Beleidigung. <\/p>\n","protected":false},"excerpt":{"rendered":"Eine 22-J\u00e4hrige hat in der Nacht von Dienstag auf Mittwoch am Mannheimer Hauptbahnhof Einsatzkr\u00e4fte der Bundespolizei angegriffen. Verletzt&hellip;\n","protected":false},"author":2,"featured_media":896007,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1845],"tags":[1634,421,3364,2030,29,2540,548,663,3934,30,3601,13,4060,2096,14,15,12],"class_list":{"0":"post-896006","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mannheim","8":"tag-baden-wuerttemberg","9":"tag-bundespolizei","10":"tag-de","11":"tag-deutsche-bahn","12":"tag-deutschland","13":"tag-einsatzkraft","14":"tag-eu","15":"tag-europa","16":"tag-europe","17":"tag-germany","18":"tag-hauptbahnhof","19":"tag-headlines","20":"tag-lokal","21":"tag-mannheim","22":"tag-nachrichten","23":"tag-news","24":"tag-schlagzeilen"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116290722668346521","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/896006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=896006"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/896006\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/896007"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=896006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=896006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=896006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}