{"id":899918,"date":"2026-03-27T04:39:13","date_gmt":"2026-03-27T04:39:13","guid":{"rendered":"https:\/\/www.europesays.com\/de\/899918\/"},"modified":"2026-03-27T04:39:13","modified_gmt":"2026-03-27T04:39:13","slug":"heidelberg-materials-aktie-schwaecher-dividende-legt-zu-bleibt-jedoch-unter-erwartungen","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/899918\/","title":{"rendered":"Heidelberg Materials-Aktie schw\u00e4cher: Dividende legt zu, bleibt jedoch unter Erwartungen"},"content":{"rendered":"<p>Heidelberg Materials will seinen Aktion\u00e4ren f\u00fcr das abgelaufene Gesch\u00e4ftsjahr eine h\u00f6here Dividende zahlen.<\/p>\n<p>So will das Unternehmen 3,60 Euro pro Aktie zahlen, 30 Cent mehr als im Vorjahr. Damit sollen 28,8 Prozent des Jahres\u00fcberschusses an die Aktion\u00e4re ausgesch\u00fcttet werden, wie aus dem jetzt ver\u00f6ffentlichten Gesch\u00e4ftsbericht des Baustoffkonzerns f\u00fcr 2025 hervorgeht. Analysten hatten mit 3,61 Euro Dividende gerechnet. <\/p>\n<p> Zahlen f\u00fcr das abgelaufene Jahr waren bereits Ende Februar ver\u00f6ffentlicht worden. Der den Aktion\u00e4ren zuzurechnende \u00dcberschuss nach Anteilen Dritter ist 2025 auf 2,205 von 2,156 Milliarden Euro gestiegen. <\/p>\n<p> <a href=\"https:\/\/www.finanzen.net\/aktien\/heidelberg_materials-aktie\" target=\"_blank\" rel=\"noopener nofollow\">Heidelberg Materials<\/a> verfolgt eine progressive Dividendenpolitik. \u00dcberdies l\u00e4uft derzeit ein Aktienr\u00fcckkaufprogramm im Volumen von 1,2 Milliarden Euro. Bis Ende 2026 soll es abgeschlossen werden. Zur\u00fcckgekaufte Aktien f\u00fcr rund 750 Millionen Euro hat Heidelberg Materials bereits eingezogen. <\/p>\n<p>So bewegt sich die Heidelberg Materials-Aktie<\/p>\n<p>&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\nDie Aktien von Heidelberg Materials wechselten am Donnerstag die Vorzeichen. &#13;<br \/>\n&#13;<br \/>\nLetztlich ging es via XETRA f\u00fcr die Aktie 0,85 Prozent auf 179,75 Euro nach unten. &#13;<br \/>\n&#13;\n<\/p>\n<p>Die Investmentbank Oddo BHF hat die Aktien des Baustoffherstellers von &#8222;Neutral&#8220; auf &#8222;Outperform&#8220; hochgestuft. H\u00e4ndler monieren allerdings, dass die Dividende geringer ausf\u00e4llt als erwartet. Das Unternehmen will f\u00fcr 2025 eine Dividende von 3,60 Euro zahlen, die Konsenssch\u00e4tzung liegt bei 3,91 Euro.&#13;<br \/>\n&#13;\n<\/p>\n<p> DOW JONES \/ FRANKFURT (dpa-AFX <a href=\"https:\/\/www.finanzen.net\/ratgeber\/broker\/produkte-vergleiche\/online-broker-vergleich\/\" rel=\"nofollow noopener\" target=\"_blank\">Broker<\/a>)<\/p>\n<p>Ausgew\u00e4hlte Hebelprodukte auf Heidelberg Materials<\/p>\n<p>Mit Knock-outs k\u00f6nnen spekulative Anleger \u00fcberproportional an Kursbewegungen partizipieren. W\u00e4hlen Sie einfach den gew\u00fcnschten Hebel und wir zeigen Ihnen passende Open-End Produkte auf Heidelberg Materials<\/p>\n<p class=\"font-color-red display-none\" id=\"lvgCustomHandleInfo\">Der Hebel muss zwischen 2 und 20 liegen<\/p>\n<p>Wer\u00adbung<\/p>\n","protected":false},"excerpt":{"rendered":"Heidelberg Materials will seinen Aktion\u00e4ren f\u00fcr das abgelaufene Gesch\u00e4ftsjahr eine h\u00f6here Dividende zahlen. So will das Unternehmen 3,60&hellip;\n","protected":false},"author":2,"featured_media":899919,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[134],"tags":[175,170,169,29,30,171,174,173,172],"class_list":{"0":"post-899918","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-unternehmen-maerkte","8":"tag-business","9":"tag-companies","10":"tag-companies-markets","11":"tag-deutschland","12":"tag-germany","13":"tag-markets","14":"tag-maerkte","15":"tag-unternehmen","16":"tag-unternehmen-maerkte"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116299298621763967","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/899918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=899918"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/899918\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/899919"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=899918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=899918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=899918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}