{"id":901082,"date":"2026-03-27T15:26:16","date_gmt":"2026-03-27T15:26:16","guid":{"rendered":"https:\/\/www.europesays.com\/de\/901082\/"},"modified":"2026-03-27T15:26:16","modified_gmt":"2026-03-27T15:26:16","slug":"ferrari-nur-dritte-kraft-in-suzuka","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/901082\/","title":{"rendered":"Ferrari nur dritte Kraft in Suzuka?"},"content":{"rendered":"<p>     12:55\u00a0Uhr<br \/>\n                        Feierabend<\/p>\n<p>Gleich ist es in Japan 21:00 Uhr, und damit sind wir hier an dieser Stelle am Ende des Freitags angekommen. Morgen m\u00fcssen wir unsere Wecker erneut fr\u00fch stellen, FT3 steht bereits um 03:30 Uhr MEZ an.<\/p>\n<p>Das Qualifying beginnt um 07:00 Uhr MEZ, und dann sind auch wir hier wieder mit einer neuen Tickerausgabe f\u00fcr euch am Start. Habt noch einen sch\u00f6nen Rest-Freitag, kommt gut ins Wochenende und bis dann!<\/p>\n<p>     12:45\u00a0Uhr<br \/>\n                        McLaren: Wir vertrauen Mercedes<\/p>\n<p>Und auch zwischen McLaren und Mercedes gibt es keinen \u00c4rger, nachdem in China keiner der beiden McLaren-Piloten am Rennen teilnehmen konnte. Zwar war in beiden F\u00e4llen die Batterie von Mercedes daf\u00fcr verantwortlich.<\/p>\n<p>Doch Teamchef Andrea Stella betont: &#8222;Wir haben gemeinsam mit HPP das Problem untersucht.&#8220; Und nun vertraue man &#8222;zu 100 Prozent darauf, dass HPP Abhilfema\u00dfnahmen ergriffen hat.&#8220;<\/p>\n<p>&#8222;HPP hat sehr hohe Standards&#8220;, sagt Stella und erkl\u00e4rt: &#8222;Wenn sie Informationen aus einem Fehler zu verarbeiten haben, werden sie mit Sicherheit alle notwendigen Erkenntnisse, Anpassungen und Ma\u00dfnahmen umsetzen, um eine Wiederholung zu vermeiden.&#8220;<\/p>\n<p>Daher habe man keine Angst davor, dass man in Japan noch einmal so ein Debakel erlebe.<\/p>\n<p>    12:28\u00a0Uhr<br \/>\n                        Honda: Keine Probleme mit Aston Martin<\/p>\n<p>Laut HRC-Pr\u00e4sident Koji Watanabe ist die Stimmung zwischen Honda und Aston Martin aktuell nicht angespannt. &#8222;Die Beziehung zwischen Aston Martin und Honda ist recht gut&#8220;, stellt er klar.<\/p>\n<p>Obwohl das Projekt in einer Krise steckt, versichert er, dass die Zusammenarbeit zwischen beiden Seiten &#8222;eng&#8220; sei. &#8222;Auch ich habe mit Herrn Stroll und Adrian Newey ein recht gutes Verh\u00e4ltnis&#8220;, so Watanabe.<\/p>\n<p>Er mache sich daher &#8222;keine Sorgen&#8220;, betont er.<\/p>\n<p>     12:13\u00a0Uhr<br \/>\n                        Verstappen muss sich erkl\u00e4ren<\/p>\n<p>Die <a href=\"https:\/\/www.bild.de\/sport\/mehr-sport\/formel-1-verstappen-musste-zum-rapport-bei-red-bull-nach-journalisten-eklat-69c65345af187d606b814bc5\" target=\"_blank\" rel=\"nofollow noopener\">Kollegen von Bild berichten<\/a>, dass es heute am Morgen ein Treffen zwischen Max Verstappen und Red-Bull-Teamchef Laurent Mekies gab. Dabei sollte der Niederl\u00e4nder erkl\u00e4ren, wie es zu der <a href=\"https:\/\/www.formel1.de\/news\/news\/2026-03-26\/geh-raus-max-verstappen-schmeisst-journalisten-aus-seiner-medienrunde\" target=\"_self\" rel=\"nofollow noopener\">Situation gestern in seiner Medienrunde<\/a> kam.<\/p>\n<p>Dem Bericht nach habe der Vorfall f\u00fcr Verstappen keine Konsequenzen, doch Mekies habe klargestellt, &#8222;dass Red Bull kein Team ist, das Journalisten aus der Hospitality wirft&#8220;, hei\u00dft es.<\/p>\n<p>     11:56\u00a0Uhr<br \/>\n                        Ferrari: R\u00fcckstand keine \u00dcberraschung<\/p>\n<p>Bei der Rennpace sieht es besser aus, aber auf einer schnellen Runde hat Ferrari aktuell R\u00fcckstand. Sportdirektor Diego Ioverno sagt dazu: &#8222;Ich denke, der Abstand entspricht mehr oder weniger unseren Erwartungen.&#8220;<\/p>\n<p>Er stehe in Einklang mit den ersten Rennen, &#8222;vor allem bei den kurzen Runs&#8220;, so der Italiener, der betont: &#8222;Dennoch m\u00fcssen wir versuchen, uns zu verbessern. Wir werden unser Bestes geben, die Daten analysieren und versuchen, einige kleinere Probleme zu beheben, die wir hatten.&#8220;<\/p>\n<p>&#8222;Ich glaube, ihr habt geh\u00f6rt, wie Lewis sich \u00fcber den Mangel an Vertrauen beklagt hat. Die Strecke ist mit dem neuen Asphalt im zweiten Abschnitt schwierig. Entscheidend wird sein, dass die Reifen schon ab der ersten Runde richtig funktionieren&#8220;, so Ioverno.<\/p>\n<p>      11:35\u00a0Uhr<br \/>\n                        Haas zufrieden: Fokus auf dem Qualifying<\/p>\n<p>Oliver Bearman landete heute auf P9 und berichtet: &#8222;Es war ein guter Tag.&#8220; Allerdings betont er auch, dass die Abst\u00e4nde im Mittelfeld sehr eng seien. Daher m\u00fcsse man \u00fcber Nacht noch &#8222;etwas Rundenzeit&#8220; finden.<\/p>\n<p>Er erinnert: &#8222;Letztes Jahr war es hier sehr schwer zu \u00fcberholen, und es war vielleicht eines der Rennen mit den wenigsten \u00dcberholman\u00f6vern. Mit diesen neuen Regeln wird es jedoch mehr M\u00f6glichkeiten geben.&#8220;<\/p>\n<p>&#8222;Aber das Qualifying wird weiterhin oberste Priorit\u00e4t haben&#8220;, so Bearman. Teamkollege Esteban Ocon betont derweil nach P11 ebenfalls, dass der Freitag &#8222;positiv&#8220; f\u00fcr Haas verlaufen sei.<\/p>\n<p>Das US-Team ist nach den ersten beiden Rennen \u00fcberraschend WM-Vierter und will auch in Suzuka wieder punkten.<\/p>\n<p>    11:21\u00a0Uhr<br \/>\n                        N\u00e4chstes Einstopprennen<\/p>\n<p>Auch in Suzuka wird es am Sonntag im Normalfall wohl wieder lediglich einen Boxenstopp pro Fahrer geben. Es werde &#8222;mit ziemlicher Sicherheit&#8220; ein Einstopprennen werden, sagt Pirelli-Chefingenieur Simone Berra.<\/p>\n<p>&#8222;Es ist interessant, dass McLaren als einziges Team heute nicht mit den harten Reifen getestet hat. Das ist eine merkw\u00fcrdige Entscheidung, die vielleicht darauf abzielt, beide S\u00e4tze C1-Reifen f\u00fcr den Sonntag zu schonen, damit im Falle einer Neutralisierung ein frischer Satz zur Verf\u00fcgung steht&#8220;, so Berra.<\/p>\n<p>Hei\u00dft: Sollte es am Sonntag ein Safety-Car geben, k\u00f6nnte es auch mehr als einen Stopp geben. Unter normalen Umst\u00e4nden sollten aber die meisten Piloten mit einem Boxenstopp durchfahren.<\/p>\n","protected":false},"excerpt":{"rendered":"12:55\u00a0Uhr Feierabend Gleich ist es in Japan 21:00 Uhr, und damit sind wir hier an dieser Stelle am&hellip;\n","protected":false},"author":2,"featured_media":901083,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[136],"tags":[29,1641,1642,1640,1645,1643,1639,30,1644,1638,265],"class_list":{"0":"post-901082","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sport","8":"tag-deutschland","9":"tag-f1-news","10":"tag-formel-1-heute","11":"tag-formel-1-news","12":"tag-formel-1news","13":"tag-formel-eins-news","14":"tag-formel1-news","15":"tag-germany","16":"tag-news-formel-1","17":"tag-news-formel1","18":"tag-sport"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116301842801263203","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/901082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=901082"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/901082\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/901083"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=901082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=901082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=901082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}