{"id":901413,"date":"2026-03-27T18:24:18","date_gmt":"2026-03-27T18:24:18","guid":{"rendered":"https:\/\/www.europesays.com\/de\/901413\/"},"modified":"2026-03-27T18:24:18","modified_gmt":"2026-03-27T18:24:18","slug":"b38-21-jaehriger-rammt-mittelleitplanke-mannheim","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/901413\/","title":{"rendered":"B38: 21-J\u00e4hriger rammt Mittelleitplanke &#8211; Mannheim"},"content":{"rendered":"<p><b\/>Ein 21-j\u00e4hriger Autofahrer ist am Donnerstagabend auf der B38 in Mannheim in die Mittelleitplanke gefahren. Der Mann wurde dabei leicht verletzt und in ein Krankenhaus gebracht. Er  war gegen 21 Uhr auf der Bundesstra\u00dfe 38 in Richtung Stadtmitte unterwegs, als er ersten Ermittlungen zufolge durch sein Handy abgelenkt war und nach links von der Fahrbahn abkam. Danach kollidierte sein Wagen mit der Leitplanke. Dieser war ein   Totalschaden. Die Schadensh\u00f6he sch\u00e4tzt die Polizei  auf mehrere Tausend Euro, teilen die Beamten  mit. Das Auto wurde abgeschleppt. W\u00e4hrend der Unfallaufnahme sowie der Abschleppma\u00dfnahmen wurde die linke Fahrspur gesperrt. <\/p>\n","protected":false},"excerpt":{"rendered":"Ein 21-j\u00e4hriger Autofahrer ist am Donnerstagabend auf der B38 in Mannheim in die Mittelleitplanke gefahren. Der Mann wurde&hellip;\n","protected":false},"author":2,"featured_media":901414,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1845],"tags":[1634,3364,29,548,663,3934,30,13,4060,2096,14,15,12],"class_list":{"0":"post-901413","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-mannheim","8":"tag-baden-wuerttemberg","9":"tag-de","10":"tag-deutschland","11":"tag-eu","12":"tag-europa","13":"tag-europe","14":"tag-germany","15":"tag-headlines","16":"tag-lokal","17":"tag-mannheim","18":"tag-nachrichten","19":"tag-news","20":"tag-schlagzeilen"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116302542823359874","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/901413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=901413"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/901413\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/901414"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=901413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=901413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=901413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}