{"id":903293,"date":"2026-03-28T12:36:21","date_gmt":"2026-03-28T12:36:21","guid":{"rendered":"https:\/\/www.europesays.com\/de\/903293\/"},"modified":"2026-03-28T12:36:21","modified_gmt":"2026-03-28T12:36:21","slug":"ein-regelrechter-krieg-der-roboter","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/903293\/","title":{"rendered":"\u201eEin regelrechter Krieg der Roboter\u201c"},"content":{"rendered":"<p class=\"article_paragraph__hXYKJ\">Der Ukraine-Krieg ger\u00e4t fast schon in Vergessenheit. Der Krieg im <a href=\"https:\/\/www.berliner-zeitung.de\/topics\/iran\" rel=\"nofollow noopener\" target=\"_blank\">Iran<\/a> bestimmt das geopolitische Geschehen dieser Tage. Dabei geht der Krieg in Osteuropa ungemindert weiter. Kleine Einheiten, Drohnen und strategische Verschiebungen pr\u00e4gen die Lage an der Donbass-Front. W\u00e4hrend die Aufmerksamkeit der <a href=\"https:\/\/www.berliner-zeitung.de\/topics\/usa\" rel=\"nofollow noopener\" target=\"_blank\">USA<\/a> zunehmend durch den Konflikt im Nahen Osten gebunden ist, profitiert Russland wirtschaftlich und milit\u00e4risch. Oberst Markus Reisner analysiert im Interview mit der Berliner Zeitung, warum sich die Kr\u00e4fteverh\u00e4ltnisse ver\u00e4ndern und welche Folgen das f\u00fcr die Ukraine und Europa hat.<\/p>\n<p class=\"article_paragraph__hXYKJ\">Herr Reisner, wie beurteilen Sie aktuell die Lage im Ukraine-Krieg \u2013 insbesondere an der Donbass-Front?<\/p>\n<p>Ich bewerte den Kriegsverlauf grunds\u00e4tzlich immer auf drei Ebenen: strategisch, operativ und taktisch. Und aktuell hat sich vor allem auf der strategischen Ebene etwas ver\u00e4ndert, das unmittelbare Auswirkungen auf das Gefechtsfeld hat.<\/p>\n<p class=\"article_paragraph__hXYKJ\">Sie meinen den Angriff Israels und der USA auf den Iran? <\/p>\n<p>Ganz genau. Dieser Konflikt bindet zunehmend die Aufmerksamkeit und auch milit\u00e4rischen Ressourcen der USA, etwa Flugabwehrsysteme, Raketen oder Luft-Boden-Munition. Das f\u00fchrt dazu, dass die Ukraine auf der Priorit\u00e4tenliste nach hinten r\u00fcckt. Pr\u00e4sident <a href=\"https:\/\/www.berliner-zeitung.de\/topics\/wolodymyr-selenskyj\" rel=\"nofollow noopener\" target=\"_blank\">Wolodymyr Selenskyj<\/a> versucht zwar gegenzusteuern, aber faktisch ist diese Verschiebung bereits sichtbar. Die Ukraine versucht ihrerseits, daraus Nutzen zu ziehen, indem sie ihre Expertise \u2013 etwa bei der Drohnenabwehr \u2013 aktiv anbietet. Die Idee der Ukrainer ist: Man unterst\u00fctzt die Verb\u00fcndeten in einem anderen Krieg und erhofft sich dadurch eine Gegenleistung, beispielsweise durch Zugang zu bestimmten Waffensystemen.<\/p>\n<p class=\"article_paragraph__hXYKJ\">Welche konkreten Auswirkungen hat das auf die milit\u00e4rische Unterst\u00fctzung?<\/p>\n<p>Man sieht das sehr deutlich am Ressourcenverbrauch. Es gibt Sch\u00e4tzungen, dass im Nahen Osten innerhalb der vergangenen drei Wochen bis zu 1000 Patriot-Abfangraketen eingesetzt wurden. Das ist mehr, als die Ukraine in den vergangenen Jahren insgesamt erhalten hat. Das zeigt: Kostbare milit\u00e4rische Ressourcen werden immer knapper. Und das hat unmittelbare Konsequenzen f\u00fcr die <a href=\"https:\/\/www.berliner-zeitung.de\/topics\/ukraine\" rel=\"nofollow noopener\" target=\"_blank\">Ukraine<\/a>.<\/p>\n<p class=\"article_paragraph__hXYKJ\">Welche Rolle spielt Europa?<\/p>\n<p>Wenn die USA ihre Unterst\u00fctzung f\u00fcr die Ukraine reduzieren, wird Europa deutlich st\u00e4rker gefordert sein. M\u00f6glicherweise muss dann die EU sogar den Gro\u00dfteil der Last tragen. Das Problem ist: Europa hat bislang nicht gezeigt, dass es die notwendigen Kapazit\u00e4ten schnell genug aufbauen kann, um diese Rolle vollst\u00e4ndig zu \u00fcbernehmen.<\/p>\n<p class=\"article_paragraph__hXYKJ\">Wie stellt sich die strategische Lage aus russischer Sicht dar?<\/p>\n<p>Russland profitiert aktuell von der Lage. Wirtschaftlich insbesondere durch den \u00d6lverkauf \u00fcber Indien oder China etwa. W\u00e4hrend Russland am Beginn des Jahres mit etwa 60 Dollar pro Barrel kalkuliert hat, liegen die Preise heute teils deutlich dar\u00fcber. Das sp\u00fclt Geld in die Staatskasse und stabilisiert die Kriegsf\u00fchrung. Zusammen mit der sinkenden internationalen Aufmerksamkeit f\u00fcr die Ukraine ergibt sich daraus ein strategischer Vorteil f\u00fcr Russland \u2013 auch im Zusammenspiel mit China.<\/p>\n<p><img alt=\"Infobox image\" loading=\"lazy\" width=\"195\" height=\"147\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;max-width:100%;height:auto\"  src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/d3819151-3097-45e8-8ca9-8f2c0e59aa58.jpg\"\/><\/p>\n<p>Paul Kulec<\/p>\n<p>Zur Person<\/p>\n<p>Markus Reisner ist 48 Jahre alt und wurde in Nieder\u00f6sterreich geboren. Er ist Offizier des \u00f6sterreichischen Bundesheeres und kommandiert im Rang eines Obersts die Garde in Wien. Zuvor promovierte Reisner in Geschichte und publizierte mehrere milit\u00e4rhistorische B\u00fccher.<\/p>\n<p class=\"article_paragraph__hXYKJ\">Kommen wir zur operativen Ebene: Wie sieht die Lage entlang der Front konkret aus?<\/p>\n<p>Die Front ist enorm lang \u2013 etwa 1300 bis 1400 Kilometer. Um das f\u00fcr Ihre Leserinnen und Leser greifbar zu machen: Das entspricht in Europa einer gedachten Linie von <a href=\"https:\/\/www.berliner-zeitung.de\/topics\/berlin\" rel=\"nofollow noopener\" target=\"_blank\">Berlin<\/a> \u00fcber Prag und Wien bis nach Mailand. Das ist wichtig zu verstehen, weil einzelne Ereignisse an einem Frontabschnitt oft \u00fcberinterpretiert werden. Was an einem Punkt passiert, l\u00e4sst sich nicht automatisch auf die gesamte Front \u00fcbertragen.<\/p>\n<p class=\"article_paragraph__hXYKJ\">Gibt es denn aktuell wichtige Entwicklungen an einzelnen Abschnitten?<\/p>\n<p>Ja. Die Ukraine konnte beispielsweise in bestimmten Bereichen \u2013 etwa bei Pokrowsk im S\u00fcdabschnitt \u2013 in sogenannte Grauzonen vorsto\u00dfen. Gleichzeitig gab es aber auch russische Fortschritte, etwa im Raum Siwersk. Dort ist es Russland gelungen, wichtige Positionen einzunehmen, was medial vergleichsweise wenig Beachtung fand.<\/p>\n<p class=\"article_paragraph__hXYKJ\">Welche Rolle spielt dabei der Informationsraum \u2013 also wie \u00fcber diesen Krieg berichtet wird?<\/p>\n<p>Eine sehr gro\u00dfe. Die Ukraine ist darauf angewiesen, im Informationsraum pr\u00e4sent zu bleiben und Erfolgsmeldungen zu produzieren. Das ist auch v\u00f6llig nachvollziehbar, weil es um internationale Unterst\u00fctzung geht. Das bedeutet aber auch, dass Erfolge betont und teilweise zugespitzt werden, w\u00e4hrend negative Entwicklungen eher in den Hintergrund treten. Das ist ein klassisches Muster in jedem Krieg. Gleichzeitig sehen wir, dass auch im Westen die Wahrnehmung selektiv ist. Viele klammern sich an jede positive Meldung von ukrainischer Seite, w\u00e4hrend russische Fortschritte oft weniger Beachtung finden.<\/p>\n<p class=\"article_paragraph__hXYKJ\">Wie muss man sich die K\u00e4mpfe vor Ort konkret vorstellen?<\/p>\n<p>Der Krieg im Donbass hat sich fundamental ver\u00e4ndert. Heute sieht ein Gefecht oft so aus: Kleine Sto\u00dftrupps von zwei bis drei Soldaten bewegen sich vor. Sie werden in der Regel von Aufkl\u00e4rungsdrohnen erkannt. Zwei dieser Trupps werden durch Angriffsdrohnen ausgeschaltet, einer schafft es vielleicht in ein zerst\u00f6rtes Geb\u00e4ude oder einen Keller. Sie melden ihre Position. Dann folgen weitere Trupps, die versuchen, diesen Punkt zu verst\u00e4rken. Schritt f\u00fcr Schritt entsteht so ein kleiner Br\u00fcckenkopf. Das ist extrem langsam, extrem verlustreich. Aber genau so wird aktuell gek\u00e4mpft.<\/p>\n<p><img alt=\"Ukrainische Soldaten der 43. Artilleriebrigade feuern mit einer Panzerhaubitze auf russische Stellungen an der Frontlinie in der Region Donezk.\" loading=\"lazy\" width=\"2048\" height=\"1365\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto\"   src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/ff3af0a0-5760-4c7f-8c21-7e3544ebe0fc.jpg\"\/><\/p>\n<p>Ukrainische Soldaten der 43. Artilleriebrigade feuern mit einer Panzerhaubitze auf russische Stellungen an der Frontlinie in der Region Donezk.Evgeniy Maloletka\/AP<\/p>\n<p class=\"article_paragraph__hXYKJ\">Wenn wir noch einmal auf Ihre Dreiteilung zur\u00fcckkommen \u2013 strategisch, operativ, taktisch: Was bedeutet das konkret auf der taktischen Ebene?<\/p>\n<p>Auf der taktischen Ebene sehen wir derzeit die wohl gravierendste Ver\u00e4nderung dieses Krieges. Die Drohnenkriegsf\u00fchrung ist so dominant geworden, dass man fast sagen kann: Es bewegt sich keine Maus mehr unbeobachtet. Wir haben es heute mit gro\u00dffl\u00e4chigen \u201eKill-Zonen\u201c zu tun, die von Aufkl\u00e4rungs- und Kampfdrohnen permanent \u00fcberwacht werden. Klassische Bewegungen \u2013 etwa mit Fahrzeugen oder gar gr\u00f6\u00dferen Verb\u00e4nden \u2013 sind kaum noch m\u00f6glich. Auch von Panzern ist kaum noch die Rede.<\/p>\n<p class=\"article_paragraph__hXYKJ\">Immer wieder h\u00f6rt man, der Ukraine-Krieg sei ein Drohnenkrieg geworden.<\/p>\n<p>Sobald sich etwas bewegt, wird es bek\u00e4mpft. Das f\u00fchrt dazu, dass beide Seiten gezwungen sind, mit kleinsten Einheiten zu operieren. Diese bewegen sich zu Fu\u00df, oft \u00fcber Stunden oder Tage, und versuchen punktuell Gel\u00e4nde zu gewinnen. Selbst die Versorgung erfolgt mittlerweile vielfach \u00fcber Drohnen oder unbemannte Bodenfahrzeuge. Ein weiterer entscheidender Punkt: Es gibt bislang keine wirkliche Antwort auf diese Dominanz der Drohnen. Man hatte gehofft, \u00fcber elektronische Kriegsf\u00fchrung einen Vorteil zu erzielen. Doch dann kamen etwa glasfasergesteuerte Drohnen, die sich dieser St\u00f6rung entziehen. Deshalb sehen wir heute einen hochgradig technisierten Abnutzungskrieg, in dem sich beide Seiten permanent anpassen. Ein klassisches \u201eKatz-und-Maus-Spiel\u201c. Es ist ein regelrechter \u201eKrieg der Roboter\u201c, auch wenn die Systeme noch von Menschen gesteuert werden.<\/p>\n<p class=\"article_paragraph__hXYKJ\">In den vergangenen Kriegsjahren sorgten die Fr\u00fchjahrsoffensiven hin und wieder f\u00fcr Bewegung entlang der Frontlinie. Wie schaut es jetzt aus? <\/p>\n<p>Die Fr\u00fchjahrsoffensive dient vor allem der Vorbereitung \u2013 dem sogenannten \u201eShaping\u201c. Dabei geht es darum, g\u00fcnstige Ausgangspositionen f\u00fcr die eigentliche Sommeroffensive zu schaffen. Zum Beispiel, indem man wichtige Gel\u00e4ndeabschnitte, wie zum Beispiel H\u00f6hen oder Fluss\u00fcberg\u00e4nge, sichert.<\/p>\n<p class=\"article_paragraph__hXYKJ\">In welchem Zeitraum bewegen wir uns hier?<\/p>\n<p>Traditionell reicht die Fr\u00fchjahrsoffensive bis etwa April oder Mai. Ab Juni beginnt die Sommeroffensive. Ein wichtiger Faktor ist die Vegetation im Donbass: Mit zunehmendem Laub und Bl\u00e4tterbewuchs haben die Soldaten und ihr Kriegsger\u00e4t es wieder leichter, sich zu tarnen, Bewegungen werden einfacher m\u00f6glich. Zudem gibt es im Fr\u00fchjahr h\u00e4ufig Nebelphasen, die f\u00fcr gezielte Vorst\u00f6\u00dfe genutzt werden.<\/p>\n<p class=\"article_paragraph__hXYKJ\">Herr Reisner, was waren aus Ihrer Sicht die gr\u00f6\u00dften strategischen Fehler im bisherigen Kriegsverlauf?<\/p>\n<p>Auf russischer Seite war der gr\u00f6\u00dfte Fehler die massive Untersch\u00e4tzung der Ukraine zu Beginn des Krieges. Man ist mit Annahmen und Methoden aus 2014 in diesen Krieg gegangen und das hat nicht funktioniert. Die Ukraine hat aus den Erfahrungen seit 2014 gelernt und sich besser vorbereitet als erwartet. In <a href=\"https:\/\/www.berliner-zeitung.de\/topics\/moskau\" rel=\"nofollow noopener\" target=\"_blank\">Moskau<\/a> hat man anscheinend wirklich gedacht, man k\u00f6nne Kiew in drei Tagen einnehmen. Das ist kl\u00e4glich gescheitert.<\/p>\n<p><img alt=\"Der ehemalige US-Pr\u00e4sident Joe Biden und der ukrainische Pr\u00e4sident Wolodymyr Selenskyj\" loading=\"lazy\" width=\"2048\" height=\"1365\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto\"   src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/479d2b56-a2a9-4066-8d51-e2090692d18b.jpg\"\/><\/p>\n<p>Der ehemalige US-Pr\u00e4sident Joe Biden und der ukrainische Pr\u00e4sident Wolodymyr SelenskyjEvan Vucci\/AP<\/p>\n<p class=\"article_paragraph__hXYKJ\">Und auf ukrainischer Seite?<\/p>\n<p>Aus meiner Sicht war der gr\u00f6\u00dfte strategische Fehler, im Sommer 2022 ein m\u00f6gliches Verhandlungsfenster nicht genutzt zu haben. Nach den ukrainischen Erfolgen bei Kiew, Charkiw und Cherson gab es einen Moment, in dem \u2013 auch auf Initiative der USA unter Joe Biden \u2013 Verhandlungen m\u00f6glich gewesen w\u00e4ren. Damals lagen die Verluste auf beiden Seiten bereits bei rund je 140.000 Toten und Verwundeten. Der damalige US-Generalstabschef Mark Milley hat \u00f6ffentlich gesagt: Das ist der Moment f\u00fcr Verhandlungen. Die Ukraine hat sich dagegen entschieden, auch aus einer verst\u00e4ndlichen Euphorie heraus.<\/p>\n<p class=\"article_paragraph__hXYKJ\">Welche Konsequenzen hatte das?<\/p>\n<p>Eine Chance wurde nicht genutzt. Vermutlich h\u00e4tte es damals einen Kompromiss gegeben. Wahrscheinlich w\u00e4re das kein perfekter Frieden f\u00fcr die ukrainische F\u00fchrung gewesen, aber ein fr\u00fcherer Kriegsstopp. Heute laufen alle realistischen Szenarien darauf hinaus, dass die Ukraine Territorium abgeben muss. Da ist es egal, ob es auf das koreanische, deutsche oder finnische Modell hinausl\u00e4uft.<\/p>\n<p class=\"article_paragraph__hXYKJ\">K\u00f6nnen Sie diese drei Szenarien kurz erkl\u00e4ren?<\/p>\n<p>Das sind drei h\u00e4ufig diskutierte Optionen f\u00fcr ein m\u00f6gliches Kriegsende, die sich historisch ableiten. Das koreanische Modell w\u00fcrde bedeuten: ein Waffenstillstand entlang einer Frontlinie, ohne echten Friedensvertrag. Also eine dauerhaft milit\u00e4risch gesicherte Grenze, vergleichbar mit Nord- und S\u00fcdkorea. Der Konflikt w\u00e4re damit eingefroren, aber nicht gel\u00f6st. Das deutsche Modell meint eine Teilung des Landes mit klarer politischer und milit\u00e4rischer Ausrichtung. Also eine West-Ukraine, die sich stark an EU und <a href=\"https:\/\/www.berliner-zeitung.de\/topics\/nato\" rel=\"nofollow noopener\" target=\"_blank\">Nato<\/a> orientiert beziehungsweise deren Mitglied ist, und ein von Russland kontrollierter Teil im Osten.<\/p>\n<p class=\"article_paragraph__hXYKJ\">\u00c4hnlich wie die Bundesrepublik und die DDR im Kalten Krieg.<\/p>\n<p>Genau. Und das finnische Modell, angelehnt an den finnisch-sowjetischen Krieg von 1939\/40, w\u00e4re eine Art Kompromissl\u00f6sung. Die Ukraine m\u00fcsste Gebiete abgeben, w\u00fcrde aber als souver\u00e4ner Staat bestehen bleiben und sich langfristig politisch und wirtschaftlich an den Westen ann\u00e4hern. \u00c4hnlich wie eben Finnland nach dem Zweiten Weltkrieg gegen\u00fcber der Sowjetunion.<\/p>\n<p class=\"article_paragraph__hXYKJ\">Alle drei Szenarien haben aber auch etwas gemeinsam.<\/p>\n<p>Ja, dass die Ukraine Territorium abgeben muss. Der Unterschied liegt vor allem darin, wie stabil diese L\u00f6sung w\u00e4re und wie stark die Ukraine politisch und milit\u00e4risch abgesichert wird. Und genau hier liegt auch das Kernproblem aus Sicht der ukrainischen F\u00fchrung. Die Frage ist: Wer garantiert, dass Russland nicht zu einem sp\u00e4teren Zeitpunkt erneut angreift?<\/p>\n<p class=\"article_paragraph__hXYKJ\">Kommen wir zur Mobilisierung. Wie stellt sich die Lage in der Ukraine dar?<\/p>\n<p>Das zentrale Problem ist die Verf\u00fcgbarkeit von Soldaten. Russland hat aufgrund seiner Bev\u00f6lkerungsgr\u00f6\u00dfe (ca. 145 Millionen) einen klaren Vorteil gegen\u00fcber der Ukraine. Zudem sorgt das Wehrpflichtsystem daf\u00fcr, dass kontinuierlich ausgebildete Soldaten in einem Vertragsverh\u00e4ltnis verf\u00fcgbar sind. Hinzu kommen finanzielle Anreize, gerade in wirtschaftlich schw\u00e4cheren Regionen au\u00dferhalb des Moskauer Rings oder Sankt Petersburgs.<\/p>\n<p><img alt=\"Russische Soldaten auf dem Roten Platz in Moskau\" loading=\"lazy\" width=\"4305\" height=\"2870\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto\"   src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/675da6c4-6481-45cb-8d58-90ea00414749.jpg\"\/><\/p>\n<p>Russische Soldaten auf dem Roten Platz in MoskauYekaterina Shtukina\/imago<\/p>\n<p class=\"article_paragraph__hXYKJ\">Und wie sieht es auf ukrainischer Seite aus?<\/p>\n<p>Die Ukraine hat deutlich weniger Bev\u00f6lkerung \u2013 etwa 30 bis 35 Millionen Menschen leben aktuell noch in den ukrainisch kontrollierten Gebieten. Zudem gibt es ein massives demografisches Problem. In den 1990er- und 2000er-Jahren wurden deutlich weniger Kinder geboren. Das f\u00fchrt heute zu einem Mangel an jungen Soldaten im wehrf\u00e4higen Alter. Deshalb greift die Ukraine h\u00e4ufig auf \u00e4ltere Jahrg\u00e4nge zur\u00fcck.<\/p>\n<p class=\"article_paragraph__hXYKJ\">Welche Rolle spielt dabei die sogenannte Busifizierung?<\/p>\n<p>Die Rekrutierungsma\u00dfnahmen sind deutlich h\u00e4rter geworden. Das ist Ausdruck des Mangels an Personal. Gleichzeitig bleibt die Frage politisch sensibel, ob j\u00fcngere Jahrg\u00e4nge st\u00e4rker einbezogen werden sollen. Hier gab es auch Druck aus den USA, dass die Ukraine endlich im gr\u00f6\u00dferen Ausma\u00df mobilisieren solle.<\/p>\n<p class=\"article_paragraph__hXYKJ\">Versucht die Ukraine, das durch ausl\u00e4ndische K\u00e4mpfer zu kompensieren?<\/p>\n<p>Ja. Es gibt Sch\u00e4tzungen, dass bis zu 20.000 ausl\u00e4ndische K\u00e4mpfer, vor allem aus Mittel- und S\u00fcdamerika, in der Ukraine im Einsatz sind. Beispielsweise in der Internationalen Legion. Aber auch Russland nutzt externe Unterst\u00fctzung, etwa aus Nordkorea oder afrikanischen Staaten.<\/p>\n<p class=\"article_paragraph__hXYKJ\">Was bedeutet das langfristig?<\/p>\n<p>Am Ende bleibt es ein Ressourcen- und somit Abnutzungskrieg, und vor allem ein Krieg der verf\u00fcgbaren Soldaten. Die Ukraine versucht vermehrt, durch Drohnen den Gegner st\u00e4rker zu dezimieren, als dieser neue Soldaten nachf\u00fchren kann. Ob das auf lange Sicht gelingt, ist jedoch offen.<\/p>\n<p class=\"article_paragraph__hXYKJ\">Ukraine-Kenner, aber auch Laien beobachten, dass es sich hin zu einem eingefrorenen Konflikt entwickelt. Stimmen Sie dem zu?<\/p>\n<p>Teilweise. Gro\u00dfe Bewegungsman\u00f6ver, wie wir sie aus fr\u00fcheren Etappen des Ukraine-Kriegs kennen, gibt es kaum noch. Aber der Krieg ist nicht eingefroren. Er hat sich blo\u00df ver\u00e4ndert. Statt klarer Frontlinien gibt es heute breite Grauzonen, sogenannte \u201eKill-Zonen\u201c. Dort operieren kleine Einheiten, unterst\u00fctzt von Drohnen. Fortschritte sind sehr wohl m\u00f6glich, aber meist nur in sehr kleinen Schritten.<\/p>\n<p class=\"article_paragraph__hXYKJ\">Warum entsteht dann bei vielen, besonders in Deutschland, der Eindruck vom Stillstand?<\/p>\n<p>Weil Erfolge oft nur selektiv wahrgenommen werden. Ukrainische Fortschritte werden st\u00e4rker berichtet, russische weniger. Ein Beispiel ist die Stadt Pokrowsk. Sie ist faktisch f\u00fcr die Ukrainer bereits fr\u00fch gefallen. Das wird aber oft so nicht festgestellt, weil sich die Ukrainer in noch ein oder zwei H\u00e4userbl\u00f6cken verschanzt haben.<\/p>\n<p class=\"article_paragraph__hXYKJ\">Welche Rolle spielen aktuell internationale Unterst\u00fctzungsma\u00dfnahmen?<\/p>\n<p>Eine sehr gro\u00dfe. Die USA und ausgew\u00e4hlte europ\u00e4ische Staaten liefern der Ukraine umfangreiche Aufkl\u00e4rungsdaten. Das ist ein entscheidender Vorteil. Ich vergleiche das gerne mit einem Boxkampf. Beide K\u00e4mpfer stehen im Ring, der eine bekommt aber gro\u00dfe zus\u00e4tzliche Unterst\u00fctzung von au\u00dfen. Er hat quasi Hufeisen in seinen Boxhandschuhen.<\/p>\n<p><img alt=\"Ukrainische Soldaten verfolgen auf Monitoren die \u00dcbertragung von Drohnen in einer unterirdischen Kommandozentrale.\" loading=\"lazy\" width=\"3054\" height=\"2036\" decoding=\"async\" data-nimg=\"1\" style=\"color:transparent;width:100%;height:auto\"   src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/ecdb8d5c-98ab-4500-a43f-073360855cc9.jpg\"\/><\/p>\n<p>Ukrainische Soldaten verfolgen auf Monitoren die \u00dcbertragung von Drohnen in einer unterirdischen Kommandozentrale.Libkos\/AP<\/p>\n<p class=\"article_paragraph__hXYKJ\">Und auf der Gegenseite?<\/p>\n<p>Russland und China unterst\u00fctzen wiederum den Iran, etwa bei Zielaufkl\u00e4rung. Das ist im Grunde das gleiche Prinzip. Selbst US-Pr\u00e4sident Donald Trump hat sinngem\u00e4\u00df gesagt: \u201eWir machen es \u2013 und sie machen es auch.\u201c Nun k\u00e4mpft der Iran mit russischen und chinesischen Hufeisen in seinen Boxhandschuhen. Das bedeutet empfindliche Treffer f\u00fcr die USA.<\/p>\n<p class=\"article_paragraph__hXYKJ\">Was w\u00fcrde passieren, wenn die USA ihre Unterst\u00fctzung in der Ukraine-Frage zur\u00fcckfahren?<\/p>\n<p>Dann h\u00e4tte Kiew ein massives Problem, vor allem im Bereich Aufkl\u00e4rung. Ohne die US-Geheimdienstdaten w\u00e4re die ukrainische Armee bei ihren weitreichenden Drohnenangriffen in Russland blind. Europa kann das nur begrenzt kompensieren, weil die entsprechenden F\u00e4higkeiten nicht im gleichen Umfang vorhanden sind. Die Qualit\u00e4t der US-Informationen ist enorm hoch. Das wurde sp\u00e4testens durch die geleakten Geheimdokumente im Jahr 2023 deutlich. Damals hat ein amerikanischer Soldat Geheimdokumente auf Discord geteilt.<\/p>\n<p class=\"article_paragraph__hXYKJ article_paragraph_end-of-article-icon__tzjPO\">Herr Oberst, was ist Ihr Gesamtfazit zur aktuellen Lage?<\/p>\n<p>Dieser Krieg wird am Ende von der Seite entschieden, die die meisten Ressourcen mobilisieren kann, materiell und personell. Und aktuell sehen wir, dass sich genau diese Voraussetzungen, beeinflusst durch die Bindung der USA im Krieg mit dem Iran, zugunsten der Russen und ihrer chinesischen und nordkoreanischen Verb\u00fcndeten verschieben. Die Hoffnung auf einen baldigen Frieden schwindet, und der blutige und elende Krieg setzt sich fort.<\/p>\n","protected":false},"excerpt":{"rendered":"Der Ukraine-Krieg ger\u00e4t fast schon in Vergessenheit. Der Krieg im Iran bestimmt das geopolitische Geschehen dieser Tage. Dabei&hellip;\n","protected":false},"author":2,"featured_media":903294,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4012],"tags":[331,332,13,14,15,12,317],"class_list":{"0":"post-903293","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ukraine","8":"tag-aktuelle-nachrichten","9":"tag-aktuelle-news","10":"tag-headlines","11":"tag-nachrichten","12":"tag-news","13":"tag-schlagzeilen","14":"tag-ukraine"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116306837003069386","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/903293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=903293"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/903293\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/903294"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=903293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=903293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=903293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}