{"id":905004,"date":"2026-03-29T05:27:14","date_gmt":"2026-03-29T05:27:14","guid":{"rendered":"https:\/\/www.europesays.com\/de\/905004\/"},"modified":"2026-03-29T05:27:14","modified_gmt":"2026-03-29T05:27:14","slug":"no-kings-usa-weite-proteste-gegen-trump","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/905004\/","title":{"rendered":"&#8222;No Kings&#8220;: USA-weite Proteste gegen Trump"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" fetchpriority=\"low\" alt=\"Unter dem Motto &quot;No Kings&quot; kritisieren Millionen Demonstranten die Politik Trumps.\" class=\"pei0kpe\"\/><\/p>\n<p class=\"c1pbsmr2\">Zum dritten Mal wollen Millionen Menschen unter dem Motto &#8222;No Kings&#8220; gegen die Politik von US-Pr\u00e4sident Donald Trump demonstrieren.<\/p>\n<p>28.03.2026 | 1:41 min<\/p>\n<p class=\"r1nj4qn5 rvqyqzi\">Plakate mit durchgestrichenen Kronen, Demonstrierende in Verkleidungen als Parodien von US-Pr\u00e4sident <a data-testid=\"richtext-link\" class=\"_nl_\" id=\"3e011e66\" href=\"https:\/\/www.zdfheute.de\/thema\/donald-trump-742.html\" rel=\"nofollow noopener\" target=\"_blank\">Donald Trump<\/a> und Mitgliedern seiner Regierung &#8211; und immer wieder laute Sprechch\u00f6re: &#8222;No Kings, no Kings&#8220;, also &#8222;keine K\u00f6nige, keine K\u00f6nige&#8220;.<\/p>\n<p class=\"r1nj4qn5 rvqyqzi\">Am Samstag protestierten landesweit Millionen Menschen in den USA gegen die Politik von Trump. Nach Angaben der Organisatoren beteiligten sich insgesamt mehr als acht Millionen Menschen an Demonstrationen in allen 50 Bundesstaaten. Die Angaben lassen sich derzeit nicht unabh\u00e4ngig \u00fcberpr\u00fcfen.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" fetchpriority=\"low\" alt=\"Donald Trumps Gesicht und das gelbe auslandsjournal-a.\" class=\"pei0kpe\"\/><\/p>\n<p class=\"c1pbsmr2\">US-Pr\u00e4sident Trump pflegt enge wirtschaftliche Beziehungen in die Golfregion, ebenso wie einige seiner engsten Vertrauten. Doch welche Rolle spielen die Interessen des Trump-Clans im Iran-Krieg?<\/p>\n<p>25.03.2026 | 6:16 min<\/p>\n<p>Kritik an Machtanspruch und Politik der US-Regierung<\/p>\n<p class=\"r1nj4qn5 rvqyqzi\">Unter dem Motto &#8222;No Kings&#8220; &#8211; also gegen eine Art Alleinherrschaft &#8211; werfen die Demonstrierenden der Regierung vor, demokratische Prinzipien wie Meinungsfreiheit, B\u00fcrgerrechte und das Wahlrecht zu gef\u00e4hrden. Bei Protesten in Washington, D.C. sagten Teilnehmende gegen\u00fcber ZDFheute: <\/p>\n<blockquote class=\"bosa0j6\">\n<p class=\"tley63f hhhtovw\">Ich m\u00f6chte, dass er und seine Administration transparent sind und aufh\u00f6ren zu l\u00fcgen.<\/p>\n<p>\u201e<\/p><\/blockquote>\n<p class=\"abqjgdv m1lnp037\">Demonstrant in Washington, D.C. <\/p>\n<blockquote class=\"bosa0j6\">\n<p class=\"tley63f hhhtovw\">Unsere Demokratie ist in Gefahr.<\/p>\n<p>\u201e<\/p><\/blockquote>\n<p class=\"abqjgdv m1lnp037\">Demonstrantin in Washington, D.C.<\/p>\n<blockquote class=\"bosa0j6\">\n<p class=\"tley63f hhhtovw\">Ich m\u00f6chte, dass die Demokratie hier gesch\u00fctzt wird in den USA. Ich bin in Deutschland geboren und kann vergleichen, welche Geschichte wir erfahren haben.<\/p>\n<p>\u201e<\/p><\/blockquote>\n<p class=\"abqjgdv m1lnp037\">Demonstrant in Washington, D.C.<\/p>\n<p>US-Philosoph<\/p>\n<p>:<a class=\"f1mro3s7 lzfsw8u _nl_\" id=\"00b37c7a\" href=\"https:\/\/www.zdfheute.de\/politik\/ausland\/usa-trump-jason-stanley-interview-100.html\" rel=\"nofollow noopener\" target=\"_blank\">Stanley: &#8222;USA sind ein autorit\u00e4res Regime&#8220;<\/a><\/p>\n<p>US-Philosoph Jason Stanley warnt im ZDF: Die USA sind kein demokratischer Staat mehr, sondern &#8222;ein autorit\u00e4res Regime&#8220;. Es gebe einen F\u00fchrerkult und kaum Widerstand gegen Trump.<\/p>\n<p>mit Video5:19<\/p>\n<p><img src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/donald-trump-us-open-100~1920x1080.jpeg\"  alt=\"Donald Trump\" decoding=\"async\" loading=\"lazy\"  style=\"object-fit:cover;object-position:center\" fetchpriority=\"low\" class=\"f1mqliu0\"\/><\/p>\n<p>Interview<\/p>\n<p>Dritter gro\u00dfer &#8222;No Kings&#8220;-Protesttag <\/p>\n<blockquote class=\"bosa0j6\">\n<p class=\"tley63f hhhtovw\">Ich m\u00f6chte nicht, dass wir im Krieg sind. Trump hat gesagt, dass wir nicht in den Krieg gehen. Und jetzt sind wir aktiv in Kriegen, in denen wir nicht sein sollten.<\/p>\n<p>\u201e<\/p><\/blockquote>\n<p class=\"abqjgdv m1lnp037\">Demonstrantin in Washington, D.C.<\/p>\n<blockquote class=\"bosa0j6\">\n<p class=\"tley63f hhhtovw\">Ich fordere, dass Trump den Krieg in Iran stoppt, ich fordere, dass Trump anf\u00e4ngt, sich um die Menschen in den USA zu k\u00fcmmern.<\/p>\n<p>\u201e<\/p><\/blockquote>\n<p class=\"abqjgdv m1lnp037\">Demonstrantin in Washington, D.C.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" fetchpriority=\"low\" alt=\"Demonstranten nehmen an der \u00abNo Kings\u00bb-Demonstration teil und halten ihre Schilder hoch.\" class=\"pei0kpe\"\/><\/p>\n<p class=\"c1pbsmr2\">Mit einer Milit\u00e4rparade hat US-Pr\u00e4sident Trump das 250. Jubil\u00e4um der US-Armee und seinen 79. Geburtstag gefeiert. Zeitgleich hat sich der bisher gr\u00f6\u00dfte Protest gegen ihn formiert.<\/p>\n<p>15.06.2025 | 0:21 min<\/p>\n<p>Bruce Springsteen in Minnesota aufgetreten <\/p>\n<p class=\"r1nj4qn5 rvqyqzi\">Landesweit wurde demonstriert &#8211; in Metropolen ebenso wie in kleineren St\u00e4dten. Laut Organisatoren kamen die Teilnehmenden aus ganz unterschiedlichen Regionen, auch aus konservativen l\u00e4ndlichen Gebieten und Vororten.<\/p>\n<p class=\"r1nj4qn5 rvqyqzi\">Bei einer zentralen Veranstaltung in St. Paul im US-Staat Minnesota trat unter anderem <a data-testid=\"richtext-link\" class=\"_nl_\" id=\"0d5764a5\" href=\"https:\/\/www.zdfheute.de\/video\/zdfheute-xpress\/bruce-springsteen-proteste-ice-trump-video-100.html\" rel=\"nofollow noopener\" target=\"_blank\">Bruce Springsteen<\/a> auf. Er unterst\u00fctzte die Proteste mit seinem neuen Song &#8222;Streets of Minneapolis&#8220;, der sich gegen umstrittene Abschiebe-Razzien richtet.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" fetchpriority=\"low\" alt=\"Bruce Springsteen tritt im Rahmen eines mit Rockstars besetzten Konzerts im First Avenue im Stadtzentrum von Minneapolis auf.\" class=\"pei0kpe\"\/><\/p>\n<p class=\"c1pbsmr2\">In den USA wurde in vielen St\u00e4dten gegen den US-Pr\u00e4sidenten und ICE demonstriert. In Minneapolis trat Rockstar Bruce Springsteen mit seinem Protestsong auf.<\/p>\n<p>31.01.2026 | 1:43 min<\/p>\n<p>&#8222;No Kings&#8220;-Proteste in Deutschland <\/p>\n<p class=\"r1nj4qn5 rvqyqzi\">Auch au\u00dferhalb der USA gab es Proteste gegen die US-Regierung, unter anderem in mehreren deutschen St\u00e4dten. In <a data-testid=\"richtext-link\" class=\"_nl_\" id=\"f5aa8ef4\" href=\"https:\/\/www.zdfheute.de\/thema\/berlin-news-100.html\" rel=\"nofollow noopener\" target=\"_blank\">Berlin<\/a> warfen Demonstrierende Trump Angriffe auf die Demokratie vor, kritisierten ICE und forderten die Freigabe der Epstein-Akten rund um <a data-testid=\"richtext-link\" class=\"_nl_\" id=\"ce9d11e6\" href=\"https:\/\/www.zdfheute.de\/thema\/jeffrey-epstein-110.html\" rel=\"nofollow noopener\" target=\"_blank\">Jeffrey Epstein<\/a>. Auch in M\u00fcnchen und Frankfurt gingen Menschen auf die Stra\u00dfe.<\/p>\n<p class=\"r1nj4qn5 rvqyqzi\">Das Wei\u00dfe Haus kritisierte den Protesttag: Eine Sprecherin hatte die Veranstaltungen laut Medienberichten vorab als Treffen einer kleinen, von linken Netzwerken unterst\u00fctzten Gruppe ohne breite Unterst\u00fctzung in der Bev\u00f6lkerung bezeichnet.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" fetchpriority=\"low\" alt=\"Bruce Springsteen tritt im Rahmen eines mit Rockstars besetzten Konzerts im First Avenue im Stadtzentrum von Minneapolis auf, um gegen Bundesbeamte in Minnesota zu protestieren.\" class=\"pei0kpe\"\/><\/p>\n<p class=\"c1pbsmr2\">Am Freitag spielte Bruce Springsteen in Minneapolis ein Benefizkonzert, das die Familien von Pretti und Good unterst\u00fctzen soll. Sie wurden von ICE- und Grenzschutzbeamten get\u00f6tet.<\/p>\n<p>31.01.2026 | 0:42 min<\/p>\n<p class=\"r1nj4qn5 rvqyqzi\">Fr\u00e4nzi Meyer ist Reporterin im ZDF-Studio Washington, D.C.<\/p>\n<p>\u00dcber dieses Thema berichteten am 28.03.2026 mehrere Sendungen, etwa die heute-Nachrichten ab 19:00 Uhr und das <a data-testid=\"richtext-link\" class=\"_nl_\" id=\"c06425bd\" href=\"https:\/\/www.zdfheute.de\/video\/heute-journal-update\/ausblick-am-wochenende-100.html\" rel=\"nofollow noopener\" target=\"_blank\">heute journal update<\/a> ab 00:20 Uhr.<\/p>\n","protected":false},"excerpt":{"rendered":"Zum dritten Mal wollen Millionen Menschen unter dem Motto &#8222;No Kings&#8220; gegen die Politik von US-Pr\u00e4sident Donald Trump&hellip;\n","protected":false},"author":2,"featured_media":905005,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3977],"tags":[331,332,13,14,15,12,4017,4018,4016,64,4019,4020],"class_list":{"0":"post-905004","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-usa","8":"tag-aktuelle-nachrichten","9":"tag-aktuelle-news","10":"tag-headlines","11":"tag-nachrichten","12":"tag-news","13":"tag-schlagzeilen","14":"tag-united-states","15":"tag-united-states-of-america","16":"tag-us","17":"tag-usa","18":"tag-vereinigte-staaten","19":"tag-vereinigte-staaten-von-amerika"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116310811992634217","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/905004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=905004"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/905004\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/905005"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=905004"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=905004"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=905004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}