{"id":905960,"date":"2026-03-29T15:00:28","date_gmt":"2026-03-29T15:00:28","guid":{"rendered":"https:\/\/www.europesays.com\/de\/905960\/"},"modified":"2026-03-29T15:00:28","modified_gmt":"2026-03-29T15:00:28","slug":"zwei-abende-eine-band-kraftklub-reissen-kiel-und-bremen-gleichermassen-ab","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/905960\/","title":{"rendered":"Zwei Abende, eine Band: Kraftklub rei\u00dfen Kiel und Bremen gleicherma\u00dfen ab"},"content":{"rendered":"<p> Zwei Abende, eine Band: Kraftklub rei\u00dfen Kiel und Bremen gleicherma\u00dfen ab &#8211; frontstage-magazine.de<br \/>\n   <br \/><b>Cookie Hinweis<\/b><br \/> Diese Website verwendet Cookies, um Ihre Erfahrung zu verbessern und um die Bereitstellung einiger Dienste zu erleichtern. Mit der Nutzung unserer Dienste erkl\u00e4ren Sie sich damit einverstanden, dass wir Cookies verwenden. <b><a href=\"https:\/\/frontstage-magazine.de\/datenschutzerklaerung\/\" id=\"CONSTANT_OPEN_URL\" class=\"cli-plugin-main-link\" rel=\"nofollow noopener\" target=\"_blank\">Datenschutzerkl\u00e4rung<\/a><\/b><\/p>\n<p>Datenschutz- &amp; Cookie-Richtlinie<\/p>\n","protected":false},"excerpt":{"rendered":"Zwei Abende, eine Band: Kraftklub rei\u00dfen Kiel und Bremen gleicherma\u00dfen ab &#8211; frontstage-magazine.de Cookie Hinweis Diese Website verwendet&hellip;\n","protected":false},"author":2,"featured_media":905961,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1852],"tags":[2420,3364,29,548,663,3934,30,13,4949,44170,14,15,19424,12,1971],"class_list":{"0":"post-905960","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-kiel","8":"tag-bremen","9":"tag-de","10":"tag-deutschland","11":"tag-eu","12":"tag-europa","13":"tag-europe","14":"tag-germany","15":"tag-headlines","16":"tag-kiel","17":"tag-kraftklub","18":"tag-nachrichten","19":"tag-news","20":"tag-review","21":"tag-schlagzeilen","22":"tag-schleswig-holstein"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116313065134642137","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/905960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=905960"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/905960\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/905961"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=905960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=905960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=905960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}