{"id":91128,"date":"2025-05-07T08:28:12","date_gmt":"2025-05-07T08:28:12","guid":{"rendered":"https:\/\/www.europesays.com\/de\/91128\/"},"modified":"2025-05-07T08:28:12","modified_gmt":"2025-05-07T08:28:12","slug":"microsoft-streicht-vr-support-fuer-minecraft","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/91128\/","title":{"rendered":"Microsoft streicht VR-Support f\u00fcr &#8222;Minecraft&#8220;"},"content":{"rendered":"<p>Minecraft und VR \u2013 auf den ersten Blick eine unschlagbare Kombination. Doch offenbar kam die virtuelle Realit\u00e4t auch bei Minecraft-Spielern nicht gut genug an: Microsoft hat den VR-Support mit dem j\u00fcngsten Update f\u00fcr die Bedrock-Variante von &#8222;Minecraft&#8220; eingestellt.<\/p>\n<p>&#8222;Zugang zu Gameplay in Virtual und Mixed Reality entfernt&#8220;, hei\u00dft es in den <a href=\"https:\/\/www.minecraft.net\/en-us\/article\/minecraft-bedrock-edition-1-21-80\" rel=\"external noopener nofollow\" target=\"_blank\">Patchnotes von Version 1.21.80 schlicht<\/a>. Ein bisschen ausf\u00fchrlicher, aber kaum aussagekr\u00e4ftiger ist die Ank\u00fcndigung aus dem vergangenen Jahr. Damals hatte Microsoft bereits angek\u00fcndigt, dass der VR-Support im Fr\u00fchjahr 2025 enden w\u00fcrde. &#8222;Unsere F\u00e4higkeit, &#8222;VR\/MR-Ger\u00e4te zu unterst\u00fctzen, ist am Ende angekommen&#8220;, schrieb Microsoft damals.<\/p>\n<p>Eine wirkliche Begr\u00fcndung f\u00fcr das Aus des VR-Supports von Minecraft bleibt Microsoft also schuldig. Es liegt nahe, dass die VR-Version des Kreativspiels nicht von genug Usern gespielt wurde. \u00c4rgerlich ist der Schritt f\u00fcr die Fans des VR-&#8222;Minecrafts&#8220;. Die Funktion wurde mit dem j\u00fcngsten Patch g\u00e4nzlich entfernt und kann nicht mehr genutzt werden.<\/p>\n<p>Mod-Alternative Vivecraft<\/p>\n<p>Als Alternative bleibt nur die Nutzer-Mod Vivecraft, <a href=\"https:\/\/www.pcworld.com\/article\/2773555\" rel=\"external noopener nofollow\" target=\"_blank\">\u00fcber die das Magazin PCWorld berichtet<\/a>. W\u00e4hrend der offizielle VR-Support von &#8222;Minecraft&#8220; sich auf die Bedrock-Version beschr\u00e4nkte, ist <a href=\"https:\/\/www.vivecraft.org\/\" rel=\"external noopener nofollow\" target=\"_blank\">Vivecraft<\/a> lediglich f\u00fcr die Java-Variante des Kreativspiels verf\u00fcgbar. Besitzer von VR-Headsets m\u00fcssen also auf die andere Variante von &#8222;Minecraft&#8220; umsteigen. Das ist finanziell verschmerzbar, bedeutet aber auch einen neuen Spielstand und damit das Ende von m\u00f6glicherweise lange gepflegten Spielwelten und Bauten.<\/p>\n<p>Microsoft hat seine Mixed-Reality-Bem\u00fchungen in den vergangenen Jahren weitgehend eingestellt. Ein eigenes VR-Headset hat das Unternehmen nie auf den Markt gebracht, stattdessen probierte man es mit der Hololens in der Augmented Reality. <a href=\"https:\/\/www.heise.de\/news\/Aus-fuer-Hololens-Microsoft-uebergibt-Militaerauftraege-an-Anduril-10281800.html\" rel=\"nofollow noopener\" target=\"_blank\">Auch diese Experimente wurden mittlerweile aber beendet.<\/a><\/p>\n<p>(<a class=\"redakteurskuerzel__link\" href=\"https:\/\/www.heise.de\/news\/mailto:dahe@heise.de\" title=\"Daniel Herbig\" rel=\"nofollow noopener\" target=\"_blank\">dahe<\/a>)<\/p>\n","protected":false},"excerpt":{"rendered":"Minecraft und VR \u2013 auf den ersten Blick eine unschlagbare Kombination. Doch offenbar kam die virtuelle Realit\u00e4t auch&hellip;\n","protected":false},"author":2,"featured_media":91129,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_share_on_mastodon":"0"},"categories":[135],"tags":[29,214,30,5682,190,189,8267,194,191,16517,193,192],"class_list":["post-91128","post","type-post","status-publish","format-standard","has-post-thumbnail","category-wissenschaft-technik","tag-deutschland","tag-entertainment","tag-germany","tag-minecraft","tag-science","tag-science-technology","tag-spiele","tag-technik","tag-technology","tag-virtual-reality","tag-wissenschaft","tag-wissenschaft-technik"],"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/114465610581879111","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/91128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=91128"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/91128\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/91129"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=91128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=91128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=91128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}