{"id":912203,"date":"2026-04-01T02:57:15","date_gmt":"2026-04-01T02:57:15","guid":{"rendered":"https:\/\/www.europesays.com\/de\/912203\/"},"modified":"2026-04-01T02:57:15","modified_gmt":"2026-04-01T02:57:15","slug":"ukraine-krieg-im-liveticker-0425-wadephul-und-kallas-uebergeben-hilfslieferungen-an-ukraine","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/912203\/","title":{"rendered":"Ukraine-Krieg im Liveticker: +++ 04:25 Wadephul und Kallas \u00fcbergeben Hilfslieferungen an Ukraine +++"},"content":{"rendered":"<p>Ukraine-Krieg im Liveticker+++ 04:25 Wadephul und Kallas \u00fcbergeben Hilfslieferungen an Ukraine +++TeilenFolgen auf:<a href=\"https:\/\/www.whatsapp.com\/channel\/0029Va5cdVJD8SDp5YZgYF01\" title=\"Auf WhatsApp folgen\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/www.n-tv.de\/socialIcons\/whatsapp.svg\" alt=\"whatsapp\" class=\"ArticleShare_icon__FsrC2\"\/><\/a><a href=\"https:\/\/news.google.com\/publications\/CAAiEPMdif5mpRNxiLOeUpHCwwsqFAgKIhDzHYn-ZqUTcYiznlKRwsML?hl=de&amp;gl=DE&amp;ceid=DE%3Ade\" title=\"Auf Google News folgen\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/www.n-tv.de\/socialIcons\/google.svg\" alt=\"whatsapp\" class=\"ArticleShare_icon__FsrC2\"\/><\/a><\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Deutschland und die Europ\u00e4ische Union unterst\u00fctzen die durch den russischen Angriffskrieg angeschlagene ukrainische Eisenbahn mit Material im Wert von rund zwei Millionen Euro. Au\u00dfenminister Johann Wadephul und EU-Chefdiplomatin Kaja Kallas \u00fcbergeben das Material zur Unterst\u00fctzung der ukrainischen Eisenbahn zum Abschluss ihres Solidarit\u00e4tsbesuches in der ukrainischen Hauptstadt Kiew. Kallas \u00fcbergibt f\u00fcr die EU 10 von insgesamt 32 Generatoren. Das Paket im Wert von 1,4 Millionen Euro umfasst zudem Baumaschinen und Lastwagen. Deutschland stellt der Ukraine bilateral 18 Fahrzeuge im Wert von rund 600.000 Euro zur Verf\u00fcgung. Wadephul \u00fcbergibt symbolisch mehrere Pickups und Minibusse.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\"><b class=\"bold\">+++ 02:53 Drei Tote bei Explosion in russischer Chemiefabrik +++<\/b><\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Bei einem Gro\u00dfbrand in einer Petrochemie-Anlage in der russischen Region Tatarstan sind mindestens drei Menschen ums Leben gekommen, darunter ein Feuerwehrmann. 68 Menschen wurden verletzt, teilt der Betreiber Sibur mit. Im Werk Nizhnekamskneftekhim sei nach einem Druckverlust ein Gasgemisch in einer Anlage f\u00fcr synthetischen Kautschuk explodiert. Das Feuer ist unter Kontrolle, eine Ausbreitung droht nicht. Die Produktion werde um sechs Prozent reduziert, sagt Sibur-Chef Mikhail Karasalow. In umliegenden Wohnblocks sind Fenster zerst\u00f6rt worden.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\"><b class=\"bold\">+++ 01:47 Selenskyj k\u00fcndigt Videogespr\u00e4ch mit US-Vertretern an +++<\/b><\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Der ukrainische Pr\u00e4sident Wolodymyr Selenskyj wird heute ein Videogespr\u00e4ch mit US-Vertretern f\u00fchren. Die US-Seite habe darum gebeten, so Selenskyj. Dabei sein sollen demnach Selenskyj selbst und der Sekret\u00e4r des nationalen Sicherheitsrats, Rustem Umjerow, sowie der US-Sondergesandte Steve Witkoff, US-Pr\u00e4sident Donald Trumps Schwiegersohn Jared Kushner und der US-Senator Lindsey Graham. Es werde darum gehen &#8222;wo wir stehen&#8220; und wie nah ein dreiseitiges Treffen sei, sagt Selenskyj. Die Ukraine sei bereit, einen Waffenstillstand zu vereinbaren, dort wo sie stehe, sagt das ukrainische Staatsoberhaupt. Das sei eine starke Kompromisssituation, um zu einer diplomatischen L\u00f6sung zu gelangen. Russland habe den USA neue Fristen f\u00fcr die Erreichung seiner Ziele an der Front genannt, f\u00fchrt Selenskyj aus.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\"><b class=\"bold\">+++ 00:50 Russisches Milit\u00e4rflugzeug st\u00fcrzt auf der Krim ab &#8211; 29 Tote +++<\/b><\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Ein russisches Milit\u00e4rflugzeug ist auf der annektierten Halbinsel Krim abgest\u00fcrzt. Nach Angaben der staatlichen Nachrichtenagentur Tass sind sechs Besatzungsmitglieder und 23 Passagiere ums Leben gekommen. Das Transportflugzeug vom Typ Antonow-26 befand sich demnach auf einem planm\u00e4\u00dfigen Flug \u00fcber die Halbinsel, als der Kontakt gegen 18.00 Uhr verlorenging. Ein Such- und Rettungsteam habe sp\u00e4ter die Absturzstelle ausfindig gemacht. An den Tr\u00fcmmern des Flugzeugs seien keinerlei Spuren eines \u00e4u\u00dferen Einschlags festgestellt worden.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\"><b class=\"bold\">+++ 00:29 Kallas wirbt f\u00fcr gemeinsames Vorgehen gegen Schattenflotte +++<\/b><\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Die EU-Au\u00dfenbeauftragte Kaja Kallas pl\u00e4diert daf\u00fcr, f\u00fcr ein Ende des Ukraine-Kriegs den wirtschaftlichen Druck auf Russland noch einmal deutlich zu erh\u00f6hen. &#8222;Wir m\u00fcssen mit der Schattenflotte etwas tun, denn das ist ein Instrument, das Russland nutzt, um \u00d6l herauszuholen aus Russland und zu verteilen&#8220;, sagt sie den ARD-&#8222;Tagesthemen&#8220;. Auf diese Weise bekomme Russland Eink\u00fcnfte, um den Krieg zu finanzieren. &#8222;Hier m\u00fcssen wir kreativ sein, wir m\u00fcssen mit unseren Partnern zusammensitzen, mit ihnen sprechen, denn wenn das Vereinigte K\u00f6nigreich, die USA, Europa, die G7-Partner die gleichen Sanktionen erlassen, dann haben wir gro\u00dfen Effekt&#8220;. Jetzt liege der Schwerpunkt darauf, mehr Druck auf Russland auszu\u00fcben, so dass Moskau diesen Krieg beende. Der russischen Volkswirtschaft gehe es nicht gut, betont Kallas. <\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\"><b class=\"bold\">+++ 22:58 Gericht erlaubt Pf\u00e4ndung russischer Immobilien in \u00d6sterreich +++<\/b><\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Sechs ukrainische Unternehmen, darunter der staatliche Energiekonzern Naftogaz, haben in \u00d6sterreich einen juristischen Etappensieg gegen Russland erzielt. Das Wiener Landesgericht f\u00fcr Zivilrechtssachen best\u00e4tigt die Vollstreckbarkeit eines internationalen Schiedsspruchs. Damit bleibt der Weg f\u00fcr die Zwangsversteigerung von 23 russischen Immobilien in \u00d6sterreich offen. Mit dem Erl\u00f6s wollen die ukrainischen Firmen einen Teilbetrag von 120 Millionen Euro eintreiben. Hintergrund ist ein Schiedsspruch aus Den Haag vom April 2023, der Russland zur Zahlung von rund 4,2 Milliarden Dollar an die ukrainischen Gesellschaften verpflichtet. Russland hatte sich gegen die Pf\u00e4ndungen in \u00d6sterreich gewehrt und sich auf die Staatenimmunit\u00e4t berufen. Nach v\u00f6lkerrechtlichen Bestimmungen unterl\u00e4gen die betroffenen Immobilien nicht der \u00f6sterreichischen Gerichtsbarkeit.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\"><b class=\"bold\">+++ 21:54 Tr\u00fcmmerteile von Drohne in Estland entdeckt +++<\/b><\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Auf einem Feld im S\u00fcdosten Estlands sind Tr\u00fcmmerteile einer Drohne gefunden worden. Nach Angaben der Polizei haben Sicherheitskr\u00e4fte den Fundort abgesperrt und untersuchen die Gegenst\u00e4nde. Von estnischen Medien ver\u00f6ffentlichte Bilder zeigen einen Propeller und weitere Teile, die in einem Feld liegen. Die Ukraine hatte in der vergangenen Nacht erneut den russischen \u00d6l- und Gashafen Ust-Luga bei St. Petersburg angegriffen. Nach Angaben des estnischen Milit\u00e4rs drangen mehrere Drohnen auch in den Luftraum des baltischen Landes ein. Die Flugobjekte seien von Radarsystemen und von in Estland stationierten Nato-Kampfjets gesichtet worden. Dem Milit\u00e4rsprecher zufolge wurde keines der ausl\u00e4ndischen Flugobjekte auf estnischem Gebiet abgeschossen.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\"><b class=\"bold\">+++ 21:16 Blockierter EU-Kredit: Selenskyj beklagt verlorenen Monat +++<\/b><\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Vor dem Hintergrund eines durch Ungarn blockierten EU-Kredits hat der ukrainische Pr\u00e4sident Wolodymyr Selenskyj einen vers\u00e4umten Monat f\u00fcr die Vorbereitung auf den n\u00e4chsten Winter beklagt. &#8222;Hier geht es um Menschenleben. Wir h\u00e4tten damit im M\u00e4rz beginnen m\u00fcssen, aber jemand hat diesen Monat blockiert&#8220;, sagt der Staatschef bei einem Treffen mit EU-Au\u00dfenministern in Kiew. Konkret seien f\u00fcnf Milliarden Euro f\u00fcr &#8222;Schutz und Wiederaufbau&#8220; noch nicht verwendbar. Die Drohung des Scheiterns der Vorbereitungen auf den n\u00e4chsten Winter bleibe f\u00fcr die Dauer der Blockade bestehen. &#8222;Und das passiert, weil eine Person in Europa gegen ganz Europa steht, einfach um Moskau zufriedenzustellen&#8220;, sagt Selenskyj im Hinblick auf Ungarns Ministerpr\u00e4sidenten Viktor Orban. Es sei offensichtlich, dass dies in Absprache mit Moskau geschehe.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\"><b class=\"bold\">+++ 20:45 &#8222;Butscha muss auf Europa-Ebene aufgearbeitet werden&#8220; +++<\/b><\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Ukraineexpertin Oxana Huss meint, sp\u00e4testens nach dem Angriff auf Butscha h\u00e4tten die Ukrainer verstanden, &#8222;mit wem sie es zu tun haben&#8220;. Entsprechend stark beeinflusst die Trag\u00f6die ihre Abwehrbereitschaft. Die Aufarbeitung der russischen Kriegsverbrechen m\u00fcsse auf internationaler Ebene erfolgen.\u00a0<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\"><b class=\"bold\">+++ 20:21 Ex-Trump-Botschafterin: &#8222;Russland ist wahrscheinlich der gr\u00f6\u00dfte Gewinner&#8220; +++<\/b><\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Die ehemalige US-Botschafterin bei den Vereinten Nationen, Nikki Haley sieht den Kreml als einen der Profiteure des aktuellen Kriegs gegen den Iran. &#8222;Russland ist wahrscheinlich der gr\u00f6\u00dfte Gewinner in der ganzen Angelegenheit aufgrund der gestiegenen \u00d6lpreise&#8220;, so Haley. Moskau mache nun Deals mit Indien und k\u00f6nne sein \u00d6l wieder verschiffen, so die ehemalige Ministerin mit Blick auf die gelockerten US-Sanktionen.\u00a0<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Alle fr\u00fcheren Entwicklungen k\u00f6nnen Sie <a class=\"inline_link\" href=\"https:\/\/www.n-tv.de\/politik\/22-58-Gericht-erlaubt-Pfaendung-russischer-Immobilien-in-Oesterreich-id30655737.html\" target=\"_blank\" rel=\"nofollow noopener\">hier nachverfolgen<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Ukraine-Krieg im Liveticker+++ 04:25 Wadephul und Kallas \u00fcbergeben Hilfslieferungen an Ukraine +++TeilenFolgen auf: Deutschland und die Europ\u00e4ische Union&hellip;\n","protected":false},"author":2,"featured_media":564124,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4012],"tags":[331,332,661,7225,13,929,7226,3286,14,1159,15,16,307,12,317,3081,306,107],"class_list":{"0":"post-912203","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-ukraine","8":"tag-aktuelle-nachrichten","9":"tag-aktuelle-news","10":"tag-angriff-auf-die-ukraine","11":"tag-cyberwar","12":"tag-headlines","13":"tag-kriege-und-konflikte","14":"tag-kriegsverbrechen","15":"tag-militaereinsaetze","16":"tag-nachrichten","17":"tag-nato","18":"tag-news","19":"tag-politik","20":"tag-russland","21":"tag-schlagzeilen","22":"tag-ukraine","23":"tag-ukraine-konflikt","24":"tag-wladimir-putin","25":"tag-wolodymyr-selenskyj"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116327209243606572","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/912203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=912203"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/912203\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/564124"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=912203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=912203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=912203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}