{"id":913285,"date":"2026-04-01T13:06:22","date_gmt":"2026-04-01T13:06:22","guid":{"rendered":"https:\/\/www.europesays.com\/de\/913285\/"},"modified":"2026-04-01T13:06:22","modified_gmt":"2026-04-01T13:06:22","slug":"berlin-brandenburg-mehr-waffengewalt-in-berlin-afd-fordert-mehr-transparenz","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/913285\/","title":{"rendered":"Berlin &#038; Brandenburg: Mehr Waffengewalt in Berlin \u2013 AfD fordert mehr Transparenz"},"content":{"rendered":"<p>Berlin &amp; BrandenburgMehr Waffengewalt in Berlin \u2013 AfD fordert mehr Transparenz<img decoding=\"async\" class=\"Image_img__fQCi0 Image_Img_16_9__4BLfH\" loading=\"eager\" fetchpriority=\"high\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/04\/Ein-Bildschirm-zeigt-eine-von-der-Berliner-AfD-Fraktion-vorgestellte-Uebersicht-von-Vorfaellen-mit-M.webp\" alt=\"Ein-Bildschirm-zeigt-eine-von-der-Berliner-AfD-Fraktion-vorgestellte-Uebersicht-von-Vorfaellen-mit-Messern-die-auf-der-AfD-Webseite-abrufbar-ist\"\/>TeilenFolgen auf:<a href=\"https:\/\/www.whatsapp.com\/channel\/0029Va5cdVJD8SDp5YZgYF01\" title=\"Auf WhatsApp folgen\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/www.n-tv.de\/socialIcons\/whatsapp.svg\" alt=\"whatsapp\" class=\"ArticleShare_icon__FsrC2\"\/><\/a><a href=\"https:\/\/news.google.com\/publications\/CAAiEPMdif5mpRNxiLOeUpHCwwsqFAgKIhDzHYn-ZqUTcYiznlKRwsML?hl=de&amp;gl=DE&amp;ceid=DE%3Ade\" title=\"Auf Google News folgen\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/www.n-tv.de\/socialIcons\/google.svg\" alt=\"whatsapp\" class=\"ArticleShare_icon__FsrC2\"\/><\/a><\/p>\n<p class=\"Typography_text-m__XI0da Typography_weight-bold__uT6mq storyline_lead_text_leadtext__q_wg8\">Messer- und Schusswaffengewalt bleibt ein zentrales Thema in Berlin. Die AfD wirft dem schwarz-roten Senat mangelnde Transparenz vor und reagiert mit einem Internetangebot. Was bringt das?<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Berlin (dpa\/bb) &#8211; Die Berliner AfD macht die steigende Messerkriminalit\u00e4t in der Hauptstadt zum Wahlkampfthema. Die Fraktionsvorsitzende Kristin Brinker wirft der Koalition von CDU und SPD mangelnde Transparenz im Umgang mit Gewaltstraftaten vor. &#8222;Das Unsicherheitsgef\u00fchl in der Stadt hat erheblich zugenommen&#8220;, erkl\u00e4rte Brinker. Dies stehe im Gegensatz dazu, dass der heutige Regierende B\u00fcrgermeister Kai Wegner im Wahlkampf 2023 ein &#8222;sicheres Berlin&#8220; versprochen habe.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Mit einer \u00dcbersicht der von der Polizei gemeldeten Vorf\u00e4lle mit Messern will die AfD-Fraktion nach eigenen Worten f\u00fcr mehr Transparenz sorgen. Der schwarz-rote Senat soll so dazu gedr\u00e4ngt werden, mehr Daten zu ver\u00f6ffentlichen &#8211; beispielsweise zur Nationalit\u00e4t der Verd\u00e4chtigen. Berlin geh\u00f6re zu den wenigen L\u00e4ndern, wo dies weiterhin nicht passiere, kritisierte der innenpolitische Sprecher Thorsten Wei\u00df. Nach seinen Angaben gibt es \u00dcberlegungen, die Darstellung um den Schusswaffengebrauch und Sexualstraftaten auszuweiten.<\/p>\n<p>Bekannte Zahlen zusammengestellt<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Die von der Fraktion als &#8222;Messer-App&#8220; angek\u00fcndigte \u00dcbersicht ist auf der Webseite der AfD-Fraktion abrufbar. In der \u00dcbersicht sind unter anderem die Anzahl der von der Polizei ver\u00f6ffentlichten Vorf\u00e4lle der vergangenen 30 Tage sowie die Zahl der dabei Verletzten zu sehen. Es gibt eine interaktive Karte, die zeigt, wo sich die Vorf\u00e4lle ereigneten.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Zudem wird eine durchschnittliche Zahl der Vorf\u00e4lle nach der polizeilichen Kriminalstatistik (PKS) genannt. Diese Daten stammen jedoch aus dem Jahr 2025. Der Vergleich beider Zahlen soll aus Sicht der AfD eine gro\u00dfe Differenz zwischen den von der Polizei ver\u00f6ffentlichten Eins\u00e4tzen und den in der PKS erfassten Vorf\u00e4llen zeigen.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Kritik kam von der Linken-Fraktion: Der AfD gehe es darum, &#8222;gezielt Angst in der Bev\u00f6lkerung zu verst\u00e4rken und zu instrumentalisieren, um Hass gegen Zugewanderte zu sch\u00fcren&#8220;.<\/p>\n<p>Deutlich mehr Messer- und Schusswaffengewalt<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Messergewalt ist in Berlin ein ernsthaftes Problem, das die Sicherheitsbeh\u00f6rden und Politik besch\u00e4ftigt. 2024 registrierte die Polizei laut Kriminalit\u00e4tsstatistik 3.412 Messerangriffe. Im vergangenen Jahr wurden nach der Statistik 3.599 F\u00e4lle im Bereich &#8222;Messerangriff&#8220; registriert (plus 5,5 Prozent). Etwa die H\u00e4lfte waren Drohungen. 1.906 Verd\u00e4chtige ermittelte die Polizei. 86 Prozent waren demnach m\u00e4nnlich, 56 Prozent mit nichtdeutscher Staatsangeh\u00f6rigkeit.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Zudem hat der Gebrauch von Schusswaffen stark zugenommen. 2025 erfasste die Polizei 68 Prozent mehr Straftaten, bei denen mit Waffen gedroht oder geschossen wurde. Insgesamt wurden laut Statistik 1.119 F\u00e4lle registriert, etwas mehr als die H\u00e4lfte waren Drohungen, in 515 F\u00e4llen wurde geschossen.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Polizei und Staatsanwaltschaft reagierten mit Sondereinheiten auf die Entwicklung. Zudem hat der Senat drei Waffen- und Messerverbotszonen &#8211; G\u00f6rlitzer Park und Kottbusser Tor in Kreuzberg sowie Leopoldplatz in Wedding &#8211; errichtet. Polizei und Senat sehen erste Erfolge.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Die Messerkriminalit\u00e4t sei in diesen drei Zonen um bis zu 45 Prozent zur\u00fcckgegangen, erkl\u00e4rte der innenpolitische Sprecher der CDU-Fraktion Burkhard Dregger. &#8222;Ich pl\u00e4diere daf\u00fcr, die Messerverbotszonen regelm\u00e4\u00dfig zu verlegen oder im Rahmen der personellen Ressourcen der Polizei zahlenm\u00e4\u00dfig zu erh\u00f6hen, um auch andere neuralgische Punkte mit einer erh\u00f6hten Messerkriminalit\u00e4t entsprechend zu sch\u00fctzen&#8220;, so Dregger weiter.<\/p>\n<p class=\"Typography_text-s__wu_cm Typography_weight-normal__pqUbH Typography_color-darkgrey__sZEnP article-detail-footer_source__KslPc\">Quelle: dpa<\/p>\n","protected":false},"excerpt":{"rendered":"Berlin &amp; BrandenburgMehr Waffengewalt in Berlin \u2013 AfD fordert mehr TransparenzTeilenFolgen auf: Messer- und Schusswaffengewalt bleibt ein zentrales&hellip;\n","protected":false},"author":2,"featured_media":913286,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1816],"tags":[1960,1958,1959,1957,1956,1890,29,30],"class_list":{"0":"post-913285","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brandenburg","8":"tag-aktuelle-nachrichten-aus-berlin-und-brandenburg","9":"tag-aktuelle-nachrichten-aus-brandenburg","10":"tag-aktuelle-news-aus-berlin-und-brandenburg","11":"tag-aktuelle-news-aus-brandenburg","12":"tag-berlin-und-brandenburg","13":"tag-brandenburg","14":"tag-deutschland","15":"tag-germany"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/913285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=913285"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/913285\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/913286"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=913285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=913285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=913285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}