{"id":919016,"date":"2026-04-03T20:03:32","date_gmt":"2026-04-03T20:03:32","guid":{"rendered":"https:\/\/www.europesays.com\/de\/919016\/"},"modified":"2026-04-03T20:03:32","modified_gmt":"2026-04-03T20:03:32","slug":"delfinlagune-nuernberg-oeffnet-wieder-sanierung-beendet-delfine-draussen","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/919016\/","title":{"rendered":"Delfinlagune N\u00fcrnberg \u00f6ffnet wieder: Sanierung beendet, Delfine drau\u00dfen"},"content":{"rendered":"<p>Millionen-Sanierung <\/p>\n<p>N\u00fcrnberger Delfinlagune wird wieder ge\u00f6ffnet<\/p>\n<ul class=\"grid grid-flow-col gap-4\" aria-label=\"Autorenbilder\">\n<li class=\"leading-0\"><img data-tb-author-image=\"\"  loading=\"lazy\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2025\/11\/1764485653_271_image.jpg\" alt=\"\" title=\"\" width=\"40\" height=\"40\" class=\"\" decoding=\"async\"\/><\/li>\n<\/ul>\n<p>Aktualisiert am 03.04.2026 &#8211; 18:06 UhrLesedauer: 2 Min.<\/p>\n<p><a href=\"#focus-0\" class=\"transition-colors duration-200 block text-current relative\" data-sctrack=\"FocusGalleryImage.Reference\"><img fetchpriority=\"high\" data-testid=\"Opener.Image\" style=\"--lqipURL:url('https:\/\/images.t-online.de\/2026\/03\/DR2jK231BtdB\/0x169:4000x2250\/fit-in\/150x0\/filters:blur(25)\/tiergarten-nuernberg-delphinlagune-16-112019-nuernberg-delphinlagune-delphinshow-zoo-nuremberg-dolphin-lagoon-16-11-2019-nuremberg-dolphin-lagoon-dolphin-show.jpg')\"   loading=\"eager\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/03\/tiergarten-nuernberg-delphinlagune-16-112019-nuernberg-delphinlagune-delphinshow-zoo-nuremberg-dolph.jpeg\" alt=\"imago images 95094143\" title=\"imago images 95094143\" width=\"4000\" height=\"2250\" class=\"bg-[url:var(--lqipURL)] bg-cover bg-center flex h-full w-full max-w-full\" decoding=\"async\"\/><img style=\"--width:32;--height:32\" loading=\"lazy\" src=\"https:\/\/nuernberg.t-online.de\/s\/paper\/_next\/static\/media\/zoom-in.f7dae02f.svg\" alt=\"Vergr\u00f6\u00dfern des Bildes\" title=\"Vergr\u00f6\u00dfern des Bildes\" class=\"block h-[calc(var(--height)_\/_16_*_1rem)] w-[calc(var(--width)_\/_16_*_1rem)] max-w-none absolute bottom-8 right-8 rounded-4 bg-snow p-8\" decoding=\"async\"\/><\/a><\/p>\n<p>Delfine im Tiergarten N\u00fcrnberg: Die T\u00fcmmler k\u00f6nnen nun vollumf\u00e4nglich in die Lagune zur\u00fcckkehren. (Quelle: KH via www.imago-images.de\/imago)<\/p>\n<p class=\"font-bold text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\">Die Bauarbeiten an der Lagune sind abgeschlossen, die Tiere nun wieder drau\u00dfen zu sehen. Doch die Kritik an dem Konzept des N\u00fcrnberger Tiergartens bleibt.<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\">In N\u00fcrnberg sind die Bauarbeiten an der umstrittenen Delfinlagune abgeschlossen. Damit sind die Gro\u00dfen T\u00fcmmler wieder in der Lagune zu sehen und die Besuchertrib\u00fcnen stehen wieder vollst\u00e4ndig zur Verf\u00fcgung.<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\">Seit Jahren gibt es \u00c4rger um die Delfinlagune im <a class=\"transition-colors duration-200 cursor-pointer text-inherit no-underline text-salemsfur md:hover:text-magenta md:hover:border-magenta md:focus:text-magenta border-current border-b border-solid break-words\" data-tracking=\"{&quot;action&quot;:&quot;click&quot;,&quot;category&quot;:&quot;intextLink&quot;,&quot;label&quot;:&quot;https:\/\/www.t-online.de\/themen\/nuernberger-tiergarten\/&quot;}\" href=\"https:\/\/www.t-online.de\/themen\/nuernberger-tiergarten\/\" data-sctrack=\"BodyAnchor\" rel=\"nofollow noopener\" target=\"_blank\">N\u00fcrnberger Tiergarten<\/a> \u2013 etwa, weil Wasser auslief. Nun sind die langwierigen Bauarbeiten an der Lagune abgeschlossen. Gerade liefen noch &#8222;kleinere, witterungsbedingte Restarbeiten&#8220;. Das erkl\u00e4ren die Verantwortlichen des Tiergartens N\u00fcrnberg auf Nachfrage der N\u00fcrnberger Lokalredaktion von t-online. Die Traglufthalle, die die Delfine in den Wintermonaten vor frostigen Temperaturen gesch\u00fctzt hat, sei nun abgebaut.<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\">Sieben Delfine und Kalifornische Seel\u00f6wen h\u00e4lt der st\u00e4dtische Eigenbetrieb in der Lagune. Die Tiere waren in der Zeit der Bauarbeiten gr\u00f6\u00dftenteils in den Innenbecken untergebracht.<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\">Tiergartendirektor Dag Encke sagt, dass die Lagune im Tiergarten eine moderne Delfinhaltung erm\u00f6gliche, die nach den Bed\u00fcrfnissen der Tiere gestaltet sei. &#8222;Insofern sind wir heilfroh, dass wir nun wieder das gesamte Beckensystem zur Verf\u00fcgung haben.&#8220;<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\">Auch technisch sei nachgebessert worden, betont Thomas Schiller, der technische Leiter. So seien im Zuge der Sanierungsarbeiten auch die Beleuchtung und die Audioanlage modernisiert worden. Neue Handl\u00e4ufe an den Besuchertrib\u00fcnen erleichtern zudem deren Nutzung f\u00fcr Menschen mit Gehbeeintr\u00e4chtigungen, hei\u00dft es zus\u00e4tzlich in einer Pressemitteilung. In der Delfinlagune finden t\u00e4glich Vorf\u00fchrungen der Tiere statt.<\/p>\n<p class=\"text-18 leading-17 user-text-lg:text-22 user-text-xl:text-24\">Seit ihrer Er\u00f6ffnung im Jahr 2011 steht die Lagune wegen baulicher M\u00e4ngel in der Kritik. Undichte Becken und andere Sch\u00e4den haben fr\u00fchzeitig die Sanierung notwendig gemacht. Salzhaltiges Wasser sei in die Bausubstanz eingedrungen. Es kam zum Rechtsstreit mit der Baufirma. Die Kosten f\u00fcr die Beckenkopfsanierung betragen laut offiziellen Angaben rund eine Million Euro, getragen durch die Stadt N\u00fcrnberg.<\/p>\n","protected":false},"excerpt":{"rendered":"Millionen-Sanierung N\u00fcrnberger Delfinlagune wird wieder ge\u00f6ffnet Aktualisiert am 03.04.2026 &#8211; 18:06 UhrLesedauer: 2 Min. Delfine im Tiergarten N\u00fcrnberg:&hellip;\n","protected":false},"author":2,"featured_media":905030,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1837],"tags":[522,772,88043,3364,198650,198649,29,30,3783,24891,226,24889],"class_list":{"0":"post-919016","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-nuernberg","8":"tag-522","9":"tag-bayern","10":"tag-dag-encke","11":"tag-de","12":"tag-delfin","13":"tag-delfinlagune","14":"tag-deutschland","15":"tag-germany","16":"tag-nuernberg","17":"tag-nuernberger-tiergarten","18":"tag-t-online","19":"tag-tiergarten-nuernberg"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116342568300306920","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/919016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=919016"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/919016\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/905030"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=919016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=919016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=919016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}