{"id":925338,"date":"2026-04-06T12:17:17","date_gmt":"2026-04-06T12:17:17","guid":{"rendered":"https:\/\/www.europesays.com\/de\/925338\/"},"modified":"2026-04-06T12:17:17","modified_gmt":"2026-04-06T12:17:17","slug":"berlin-unfall-in-berlin-lichtenberg-motorroller-fahrerin-stirbt","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/925338\/","title":{"rendered":"Berlin: Unfall in Berlin-Lichtenberg: Motorroller-Fahrerin stirbt"},"content":{"rendered":"<p>            <img loading=\"lazy\" decoding=\"async\" class=\"ts-image\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/04\/rbb-559213946-unfall-100.jpg\" alt=\"Blaulicht eines Notarztfahrzeuges. (Quelle: dpa\/Caro Kadatz)\" title=\"559213946 Unfall | dpa\/Caro Kadatz\"\/><\/p>\n<p class=\"metatextline\">Stand: 06.04.2026 \u2022 12:44 Uhr<\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">Eine Frau ist am Sonntagabend nach einem Verkehrsunfall in Berlin-Lichtenberg ums Leben gekommen.<\/p>\n<p>Wie die Polizei am Montag mitteilte, fuhr die 50-J\u00e4hrige gegen 21:30 Uhr auf der Frankfurter Allee, als sie aus bislang unklarer Ursache von der Fahrbahn abkam und gegen den Bordstein der Mittelinsel stie\u00df. Anschlie\u00dfend st\u00fcrzte sie auf die Stra\u00dfe, der Roller prallte gegen ein Auto im Gegenverkehr.<\/p>\n<p>Laut Feuerwehr befand sich ein L\u00f6schfahrzeug in der N\u00e4he, weshalb schon unmittelbar danach mit der Wiederbelebung begonnen werden konnte. Trotzdem starb die Frau an der Unfallstelle.<\/p>\n<p>W\u00e4hrend der Aufr\u00e4um- und Vermessungsarbeiten wurde die Frankfurter Allee in H\u00f6he der Buchberger Stra\u00dfe stadteinw\u00e4rts bis zwei Uhr nachts gesperrt.<\/p>\n<p class=\"textabsatz m-ten m-offset-one l-eight l-offset-two columns twelve\">Sendung: rbb|24, 06.04.2026, 09:07 Uhr<br \/>Audio: rbb|24, 06.04.2026, Patrik Buchm\u00fcller<\/p>\n<p>                                        <a class=\"backlink__link\" href=\"https:\/\/www.rbb24.de\/panorama\/beitrag\/2026\/04\/berlin-lichtenberg-unfall-motorroller-frau-tot.html\" rel=\"nofollow noopener\" target=\"_blank\"><\/p>\n<p>                                                <img decoding=\"async\" src=\"https:\/\/images.tagesschau.de\/image\/898f19c3-6760-4be2-a33f-1fa765216ec2\/AAABlap_olM\/AAABnR8VW9w\/original\/lra-rbb-logo-100.svg\" alt=\"Rundfunk Berlin-Brandenburg\"\/><\/p>\n<p>                                        <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"Stand: 06.04.2026 \u2022 12:44 Uhr Eine Frau ist am Sonntagabend nach einem Verkehrsunfall in Berlin-Lichtenberg ums Leben gekommen.&hellip;\n","protected":false},"author":2,"featured_media":925339,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1825],"tags":[296,29,30,2239],"class_list":{"0":"post-925338","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-berlin","8":"tag-berlin","9":"tag-deutschland","10":"tag-germany","11":"tag-rbb"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116357722791194130","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/925338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=925338"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/925338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/925339"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=925338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=925338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=925338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}