{"id":929724,"date":"2026-04-08T07:55:18","date_gmt":"2026-04-08T07:55:18","guid":{"rendered":"https:\/\/www.europesays.com\/de\/929724\/"},"modified":"2026-04-08T07:55:18","modified_gmt":"2026-04-08T07:55:18","slug":"wissen-in-leipzig-das-kneipengespraech-zur-situation-der-wirtschaft-in-deutschland","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/929724\/","title":{"rendered":"Wissen in Leipzig: Das Kneipengespr\u00e4ch zur Situation der Wirtschaft in Deutschland"},"content":{"rendered":"\n<p>Deutschlands Wirtschaft steht durch verschiedene Faktoren unter Druck. Gleichzeitig wird kontrovers gestritten, ob Reformen, neue industriepolitische Impulse oder mehr technologischer Mut den entscheidenden Aufbruch bringen k\u00f6nnen. Die Wissenschaftler Moritz Pfeifer und Dr. Benjamin Winter stellen ihre Einsch\u00e4tzung vor und diskutieren mit dem Publikum verschiedene Aspekte der Thematik wie: Wo steht die deutsche Wirtschaft aktuell? Was kann die Politik tun? Welche Wirtschaftsbranchen sind \u00fcberhaupt zukunftsf\u00e4hig?<\/p>\n<p>Moritz Pfeifer, Postdoktorand am Institut f\u00fcr Wirtschaftspolitik der Universit\u00e4t Leipzig, befasst sich schwerpunktm\u00e4\u00dfig mit Geldpolitik und institutioneller \u00d6konomie. Au\u00dferdem arbeitet er zu makro\u00f6konomischen Themen und zur Kommunikation von Zentralbanken.\u00a0<\/p>\n<p>Dr. Benjamin Klement leitet die Arbeitsgruppe \u201eInnovative Regionen\u201c am Leipziger Standort des Fraunhofer-Institut f\u00fcr System- und Innovationsforschung. Er forscht zu regionalen Innovationssystemen, Strukturwandel und evaluiert innovationspolitische F\u00f6rderma\u00dfnahmen.<\/p>\n<p> Veranstaltungsreihe \u201eWissen in Leipzig: Das Kneipengespr\u00e4ch\u201c <\/p>\n<p>In der Veranstaltungsreihe \u201eWissen in Leipzig: Das Kneipengespr\u00e4ch\u201c ordnen Wissenschaftler und Expertinnen tagesaktuelle Themen ein. Das Hotel Seeblick bietet au\u00dferhalb der Hochschule einen Raum f\u00fcr den Austausch zwischen der Forschung und interessierten B\u00fcrgerinnen und B\u00fcrgern, um in lockerer Runde zu aktuellen Themen ins Gespr\u00e4ch zu kommen.<\/p>\n<p> Zeit und Ort <\/p>\n<p>13. April 2026<br \/>18 Uhr<\/p>\n<p>Hotel Seeblick<br \/>Karl-Liebknecht-Stra\u00dfe 125<br \/>04275 Leipzig<\/p>\n","protected":false},"excerpt":{"rendered":"Deutschlands Wirtschaft steht durch verschiedene Faktoren unter Druck. Gleichzeitig wird kontrovers gestritten, ob Reformen, neue industriepolitische Impulse oder&hellip;\n","protected":false},"author":2,"featured_media":929725,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1832],"tags":[3364,29,30,37594,71,859,55,193],"class_list":{"0":"post-929724","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-leipzig","8":"tag-de","9":"tag-deutschland","10":"tag-germany","11":"tag-kneipengespraech","12":"tag-leipzig","13":"tag-sachsen","14":"tag-wirtschaft","15":"tag-wissenschaft"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116368017296795846","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/929724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=929724"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/929724\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/929725"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=929724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=929724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=929724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}