{"id":941260,"date":"2026-04-12T23:03:26","date_gmt":"2026-04-12T23:03:26","guid":{"rendered":"https:\/\/www.europesays.com\/de\/941260\/"},"modified":"2026-04-12T23:03:26","modified_gmt":"2026-04-12T23:03:26","slug":"die-grosse-show-der-domenika-mayer-in-hannover","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/941260\/","title":{"rendered":"Die gro\u00dfe Show der Domenika Mayer in Hannover"},"content":{"rendered":"<p>Domenika Mayer lieferte beim ADAC Hannover-Marathon ihre eigene Show: Die konstanteste deutsche Marathonl\u00e4uferin der letzten Jahre gewann das Rennen in 2:21:26 Stunden, pulverisierte ihren eigenen Streckenrekord sowie ihre pers\u00f6nliche Bestzeit, wurde zur zweitschnellsten deutschen L\u00e4uferin aller Zeiten und zur elftschnellsten Europ\u00e4erin, verteidigte ein weiteres Mal ihren deutschen Meistertitel, schaffte mit drei Siegen in Folge einen \u201eHattrick\u201c in Hannover und wurde mit insgesamt nunmehr vier Siegen zur alleinigen Rekord-Gewinnerin des Rennens.<\/p>\n<p>Bei den M\u00e4nnern siegte der Kenianer Maru Thomas Kibet in 2:07:53 w\u00e4hrend Tom Thurley als Sechster mit einer pers\u00f6nlichen Bestzeit von 2:11:02 zu seinem ersten deutschen Meistertitel lief.<\/p>\n<p>Das erwartete Duell zwischen Domenika Mayer (LG Telis Finanz Regensburg) und Fabienne K\u00f6nigstein (Hannover 96) fand in Hannover nicht statt. Es war genau umgekehrt wie in Berlin im vergangenen September. Damals lief K\u00f6nigstein vorneweg zu einer Bestzeit von 2:22:17 w\u00e4hrend Mayer sich nach Problemen in der Vorbereitung zwar auf 2:23:16 verbesserte, jedoch einen deutlichen R\u00fcckstand hatte. Im Vorfeld des Rennens in Hannover war es Fabienne K\u00f6nigstein, die nach Verletzungsproblemen nicht optimal vorbereitet war und mit ihrer nationalen Konkurrentin dann nicht mithalten konnte.<\/p>\n<p>Vom Start weg setzte sich Domenika Mayer an die Spitze und baute den Vorsprung immer weiter aus. Mit einer Halbmarathon-Durchgangszeit von 70:31 lag die 35-J\u00e4hrige bereits eine knappe Minute vor Fabienne K\u00f6nigstein (71:25), die ihr erstes Rennen seit dem Berlin-Marathon lief. In der Schlussphase konnte K\u00f6nigstein ihr Tempo nicht mehr halten und verlor weitere Zeit. \u201eAber angesichts der kurzen Vorbereitungszeit bin ich zufrieden mit meinem Rennen. Domenika war heute sehr stark\u201c, sagte Fabienne K\u00f6nigstein, die als Zweite nach 2:24:31 im Ziel war. Mit deutlichem Abstand belegte Almaz Negede (\u00c4thiopien) Rang drei in 2:30:25. \u201eIch hatte keinerlei Probleme mehr nach der Verletzung &#8211; das ist prima\u201c, sagte Fabienne K\u00f6nigstein. W\u00e4hrend Laura Hottenrott (D\u00fcsseldorf Athletics) das Rennen nach der 30-km-Marke aufgab, lief Katharina Saathoff (Braunschweiger LC) als F\u00fcnfte nach 2:30:51 ins Ziel und belegte damit in der nationalen Meisterschaft Platz drei.<\/p>\n<p>\u201eIch bin super zufrieden. Am Anfang war das Tempo ein bisschen zu schnell, daf\u00fcr b\u00fc\u00dft man dann hinten raus\u201c, sagte Domenika Mayer, die auf den letzten Kilometern auch etwas Zeit verlor. Aber mit 2:21:26 verbesserte sie sich um fast zwei Minuten und steigerte bei ihrem vierten Hannover-Sieg nach 2022, 2024 und 2025 ihren vor zwei Jahren aufgestellten Kursrekord (2:23:50) um fast zweieinhalb Minuten. In der europ\u00e4ischen Jahresbestenliste steht sie derzeit auf Platz zwei. In der deutschen Alltime-Liste ist nur noch Irina Mikitenko (2:19:19) vor ihr. Die 2:20-Barriere k\u00f6nnte ein n\u00e4chstes Ziel sein f\u00fcr Domenika Mayer. \u201eEs geht noch mehr, die Marke habe ich im Blick. Ich versuche immer schneller zu laufen und zu sehen, was m\u00f6glich ist. Denn meine Zeit ist ja begrenzt &#8211; ich bin nicht mehr 25\u201c, sagte Domenika Mayer.<\/p>\n<p>Bei den M\u00e4nnern gab es auf den letzten Kilometern im Kampf um den Sieg noch eine dramatische Wende. Nach einem Alleingang gingen Godwin Katakura (Simbabwe) die Kr\u00e4fte aus. Sein deutlicher Vorsprung schmolz und gut zwei Kilometer vor dem Ziel \u00fcberholte ihn Maru Thomas Kibet. Der Kenianer gewann in 2:07:53 vor Katakura (2:08:46) und dem \u00c4thiopier Asnake Dubre (2:10:22). \u201eIch hatte nicht erwartet, dass ich noch gewinnen k\u00f6nnte und hatte mich schon mit Platz zwei abgefunden. Das ist eine gro\u00dfe PB f\u00fcr mich. In der Zukunft m\u00f6chte ich 2:03 Stunden laufen\u201c, sagte Maru Thomas Kibet, der mit einer Bestzeit von 2:13:48 an den Start gegangen war.<\/p>\n<p>Nachdem Filimon Abraham (LG Telis Finanz Regensburg) verletzungsbedingt passen musste und Johannes Motschmann (SCC Berlin) nach rund 25 km mit Problemen an der Leiste, unter denen er schon im Vorfeld litt, ausgestiegen war, war der Weg frei f\u00fcr Tom Thurley. Der 32-j\u00e4hrige Halbprofi setzte sich bald darauf von Erik Hille (Munich Athletics) ab und gewann das Rennen um den nationalen Titel dann in 2:11:02 deutlich. \u201eIch hatte gehofft, dass es klappen k\u00f6nnte &#8211; aber ein Marathon ist lang, man wei\u00df nie was passiert. Ich bin super zufrieden\u201c, sagte Tom Thurley, der sich um 17 Sekunden verbesserte. \u201eMein Ziel ist es, eine Zeit unter 2:10:00 zu erreichen. Wenn ich die Chance bekommen w\u00fcrde, im Sommer bei der EM im deutschen Team zu starten, w\u00fcrde ich das nat\u00fcrlich machen.\u201c Erik Hille war als Achter in 2:12:21 zweitbester deutscher L\u00e4ufer. Rang drei in der nationalen Wertung und Platz zehn in der Gesamtwertung belegte Lorenz Baum (LAV Stadtwerke T\u00fcbingen) mit 2:16:38.<\/p>\n<p><strong>Ergebnisse der M\u00e4nner<\/strong><\/p>\n<ol class=\"text\">\n<li>Maru Thomas Kibet KEN 2:07:53<\/li>\n<li>Godwin Katakura ZIM 2:08:46<\/li>\n<li>Asnake Dubre ETH 2:10:22<\/li>\n<li>Christopher Kitetu KEN 2:10:45<\/li>\n<li>Archie Casteel SWE 2:10:56<\/li>\n<li>Tom Thurley GER 2:11:02<\/li>\n<\/ol>\n<p><strong>Ergebnisse der Frauen<\/strong><\/p>\n<ol class=\"text\">\n<li>Domenika Mayer GER 2:21:26<\/li>\n<li>Fabienne K\u00f6nigstein GER 2:24:31<\/li>\n<li>Almaz Negede ETH 2:30:25<\/li>\n<li>Cecilia Wayua KEN 2:30:36<\/li>\n<li>Katharina Saathoff GER 2:30:51<\/li>\n<li>Mercy Kipkemoi KEN 2:31:48<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"Domenika Mayer lieferte beim ADAC Hannover-Marathon ihre eigene Show: Die konstanteste deutsche Marathonl\u00e4uferin der letzten Jahre gewann das&hellip;\n","protected":false},"author":2,"featured_media":941261,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1836],"tags":[205183,205187,3364,29,158691,158690,30,205185,46,2366,205186,32206,174824,158694,205184,32207,1411,196574,177797],"class_list":{"0":"post-941260","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-hannover","8":"tag-adac-hannover-marathon","9":"tag-braunschweiger-lc","10":"tag-de","11":"tag-deutschland","12":"tag-domenika-mayer","13":"tag-fabienne-koenigstein","14":"tag-germany","15":"tag-godwin-katakura","16":"tag-hannover","17":"tag-hannover-96","18":"tag-irina-mikitenko","19":"tag-laufevents","20":"tag-laufevents-in-hannover","21":"tag-lg-telis-finanz-regensburg","22":"tag-maru-thomas-kibet","23":"tag-news-fotos","24":"tag-niedersachsen","25":"tag-rw-artikel","26":"tag-tom-thurley"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116394236685508016","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/941260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=941260"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/941260\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/941261"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=941260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=941260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=941260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}