{"id":952161,"date":"2026-04-17T07:36:17","date_gmt":"2026-04-17T07:36:17","guid":{"rendered":"https:\/\/www.europesays.com\/de\/952161\/"},"modified":"2026-04-17T07:36:17","modified_gmt":"2026-04-17T07:36:17","slug":"part-ii-hackney-goethe-institut-vereinigtes-koenigreich-3","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/952161\/","title":{"rendered":"Part II: Hackney &#8211; Goethe-Institut Vereinigtes K\u00f6nigreich"},"content":{"rendered":"<p class=\"artikelintro\"><strong>If this was then, then you\u2019d be here.&#13;<br \/>\n<strong>Im zweiten Teil seiner Notizen \u00fcber den Hackney Brooke, einer der vielen unterirdischen Fl\u00fcsse Londons, folgt der Autor dem verborgenen Wasserpfad bis zu seinem Ende, der sich gleichzeitig als Beginn der Stadt offenbart.<\/strong><\/strong><\/p>\n<\/p>\n<p>45<br \/>\nIch gehe die westliche Grenze der Hackney Downs entlang, die durch den Verlauf des Hackney Brook definiert wird.<strong>\u00a0<\/strong>Der Wasserlauf offenbart eine geheime, unsichtbare Geometrie der Stadt. Der Park ist leer. Herbstwinde. Ich gehe schneller.<br \/>\n\u00a0<br \/>\n46<br \/>\nJe schneller wir gehen, desto mehr Boden verlieren wir.<br \/>\n\u2013 Iain Sinclair, Lights Out for the Territory: 9 Excursions in the Secret History of London<\/p>\n<p>Die Privilegien des wei\u00dfen, m\u00e4nnlichen Flaneurs.<br \/>&#13;<br \/>\n\u00a0&#13;\n<\/p>\n<p>47<br \/>\nEine Gasse mit Automechanikern, unter der Br\u00fccke, ein Auto nach dem anderen, Mechaniker lungern herum, hinter den Kulissen der autofreundlichen Stadt.<\/p>\n<ul>&#13;<\/p>\n<li>Car Care Centre<\/li>\n<p>&#13;<\/p>\n<li>Brakes<\/li>\n<p>&#13;<\/p>\n<li>Balancing<\/li>\n<p>&#13;<\/p>\n<li>Batteries<\/li>\n<p>&#13;<\/p>\n<li>Suspension<\/li>\n<p>&#13;<\/p>\n<li>Exhausts<\/li>\n<p>&#13;<\/p>\n<li>Welding<\/li>\n<p>&#13;<\/p>\n<li>Alternators<\/li>\n<p>&#13;\n<\/ul>\n<p>48<br \/>\nEine Werbung f\u00fcr ein neues Handy: signal all the way \u2013 der Bildschirm ist kaputt, digitaler M\u00fcll flackert nerv\u00f6s in einer Schleife.<br \/>\nAnkunft in Hackney Central,<br \/>\nein mittelalterlicher Turm.<br \/>\nPerfect Chicken.<br \/>\nEinst ein Vorort au\u00dferhalb der Stadtmauern, der einem d\u00e4nischen Aristokraten namens Haca geh\u00f6rte, stammt Hackney von Hacas Eoth ab und bedeutet \u201egut bew\u00e4sserter Sumpf von Haca\u201c. Marschland.<br \/>\n\u00a0<\/p>\n<p>49<\/p>\n<p>Der Fluss f\u00fchrt mich vorbei an der Mare Street; Erinnerung an das Meer, Wellen von Autos.<\/p>\n<p>Das Wort \u201emare\u201c bezieht sich entweder auf die Grenze (in Form der Stra\u00dfe) oder auf einen gro\u00dfen Teich in der Umgebung, der vom Hackney Brook gespeist wurde.<\/p>\n<p>Jetzt ist alles Wasser bedeckt. Nur manchmal zeigt sich der Fluss, in einem Namen: Zwischen Stoke Newington und den Hackney Downs liegt die Brooke Road.<\/p>\n<p>50<br \/>\nDorothy Miller Richardson ist eine der ersten Autorinnen, die im Stil des \u00bbstream of consciousness\u00ab schreibt, der Stil wird jedoch meistens Virginia Woolf zugeschrieben. Ihre feministische 13-teilige Romanserie Pilgrimage folgt der Flaneuse Miriam, die sich in London herumtreibt.<\/p>\n<p>In Backwater, dem zweiten Buch ihrer Serie, schreibt sie:<\/p>\n<p>Alles war in einer sanften Schw\u00e4rze verschwunden; nur auf dem Wasser blieb ein schwaches Licht. Es kam und ging; manchmal gab es nichts als Dunkelheit und sanfte Luft. Die kleine Papierlaterne, die am Bug geschwenkt wurde, l\u00f6ste einen kleinen Lichtfleck aus, der vom Hubsitz aus nicht sichtbar war. Das Boot fuhr schnell und problemlos. Miriam hatte das Gef\u00fchl, sie k\u00f6nnte stundenlang, an der Grenze ihrer Kr\u00e4fte rudern. Sie lehnte sich nach vorne, dr\u00fcckte die finstere Dunkelheit, die Ruder bei voller Reichweite ihrer Arme zur\u00fcck, lehnte sich zur\u00fcck und dr\u00fcckte ihr gesamtes Gewicht vom Fu\u00dfbrett gegen den Zug des Wassers. Ihr K\u00f6rper wurde zu einem ausgestreckten elastischen Muskelsystem; rhythmisch gegen das sanfte Ziehen des Widerstands des dunklen Wassers.&#13;<br \/>\n&#13;\n<\/p>\n<p>51<br \/>\nIn der Mortimer Road in Hackney gr\u00e4bt William Lyttle, Besitzer eines alten viktorianischen Anwesens, seit den fr\u00fchen 1960er-Jahren ein Netz aus Tunneln und H\u00f6hlen. Ultraschalluntersuchungen zufolge breiten sich die Tunnel in jeder Richtung seines Hauses bis zu zwanzig Meter aus. Er sagt: \u201eDinge zu erfinden, die nicht funktionieren, ist eine brillante Sache. Die Leute fragen dich, was das gro\u00dfe Geheimnis ist. Und wei\u00dft du was? Es gibt keins.\u201c<\/p>\n<p>52<br \/>\nPostindustrielle Gentrifizierungsstra\u00dfe, schwarze T\u00fcren, ein rotes Neonlicht: Night Tales. Ein Lied, das aus der offenen T\u00fcr spielt:<\/p>\n<p>I&#8217;m giving you a night call to tell you how I feel<br \/>&#13;<br \/>\nI want to drive you through the night, down the hills<br \/>&#13;<br \/>\nI&#8217;m gonna tell you something you don&#8217;t want to hear<br \/>&#13;<br \/>\nI&#8217;m gonna show you where it&#8217;s dark, but have no fear<br \/>&#13;<br \/>\n\u00a0&#13;\n<\/p>\n<\/p>\n<p>\u00a0<\/p>\n<p>53<br \/>\nQuertunnel,<br \/>\nStacheldraht,<br \/>\nhinter den Kulissen von Tesco<br \/>\nblinde W\u00e4nde zu Wohnanlagen,<br \/>\nein leeres Werbeplakat auf einer Brandmauer.<br \/>\n\u00a0<br \/>\n54<\/p>\n<blockquote class=\"artikel-zitat\"><p>&#13;<\/p>\n<p class=\"zitat-text\">Er parkte in einer nahe gelegenen Stra\u00dfe und ging zur Br\u00fccke hinaus. Unter ihm breiteten sich die Lichter von London in einer Wanne niedriger Wattleistung aus. Ihre Schw\u00e4che, die L\u00fcge der Weite der Stadt. Bull h\u00f6rte ihr fernes Gebr\u00fcll, ihr n\u00e4chtliches Rauschen, ihr endloses Husten.<\/p>\n<p>&#13;<\/p>\n<p class=\"zitat-autor\">Will Self, Cock &amp; Bull<\/p>\n<p>&#13;\n\t\t<\/p><\/blockquote>\n<p>55<br \/>\nMorning news off license grocery fresh fruit news agent<br \/>\nEin blauer Zaun, frisch gestrichen, ein Loch, gebogener Zaun, eine Abk\u00fcrzung: der Weg des geringsten Widerstands<br \/>\nDocklands, Stratford, Blackwell Tunnel geradeaus<br \/>\nStansted nach links,<br \/>\nRed Route,<br \/>&#13;<br \/>\nClearway,<br \/>&#13;<br \/>\nNo Stopping,<br \/>\nM\u00fcll in den B\u00fcschen,<br \/>\nCruising spots,<br \/>\nniemand wartet an der Bushaltestelle,<br \/>\nNew Map coming soon<br \/>\n\u00a0<br \/>\n56<br \/>\nIn Hackney Wick angekommen, ist der Himmel voller Kr\u00e4ne: die Leere der Modernisierung.<\/p>\n<p>Well it&#8217;s like cranes in the sky<br \/>&#13;<br \/>\nSometimes I don&#8217;t wanna feel those metal clouds<br \/>&#13;<br \/>\n\u00a0&#13;\n<\/p>\n<\/p>\n<p>\u00a0<\/p>\n<p>57<br \/>\nBesetztes Haus links, rechts Eigentumswohnungen:<br \/>\nShithouse to Penthouse<\/p>\n<p>Auf dem Penthouse:<br \/>&#13;<br \/>\nWarehouse style apartments for Sale \/ Considerate construction &#8211; respect the community<br \/>&#13;<br \/>\nAuf dem Shithouse:<br \/>&#13;<br \/>\nMeanwhile in East London Lunatics decorate a building&#13;<br \/>\n&#13;\n<\/p>\n<p>    <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/04\/57-cfabiansaul_-formatkey-jpg-w320m.jpg\"   alt=\"57\" title=\"57\" width=\"2000\" height=\"870\" loading=\"lazy\"\/><br \/>\n\u00a9 Fabian Saul<\/p>\n<p>58<br \/>\nDie Anf\u00e4nge der Docklands. Lange Zeit ein Gebiet armer Arbeiter, doppelte Ausbeutung des Kolonialismus. Jetzt private Immobilien mit eigenen Sicherheitskr\u00e4ften. <strong>Das \u00d6dland wurde zur Wall Street \u2013 Canary Wharf calling: Es war einmal ein sich in Privatbesitz befindliches Dock, ummauert. Eine Linie vom Kolonialismus zum Neoliberalismus.<\/strong><\/p>\n<p>59<\/p>\n<blockquote class=\"artikel-zitat\"><p>&#13;<\/p>\n<p class=\"zitat-text\">\u00dcberall durften junge Menschen zwischen Liebe und M\u00fcllentsorgung w\u00e4hlen. \u00dcberall haben sie sich f\u00fcr die M\u00fcllentsorgung entschieden.<\/p>\n<p>&#13;<\/p>\n<p class=\"zitat-autor\">Guy Debord<\/p>\n<p>&#13;\n\t\t<\/p><\/blockquote>\n<p>60<br \/>\nEin Graffiti: Edwin Smells<br \/>\nZ\u00e4une, alte Industrieh\u00e4user, neue Designerb\u00fcros<br \/>\nGrafikdesign versus Graffiti<br \/>\nEdwin has herpes<br \/>&#13;<br \/>\nThe white building<br \/>\nEdwin lebt nicht mehr hier.<br \/>\n61<br \/>\nDer Olympiapark<br \/>\nRichtung Old Ford Lock.<br \/>\nRoyal Connection<br \/>&#13;<br \/>\nCyclist dismount and use footway<br \/>\nEine kleine H\u00fctte, ein Traum von Fischern, die die Netze einholen.<\/p>\n<p>    <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/04\/59-cmattbuck-cc-by-sa-2.0-canary-wharf-the-city-disappearing-in-fog-and-glass-formatkey-jpg-w320m.jp.jpeg\"   alt=\"Canary Wharf the city disappearing in fog and glass\" title=\"Canary Wharf the city disappearing in fog and glass\" width=\"3258\" height=\"2490\" loading=\"lazy\"\/><br \/>\n\u00a9 mattbuck [CC BY-SA 2.0]<\/p>\n<p>62<br \/>\nOld Ford ist der \u00e4lteste, stromabw\u00e4rts gelegene \u00dcbergangspunkt des Flusses Lea. Ein Teil einer vor-r\u00f6mischen Route, die \u00fcber einen Damm durch die S\u00fcmpfe die Oxford Street, die Old Street, Bethnal Green und Old Ford verbindet. Zu dieser Zeit war der River Lea ein schnell flie\u00dfender Fluss und die Gezeiten reichten bis nach Hackney Wick.<\/p>\n<p>\u00a0&#13;\n<\/p>\n<p>63<\/p>\n<p>In J. R. R. Tolkiens Mittelerde ist Old Ford der Punkt, an dem die Old Forest Road den Fluss Anduin \u00fcberquert. In \u00e4lteren Zeiten gab es hier eine Steinbr\u00fccke, aber am Ende des Dritten Zeitalters war die Br\u00fccke l\u00e4ngst verschwunden, die \u00dcberquerung ist nicht mehr als eine einfache Furt.<\/p>\n<p>64<br \/>\nMein Handy ist leer, der Hackney Brook ergie\u00dft sich m\u00fcde in den River Lea, ein kleiner Bach aus einem niedrigen Bogen. Niemand ist da, Antiklimax. Ein paar After-Work-Jogger checken ihre Smartwatches.<br \/>\n\u00a0<br \/>\n65<br \/>\nSupported by the Mayor of London:<br \/>&#13;<br \/>\n152 Homes for Private Sale<br \/>&#13;<br \/>\n18 Shared Ownership Homes<br \/>&#13;<br \/>\n32 Affordable Rent Homes<\/p>\n<p>Ein Schild:<br \/>&#13;<br \/>\nCanal &amp; River Trust<\/p>\n<p>Eine alte Karte mit Carpenters Road Lock, Old Ford Lock:<\/p>\n<p>If this was then, then you\u2019d be here.<\/p>\n<p>Und weiter unten auf dem Schild:<br \/>&#13;<br \/>\nYou are here, now!&#13;<br \/>\n&#13;\n<\/p>\n<p>    <img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/04\/66-cscott-wylie-cc-by-20-london-docklands-formatkey-jpg-w320m.jpg\"   alt=\"66\" title=\"66\" width=\"2000\" height=\"870\" loading=\"lazy\"\/><br \/>\n\u00a9 Scott Wylie [CC BY 2.0] -London Docklands<\/p>\n<p>\u00a0\u00a0<\/p>\n<p>66<\/p>\n<p><strong>Der Spartacus Guide erschien nicht mehr.<\/strong><\/p>\n<p>Diese Welt war zu Ende.<\/p>\n<p>Weil dies Buch zu Ende war,<br \/>&#13;<br \/>\ndas diese Welt erst geschaffen hatte.<\/p>\n<p>Die Sauna Bath wurden zugemauert,<br \/>&#13;<br \/>\nAus dem Bain de Penthi\u00e8vre, dem Proust-Bad, dem Cocteau-Bad,<br \/>&#13;<br \/>\ndem Jouhandeau-Bad, aus dem \u00e4ltesten Tempel der Liebe mit Achilles als Badew\u00e4rter,<br \/>&#13;<br \/>\nmachten sie Eigentumswohnungen.<\/p>\n<p>Das Bain Voltaire wurde eingerissen.<\/p>\n<p>Das Cin\u00e9ma Luxor am Boulevard Magenta war eine Ruine.<\/p>\n<p>Paris hatte seinen Nabel verloren.<\/p>\n<p>Wie New York Men\u2019s Country.<\/p>\n<p>Zu.<\/p>\n<p>Aus.<\/p>\n<p>Hubert Fichte<\/p>\n<p><a href=\"https:\/\/www.goethe.de\/ins\/gb\/de\/m\/kul\/past\/eur\/tor\/21507957.html\" target=\"_self\" class=\"standard btnHellGrauV4 icon-double-arrow-right XL invert\" rel=\"nofollow noopener\">\u00a0\u00a0zur\u00fcck zum Part I: Holloway<\/a><\/p>\n<p><a href=\"https:\/\/www.goethe.de\/ins\/gb\/de\/m\/kul\/past\/eur\/tor.html\" target=\"_self\" class=\"standard btnHellGrauV4 icon-double-arrow-right XL invert\" rel=\"nofollow noopener\">\u00a0\u00a0zur \u00dcbersicht: Traces of Resistance<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"If this was then, then you\u2019d be here.&#13; Im zweiten Teil seiner Notizen \u00fcber den Hackney Brooke, einer&hellip;\n","protected":false},"author":2,"featured_media":391764,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3976],"tags":[331,332,13,14,15,12,3992,3993,3994,3995,3996,3997],"class_list":{"0":"post-952161","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-vereinigtes-koenigreich","8":"tag-aktuelle-nachrichten","9":"tag-aktuelle-news","10":"tag-headlines","11":"tag-nachrichten","12":"tag-news","13":"tag-schlagzeilen","14":"tag-uk","15":"tag-united-kingdom","16":"tag-united-kingdom-of-great-britain-and-northern-ireland","17":"tag-vereinigtes-koenigreich","18":"tag-vereinigtes-koenigreich-grossbritannien-und-nordirland","19":"tag-vereinigtes-koenigreich-von-grossbritannien-und-nordirland"},"share_on_mastodon":{"url":"","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/952161","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=952161"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/952161\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/391764"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=952161"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=952161"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=952161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}