{"id":956352,"date":"2026-04-19T01:34:52","date_gmt":"2026-04-19T01:34:52","guid":{"rendered":"https:\/\/www.europesays.com\/de\/956352\/"},"modified":"2026-04-19T01:34:52","modified_gmt":"2026-04-19T01:34:52","slug":"2-fussball-bundesliga-bielefeld-bleibt-im-tabellenkeller-11-gegen-nuernberg-bayern","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/956352\/","title":{"rendered":"2. Fu\u00dfball-Bundesliga: Bielefeld bleibt im Tabellenkeller &#8211; 1:1 gegen N\u00fcrnberg &#8211; Bayern"},"content":{"rendered":"<p>Die Gastgeber erwischten einen ganz schwachen Start und wurden von den eigenen Fans ausgepfiffen. N\u00fcrnberg f\u00fchrte zur Pause v\u00f6llig verdient. Nach Wiederanpfiff kamen die Hausherren st\u00e4rker auf, belohnten sich aber vorerst nicht. Die G\u00e4ste-Defensive stand sicher, N\u00fcrnberg verlegte sich mehr aufs Kontern. So ben\u00f6tigte Bielefeld einen Standard zum Ausgleich. Handwerker fand bei einem Freisto\u00df eine L\u00fccke in der N\u00fcrnberger Mauer.<\/p>\n","protected":false},"excerpt":{"rendered":"Die Gastgeber erwischten einen ganz schwachen Start und wurden von den eigenen Fans ausgepfiffen. N\u00fcrnberg f\u00fchrte zur Pause&hellip;\n","protected":false},"author":2,"featured_media":956241,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1841],"tags":[783,13086,2368,772,1605,3364,29,30,1209],"class_list":{"0":"post-956352","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-bielefeld","8":"tag-1-fc-nuernberg","9":"tag-2-liga","10":"tag-arminia-bielefeld","11":"tag-bayern","12":"tag-bielefeld","13":"tag-de","14":"tag-deutschland","15":"tag-germany","16":"tag-nordrhein-westfalen"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116428808184718577","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/956352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=956352"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/956352\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/956241"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=956352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=956352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=956352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}