{"id":957729,"date":"2026-04-19T16:02:28","date_gmt":"2026-04-19T16:02:28","guid":{"rendered":"https:\/\/www.europesays.com\/de\/957729\/"},"modified":"2026-04-19T16:02:28","modified_gmt":"2026-04-19T16:02:28","slug":"nach-magdeburg-patzer-berlin-feiert-pokal-triumph","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/957729\/","title":{"rendered":"Nach Magdeburg-Patzer: Berlin feiert Pokal-Triumph"},"content":{"rendered":"<p class=\"is-first-paragraph\" data-external=\"Article.FirstParagraph\">Nach dem zweiten Pokal-Triumph der Vereinsgeschichte legten die Handballer der F\u00fcchse Berlin um ihr d\u00e4nisches Traum-Duo Mathias Gidsel und Lasse Andersson einen ausgelassenen Jubel-Tanz auf das Parkett. In einem einseitigen Endspiel beim Final4 in K\u00f6ln setzte sich der deutsche Meister gegen das \u00dcberraschungsteam des Bergischen HC, der im Halbfinale sensationell den souver\u00e4nen Bundesliga-Spitzenreiter SC Magdeburg ausgeschaltet hatte, deutlich mit 42:33 (22:17) durch.<\/p>\n<p>\u00abIn Deutschland Titel zu holen, ist immer schwer. Unfassbar, dass wir das geschafft haben. Ich bin extrem stolz. Das bedeutet mir sehr viel\u00bb, sagte Welthandballer Gidsel \u00fcber den zweiten Berliner Pokal-Triumph nach 2014 und erg\u00e4nzte: \u00abEs war ein sch\u00f6nes Wochenende. Jetzt genie\u00dfen wir das.\u00bb<\/p>\n<p>Vor 19.750 Fans in der ausverkauften K\u00f6lner Lanxess Arena waren Andersson mit zehn Toren und Gidsel mit neun Treffern beste Werfer f\u00fcr die Berliner. Zudem war Torwart Dejan Milosavljev mit 13 Paraden bis zu seinem verletzungsbedingten Aus in der zweiten Halbzeit ein starker R\u00fcckhalt.<\/p>\n<p>Mit dem Pokalsieg haben die F\u00fcchse eine schwierige Bundesligasaison, in der die Trennung von Sportvorstand Stefan Kretzschmar und Meistertrainer Jaron Siewert im vergangenen September hohe Wellen geschlagen hatte, doch noch mit einem Titel gekr\u00f6nt. \u00abDas war super. Wir hatten viele individuell starke Leistungen. Die braucht man auch, um den Pokal zu holen\u00bb, lobte der jetzige Coach Nicolej Krickau sein Team und k\u00fcndigte an: \u00abHeute Abend wird gefeiert.\u00bb<\/p>\n<p>Magdeburg erlebt Pokal-Alptraum<\/p>\n<p>In der Champions League sind die Berliner ebenfalls noch im Rennen. Das gilt auch f\u00fcr den designierten Meister SC Magdeburg, f\u00fcr den der Traum vom Double bereits im Halbfinale am Samstag brutal geplatzt war. Der Favorit scheiterte v\u00f6llig unerwartet im Siebenmeterwerfen am BHC und musste sich nach einem 31:35 im Spiel um Platz drei gegen den TBV Lemgo Lippe mit Rang vier begn\u00fcgen.<\/p>\n<p>\u00abDie Entt\u00e4uschung ist gro\u00df, es tut unheimlich weh. Ich h\u00e4tte mir an beiden Tagen einen besseren Auftritt von uns gew\u00fcnscht. Wir m\u00fcssen jetzt schnellstm\u00f6glich versuchen, unseren Weg wiederzufinden\u00bb, sagte SCM-Trainer Bennet Wiegert und war in Gedanken auch bei den Fans: \u00abDie traurigen Gesichter zu sehen, bricht mir das Herz.\u00bb<\/p>\n<p>Individuelle Klasse sorgt f\u00fcr Berliner Sieg<\/p>\n<p>In Hochstimmung befand sich dagegen der im Meisterrennen von den Magdeburgern schon deutlich abh\u00e4ngte Rivale aus Berlin. Nach dem schwer erk\u00e4mpften 39:36-Sieg in Halbfinale gegen Lemgo wurde der Hauptstadt-Club seiner Favoritenrolle im Finale trotz tapferer Gegenwehr des BHC gerecht.<\/p>\n<p>Nach einer ausgeglichenen Startphase konnten sich die F\u00fcchse Mitte der ersten Halbzeit beim 13:10 (18. Minute) erstmals ein Drei-Tore-Polster verschaffen. Bis zur Pause zog der Bundesliga-Dritte auf f\u00fcnf Treffer davon, weil Milosavljev wie schon am Vortag einen Sahnetag hatte und vorn neben den d\u00e4nischen Welt- und Europameistern Andersson und Gidsel auch Rechtsau\u00dfen Hakun West av Teigum (6) ein sicherer Vollstrecker war.<\/p>\n<p>Nach dem Wechsel hielten die Berliner den Gegner immer auf sicherer Distanz und lie\u00dfen damit keine Spannung mehr aufkommen. Vielmehr wuchs der Vorsprung weiter an. Kleiner Trost f\u00fcr den BHC: Sollten sich die F\u00fcchse f\u00fcr die K\u00f6nigsklasse qualifizieren, r\u00fcckt der Finalverlierer in die European League nach. \u00abWas wir hier mannschaftlich geleistet haben, war unbeschreiblich\u00bb, res\u00fcmierte Kreisl\u00e4ufer Aron Seesing den erfrischenden Pokal-Auftritt.<\/p>\n","protected":false},"excerpt":{"rendered":"Nach dem zweiten Pokal-Triumph der Vereinsgeschichte legten die Handballer der F\u00fcchse Berlin um ihr d\u00e4nisches Traum-Duo Mathias Gidsel&hellip;\n","protected":false},"author":2,"featured_media":957730,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1825],"tags":[296,29,30,45],"class_list":{"0":"post-957729","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-berlin","8":"tag-berlin","9":"tag-deutschland","10":"tag-germany","11":"tag-texttospeech"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116432217537803240","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/957729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=957729"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/957729\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/957730"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=957729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=957729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=957729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}