{"id":960007,"date":"2026-04-20T15:21:20","date_gmt":"2026-04-20T15:21:20","guid":{"rendered":"https:\/\/www.europesays.com\/de\/960007\/"},"modified":"2026-04-20T15:21:20","modified_gmt":"2026-04-20T15:21:20","slug":"vfb-stuttgart-gelebte-partnerschaft-auf-augenhoehe","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/960007\/","title":{"rendered":"VfB Stuttgart | Gelebte Partnerschaft auf Augenh\u00f6he"},"content":{"rendered":"<p>Im Doppelinterview sprechen Alexander Wehrle als VfB-Vorstandsvorsitzender und Joachim Erdle als LBBW-Vorstandsmitglied \u00fcber die Chancen der besonderen Zusammenarbeit und den schw\u00e4bischen Mittelstand.<\/p>\n<p>Die LBBW unterst\u00fctzt den VfB Stuttgart seit dieser Saison als Hauptsponsor und bringt im Rahmen dieser Partnerschaft strategische Mehrwerte ein, die enorm wertvoll f\u00fcr die Entwicklung des Clubs aus Cannstatt sind. Im Doppelinterview sprechen Alexander Wehrle und Joachim Erdle, Vorstandsmitglied der LBBW, hier\u00fcber sowie \u00fcber die Chancen dieser besonderen Zusammenarbeit und den schw\u00e4bischen Mittelstand. <\/p>\n<p><strong>\u201eDie Bank ist spielentscheidend\u201c: Was bedeutet dieser Satz f\u00fcr Sie beide?<\/strong><\/p>\n<p>Alexander Wehrle: \u201eIm Fu\u00dfball z\u00e4hlen Tore und Tabellenpl\u00e4tze, aber nachhaltiger Erfolg entscheidet sich sowohl auf als auch neben dem Platz. \u201eSpielentscheidend\u201c hei\u00dft f\u00fcr mich: Eine starke Bank gibt uns Stabilit\u00e4t f\u00fcr zentrale Weichenstellungen, etwa bei der Modernisierung unserer Infrastruktur, im Nachwuchsbereich oder bei der digitalen Transformation. Die LBBW verschafft uns Handlungsf\u00e4higkeit in einem Umfeld, das sich sportlich wie wirtschaftlich rasch ver\u00e4ndert. So k\u00f6nnen wir strategisch langfristig planen, statt nur \u201evon Spiel zu Spiel\u201c zu schauen.\u201c<\/p>\n<p>Joachim Erdle: \u201eSpielentscheidend\u201c bedeutet f\u00fcr uns als Universalbank, dass wir mehr sind als reiner Kreditgeber. Wir sind strategischer Wettbewerbsvorteil f\u00fcr Unternehmen mit gro\u00dfen Zielen. Das gilt f\u00fcr den VfB Stuttgart ebenso wie f\u00fcr viele andere mittelst\u00e4ndische Unternehmen. Als Bank schaffen wir die Finanzarchitektur, mit der sich ambitionierte Pl\u00e4ne richtig gut umsetzen lassen; von der Gro\u00dfinvestition bis hin zur Internationalisierung. Entscheidend ist f\u00fcr uns: Wir sind stark und handlungsf\u00e4hig, gerade dann, wenn Situationen komplex werden. Leistungsst\u00e4rke zeigt sich \u00fcber die gesamte \u201eSaison\u201c einer Partnerschaft, nicht nur im Einzelerfolg.\u201c<\/p>\n<p><strong>Wie unterst\u00fctzt die LBBW den VfB Stuttgart dabei, langfristig stabil und erfolgreich zu bleiben?<\/strong><\/p>\n<p>Alexander Wehrle: \u201eIm Profifu\u00dfball ist langfristige Stabilit\u00e4t die Grundvoraussetzung. Daf\u00fcr brauchen wir eine Bank, die unsere Strategie versteht, Risiken mit uns abw\u00e4gt und in Szenarien denkt. Die LBBW bringt daf\u00fcr finanzielle Leistungsst\u00e4rke und wirklich individuelle Beratung mit. Statt Standardl\u00f6sungen gibt es einen Matchplan, der zu unserem doch speziellen Gesch\u00e4ftsmodell Profifu\u00dfball passt. Ein ganz praktisches Beispiel ist die neue Bezahll\u00f6sung, die wir gemeinsam mit der LBBW in der MHP Arena implementiert haben: Dadurch bezahlen unsere Fans an den Kiosken rascher und bequemer, die Zahlungsabwicklung l\u00e4uft deutlich effizienter und wir gewinnen wertvolle Informationen f\u00fcr die weitere Optimierung unserer Serviceangebote in der MHP Arena. Die Besonderheiten von uns als Proficlub werden somit in passende Strukturen \u00fcbersetzt. Das ist ein zentraler Baustein, um sportlich wie wirtschaftlich gut aufgestellt zu sein.\u201c<\/p>\n<blockquote class=\"fright\">\n<p class=\"quoteContent\"><strong>LBBW-Vorstandsmitglied Joachim Erdle:<\/strong> <\/p>\n<p>\u201eSpielentscheidend\u201c bedeutet f\u00fcr uns als Universalbank, dass wir mehr sind als reiner Kreditgeber. Wir sind strategischer Wettbewerbsvorteil f\u00fcr Unternehmen mit gro\u00dfen Zielen. <\/p>\n<\/blockquote>\n<p><strong>Was k\u00f6nnen mittelst\u00e4ndische Unternehmen aus der Partnerschaft mit dem VfB f\u00fcr sich mitnehmen?<\/strong><\/p>\n<p>Joachim Erdle: \u201eDie Partnerschaft mit dem VfB zeigt, wie wir arbeiten und vieles davon l\u00e4sst sich direkt auf den Mittelstand \u00fcbertragen. Dank unserer \u201eTiefe im Kader\u201c bleiben die n\u00f6tigen Mittel auch dann verf\u00fcgbar, wenn Projekte l\u00e4nger dauern oder zus\u00e4tzliche Flexibilit\u00e4t gefragt ist. Unsere Partnerschaft basiert auf Vertrauen, Zuverl\u00e4ssigkeit und dem Verst\u00e4ndnis des Gesch\u00e4ftsmodells sowie der Strategie. Entscheidend ist zudem unsere wirklich individuelle Beratung. Wir verstehen das Business, nicht nur die Bilanz. So erkennen wir Chancen und Risiken fr\u00fch und entwickeln einen Matchplan, der zur aktuellen Phase, zur Organisation und zum Marktumfeld des Kunden passt. Wer sieht, welche Rolle wir f\u00fcr den VfB spielen, erkennt, wie wir auch mittelst\u00e4ndische Unternehmen begleiten: als Bank, die im entscheidenden Moment den Unterschied macht.\u201c<\/p>\n<p><strong>Wo sehen Sie die Parallelen zwischen Leadership im Profifu\u00dfball und im Mittelstand?<\/strong><\/p>\n<p>Alexander Wehrle: \u201eIn beiden Welten werden Entscheidungen unter Unsicherheit getroffen. Im Fu\u00dfball k\u00f6nnen wenige Spieltage viel ver\u00e4ndern, im Mittelstand sind es unerwartete Marktbewegungen, neue Wettbewerber oder Regulierungen. Erfolgreich ist ein F\u00fchrungsteam, das eine klare Linie verfolgt, offen kommuniziert und flexibel bleibt f\u00fcr Dinge, die sich \u00e4ndern. Viele gute Entscheidungen entstehen im direkten, offenen Austausch; nicht nur im formellen Meeting. Wenn ich mit Joachim Erdle spreche, ist es genau dieses \u201aKrawatte aus, \u00c4rmel hoch\u2018-Gef\u00fchl: Wir reden konkret \u00fcber Chancen, Risiken und Wege zum Ziel. Das ist eine gelebte Partnerschaft auf Augenh\u00f6he.\u201c<\/p>\n<p>Joachim Erdle: \u201eIch w\u00fcrde es als Kurzpassspiel bezeichnen. Wir arbeiten interdisziplin\u00e4r, teamorientiert und mit klarer Performancekultur: Spezialisten aus Finanzierung, Risiko, Internationalem und weiteren Bereichen spielen sich die B\u00e4lle zu. So entstehen L\u00f6sungen, die es den Entscheidern erm\u00f6glichen, sich auf das Wesentliche zu konzentrieren, also die Position am Markt oder in der Tabelle. Wie im Profifu\u00dfball gilt: Ohne abgestimmtes Zusammenspiel im Team \u2013 im Verein wie in der Bank \u2013 gelingt kein nachhaltiger Erfolg.\u201c<\/p>\n<p>\u00a0<\/p>\n<blockquote class=\"fleft\">\n<p class=\"quoteContent\"><strong>VfB-Vorstandsvorsitzender Alexander Wehrle :<\/strong> <\/p>\n<p>Viele gute Entscheidungen entstehen im direkten, offenen Austausch; nicht nur im formellen Meeting. Wenn ich mit Joachim Erdle spreche, ist es genau dieses \u201aKrawatte aus, \u00c4rmel hoch\u2018-Gef\u00fchl: Wir reden konkret \u00fcber Chancen, Risiken und Wege zum Ziel. Das ist eine gelebte Partnerschaft auf Augenh\u00f6he.\u201c<\/p>\n<\/blockquote>\n<p><strong>Viele Mittelst\u00e4ndler kennen den VfB sehr gut. Was w\u00fcrden Sie einer Gesch\u00e4ftsf\u00fchrerin oder einem CFO \u00fcber die LBBW sagen, aus Ihrer Erfahrung?<\/strong><\/p>\n<p>Alexander Wehrle: \u201eDie LBBW ist ein Partner, der sich einbringt und, auf den man sich 100 Prozent verlassen kann. Sie versteht unser Gesch\u00e4ft und ist bereit, in die Verantwortung zu gehen. Das zeigt sich in der Vorbereitung, bei Absprachen und der Umsetzung von Projekten. Es geht nicht um ein \u201enebenbei\u201c, sondern um ein Miteinander auf Basis von Vertrauen und eines verbindenden Wertesystems. Wer vor gr\u00f6\u00dferen Ver\u00e4nderungen steht, vor Investitionen, neuen Gesch\u00e4ftsmodellen, Wachstumsschritten oder \u00c4hnlichem, profitiert von einer Bank, die nicht nur Produkte liefert, sondern mitdenkt, mitplant und verl\u00e4sslich bleibt. So erleben wir die LBBW.\u201c<\/p>\n<p><strong>Wie k\u00f6nnte ein erster Austausch mit der LBBW aussehen, wenn man seine Bankbeziehung neu denkt?<\/strong><\/p>\n<p>Joachim Erdle: \u201eAm Anfang steht ein Gespr\u00e4ch, in dem es um die Strategie und die Ziele geht: Wo steht das Unternehmen heute, welche Ver\u00e4nderungen stehen an, welche Chancen und Risiken werden gesehen? Darauf aufbauend entwickeln wir einen individuellen Matchplan, der Finanzierung, Risikobetrachtung und Wachstumschancen verbindet.\u201c<\/p>\n<p><strong>Viele sprechen von \u201eZeiten des Wandels\u201c. Wenn Sie an die n\u00e4chsten f\u00fcnf Jahre denken: Mit welchen Themen d\u00fcrfen sich Mittelst\u00e4ndler an Sie wenden und wie wollen LBBW und VfB gemeinsam Orientierung und Mehrwert bieten?<\/strong><\/p>\n<p>Alexander Wehrle: \u201eDer VfB zeigt, wie man Ver\u00e4nderung aktiv gestalten kann &#8211; mit klarer Strategie, einem starken Team und verl\u00e4sslichen Partnern. Mittelst\u00e4ndler profitieren von unseren Erfahrungen mit Investitionen, Transformation und Standortentwicklung, indem sie diese Erfolgsfaktoren auf ihr Business \u00fcbertragen und die LBBW als strategischen Mitspieler nutzen.\u201c<\/p>\n<p>Joachim Erdle: \u201eMittelst\u00e4ndische Unternehmen kommen mit allen strategischen Finanzthemen auf uns zu: von Gro\u00dfinvestitionen \u00fcber Internationalisierung bis hin zur Finanzierung von Transformation. Entscheidend ist f\u00fcr uns dabei weniger das einzelne Produkt als das Gesamtbild: Wir denken Finanzierung, Risiko, Liquidit\u00e4t und Wachstum immer zusammen und entwickeln daraus einen Matchplan, der wirklich zur Situation des Unternehmens passt. Dank unserer finanziellen Leistungsst\u00e4rke k\u00f6nnen wir auch mehrstufige Vorhaben \u00fcber l\u00e4ngere Zeitr\u00e4ume verl\u00e4sslich begleiten. Und: Unsere Partnerschaft mit dem VfB ist eine B\u00fchne, auf der man sehr konkret erleben kann, wie dieses Zusammenspiel aus Strategie, Finanzierung und engem Austausch auf Augenh\u00f6he funktioniert \u2013 genauso, wie wir es auch im Mittelstand leben.\u201c<\/p>\n","protected":false},"excerpt":{"rendered":"Im Doppelinterview sprechen Alexander Wehrle als VfB-Vorstandsvorsitzender und Joachim Erdle als LBBW-Vorstandsmitglied \u00fcber die Chancen der besonderen Zusammenarbeit&hellip;\n","protected":false},"author":2,"featured_media":960008,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1830],"tags":[1634,3364,29,30,1441],"class_list":{"0":"post-960007","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-stuttgart","8":"tag-baden-wuerttemberg","9":"tag-de","10":"tag-deutschland","11":"tag-germany","12":"tag-stuttgart"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116437718594227245","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/960007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=960007"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/960007\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/960008"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=960007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=960007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=960007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}