{"id":967680,"date":"2026-04-23T19:20:51","date_gmt":"2026-04-23T19:20:51","guid":{"rendered":"https:\/\/www.europesays.com\/de\/967680\/"},"modified":"2026-04-23T19:20:51","modified_gmt":"2026-04-23T19:20:51","slug":"pol-h-spurensuche-statt-schulbank-760-kinder-und-jugendliche-beim-zukunftstag-der","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/967680\/","title":{"rendered":"POL-H: Spurensuche statt Schulbank: 760 Kinder und Jugendliche beim Zukunftstag der &#8230;"},"content":{"rendered":"<p class=\"date\">23.04.2026 \u2013 16:31<\/p>\n<p class=\"customer\">\n                        <a class=\"story-customer\" title=\"weiter zum newsroom von Polizeidirektion Hannover\" href=\"https:\/\/www.presseportal.de\/blaulicht\/nr\/66841\" rel=\"nofollow noopener\" target=\"_blank\">Polizeidirektion Hannover<\/a>\n                    <\/p>\n<p><a class=\"glightbox-pseudo event-trigger\" href=\"https:\/\/cache.pressmailing.net\/thumbnail\/story_hires\/ac412318-6630-4480-958d-8645c4ec836e\/Zukunftstag_2026_23-~_08-51_EOS61786.jpg.jpg\" data-description=\"Zukunftstag 2026 bei der Polizeidirektion Hannover_4\" data-category=\"medialightbox\" data-action=\"click\" data-label=\"single\" data-value=\"69ea2d6c270000fd2c56c149\" rel=\"nofollow noopener\" target=\"_blank\"><img decoding=\"async\" height=\"540\" with=\"720\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/04\/pol-h-spurensuche-statt-schulbank-760-kinder-und-jugendliche-beim-zukunftstag-der-polizei-hannover.jpeg\"   alt=\"POL-H: Spurensuche statt Schulbank: 760 Kinder und Jugendliche beim Zukunftstag der Polizei Hannover\" class=\"single\"\/><\/a><\/p>\n<p><a data-category=\"citylink-story-view\" data-action=\"click\" data-label=\"Citylink in Meldungsansicht\" class=\"story-city event-trigger\" href=\"https:\/\/www.presseportal.de\/regional\/Hannover\" title=\"News aus Hannover \" rel=\"nofollow noopener\" target=\"_blank\">Hannover<\/a> (ots)<\/p>\n<p>Am heutigen Donnerstag, 23.04.2026, herrschte in den Dienststellen der Polizeidirektion (PD) Hannover ein ganz besonderes Treiben: Insgesamt 760 Sch\u00fclerinnen und Sch\u00fcler der Klassenstufen 5 bis 9 im Alter von 10 bis 14 Jahren tauschten das Klassenzimmer gegen die spannende Welt der Verbrechensbek\u00e4mpfung.<\/p>\n<p>Besonders kreativ gestaltete sich der Tag f\u00fcr jene 135 Jugendlichen, die direkt im Stab der Polizeidirektion zu Gast waren, denn dort wurde der Zukunftstag in diesem Jahr als packendes Escape-Erlebnis konzipiert.<\/p>\n<p>Unter dem Titel &#8222;Einbruch in das Landesmuseum &#8211; Diebstahl des blauen Juwels&#8220; schl\u00fcpften die Kinder und Jugendlichen in die Rolle von Ermittlerinnen und Ermittlern und begaben sich auf die Suche nach den fl\u00fcchtigen T\u00e4tern. Der Weg zur L\u00f6sung des Falls f\u00fchrte sie durch sieben aufwendig gestaltete Stationen, die den Puls der jungen Ermittlerinnen und Ermittler h\u00f6herschlagen lie\u00dfen. In der Lage- und F\u00fchrungszentrale h\u00f6rten die Sch\u00fclerinnen und Sch\u00fcler die Meldung des Einbruchs aus dem Landesmuseum, besprachen die zu treffenden Sofortma\u00dfnahmen und teilten die Funkstreifenwagen strategisch ein.<\/p>\n<p>Mit Blick f\u00fcrs Detail ging es bei der Spurensicherung weiter. Hier wurden Schuhspuren gesucht, Fingerabdr\u00fccke gesichert und Blutspuren erkl\u00e4rt. An der Station Videoauswertung wurden Aufnahmen von der \u00dcberwachungskamera gesichtet und eine Personenbeschreibung der T\u00e4ter erstellt. Bei einer Zeugenvernehmung lernten die Kids und Teens unter fachkundiger Anleitung, wie man eine aufgeregte Zeugin beruhigt und wichtige von unwichtigen Informationen trennt. Zudem durften Ausr\u00fcstung und Fahrzeuge nicht nur bestaunt, sondern auch anprobiert und angefasst werden. Bei einer k\u00f6rperlich aktiven Fragerunde waren Konzentration und Sportlichkeit gefragt. Die Ermittlung gipfelte schlie\u00dflich in einem Highlight: der Festnahme einer der T\u00e4ter in den R\u00e4umlichkeiten des Polizeigewahrsams aus dem Jahr 1903.<\/p>\n<p>Doch nicht nur im Stab wurde Geschichte geschrieben. Bei der Polizeiinspektion (PI) Besondere Dienste erlebten 103 Kinder faszinierende Einblicke bei den Reitern und Hunden. Neben Stallf\u00fchrungen beeindruckten Vorf\u00fchrungen der Diensttiere das junge Publikum. Die Verf\u00fcgungseinheiten punkteten mit Vortr\u00e4gen, Videos und einer interessanten Materialschau der Schutzausstattung, w\u00e4hrend der Verkehrsunfalldienst (VUD) die Sch\u00fclerinnen und Sch\u00fcler selbst aktiv werden lie\u00df: Es wurden Unfallstellen vermessen. Auch wurden schwere Polizeikr\u00e4der bestaunt und die Geschwindigkeit mittels Laserpistole gemessen.<\/p>\n<p>Auch in der gesamten Region Hannover war die Begeisterung sp\u00fcrbar. Die PI Burgdorf hie\u00df 30 Kinder willkommen, w\u00e4hrend die Kommissariate in Gro\u00dfburgwedel (15), Langenhagen (32), Lehrte (24) und Mellendorf (15) ebenfalls ihre T\u00fcren \u00f6ffneten. Die PI Hannover empfing 30 Teilnehmende, unterst\u00fctzt durch die Dienststellen in D\u00f6hren (24), Laatzen (10), Lahe (15), Limmer (35), Mitte (27), der Nordstadt (19) und St\u00f6cken (18). Im Bereich der PI Garbsen (40) herrschte ebenso reger Andrang wie in Barsinghausen (16), Neustadt (15), Ronnenberg (25), Seelze (15), Springe (15) und Wunstorf (22). Ein besonderes Schwergewicht der kriminalistischen Arbeit bildete zudem der Zentrale Kriminaldienst (ZKD), der allein 80 Kindern die Komplexit\u00e4t moderner Ermittlungsmethoden n\u00e4herbrachte.<\/p>\n<p>Durch die Verbindung von spielerischen Elementen, echtem Anfassen und realit\u00e4tsnahen Einblicken in den Polizeialltag gelang es, den Sch\u00fclerinnen und Sch\u00fclern die Vielfalt des Berufslebens bei der Polizei auf lebhafte Weise n\u00e4herzubringen. Mit dem erfolgreichen Abschluss der Ermittlungen, der Sicherstellung des Juwels und vielen neuen Eindr\u00fccken im Gep\u00e4ck endete f\u00fcr die 760 Teilnehmenden ein ereignisreicher Tag, der bei vielen den Wunsch geweckt haben d\u00fcrfte, sp\u00e4ter vielleicht einmal selbst die Uniform zu tragen. \/nash, ram<\/p>\n<p class=\"contact-headline\">R\u00fcckfragen bitte an:<\/p>\n<p class=\"contact-text\">Polizeidirektion Hannover<br \/>Natalia Shapovalova<br \/>Telefon: 0511 109-1040<br \/>E-Mail: <a href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/66841\/mailto: pressestelle@pd-h.polizei.niedersachsen.de\" class=\"uri-mailto\" rel=\"nofollow noopener\" target=\"_blank\"> pressestelle@pd-h.polizei.niedersachsen.de<\/a><br \/><a target=\"_blank\" class=\"uri-ext outbound\" rel=\"noopener nofollow\" href=\"https:\/\/www.pd-h.polizei-nds.de\">https:\/\/www.pd-h.polizei-nds.de<\/a><\/p>\n<p class=\"originator\">Original-Content von: Polizeidirektion Hannover, \u00fcbermittelt durch news aktuell<\/p>\n","protected":false},"excerpt":{"rendered":"23.04.2026 \u2013 16:31 Polizeidirektion Hannover Hannover (ots) Am heutigen Donnerstag, 23.04.2026, herrschte in den Dienststellen der Polizeidirektion (PD)&hellip;\n","protected":false},"author":2,"featured_media":967681,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1836],"tags":[3364,29,30,46,177,5404,1411,121,178,180,179,181],"class_list":{"0":"post-967680","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-hannover","8":"tag-de","9":"tag-deutschland","10":"tag-germany","11":"tag-hannover","12":"tag-kriminalitt","13":"tag-ni","14":"tag-niedersachsen","15":"tag-polizei","16":"tag-presse","17":"tag-pressemeldung","18":"tag-pressemitteilung","19":"tag-pressemitteilungen"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116455650281929729","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/967680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=967680"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/967680\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/967681"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=967680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=967680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=967680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}