{"id":976072,"date":"2026-04-27T06:22:17","date_gmt":"2026-04-27T06:22:17","guid":{"rendered":"https:\/\/www.europesays.com\/de\/976072\/"},"modified":"2026-04-27T06:22:17","modified_gmt":"2026-04-27T06:22:17","slug":"berlin-brandenburg-ministerin-brauchen-bei-laengerer-krise-weitere-entlastungen","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/976072\/","title":{"rendered":"Berlin &#038; Brandenburg: Ministerin: Brauchen bei l\u00e4ngerer Krise weitere Entlastungen"},"content":{"rendered":"<p>Berlin &amp; BrandenburgMinisterin: Brauchen bei l\u00e4ngerer Krise weitere Entlastungen<img decoding=\"async\" class=\"Image_img__fQCi0 Image_Img_16_9__4BLfH\" loading=\"eager\" fetchpriority=\"high\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/04\/Brandenburgs-Wirtschaftsministerin-sieht-die-sogenannte-Entlastungspraemie-die-Unternehmen-ihren-Bes.webp\" alt=\"Brandenburgs-Wirtschaftsministerin-sieht-die-sogenannte-Entlastungspraemie-die-Unternehmen-ihren-Beschaeftigten-zahlen-koennen-sollen-kritisch\"\/>TeilenFolgen auf:<a href=\"https:\/\/www.whatsapp.com\/channel\/0029Va5cdVJD8SDp5YZgYF01\" title=\"Auf WhatsApp folgen\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/www.n-tv.de\/socialIcons\/whatsapp.svg\" alt=\"whatsapp\" class=\"ArticleShare_icon__FsrC2\"\/><\/a><a href=\"https:\/\/news.google.com\/publications\/CAAiEPMdif5mpRNxiLOeUpHCwwsqFAgKIhDzHYn-ZqUTcYiznlKRwsML?hl=de&amp;gl=DE&amp;ceid=DE%3Ade\" title=\"Auf Google News folgen\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/www.n-tv.de\/socialIcons\/google.svg\" alt=\"whatsapp\" class=\"ArticleShare_icon__FsrC2\"\/><\/a><\/p>\n<p class=\"Typography_text-m__XI0da Typography_weight-bold__uT6mq storyline_lead_text_leadtext__q_wg8\">Brandenburgs Wirtschaftsministerin sieht bei anhaltender Krise in der Golfregion weiteren Handlungsbedarf f\u00fcr Unternehmen. Die bisher getroffenen Entlastungsma\u00dfnahmen sieht sie kritisch.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Potsdam (dpa\/bb) &#8211; Brandenburgs Wirtschaftsministerin Martina Klement (CSU) h\u00e4lt weitere Entlastungsma\u00dfnahmen f\u00fcr Unternehmen f\u00fcr notwendig, wenn die Krise in der Golfregion noch l\u00e4nger andauert. &#8222;Wenn diese Krise l\u00e4nger andauert, werden wir sicherlich uns gemeinsam mit dem Bund noch mal Gedanken machen m\u00fcssen, ob wir weitere Ma\u00dfnahmen unternehmen k\u00f6nnen&#8220;, sagte sie im RBB-Inforadio. Einen l\u00e4ngeren Konflikt werde man nicht nur bei den Spritpreisen merken, sondern vielleicht auch bei Lieferketten oder erh\u00f6hten Preisen in anderen Bereichen.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Die bisher getroffenen Entlastungsma\u00dfnahmen, insbesondere die M\u00f6glichkeit f\u00fcr Unternehmen, ihren Besch\u00e4ftigten 1.000 Euro steuer- und abgabenfrei zukommen zu lassen, sieht sie kritisch. Diese sei nicht besonders hilfreich, da sie Unternehmen und insbesondere Handwerksbetriebe unn\u00f6tig unter Druck setze.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Es komme nun auf die konkrete Ausgestaltung durch den Bund an, betonte Klement. Denkbar sei etwa die M\u00f6glichkeit einer gestaffelten Auszahlung dieser sogenannten Entlastungspr\u00e4mie. &#8222;Ansonsten muss und kann das nat\u00fcrlich jedes Unternehmen nur selbst entscheiden, ob sie auszahlen wollen und vor allen Dingen, ob sie auszahlen k\u00f6nnen&#8220;, sagte die Ministerin. Sie halte andere Ma\u00dfnahmen wie etwa eine h\u00f6here Pendlerpauschale f\u00fcr sinnvoller.<\/p>\n<p class=\"Typography_text-s__wu_cm Typography_weight-normal__pqUbH Typography_color-darkgrey__sZEnP article-detail-footer_source__KslPc\">Quelle: dpa<\/p>\n","protected":false},"excerpt":{"rendered":"Berlin &amp; BrandenburgMinisterin: Brauchen bei l\u00e4ngerer Krise weitere EntlastungenTeilenFolgen auf: Brandenburgs Wirtschaftsministerin sieht bei anhaltender Krise in der&hellip;\n","protected":false},"author":2,"featured_media":976073,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1816],"tags":[1960,1958,1959,1957,1956,1890,29,30],"class_list":{"0":"post-976072","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brandenburg","8":"tag-aktuelle-nachrichten-aus-berlin-und-brandenburg","9":"tag-aktuelle-nachrichten-aus-brandenburg","10":"tag-aktuelle-news-aus-berlin-und-brandenburg","11":"tag-aktuelle-news-aus-brandenburg","12":"tag-berlin-und-brandenburg","13":"tag-brandenburg","14":"tag-deutschland","15":"tag-germany"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116475235650088417","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/976072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=976072"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/976072\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/976073"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=976072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=976072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=976072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}