{"id":981625,"date":"2026-04-29T10:37:21","date_gmt":"2026-04-29T10:37:21","guid":{"rendered":"https:\/\/www.europesays.com\/de\/981625\/"},"modified":"2026-04-29T10:37:21","modified_gmt":"2026-04-29T10:37:21","slug":"in-hamburg-hier-entstehen-mehr-als-200-neue-wohnungen","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/981625\/","title":{"rendered":"In Hamburg: Hier entstehen mehr als 200 neue Wohnungen"},"content":{"rendered":"\n<p><strong>Richtfest in Ei\u00dfendorf:<\/strong> <strong>Am Lichtenauerweg entstehen 216 Wohnungen und eine Kita. Fertig werden soll das neue Quartier im kommenden Jahr.<\/strong><\/p>\n<p>Das st\u00e4dtische Wohnungsunternehmen SAGA baut vier Mehrfamilienh\u00e4user mit je drei bis vier Geschossen \u2013 69 Wohnungen werden \u00f6ffentlich gef\u00f6rdert, 147 frei finanziert und vermietet. Alle Wohnungen erhalten einen Balkon, eine Loggia oder eine Terrasse. 70 Wohnungen sind barrierefrei geplant. 2027 sollen bereits die ersten Mieter einziehen. In der Kita sollen insgesamt 120 Kinder Platz finden.<\/p>\n<p>SAGA-Vorstand Snezana Michaelis lobt das \u201ebreit gef\u00e4cherte Angebot\u201c im Quartier. Der Mix aus gef\u00f6rdertem und freiem Wohnraum, barrierefreien Wohnungen und Kita schaffe gute Bedingungen f\u00fcr die Nachbarschaft.<\/p>\n<p>SAGA-Wohnungen: Solaranlagen und Eisspeicher<\/p>\n<p>Das Konzept setzt auf Nachhaltigkeit \u2013 auch bei der Energiegewinnung: Geplant sind unter anderem Photovoltaikanlagen auf begr\u00fcnten D\u00e4chern und ein sogenannter Eisspeicher zur Energieversorgung. Neben den Wohnungen entstehen auch autofreie Wege, begr\u00fcnte Innenh\u00f6fe mit Spiel- und Aufenthaltsfl\u00e4chen und Sitzm\u00f6glichkeiten im Au\u00dfenraum. Zum Quartier geh\u00f6ren auch 209 Stellpl\u00e4tze in einer Tiefgarage und 280 Fahrradstellpl\u00e4tze.<\/p>\n<p><strong>Das k\u00f6nnte Sie auch interessieren:<\/strong> <a href=\"https:\/\/www.mopo.de\/hamburg\/statt-pflegeheim-hamburg-startet-sechs-modellprojekte-fuer-wohnen-im-alter\/#google_vignette\" rel=\"nofollow noopener\" target=\"_blank\">Statt Pflegeheim: Hamburg startet sechs Modellprojekte f\u00fcr Wohnen im Alter<\/a><\/p>\n<p>Harburgs Bezirksamtsleiter Christian Carstensen sprach von einem \u201esehr guten Signal\u201c. Es entstehe dringend ben\u00f6tigter Wohnraum. Der Neubau soll auf einem fr\u00fcheren Sportgel\u00e4nde stehen, das die SAGA schon 2022 \u00fcbernommen hatte. (mp)<\/p>\n<p> <img decoding=\"async\" class=\"vg_wort_pixel\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/04\/vgzm.1021513-mopo-1857506.gif\" alt=\"\" style=\"width: 1px; height: 1px; position: absolute; pointer-events: none;\"\/><\/p>\n","protected":false},"excerpt":{"rendered":"Richtfest in Ei\u00dfendorf: Am Lichtenauerweg entstehen 216 Wohnungen und eine Kita. Fertig werden soll das neue Quartier im&hellip;\n","protected":false},"author":2,"featured_media":981626,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1826],"tags":[29,30,692],"class_list":{"0":"post-981625","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-hamburg","8":"tag-deutschland","9":"tag-germany","10":"tag-hamburg"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116487562765802087","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/981625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=981625"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/981625\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/981626"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=981625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=981625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=981625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}