{"id":987507,"date":"2026-05-01T20:55:28","date_gmt":"2026-05-01T20:55:28","guid":{"rendered":"https:\/\/www.europesays.com\/de\/987507\/"},"modified":"2026-05-01T20:55:28","modified_gmt":"2026-05-01T20:55:28","slug":"aus-fuer-die-lieferbots-in-hamburg-barmbek-das-ist-der-grund","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/987507\/","title":{"rendered":"Aus f\u00fcr die Lieferbots in Hamburg-Barmbek \u2013 das ist der Grund"},"content":{"rendered":"\n<p><strong>Nach rund sechs Monaten ist Schluss: Die autonomen Rewe-Lieferbots haben ihren Testlauf in Barmbek beendet. Die Supermarktkette zeigt sich zufrieden.<\/strong><\/p>\n<p>Seit Oktober 2025 waren die kleinen <a href=\"https:\/\/www.mopo.de\/hamburg\/rollender-warenkorb-rewe-schickt-die-autonomen-lieferbots-2-0-auf-den-weg\/\" rel=\"nofollow noopener\" target=\"_blank\">Lieferroboter in einem abgegrenzten Gebiet unterwegs<\/a>. Bestellt wurde per Rewe-App, dann zuckelte das W\u00e4gelchen mit maximal sechs Kilometern pro Stunde los und lieferte den Einkauf bis vor die Haust\u00fcr.<\/p>\n<p>Lieferbots legten Strecke im vierstelligen Bereich zur\u00fcck<\/p>\n<p>Rewe zieht ein \u201esehr positives Fazit\u201c, hei\u00dft es von dem Unternehmen. Grund f\u00fcr die Einstellung des Angebots sei das planm\u00e4\u00dfige Ende des Versuchs. Der Test habe gezeigt, dass autonome Lieferl\u00f6sungen im Alltag grunds\u00e4tzlich funktionieren und angenommen werden, sagt Andreas Persigehl, Vorsitzender der Gesch\u00e4ftsleitung der Rewe Region Nord. Nun folge die Auswertung: Technische Abl\u00e4ufe, Nutzung und organisatorische Rahmenbedingungen sollen gepr\u00fcft werden.<\/p>\n<p>  MOPO<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/04\/304-collage.png\" alt=\"\" class=\" size-full\"\/><\/p>\n<p><strong>Die WochenMOPO \u2013 ab Donnerstag neu und \u00fcberall, wo es Zeitungen gibt!<\/strong><br \/><strong>Diese Woche u.a. mit diesen Themen:<\/strong><\/p>\n<ul>\n<li><strong>Jobs mit Zukunft: <\/strong>Der neue Trend zum Handwerk<\/li>\n<li><strong>Sonnen-Wochenende:<\/strong> 20 tolle Tipps f\u00fcr den Start in den Mai<\/li>\n<li><strong>\u201eCold Cases\u201c: <\/strong>Vier spektakul\u00e4re F\u00e4lle aus Hamburg<\/li>\n<li><strong>Gro\u00dfe R\u00e4tselbeilage: <\/strong>Knobelspa\u00df f\u00fcr die ganze Woche<\/li>\n<li><strong>16 Seiten Sport: <\/strong>Die Folgen eines m\u00f6glichen St. Pauli-Abstiegs &amp; warum Uli Stein dem HSV Gro\u00dfes zutraut<\/li>\n<li><strong>28 Seiten Plan 7: <\/strong>Die Star-Magier Ehrlich Brothers, der \u201eHeaven Can Wait\u201c-Chor &amp; Kultur-Tipps f\u00fcr jeden Tag<\/li>\n<\/ul>\n<p>Laut Rewe legten die Lieferbots insgesamt eine Strecke im vierstelligen Bereich zur\u00fcck und lieferten ebenfalls Bestellungen im vierstelligen Bereich aus. Besonders gefragt waren Obst und Gem\u00fcse \u2013 vor allem Gurken, Bananen und rote Paprika \u2013, au\u00dferdem Getr\u00e4nke, Milch und Hafermilch, Butter, Br\u00f6tchen und Eier.<\/p>\n<p>Am meisten zu tun hatten die Lieferbots am sp\u00e4ten Nachmittag und fr\u00fchen Abend. Der beliebteste Bestelltag war der Samstag. Im Einsatz waren die Ger\u00e4te mit Technik des Partners Starship an sechs Tagen pro Woche.<\/p>\n<p><strong>Das k\u00f6nnte Sie auch interessieren:<\/strong> <a href=\"https:\/\/www.mopo.de\/news\/panorama\/wocheneinkauf-per-klick-lebensmittel-lieferungen-boomen-in-deutschland\/\" rel=\"nofollow noopener\" target=\"_blank\">Wocheneinkauf per Klick: Lebensmittel-Lieferungen boomen in Deutschland<\/a><\/p>\n<p>Hintergrund: Gestartet war das Projekt im Oktober 2025 rund um den Rewe-Markt am Holsteinischen Kamp. Die Bots fuhren in einem Radius von zwei Kilometern durch Barmbek. Sie wogen 35 Kilogramm, waren nur etwas gr\u00f6\u00dfer als ein Einkaufskorb und nutzten 360-Grad-Kameras sowie GPS. Alkoholbestellungen waren nur mit Identit\u00e4tspr\u00fcfung m\u00f6glich \u2013 \u201eheimlich Bier bestellen\u201c war also nicht drin. (tst)<\/p>\n<p> <img decoding=\"async\" class=\"vg_wort_pixel\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/vgzm.1021513-mopo-1859625.gif\" alt=\"\" style=\"width: 1px; height: 1px; position: absolute; pointer-events: none;\"\/><\/p>\n","protected":false},"excerpt":{"rendered":"Nach rund sechs Monaten ist Schluss: Die autonomen Rewe-Lieferbots haben ihren Testlauf in Barmbek beendet. Die Supermarktkette zeigt&hellip;\n","protected":false},"author":2,"featured_media":987508,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1826],"tags":[29,30,692],"class_list":{"0":"post-987507","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-hamburg","8":"tag-deutschland","9":"tag-germany","10":"tag-hamburg"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116501317562434963","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/987507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=987507"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/987507\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/987508"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=987507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=987507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=987507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}