{"id":987928,"date":"2026-05-02T01:09:17","date_gmt":"2026-05-02T01:09:17","guid":{"rendered":"https:\/\/www.europesays.com\/de\/987928\/"},"modified":"2026-05-02T01:09:17","modified_gmt":"2026-05-02T01:09:17","slug":"die-beste-klasse-deutschlands-wochenshow-1-hamburg-vs-stuttgart","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/987928\/","title":{"rendered":"Die beste Klasse Deutschlands: Wochenshow 1: Hamburg vs Stuttgart"},"content":{"rendered":"<p class=\"b1ja19fa b17iybsb b4tg6yv\" style=\"line-clamp:5;-webkit-line-clamp:5\">Die erste Wochenshow von &#8222;Die beste Klasse Deutschlands&#8220;! Norden gegen S\u00fcden &#8211; Welche Klasse sichert sich das erste Ticket der 23. Staffel f\u00fcr das gro\u00dfe Superfinale? In den Schulbattles qualifiziert haben sich 7b Gymnasium Rotherbaum Hamburg und 7c K\u00f6nigin-Katharina-Stift Gymnasium Stuttgart. Im KiKA-Studio in Erfurt erwartet die Klassen Clarissa mit tricky Fragen, verbl\u00fcffenden Experimenten und spannenden Spielrunden.<\/p>\n<p>Mehr anzeigen<\/p>\n","protected":false},"excerpt":{"rendered":"Die erste Wochenshow von &#8222;Die beste Klasse Deutschlands&#8220;! Norden gegen S\u00fcden &#8211; Welche Klasse sichert sich das erste&hellip;\n","protected":false},"author":2,"featured_media":987929,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1830],"tags":[1634,3364,29,30,1441],"class_list":{"0":"post-987928","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-stuttgart","8":"tag-baden-wuerttemberg","9":"tag-de","10":"tag-deutschland","11":"tag-germany","12":"tag-stuttgart"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116502316210223416","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/987928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=987928"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/987928\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/987929"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=987928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=987928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=987928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}