{"id":989215,"date":"2026-05-02T14:18:16","date_gmt":"2026-05-02T14:18:16","guid":{"rendered":"https:\/\/www.europesays.com\/de\/989215\/"},"modified":"2026-05-02T14:18:16","modified_gmt":"2026-05-02T14:18:16","slug":"ausbau-des-rheinboulevards-verzoegert-sich-2","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/989215\/","title":{"rendered":"Ausbau des Rheinboulevards verz\u00f6gert sich"},"content":{"rendered":"<p class=\"dm-paragraph leading-[1.5em] mb-8 my-8 dm-article-content-width\" index=\"0\" should-collapse-on-mobile=\"true\" has-padding=\"\" data-v-8f90ed31=\"\">\u201eDer Rheinboulevard l\u00f6st sich auf.\u201c Das schrieb die Stadtverwaltung im Oktober 2024 in aller Deutlichkeit \u00fcber den Zustand der rechtsrheinischen Flaniermeile zwischen Hohenzollernbr\u00fccke und Tanzbrunnen, verbunden mit einer guten Nachricht: Die 350 Meter lange Sandpiste, die sich bei Regen regelm\u00e4\u00dfig in eine Schlammw\u00fcste verwandelt, wird ab M\u00e4rz 2026 umgebaut. Daf\u00fcr stehen rund vier Millionen Euro bereit. Bauzeit: 18 Monate.<\/p>\n<p class=\"dm-paragraph leading-[1.5em] mb-8 my-8 dm-article-content-width\" index=\"1\" should-collapse-on-mobile=\"true\" has-padding=\"\" data-v-8f90ed31=\"\">Doch jetzt folgt die Ern\u00fcchterung: Auf Nachfrage teilt die Stadtverwaltung mit, dass sich der Umbau um ein Jahr verz\u00f6gern wird. Und warum?<\/p>\n<p>Verwaltung spricht von komplexen Planungen<\/p>\n<p class=\"dm-paragraph leading-[1.5em] mb-8 my-8 dm-article-content-width\" index=\"3\" should-collapse-on-mobile=\"true\" has-padding=\"\" data-v-8f90ed31=\"\">Weil der Ausbau bis zum Tanzbrunnen \u201esehr komplex\u201c sei. Zun\u00e4chst m\u00fcssten die Anforderungen des Hochwasserschutzes, des Naturschutzes, des Denkmalschutzes, der Deichverordnung und der Neuplanung der Entw\u00e4sserung in die Planungen aufgenommen werden. Auch der Ausbau des Bahnhofs K\u00f6ln-Messe\/Deutz um einen Bahnsteig mit zwei Gleisen, neue Landstromleitungen f\u00fcr den Anlegesteg und die Pr\u00fcfung eines weiteren Schiffsanlegers verz\u00f6gerten das Verfahren.<\/p>\n<p class=\"dm-paragraph leading-[1.5em] mb-8 my-8 dm-article-content-width\" index=\"4\" should-collapse-on-mobile=\"true\" has-padding=\"\" data-v-8f90ed31=\"\">Immerhin habe man die Standfestigkeit der Mauer \u00fcberpr\u00fcft und die Planungen f\u00fcr ein Gel\u00e4nder abgeschlossen. Auch sei gekl\u00e4rt, dass das Ufer mit mobilen Elementen f\u00fcr den Hochwasserschutz nachger\u00fcstet werden kann. Die Stadt geht davon aus, den Auftrag zum Umbau des Rheinboulevards im Januar 2027 zu vergeben und voraussichtlich im ersten Quartal mit den Arbeiten zu beginnen. Die Finanzierung sei im Haushalt auch f\u00fcr 2027 gesichert. Eine provisorische L\u00f6sung f\u00fcr den Sandweg sei mit Blick auf den bevorstehenden Umbau zu teuer.<\/p>\n<p>Freitreppe wurde 2015 von Oberb\u00fcrgermeister Roters er\u00f6ffnet<\/p>\n<p class=\"dm-paragraph leading-[1.5em] mb-8 my-8 dm-article-content-width\" index=\"6\" should-collapse-on-mobile=\"true\" has-padding=\"\" data-v-8f90ed31=\"\">Wenn es bei dem Baubeginn im ersten Quartal 2027 bleibt, k\u00f6nnte es tats\u00e4chlich klappen, dass\u00a0 im Jahr 2029, 14 Jahre nach der Er\u00f6ffnung der 500 Meter Freitreppe des Rheinboulevards zwischen der Hohenzollernbr\u00fccke und der Deutzer Br\u00fccke durch den damaligen Oberb\u00fcrgermeister J\u00fcrgen Roters (SPD) (\u201eDas ist der neue Logenplatz der K\u00f6lner\u201c) ein weiterer Abschnitt des Rheinufers auf der Sch\u00e4l Sick seiner Vollendung entgegengeht.<\/p>\n<p class=\"dm-paragraph leading-[1.5em] mb-8 my-8 dm-article-content-width\" index=\"7\" should-collapse-on-mobile=\"true\" has-padding=\"\" data-v-8f90ed31=\"\">Was soll entstehen? Bei einem Spaziergang vor vier Jahren, an dem sich viele K\u00f6lnerinnen und K\u00f6lner beteiligten, wurde schnell klar, dass sich auch der neue Weg Richtung Norden trennen, ein Abzweig in den Rheinpark und einer zum Tanzbrunnen f\u00fchren soll. Dort soll ein kleiner Park mit alten und neuen B\u00e4umen als Vorposten des Rheinparks entstehen. Damit sich Fu\u00dfg\u00e4nger und Radfahrer nicht in die Quere kommen, werden sie r\u00e4umlich voneinander getrennt.<\/p>\n","protected":false},"excerpt":{"rendered":"\u201eDer Rheinboulevard l\u00f6st sich auf.\u201c Das schrieb die Stadtverwaltung im Oktober 2024 in aller Deutlichkeit \u00fcber den Zustand&hellip;\n","protected":false},"author":2,"featured_media":989216,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1828],"tags":[29,30,1420,1209],"class_list":{"0":"post-989215","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-koeln","8":"tag-deutschland","9":"tag-germany","10":"tag-koeln","11":"tag-nordrhein-westfalen"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116505418728663234","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/989215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=989215"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/989215\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/989216"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=989215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=989215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=989215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}