{"id":992678,"date":"2026-05-04T02:07:16","date_gmt":"2026-05-04T02:07:16","guid":{"rendered":"https:\/\/www.europesays.com\/de\/992678\/"},"modified":"2026-05-04T02:07:16","modified_gmt":"2026-05-04T02:07:16","slug":"berlin-brandenburg-shoppen-mal-anders-blumen-aus-dem-gefaengnis","status":"publish","type":"post","link":"https:\/\/www.europesays.com\/de\/992678\/","title":{"rendered":"Berlin &#038; Brandenburg: Shoppen mal anders &#8211; Blumen aus dem Gef\u00e4ngnis"},"content":{"rendered":"<p>Berlin &amp; BrandenburgShoppen mal anders &#8211; Blumen aus dem Gef\u00e4ngnis<img decoding=\"async\" class=\"Image_img__fQCi0 Image_Img_16_9__4BLfH\" loading=\"eager\" fetchpriority=\"high\" src=\"https:\/\/www.europesays.com\/de\/wp-content\/uploads\/2026\/05\/Beim-Fruehlingsbasar-der-JVA-Tegel-gibt-es-ein-breites-Angebot.webp\" alt=\"Beim-Fruehlingsbasar-der-JVA-Tegel-gibt-es-ein-breites-Angebot\"\/>TeilenFolgen auf:<a href=\"https:\/\/www.whatsapp.com\/channel\/0029Va5cdVJD8SDp5YZgYF01\" title=\"Auf WhatsApp folgen\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/www.n-tv.de\/socialIcons\/whatsapp.svg\" alt=\"whatsapp\" class=\"ArticleShare_icon__FsrC2\"\/><\/a><a href=\"https:\/\/news.google.com\/publications\/CAAiEPMdif5mpRNxiLOeUpHCwwsqFAgKIhDzHYn-ZqUTcYiznlKRwsML?hl=de&amp;gl=DE&amp;ceid=DE%3Ade\" title=\"Auf Google News folgen\" target=\"_blank\" rel=\"nofollow noopener\"><img decoding=\"async\" src=\"https:\/\/www.n-tv.de\/socialIcons\/google.svg\" alt=\"whatsapp\" class=\"ArticleShare_icon__FsrC2\"\/><\/a><\/p>\n<p class=\"Typography_text-m__XI0da Typography_weight-bold__uT6mq storyline_lead_text_leadtext__q_wg8\">Die meisten Insassen in Gef\u00e4ngnissen arbeiten, in der G\u00e4rtnerei oder in Werkst\u00e4tten zum Beispiel. Von dem, was sie herstellen, l\u00e4sst sich einiges kaufen &#8211; wenn man wei\u00df, wo und wann.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Berlin (dpa\/bb) &#8211; Geranien oder Balkontomaten, Feuerschalen oder Vogelh\u00e4uschen &#8211; in Berlin stehen gleich zwei Termine zum Shoppen der etwas anderen Art an. Bereits am Donnerstag (7. Mai) l\u00e4dt die Jugendstrafanstalt Berlin dazu ein, beim Stra\u00dfenverkauf vor der Pforte der Anstalt am Friedrich-Olbricht-Damm in Charlottenburg-Nord Blumen und Nutzpflanzen f\u00fcr Balkon und Garten zu erwerben.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Sie sind von den Gefangenen in der anstaltseigenen G\u00e4rtnerei unter fachlicher Anleitung aufgezogen worden. Fachmitarbeiter der Jugendstrafanstalt verkaufen die Pflanzen von 9.45 Uhr bis 12.45 Uhr und \u00fcbernehmen auch die Beratung.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Die Jugendstrafanstalt verfolgt nach eigenen Angaben das Ziel, junge Gefangene durch Ausbildung und Qualifizierung f\u00fcr ein straffreies Leben nach der Haft vorzubereiten. Den Stra\u00dfenverkauf gibt es bereits seit mehr als drei Jahrzehnten.<\/p>\n<p>Von Erdbeerpflanzen bis zu Dahlien<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Im Angebot sind Balkon- und Garten-, Gem\u00fcse- und Kr\u00e4uterpflanzen. So kosten beispielsweise Erdbeerpflanzen 70 Cent, Geranien 2,00 Euro, Balkontomaten 2,50 Euro. Dahlien gibt es ab 1,70 Euro.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Am Samstag darauf (9. Mai) ist Fr\u00fchlingsbasar im Shop der Justizvollzugsanstalt (JVA) Tegel in der Seidelstra\u00dfe. Von 10.00 bis 15.00 Uhr sind dort ebenfalls Beet- und Balkonpflanzen aus eigener Anzucht im Angebot. Daneben gibt es aber auch Blumengestecke, Feuerschalen, Kerzenhalter, Vogelh\u00e4user und kleinere M\u00f6belst\u00fccke wie Hocker, St\u00fchle und Fu\u00dfb\u00e4nke.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Der Shop ist auf dem Gel\u00e4nde der JVA Tegel in der Seidelstra\u00dfe 41 zu finden, au\u00dferhalb der Anstaltsmauer. An den St\u00e4nden gibt es Produkte aus der JVA Tegel und der JVA f\u00fcr Frauen Berlin. Die Artikel kosten den Angaben zufolge zwischen 2 Euro f\u00fcr kleine Dekorationsartikel und 200 Euro f\u00fcr einen Grill.<\/p>\n<p>Erbseneintopf aus der Gulaschkanone<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Wer nicht erst zu Hause essen will, hat vor Ort etliche andere M\u00f6glichkeiten: Neben Erbseneintopf aus der Gulaschkanone gibt es Bockwurst und Wiener W\u00fcrstchen sowie alkoholfreie Getr\u00e4nke, au\u00dferdem Kekse, frisches Brot und Kuchen &#8211; darunter nicht zuletzt den Tegeler &#8222;Wochenendkuchen&#8220;, der in der Lehrb\u00e4ckerei der JVA Tegel hergestellt wird.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Besucherinnen und Besucher k\u00f6nnen au\u00dferdem einen Blick hinter die Kulissen werfen: Auf dem Platz vor Tor I in der Seidelstra\u00dfe 39 informiert der Berliner Justizvollzug \u00fcber Berufe sowie \u00fcber Einstiegs- und Karrierem\u00f6glichkeiten. Auch verschiedene Vereine und Unternehmen stellen sich vor.<\/p>\n<p class=\"Typography_text-default__P3otY Typography_weight-normal__pqUbH storyline_paragraph_p__qSR5N\">Inhaftierte der JVA Tegel nehmen selbst nicht am Fr\u00fchlingsbasar teil. Allerdings sind inhaftierte Frauen, die in einer Einrichtung des offenen Vollzuges untergebracht sind, f\u00fcr den Verkauf ihrer Produkte vor Ort.<\/p>\n<p class=\"Typography_text-s__wu_cm Typography_weight-normal__pqUbH Typography_color-darkgrey__sZEnP article-detail-footer_source__KslPc\">Quelle: dpa<\/p>\n","protected":false},"excerpt":{"rendered":"Berlin &amp; BrandenburgShoppen mal anders &#8211; Blumen aus dem Gef\u00e4ngnisTeilenFolgen auf: Die meisten Insassen in Gef\u00e4ngnissen arbeiten, in&hellip;\n","protected":false},"author":2,"featured_media":992679,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1816],"tags":[1960,1958,1959,1957,1956,1890,29,30],"class_list":{"0":"post-992678","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-brandenburg","8":"tag-aktuelle-nachrichten-aus-berlin-und-brandenburg","9":"tag-aktuelle-nachrichten-aus-brandenburg","10":"tag-aktuelle-news-aus-berlin-und-brandenburg","11":"tag-aktuelle-news-aus-brandenburg","12":"tag-berlin-und-brandenburg","13":"tag-brandenburg","14":"tag-deutschland","15":"tag-germany"},"share_on_mastodon":{"url":"https:\/\/pubeurope.com\/@de\/116513869081331438","error":""},"_links":{"self":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/992678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/comments?post=992678"}],"version-history":[{"count":0,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/posts\/992678\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media\/992679"}],"wp:attachment":[{"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/media?parent=992678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/categories?post=992678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europesays.com\/de\/wp-json\/wp\/v2\/tags?post=992678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}